{"id":77287,"date":"2024-02-14T10:35:23","date_gmt":"2024-02-14T16:35:23","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=77287"},"modified":"2024-02-14T10:35:24","modified_gmt":"2024-02-14T16:35:24","slug":"comunidades-de-aprendizaje-ciencia-educativa-en-mexico","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/comunidades-de-aprendizaje-ciencia-educativa-en-mexico\/","title":{"rendered":"Comunidades de Aprendizaje: ciencia educativa en M\u00e9xico"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong>Comunidades de Aprendizaje es un proyecto educativo basado en evidencias presente en M\u00e9xico desde el 2013.<\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sus impactos constatan que la ciencia puede y debe estar al servicio de una mejor educaci\u00f3n.<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mar\u00eda del Socorro Ocampo Castillo*<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 14 de febrero, 2024.- Al momento de escribir estas l\u00edneas, tengo la enorme satisfacci\u00f3n de participar desde distintos frentes y desde hace m\u00e1s de 12 a\u00f1os en la transferencia de las Comunidades de Aprendizaje a M\u00e9xico y conf\u00edo que sus transformaciones y la contundente y esperanzadora ciencia que le sostiene, continuar\u00e1 impactando en una mejor educaci\u00f3n y en m\u00e1s sue\u00f1os de vida que se hacen realidad a partir de ella.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comunidades de aprendizaje es un proyecto de transformaci\u00f3n social y educativa que se basa en dos elementos fundamentales para el aprendizaje: las interacciones y la participaci\u00f3n de la comunidad,<a href=\"#_ftn1\" id=\"_ftnref1\"><sup>[1]<\/sup><\/a><sup> &nbsp;<\/sup>el cual se basa en la implementaci\u00f3n de Actuaciones Educativas de \u00c9xito (AEE) identificadas por la comunidad cient\u00edfica internacional por su efectividad en la mejora de aprendizajes y de convivencia en cualquier contexto en donde se apliquen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su objetivo consiste en la transformaci\u00f3n de las escuelas tras un proceso que pasa por las fases de sensibilizaci\u00f3n (colocar con la comunidad las bases te\u00f3ricas y metodol\u00f3gicas del proyecto), toma de decisi\u00f3n (toda la comunidad decide si desea o no convertirse en una comunidad de aprendizaje), sue\u00f1o (en un evento emotivo, todas las personas sue\u00f1an con la escuela que desean), priorizaci\u00f3n (se priorizan y organizan los sue\u00f1os de todas las personas) y planificaci\u00f3n (hacer los sue\u00f1os realidad a partir de la implementaci\u00f3n de las AEE).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comunidades de Aprendizaje cuenta con una trayectoria de m\u00e1s de 45 a\u00f1os durante los cuales escuelas alrededor del mundo han experimentado y testificado estas transformaciones y se han convertido en referentes de esperanza y posibilidad. Lo anterior es posible gracias a la ciencia de impacto social que sostiene al proyecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comunidades de Aprendizaje se sustenta en el aprendizaje dial\u00f3gico, teor\u00eda educativa basada en la concepci\u00f3n comunicativa del aprendizaje la cual sostiene que las personas aprendemos m\u00e1s y mejor a partir de interacciones y que construimos y damos significados a nuestra realidad a partir de la comunicaci\u00f3n y el di\u00e1logo con otras personas. De ese modo el conocimiento se genera primero desde un plano social para luego interiorizarse como conocimiento propio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El aprendizaje dial\u00f3gico sostiene que las personas necesitamos situaciones de interacci\u00f3n para aprender, pero que no basta con generar muchas interacciones, sino que tambi\u00e9n \u00e9stas deben ser diversas y establecerse a partir del di\u00e1logo basado en relaciones de igualdad y no de poder. Ello significa reconocer que todas las personas tenemos conocimiento que aportar a partir de nuestra inteligencia cultural.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a><\/a>De manera pr\u00e1ctica, el aprendizaje dial\u00f3gico se manifiesta mediante siete principios: di\u00e1logo igualitario, inteligencia cultural, transformaci\u00f3n, dimensi\u00f3n instrumental, creaci\u00f3n de sentido, solidaridad e igualdad. Cada uno de estos principios est\u00e1 presente en todo momento en las Comunidades de Aprendizaje y es lo que logra que efectivamente se puedan obtener m\u00e1s y mejores resultados que apuntalen al \u00e9xito para todas las personas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El siguiente componente de las Comunidades de Aprendizaje son las AEE<a href=\"#_ftn2\" id=\"_ftnref2\"><sup>[2]<\/sup><\/a>, estas actuaciones han sido identificadas a partir de cuatro criterios, el primero es que fueran actuaciones educativas capaces de generar mejoras en aprendizaje y convivencia; el segundo que pudieran ser universales y transferibles a cualquier contexto; el tercero es que los dos puntos anteriores estuvieran demostrados a partir de investigaciones cient\u00edficas que hubieran tomado en cuenta las voces de toda la comunidad (y no s\u00f3lo la del equipo investigador u otros interesados); por \u00faltimo que los tres criterios mencionados estuvieran avalados por publicaciones rigurosas de la comunidad cient\u00edfica internacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siguiendo estos criterios, el proyecto INCLUD-ED desarroll\u00f3 22 estudios de casos y un despliegue internacional de m\u00e1s de 150 investigadores de 14 universidades distintas que contribuyeron a tal objetivo, teniendo por resultado la identificaci\u00f3n de seis actuaciones:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Grupos interactivos<\/li>\n\n\n\n<li>Tertulias dial\u00f3gicas<\/li>\n\n\n\n<li>Participaci\u00f3n Educativa de la comunidad<\/li>\n\n\n\n<li>Formaci\u00f3n de familiares<\/li>\n\n\n\n<li>Formaci\u00f3n dial\u00f3gica de profesorado<\/li>\n\n\n\n<li>Modelo dial\u00f3gico de prevenci\u00f3n y superaci\u00f3n de conflictos<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Todas estas AEE aseguran el mejoramiento un\u00edsono de aprendizajes acad\u00e9micos y de convivencia. Al d\u00eda de hoy, m\u00faltiples investigaciones y publicaciones cient\u00edficas contin\u00faan dando cuenta de los impactos positivos que la implementaci\u00f3n de AEE conllevan en los contextos escolares a&nbsp; nivel individual, que comprende (1) el aprendizaje instrumental de los estudiantes y 2) la autoestima y la motivaci\u00f3n; a nivel de grupal, que implica (3) mejorar las relaciones interpersonales y (4) cohesi\u00f3n y reducci\u00f3n de conflictos; y a nivel comunitario, que comprende (5) participaci\u00f3n familiar y cambio hacia la escuela y (6) reducci\u00f3n del ausentismo<a href=\"#_ftn3\" id=\"_ftnref3\"><sup>[3]<\/sup><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En M\u00e9xico, la transferencia del proyecto Comunidades de Aprendizaje inici\u00f3 en 2013 a partir del trabajo conjunto entre el centro de investigaci\u00f3n CREA, el \u00e1rea de responsabilidad social de la empresa Natura y la organizaci\u00f3n civil V\u00eda Educaci\u00f3n. Esta triada logr\u00f3 el acercamiento a las autoridades educativas estatales y locales para la formaci\u00f3n de formadores, gestores y profesorado implementador del proyecto. Desde entonces, estudiantes, docentes, directivos y familias de las m\u00e1s de 200 escuelas que participan del proyecto, dan cuenta de mejoras tanto en aprendizaje como en la creaci\u00f3n de un clima escolar participativo, solidario y dial\u00f3gico que se presenta en las relaciones e interacciones de la escuela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un ejemplo de gran relevancia es el publicado en el caso de la escuela Sor Juan In\u00e9s de la Cruz ubicada en Tlajomulco, Jalisco. Esta escuela se transform\u00f3 en una Comunidad de Aprendizaje en 2016 y a partir de la realizaci\u00f3n de todas las AEE logr\u00f3 una mejora dr\u00e1stica en los resultados de aprendizaje del estudiantado y una mejora destacable en aspectos de convivencia. Estas mejoras se manifestaron en pruebas estandarizadas como PLANEA, la cual en 2015 identificaba al 66 y 86 por ciento del estudiantado en niveles insuficientes de aprendizaje de lectura y matem\u00e1ticas respectivamente. Para el 2018, el porcentaje de estudiantes en ese nivel se redujo a 29 y 40 por ciento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/02\/mux.jpg\"><img decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/02\/mux-1024x505.jpg\" alt=\"\" class=\"wp-image-77288\"\/><\/a><figcaption class=\"wp-element-caption\"><strong>Cr\u00e9dito:<\/strong> comunidadesdeaprendizaje.com.es<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Tales mejoras no pasaron desapercibidas por la comunidad escolar y tampoco por la investigaci\u00f3n cient\u00edfica, de modo que estos resultados se publicaron en 2021 por la <em>Cambridge Journal of Education<\/em><a href=\"#_ftn4\" id=\"_ftnref4\"><sup>[4]<\/sup><\/a> mediante el trabajo de investigaci\u00f3n dial\u00f3gica efectuado por investigadores del CREA en M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este mismo caso, tambi\u00e9n permiti\u00f3 la publicaci\u00f3n del art\u00edculo: \u201c<em>Young children and a school community open pathways for a grandmother&#8217;s literacy\u201d<\/em> publicado en la revista <em>Issues in Educational Research<\/em><a href=\"#_ftn5\" id=\"_ftnref5\"><sup>[5]<\/sup><\/a>, en el cual se pone de manifiesto el impacto de la formaci\u00f3n de familias en la alfabetizaci\u00f3n e inclusi\u00f3n social de personas adultas mayores. En el art\u00edculo se comparte la historia de alfabetizaci\u00f3n de Mar\u00eda, una abuela que, a sus 70 a\u00f1os, motivada por su nieta y por las interacciones dial\u00f3gicas presentes en la escuela, inicia y concluye su proceso de alfabetizaci\u00f3n logrando aprender a leer y escribir en los espacios de formaci\u00f3n ofrecidos por la escuela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comunidades de Aprendizaje es un proyecto educativo basado en evidencias presente en M\u00e9xico desde el 2013, sus impactos constatan que la ciencia puede y debe estar al servicio de una mejor educaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.muxed.mx\/blog\/comunidades-aprendizaje-mexico\">https:\/\/www.muxed.mx\/blog\/comunidades-aprendizaje-mexico<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/02\/mux2.jpg\"><img decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/02\/mux2-1024x990.jpg\" alt=\"\" class=\"wp-image-77289\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mar\u00eda del Socorro Ocampo Castillo*. <\/strong>Integrante de MUxED. Es investigadora del Instituto de Investigaciones en Educaci\u00f3n de la Universidad Veracruzana en la l\u00ednea de Educaci\u00f3n Ambiental. Su trabajo actual se centra en contribuir a la transferencia del proyecto Comunidades de Aprendizaje y las Actuaciones Educativas de \u00c9xito a M\u00e9xico, lo cual la ha llevado a colaborar en la organizaci\u00f3n civil V\u00eda Educaci\u00f3n, como asesora especialista en Comunidades de Aprendizaje y subdirectora de Investigaci\u00f3n para la Autoridad Educativa Federal en la ciudad de M\u00e9xico y como consultora independiente para distintas organizaciones.<strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Instagram: maryocamp0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">X: @Mary1390<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"#_ftnref1\" id=\"_ftn1\">[1]<\/a> <a href=\"https:\/\/comunidadesdeaprendizaje.net\/\">https:\/\/comunidadesdeaprendizaje.net\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"#_ftnref2\" id=\"_ftn2\">[2]<\/a> Este conjunto de actuaciones fue identificado por el proyecto<em> INCLUD-ED<sup>#<\/sup>: Strategies for inclusion and social cohesion in Europe from education<\/em>, del sexto programa marco de la Comisi\u00f3n Europea desarrollado del a\u00f1o 2006 al 2011 y liderado por el centro de investigaci\u00f3n CREA (Community of Research on Excellence for All) <sup>#<\/sup> de la Universidad de Barcelona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"#_ftnref3\" id=\"_ftn3\">[3]<\/a> <a href=\"https:\/\/www.sciencedirect.com\/science\/article\/pii\/S1747938X22000513\">https:\/\/www.sciencedirect.com\/science\/article\/pii\/S1747938X22000513<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"#_ftnref4\" id=\"_ftn4\">[4]<\/a> <a href=\"https:\/\/www.tandfonline.com\/doi\/abs\/10.1080\/0305764X.2021.1973374\">https:\/\/www.tandfonline.com\/doi\/abs\/10.1080\/0305764X.2021.1973374<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"#_ftnref5\" id=\"_ftn5\">[5]<\/a> <a href=\"https:\/\/www.iier.org.au\/iier33\/2023conts.html\">https:\/\/www.iier.org.au\/iier33\/2023conts.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comunidades de Aprendizaje es un proyecto educativo basado en evidencias presente en M\u00e9xico desde el 2013.<\/p>\n","protected":false},"author":3,"featured_media":77288,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[703],"tags":[],"class_list":["post-77287","post","type-post","status-publish","format-standard","has-post-thumbnail","category-infancia"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/77287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=77287"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/77287\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/77288"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=77287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=77287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=77287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}