{"id":77080,"date":"2024-02-08T17:03:35","date_gmt":"2024-02-08T23:03:35","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=77080"},"modified":"2024-02-08T17:03:36","modified_gmt":"2024-02-08T23:03:36","slug":"distinguen-luminosidad-y-color-la-obra-de-la-artista-uruguaya-petrona-viera","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/distinguen-luminosidad-y-color-la-obra-de-la-artista-uruguaya-petrona-viera\/","title":{"rendered":"Distinguen luminosidad y color la obra de la artista uruguaya Petrona Viera"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">*Andrea Garc\u00eda Rodr\u00edguez destac\u00f3 el papel de la pintora en el arte moderno latinoamericano, en una conferencia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">* Artistas uruguayas contribuyeron a crear un arte moderno latinoamericano<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Redacci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 8 de febrero, 2024.- Con el fin de provocar en el espectador otra mirada a la obra de la pintora uruguaya Petrona Viera, la investigadora Andrea Garc\u00eda Rodr\u00edguez imparti\u00f3 una conferencia en el Museo Nacional de Arte (Munal), donde se exhibe&nbsp;<em>Petrona Viera. Una creaci\u00f3n sin fin<\/em>, la cual se presentar\u00e1 hasta abril en el recinto del Instituto Nacional de Bellas Artes y Literatura (Inbal).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tema de la ponencia&nbsp;<em>Del planismo al constructivismo: redes de artistas uruguayas en el arte moderno latinoamericano<\/em>&nbsp;comprendi\u00f3 una amplia disertaci\u00f3n sobre el arte que cre\u00f3 la pintora y que influy\u00f3 en el sur del Continente Americano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Garc\u00eda Rodr\u00edguez dijo que su conferencia fue una provocaci\u00f3n para ver con otra mirada la obra de Petrona Viera y acercarse al ambiente \u00edntimo de la artista, al contexto sociocultural de principios del siglo pasado en Uruguay, \u201cun pa\u00eds que se me antoja demasiado lejos de nuestro \u00e1mbito y de nuestra historia\u201d, coment\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La doctora en Historia del arte por la Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM) indic\u00f3 que no debe olvidarse que algunas artistas uruguayas contribuyeron a crear un arte moderno latinoamericano, como Petrona Viera, una de las caras visibles de esta historia. Tambi\u00e9n cit\u00f3 a creadoras como&nbsp;Amalia Nieto y Rosa Acle, que se desenvolvieron en este mismo \u00e1mbito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recomend\u00f3 observar atentamente su autorretrato de 1930, que describi\u00f3 como una imagen imponente y profunda de una mujer que hab\u00eda vivido desde los cuatro a\u00f1os de edad con sordera derivada posiblemente de una meningitis aguda, seg\u00fan se cree.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La especialista en vanguardias latinoamericanas en el arte y la literatura se\u00f1al\u00f3 que esa imagen muestra una figura altiva que devuelve su mirada sin concesiones, sin pretensi\u00f3n o recelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSu mirada \u2014explic\u00f3\u2014 sugiere una severidad intelectual frente a lo que la rodea, nos hace un recuento de su vida muy minucioso para ver el detalle, un ejercicio exhaustivo al observar e inspeccionar la luz, el color y tambi\u00e9n lo cotidiano\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00f1adi\u00f3 que su autorretrato refleja la personalidad espec\u00edfica de la pintora nacida en 1895 y fallecida en 1960 en Montevideo, Uruguay.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que en 1905 muchos artistas uruguayos emigraron a Europa para conocer las nuevas vanguardias art\u00edsticas y completar su formaci\u00f3n, adem\u00e1s de que se crean varias revistas literarias. La cultura comienza a estar presente en Uruguay, pero Viera estar\u00e1 al margen de este ambiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cFue una artista que entre muchas otras cosas pint\u00f3 a un Uruguay feliz y lleno de luz\u201d, explic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, la ponente celebr\u00f3 que se le haya dado su lugar a la pintora en la historia del arte uruguayo, luego de haber permanecido varios a\u00f1os subestimada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Museo Nacional de Arte se ubica en Tacuba 8, Centro Hist\u00f3rico, abierto de martes a domingo de 10:00 a 18:00 horas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/02\/petrona-1.jpeg\"><img decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/02\/petrona-1-1024x816.jpeg\" alt=\"\" class=\"wp-image-77082\"\/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Con el fin de provocar en el espectador otra mirada a la obra de la pintora uruguaya Petrona Viera, la investigadora Andrea Garc\u00eda Rodr\u00edguez imparti\u00f3 una conferencia en el Museo Nacional de Arte (Munal), donde se exhibe\u00a0Petrona Viera.<\/p>\n","protected":false},"author":3,"featured_media":77081,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[45,46],"tags":[],"class_list":["post-77080","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura","category-cultura-cultura"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/77080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=77080"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/77080\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/77081"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=77080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=77080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=77080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}