{"id":77060,"date":"2024-02-08T12:08:07","date_gmt":"2024-02-08T18:08:07","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=77060"},"modified":"2024-02-08T12:13:26","modified_gmt":"2024-02-08T18:13:26","slug":"regresiva-la-iniciativa-de-amlo-para-desaparecer-organos-autonomos","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/regresiva-la-iniciativa-de-amlo-para-desaparecer-organos-autonomos\/","title":{"rendered":"Regresiva la iniciativa de AMLO para desaparecer \u00f3rganos aut\u00f3nomos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">* En carta p\u00fablica, unas mil personas y organizaciones llaman al Congreso de la Uni\u00f3n a rechazar la propuesta<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">* Violenta garant\u00eda de los derechos humanos de las personas y al esquema de controles y contrapesos democr\u00e1ticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adela Ram\u00edrez Mu\u00f1oz&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 8 de febrero, 2024.- Unas mil personas, organizaciones de la sociedad civil, periodistas, acad\u00e9micas y defensoras de derechos humanos, califican de regresiva y preocupante la iniciativa de desaparecer \u00f3rganos aut\u00f3nomos como el Instituto Nacional de Transparencia y Acceso a la Informaci\u00f3n y Protecci\u00f3n de Datos Personales (INAI) y llaman al Congreso de la Uni\u00f3n a rechazar esta iniciativa y poner en el centro del debate la progresividad de los derechos que tenemos todas las personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una carta p\u00fablica llaman al Legislativo a asumir un compromiso real por parte de las autoridades para garantizar los derechos humanos, para garantizar la transparencia y el combate a la corrupci\u00f3n busca robustecer y no atacar a las instituciones aut\u00f3nomas encargadas de su protecci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo anterior, luego de las iniciativas que present\u00f3 el presidente Andr\u00e9s Manuel L\u00f3pez Obrador en un paquete de 18 reformas constitucionales y dos leyes secundarias, a tan solo cuatro meses de que ocurran las elecciones presidenciales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunas de estas iniciativas proponen cambios preocupantes, sobre todo las de materia pol\u00edtico-electoral, las que buscan reformar al Poder Judicial o las que proponen la desaparici\u00f3n de distintos \u00f3rganos, pues generan importantes regresiones en la garant\u00eda de los derechos humanos de las personas y al esquema de controles y contrapesos democr\u00e1ticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explican que la propuesta del Ejecutivo Federal plantea la eliminaci\u00f3n de cuatro \u00f3rganos constitucionales aut\u00f3nomos y otros tres desconcentrados y descentralizados, entre los que se encuentra INAI, bajo el argumento de \u00abduplicaci\u00f3n de funciones\u201d y pretende trasladar esas funciones a otras dependencias como la Secretar\u00eda de la Funci\u00f3n P\u00fablica (SFP), a las contralor\u00edas de los otros Poderes de la Uni\u00f3n, al Instituto Nacional Electoral y al Centro Federal de Conciliaci\u00f3n y Registro Laboral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, argumentan que se proponga que la SFP asuma las funciones que realiza el INAI es contrario a los avances registrados en materia de transparencia, acceso a la informaci\u00f3n y rendici\u00f3n de cuentas construidos a lo largo de los \u00faltimos 20 a\u00f1os, adem\u00e1s de que no forman parte de su mandato. &nbsp;A la SFP le corresponde verificar el correcto funcionamiento de la administraci\u00f3n p\u00fablica y de las personas servidoras p\u00fablicas a nivel federal y se restringe al \u00e1mbito del Poder Ejecutivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y enfatizan que la desaparici\u00f3n del INAI implicar\u00eda la desaparici\u00f3n, en cadena, de los \u00f3rganos garantes de transparencia de las distintas entidades federativas, poniendo en riesgo el sistema de transparencia del pa\u00eds y el derecho a saber de la sociedad en su conjunto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, exponen que la desaparici\u00f3n de los organismos aut\u00f3nomos que propone el presidente tampoco se garantizan ahorros significativos, pues tan s\u00f3lo el presupuesto del INAI (mil,168 millones de pesos asignados para 2024) apenas representa el 0.01% del gasto total del gobierno federal, de ah\u00ed que es preocupante \u201cque el discurso de austeridad se establezca por encima del fortalecimiento institucional y la garant\u00eda de los derechos humanos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente recuerdan que la existencia de un \u00f3rgano aut\u00f3nomo se logr\u00f3 abrir informaci\u00f3n que las entidades p\u00fablicas se han negado a divulgar, como lo son casos emblem\u00e1ticos de corrupci\u00f3n y graves violaciones a los derechos humanos. De ah\u00ed que es indispensable apostar a mecanismos rigurosos que aseguren que dichos \u00f3rganos cuenten con los mejores perfiles, independientes y con la experiencia necesaria para la protecci\u00f3n y defensa de los derechos humanos sin injerencias por parte de otros poderes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/arm\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Califican de regresiva y preocupante la iniciativa de desaparecer \u00f3rganos aut\u00f3nomos como el Instituto Nacional de Transparencia y Acceso a la Informaci\u00f3n y Protecci\u00f3n de Datos Personales (INAI) y llaman al Congreso de la Uni\u00f3n a rechazar esta iniciativa y poner en el centro del debate la progresividad de los derechos que tenemos todas las personas.<\/p>\n","protected":false},"author":3,"featured_media":77061,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[682],"tags":[],"class_list":["post-77060","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/77060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=77060"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/77060\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/77061"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=77060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=77060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=77060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}