{"id":76446,"date":"2024-01-24T12:03:57","date_gmt":"2024-01-24T18:03:57","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=76446"},"modified":"2024-01-24T12:03:57","modified_gmt":"2024-01-24T18:03:57","slug":"alarmante-crisis-en-materia-de-derechos-humanos-profundizada-en-este-gobierno-que-la-niega-epu","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/alarmante-crisis-en-materia-de-derechos-humanos-profundizada-en-este-gobierno-que-la-niega-epu\/","title":{"rendered":"Alarmante crisis en materia de derechos humanos, profundizada en este gobierno que la niega: EPU"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong>M\u00e9xico vive feminicidios, desaparici\u00f3n, asesinatos de madres buscadoras m\u00e1s<\/strong><\/li>\n\n\n\n<li><strong>Hay 5 mil hu\u00e9rfanas y hu\u00e9rfanos por feminicidios y 82 asesinatos de medio ambientalistas<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Elda Montiel<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 23 de enero, 2024.- A un d\u00eda del Examen Peri\u00f3dico Universal (EPU) de M\u00e9xico ante la Asamblea General de la ONU el 4\u00ba Informe del Colectivo EPU.MX expone la crisis de derechos humanos que vive el pa\u00eds y que no atiende el Estado Mexicano, lo que resulta en 3 mil mujeres v\u00edctimas anuales, 11 asesinadas diariamente, 40 mil mujeres desparecidas entre el 2018 \u2013 2022 en edades entre los 10 y 19 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e9xico enfrenta una alarmante crisis en materia de derechos humanos que, lejos de atenuarse, se ha profundizado, particularmente desde el tercer ciclo del Examen Peri\u00f3dico Universal (EPU), efectuado en noviembre de 2018, periodo que coincide con un cambio en la administraci\u00f3n federal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin pol\u00edticas p\u00fablicas a pesar del reconocimiento de la violencia contra las mujeres con la declaraci\u00f3n de 25 alertas de Violencia de G\u00e9nero en 22 de las 32 entidades del pa\u00eds, sin diagn\u00f3sticos oficiales que permitan el cruce de violencias de trata y feminicidios y su relaci\u00f3n con el crimen organizado para la adoptaci\u00f3n de pol\u00edticas p\u00fablicas para detener estas violencias.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante este panorama destaca el incumplimiento por parte del Estado Mexicano de las recomendaciones en la materia, el debilitamiento del Estado de Derecho, el avance de la militarizaci\u00f3n, el deterioro del espacio c\u00edvico y de \u00f3rganos aut\u00f3nomos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><em>La postura del gobierno mexicano es negar la crisis de derechos humanos.<\/em><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el Ejecutivo federal se han dirigido constantemente mensajes de deslegitimaci\u00f3n contra organizaciones de la sociedad civil, personas defensoras de derechos humanos, activistas, periodistas y medios de comunicaci\u00f3n e, incluso, operadoras de justicia y organismos internacionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diversas organizaciones y mecanismos internacionales han constatado que el discurso oficial estigmatizante, en particular sobre la prensa, contribuye al deterioro de la opini\u00f3n p\u00fablica y potencializa el riesgo de la labor period\u00edstica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En M\u00e9xico entre diciembre del 2018 y noviembre del 2022 se han asesinado a 106 defensoras y defensores de derechos humanos. A 59 periodistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre 2018 y mayo del 2023 fueron asesinadas 10 buscadoras de sus familiares desaparecidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre 2019 y mayo de 2022, 82 personas defensoras del medio ambiente tambi\u00e9n fueron asesinadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras que a nivel extrajudicial las ejecuciones por parte de agentes de seguridad estatales y federales, desde su creaci\u00f3n y hasta el cierre del 2022, la Guardia Nacional ha hecho uso de la fuerza con arma de fuego en 402 eventos, en los cuales fallecieron 162 personas civiles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Guardia Nacional report\u00f3 en esos a\u00f1os s\u00f3lo tres casos de uso excesivo de la fuerza refiri\u00e9ndose exclusivamente a aquellos en los que la CNDH emiti\u00f3 una recomendaci\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">&nbsp;<strong><em>La violencia contra las mujeres en M\u00e9xico&nbsp;<\/em><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En 2019 asesinaron a 11 mujeres diariamente y en 2021 se tuvo el m\u00e1ximo registro hist\u00f3rico de feminicidios con 1, 018.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De diciembre de 2018 a abril de 2021, 5,072 personas de 0 a 17 a\u00f1os han quedado hu\u00e9rfanas por feminicidios en M\u00e9xico En promedio, de diciembre de 2018 a marzo de 2021 se han registrado 177 casos mensuales de orfandad por feminicidio; m\u00e1s de cinco ni\u00f1as, ni\u00f1os y adolescentes hu\u00e9rfanos por d\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2022 se denunciaron 82 mil 715 delitos sexuales en todo el pa\u00eds, de los cuales 23 mil 099 fueron violaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mayor\u00eda de los estados no cuentan con protocolos para v\u00edctimas de violencia sexual, o bien, est\u00e1n desactualizados a pesar de que M\u00e9xico est\u00e1 obligado desde la sentencia del Campo Algodonero a contar con protocolos de investigaci\u00f3n de delitos sexuales y de acceso a servicios m\u00e9dicos y de apoyo a v\u00edctimas de delitos sexuales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La NOM 046 de la Secretar\u00eda de Salud no se aplica adecuadamente porque hay poco personal capacitado para brindar atenci\u00f3n a las v\u00edctimas, quienes muchas veces sufren revictimizaci\u00f3n por ello.<strong>&nbsp;&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el estado de Jalisco, de acuerdo con informaci\u00f3n de la Fiscal\u00eda General del Estado, existe un alto porcentaje de abuso sexual a ni\u00f1as de entre 12 y 17 a\u00f1os de edad. En los \u00faltimos tres meses de 2023, se registraron 818 casos de abuso sexual contra menores de 18 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es importante se\u00f1alar que en Jalisco, la tipificaci\u00f3n de la violaci\u00f3n a menores de 18 a\u00f1os como abuso sexual (la clasificaci\u00f3n m\u00e1s grave en materia penal), ha servido como excusa para negar la atenci\u00f3n integral a las v\u00edctimas hasta el aborto, bajo la Norma Oficial Mexicana (NOM) 04615.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Estado niega a las mujeres el derecho al aborto porque asume que el delito de abuso sexual es menos grave, menos violento y m\u00e1s severo que el delito de violaci\u00f3n. Se niega el aborto y se niegan todos los derechos previos que concurren y se vinculan con la pr\u00e1ctica del aborto.<\/p>\n\n\n\n<figure class=\"wp-block-embed alignleft is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\ud83d\udfe1 En el marco del 45 periodo de sesiones del grupo de trabajo sobre el Examen Peri\u00f3dico Universal <a href=\"https:\/\/twitter.com\/hashtag\/EPU?src=hash&amp;ref_src=twsrc%5Etfw\">#EPU<\/a>, hacemos un llamado para que se realicen las siguientes recomendaciones en los temas de violencias contra las mujeres, seguridad p\u00fablica, derecho a la protesta y seguridad de\u2026 <a href=\"https:\/\/t.co\/wXCtfzT3yC\">pic.twitter.com\/wXCtfzT3yC<\/a><\/p>&mdash; Amnist\u00eda Int. M\u00e9xico (@amnistiamexico) <a href=\"https:\/\/twitter.com\/amnistiamexico\/status\/1750171606695985380?ref_src=twsrc%5Etfw\">January 24, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Por lo que el Colectivo EPU MX, una coalici\u00f3n de&nbsp;<strong>300 organizaciones<\/strong>&nbsp;de la sociedad civil que trabajan en el \u00e1mbito de los derechos humanos en M\u00e9xico, recomienda:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Homologar la legislaci\u00f3n en materia de interrupci\u00f3n voluntaria del embarazo en las 32 entidades federativas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Homologar y actualizar los protocolos para la atenci\u00f3n e investigaci\u00f3n de casos de violencia sexual contra las mujeres<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Garantizar partidas presupuestales progresivas para los Centros de Justicia para las Mujeres (CEJUM) en los presupuestos de las entidades federativas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><em>M\u00e1s de 7 mil ni\u00f1as desaparecidas<\/em><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En el pa\u00eds hay&nbsp;7,382 ni\u00f1as, ni\u00f1os y adolescentes desaparecidos<strong>,<\/strong>&nbsp;siendo la mayor\u00eda mujeres. Aunque se aprob\u00f3 un protocolo especializado para su b\u00fasqueda, su implementaci\u00f3n presenta serias dificultades, por la falta de coordinaci\u00f3n entre las varias autoridades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En relaci\u00f3n con la migraci\u00f3n, ha habido un fuerte aumento en los flujos migratorios de ni\u00f1as, ni\u00f1os y adolescentes, superando la capacidad de los centros de asistencia social y resultando en la separaci\u00f3n de familias y un retorno sin considerar su inter\u00e9s superior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El&nbsp;<strong>49.5 por ciento de poblaci\u00f3n tiene menos de 30 a\u00f1os<\/strong>, a pesar de eso se pretende desmantelar al Sistema de Protecci\u00f3n Integral de ni\u00f1as, ni\u00f1os y adolescentes (SIPINNA)), encargado de pol\u00edticas p\u00fablicas para ni\u00f1as y adolescentes<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><em>El colectivo EPU MX recomienda:<\/em><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mantener el SIPINNA como \u00f3rgano desconcentrado de la Secretar\u00eda de Gobernaci\u00f3n, con el car\u00e1cter deliberativo y decisorio y la estructura org\u00e1nica; asegurar la implementaci\u00f3n efectiva del Protocolo Adicional para la B\u00fasqueda de Ni\u00f1as, Ni\u00f1os y Adolescentes y tipificar en el C\u00f3digo Penal Federal el delito de reclutamiento y utilizaci\u00f3n de ni\u00f1as, ni\u00f1os y adolescentes por grupos delictivos como delito aut\u00f3nomo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recomienda al Estado&nbsp; Mexicano implementar una pol\u00edtica de seguridad ciudadana de acuerdo a los est\u00e1ndares internacionales de derecho humanos que garantice el fortalecimiento de los cuerpos de seguridad civiles el retiro paulatino de las fuerzas armadas de la labores de seguridad p\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una adecuada implementaci\u00f3n de la Ley en materia de desapariciones, medidas efectivas de b\u00fasqueda e identificaci\u00f3n de personas desaparecidas y el combate a la impunidad particularmente en las instituciones de procuraci\u00f3n de justicia.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e9xico enfrenta una alarmante crisis en materia de derechos humanos que, lejos de atenuarse, se ha profundizado, particularmente desde el tercer ciclo del Examen Peri\u00f3dico Universal (EPU), efectuado en noviembre de 2018, periodo que coincide con un cambio en la administraci\u00f3n federal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La postura del gobierno mexicano es negar la crisis de derechos humanos al que se suma la resistencia al escrutinio internacional, los mensajes de deslegitimaci\u00f3n a la observancia de la comunidad internacional \u2013 incluyendo la de las Naciones Unidas\u2013 y a las labores de observaci\u00f3n de la sociedad civil organizada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el actual periodo, se ha deteriorado y reducido el espacio c\u00edvico, perpetuando situaciones de riesgo para el ejercicio del derecho a defender derechos humanos y la libertad de expresi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico vive feminicidios, desaparici\u00f3n, asesinatos de madres buscadoras m\u00e1s<\/p>\n","protected":false},"author":3,"featured_media":76447,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[694,48],"tags":[142],"class_list":["post-76446","post","type-post","status-publish","format-standard","has-post-thumbnail","category-destacadas","category-no-mas-impunidad-no-mas-impunidad","tag-violencia"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/76446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=76446"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/76446\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/76447"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=76446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=76446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=76446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}