{"id":74289,"date":"2023-11-22T13:22:54","date_gmt":"2023-11-22T19:22:54","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=74289"},"modified":"2023-11-22T13:22:54","modified_gmt":"2023-11-22T19:22:54","slug":"eduquemos-sin-cordon-umbilical-autonomia-participacion-social-o-democracia","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/eduquemos-sin-cordon-umbilical-autonomia-participacion-social-o-democracia\/","title":{"rendered":"Eduquemos sin cord\u00f3n umbilical: autonom\u00eda, participaci\u00f3n social o democracia"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><em>Vivir en libertad es una de las mayores aspiraciones humanas, al menos en teor\u00eda. Pero, \u00bfd\u00f3nde est\u00e1 el punto medio? Este texto explora las finas l\u00edneas que separan la libertad y la responsabilidad en la sociedad. Con reflexiones sobre la autonom\u00eda, la participaci\u00f3n social y la democracia, se cuestiona c\u00f3mo construir una democracia con justicia social desde las aulas.<\/em><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alejandra Luna Guzm\u00e1n*<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 22 de noviembre, 2023.- Vivir en libertad es una de las mayores aspiraciones humanas\u2026 al menos en teor\u00eda. En el \u00e1mbito emocional, finas l\u00edneas son las que separan el sano apego de la dependencia; la crianza responsable de la sobreprotecci\u00f3n; la vigilancia del bienestar superior de ni\u00f1as, ni\u00f1os y adolescentes del trastocarlos en tiranos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la esfera social no es tan diferente. Algunos sectores que claramente deben estar protegidos por el Estado son tachados por otros como entes parasitarios; las acciones de gobierno que pretenden apoyar a quienes m\u00e1s lo necesitan no est\u00e1n focalizadas y terminan dando m\u00e1s a quienes m\u00e1s tienen, y los beneficiarios del clientelismo de anta\u00f1o exigen airadamente que se les siga cubriendo con el manto protector del dispendio. \u00bfD\u00f3nde est\u00e1 el punto medio?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya que la escuela es uno de los universos que mejor refleja nuestras sociedades, tom\u00e9mosla de ejemplo. La organizaci\u00f3n escolar se rige por normativas externas e internas orientadas a regular el actuar de quienes se encuentran en ella.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, todos quienes hemos pasado por una instituci\u00f3n educativa sabemos bien que esas normas no son obedecidas autom\u00e1ticamente, sino que tienden a cuestionarse, flexibilizarse, someterse a presiones o incluso romperse de forma constante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los criterios detr\u00e1s de estas tensiones parten del conocimiento de la existencia de la norma en cuesti\u00f3n y, despu\u00e9s, de una toma de decisi\u00f3n individual o colectiva, a adoptarla o no. Idealmente, la figura a cargo de aplicar la norma (ll\u00e1mese autoridad) establece medios de comunicaci\u00f3n para liberar cualquier tipo de diatribas sobre la misma. La utilizaci\u00f3n de esos medios para emitir opiniones y tomar decisiones es un ejemplo de participaci\u00f3n social. Sin embargo, el presentarlas por medios alternativos, ya sea de manera formal o no, organizada o no, tambi\u00e9n es participaci\u00f3n social. Es as\u00ed que, el usar el buz\u00f3n escolar o unirse en grupo a manifestar un descontento ante la direcci\u00f3n, son participaci\u00f3n social. \u00bfY la resistencia? \u00bfEl solo hecho de no seguir una norma sin expresarse?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La desobediencia civil, tal como la plante\u00f3 Henry David Thoreau hace ya casi 200 a\u00f1os (Thoreau, 2022), es una forma de activismo, ciertamente. Conlleva sobreponerse a las imposiciones de una autoridad con fines cuestionables en t\u00e9rminos de justicia. Es un espacio de inter\u00e9s en especial para las minor\u00edas que, en ocasiones, son aplastadas por decisiones \u201cdemocr\u00e1ticas\u201d tomadas por las mayor\u00edas dominantes. Sin embargo, la desobediencia civil presentada por Thoreau no era silenciosa y, menos, invisible. No se trata solo de no acatar la norma. Para que la desobediencia conlleve al cambio implica compromiso, como devela bell hooks (2021).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Volviendo al \u00e1mbito educativo, sentarse de brazos cruzados en una junta de Consejo T\u00e9cnico Escolar y negarse a participar, por ejemplo, no es activismo silencioso, ni muestra de ser \u201cde pensamiento independiente\u201d.&nbsp; Si bien tiene repercusiones en la din\u00e1mica organizacional, carece de poder. M\u00e1s que perseguir independencia habr\u00eda que sumarse a la autonom\u00eda escolar. \u00c9sta implica procesos de toma de decisiones sobre los distintos recursos con los que cuenta la escuela, d\u00edgase materiales, espacios, estrategias did\u00e1cticas y de intervenci\u00f3n, tiempo y, s\u00ed, idealmente, tambi\u00e9n la distribuci\u00f3n de poder. La autonom\u00eda escolar se sirve de la participaci\u00f3n social para sistematizar las decisiones que derivan de ella y transformarlas en acciones y hechos. Se le reconoce como una gesti\u00f3n democratizante (Mitchell, 2017).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, la autonom\u00eda escolar no equivale a una libertad desenfrenada, detr\u00e1s de ella deben encontrarse las propias normas y los distintos niveles de gobierno no solo en su labor de supervisi\u00f3n, sino tambi\u00e9n en el cumplimiento de sus responsabilidades. Cruzamos en este punto con la gobernabilidad \u2212esa capacidad del Estado para dar respuestas a las demandas sociales\u2212, y la gobernanza \u2212la interdependencia y la colaboraci\u00f3n entre el gobierno y los distintos tipos de organizaciones. Asimismo, nos enfrentamos a las finas l\u00edneas que se entretejen entre los distintos niveles y actores, cada uno con sus propios intereses, con sus conflictos internos y disputas externas. Para conciliar, solemos recurrir a tomas de decisiones democr\u00e1ticas que, retornando a Thoreau, a veces son aplastantes para las minor\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 nos deja la democracia, entonces? \u00bfQu\u00e9 herramientas nos dan la participaci\u00f3n social y la autonom\u00eda? La primera pregunta la podemos responder primero con otra: \u00bfde qu\u00e9 modelo de democracia estamos hablando? Porque lo cierto es que, \u00e9ste que tenemos funciona de tal manera que unos cuantos toman decisiones ejecutivas y legislativas a nombre de las mayor\u00edas que los pusieron en su cargo. Y esas mayor\u00edas &#8211; que en la realidad tan diversa de nuestro pa\u00eds son la suma de numerosas minor\u00edas &#8211; a veces se tornan en figuras expectantes siguiendo un juego paternalista de la ciudadan\u00eda infantil y el pap\u00e1 Estado respondiente. Con los procesos democr\u00e1ticos del pa\u00eds en ciernes, cabe reflexionar qu\u00e9 modelos estamos dando a la ni\u00f1ez y juventud mexicana de participaci\u00f3n social, de autonom\u00eda, de democracia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo resolvemos los conflictos en nuestras aulas, entre docentes, con las autoridades? \u00bfQu\u00e9 tan horizontal es la toma de decisiones? \u00bfCu\u00e1nto nos involucramos en la b\u00fasqueda de soluciones? \u00bfC\u00f3mo dialogamos con la comunidad en extenso? \u00bfHasta d\u00f3nde iniciamos procesos de exigibilidad y justiciabilidad o emprendemos berrinches varios?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La formaci\u00f3n en ciudadan\u00eda se construye mejor, como la gran mayor\u00eda de los procesos educativos, a trav\u00e9s del ejemplo. Ser\u00e1 momento entonces de comenzar a educar sin cordones umbilicales, sin letargo ni apat\u00eda, sin solapamientos ni encubrimientos, con consensos tomados en autonom\u00eda, el compromiso de la participaci\u00f3n social, para poder vivir la verdadera libertad de hacernos cargo los unos de los otros, alcanzar el ideal de una democracia con justicia social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.muxed.mx\/blog\/educacion-libertad-democracia\">https:\/\/www.muxed.mx\/blog\/educacion-libertad-democracia<\/a><\/p>\n\n\n<div class=\"wp-block-image is-style-rounded\">\n<figure class=\"alignleft size-full is-resized\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2023\/11\/Imagen4-6.png\"><img loading=\"lazy\" decoding=\"async\" width=\"199\" height=\"253\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2023\/11\/Imagen4-6.png\" alt=\"\" class=\"wp-image-74290\" style=\"width:153px;height:auto\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong><em>*Alejandra Luna Guzm\u00e1n Integrante de MUxED. Pertenece al Departamento de Educaci\u00f3n de la Universidad Iberoamericana, Ciudad de M\u00e9xico, donde se desempe\u00f1a en la gesti\u00f3n editorial de revistas acad\u00e9micas arbitradas. Sus l\u00edneas de investigaci\u00f3n son la gesti\u00f3n educativa por la calidad y equidad, comunicaci\u00f3n cient\u00edfica, derecho a la educaci\u00f3n y an\u00e1lisis de pol\u00edticas educativas.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Redes sociales<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Twitter <a href=\"https:\/\/twitter.com\/EducaleNarte\">@EducaleNarte<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Linkedin <a href=\"https:\/\/www.linkedin.com\/in\/alejandra-luna-guzm%C3%A1n-81785082\/\">Alejandra Luna Guzm\u00e1n<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">FB <a href=\"https:\/\/www.facebook.com\/profile.php?id=100028939338915\">Alejandra Luna<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Referencias<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">hooks, b. (2021). <em>El deseo de cambiar.<\/em> Manresa: Belaterra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mitchell, R. (2017). Democracy or control? The participation of management, teachers, students and parents in school leadership in Tigray, Ethiopia. <em>International Journal of Educational Development, 55<\/em>, 49-55. <a href=\"https:\/\/doi.org\/10.1016\/j.ijedudev.2017.05.005\">https:\/\/doi.org\/10.1016\/j.ijedudev.2017.05.005<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Thoreau, H. D. (2022). <em>Desobediencia Civil<\/em>. Los \u00c1ngeles: LA CASE.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vivir en libertad es una de las mayores aspiraciones humanas, al menos en teor\u00eda. Pero, \u00bfd\u00f3nde est\u00e1 el punto medio? <\/p>\n","protected":false},"author":3,"featured_media":74291,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[703],"tags":[],"class_list":["post-74289","post","type-post","status-publish","format-standard","has-post-thumbnail","category-infancia"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/74289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=74289"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/74289\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/74291"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=74289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=74289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=74289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}