{"id":73600,"date":"2023-11-06T17:23:13","date_gmt":"2023-11-06T23:23:13","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=73600"},"modified":"2023-11-06T17:23:14","modified_gmt":"2023-11-06T23:23:14","slug":"palabra-de-antigona-mujeres-se-quedan-atras","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/palabra-de-antigona-mujeres-se-quedan-atras\/","title":{"rendered":"Palabra de Ant\u00edgona| Mujeres se quedan atr\u00e1s"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Sara Lovera<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 6 de noviembre, 2023.- Inminente es la aprobaci\u00f3n del presupuesto para 2024 en la C\u00e1mara de Diputados, para el \u00faltimo a\u00f1o de este gobierno, gasto pensado para garantizar recursos para la campa\u00f1a electoral, la contingencia de Acapulco y continuar las obras insignia del presidente Andr\u00e9s Manuel L\u00f3pez Obrador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se esperan 20 mil reservas, discusiones y manotazos hasta el pr\u00f3ximo viernes. Las &nbsp;demandas de revisi\u00f3n de las asignaciones para la pol\u00edtica de g\u00e9nero ni siquiera se oyen, no se tomaron en cuenta. &nbsp;Ya es frustrante insistir en que en esta administraci\u00f3n, esa &nbsp;pol\u00edtica se borr\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En mesas semejantes al parlamento abierto, donde invitan a la sociedad civil, &nbsp;se hizo una&nbsp; lista para reasignaci\u00f3n de recursos al Anexo 13, creado para atender la igualdad entre hombres y mujeres. Se enlistaron propuestas &nbsp;de no m\u00e1s de 500 millones, que en los m\u00e1s de 9 mil millones para todo, no significa ni el 0.5 por ciento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El dictamen ni lo consider\u00f3. Lamentablemente. No se har\u00e1 rectificaci\u00f3n alguna, ni consideraci\u00f3n frente a la violencia contra las mujeres; la inseguridad que afecta de manera diferenciada a la mitad de la poblaci\u00f3n. Ni para la salud, a pesar de los c\u00e1nceres femeninos. Ni para la reeducaci\u00f3n necesaria en las relaciones humanas, entre hombres y mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta administraci\u00f3n &nbsp;el Anexo 13 del PEF, &nbsp;destinado a la igualdad y no discriminaci\u00f3n&nbsp; de las mujeres, se vaci\u00f3. Se dice que crece, crecimiento que en 80 por ciento es para las becas de adultos mayores, &nbsp;j\u00f3venes construyendo el futuro y becas Benito Ju\u00e1rez, con el argumento que esos programas benefician a hombres y mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que resultar\u00e1 ser\u00e1 una nueva &nbsp;derrota pol\u00edtica y presupuestal para las mujeres. No hay escucha sobre &nbsp;&nbsp;algo tan simple, como que las mujeres son la mitad de la poblaci\u00f3n que &nbsp;tienen necesidades espec\u00edficas por ser mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hace 5 a\u00f1os que se recortaron los &nbsp;recursos para la transversalidad, son insuficientes los destinados a los Refugios para mujeres violentadas; no los hay para &nbsp;los tamizajes para detectar &nbsp;el c\u00e1ncer de mama, primera causa de muerte en mujeres productivas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;La Auditor\u00eda Superior de la Federaci\u00f3n, certific\u00f3 que s\u00f3lo hay 272 mast\u00f3grafos, para detectar el c\u00e1ncer de mama,&nbsp; que demandaron 73 mil 537 mujeres, en 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya se plante\u00f3 el intento de destinar 300 millones, adicionales, para los 65 Centros de Justicia para las Mujeres, de la morenista Aleida Alavez Ru\u00edz, coordinadora del grupo plural de igualdad sustantiva en el Congreso, podr\u00eda aceptarse, pese a que &nbsp;300 millones para 65 Centros, ser\u00e1 de apenas 4 millones anuales, para cada uno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presupuesto, que no es m\u00e1s que la expresi\u00f3n de voluntad sobre la pol\u00edtica, dejar\u00e1 atr\u00e1s, nuevamente a las mujeres. No se piensa que mientras no cambien las relaciones entre&nbsp; hombres y mujeres y ellas sean las principales responsables del cuidado de sus hijas e hijos necesitan las estancias infantiles y el Sistema Nacional de Cuidados, recursos para los programas de salud reproductiva, necesarios m\u00e1s que nunca para las mujeres de Guerrero, expuestas en la contingencia no s\u00f3lo a abusos, sino a embarazos no deseados o enfermedades de transmisi\u00f3n sexual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como dir\u00eda la diputada de Movimiento Ciudadano, Mirza Flores G\u00f3mez \u201cel desinter\u00e9s para atender la&nbsp; violencia contra las mujeres se observa en el presupuesto para las dependencias encargadas de operar la pol\u00edtica de igualdad de g\u00e9nero y combate a la violencia contra las mujeres, que sigue sin ser progresiva, todas, contar\u00e1n en 2024 con menos recursos de los asignados en 2019\u201d. Veremos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">*Periodista, directora del portal informativo <a href=\"http:\/\/www.semexico.mx\">http:\/\/www.semexico.mx<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inminente es la aprobaci\u00f3n del presupuesto para 2024 en la C\u00e1mara de Diputados, para el \u00faltimo a\u00f1o de este gobierno, gasto pensado para garantizar recursos para la campa\u00f1a electoral, la contingencia de Acapulco y continuar las obras insignia del presidente Andr\u00e9s Manuel L\u00f3pez Obrador.<\/p>\n","protected":false},"author":3,"featured_media":71398,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[35,95,69],"tags":[149,459],"class_list":["post-73600","post","type-post","status-publish","format-standard","has-post-thumbnail","category-opinion","category-palabra-de-antigona","category-sara-lovera","tag-mujeres","tag-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/73600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=73600"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/73600\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/71398"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=73600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=73600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=73600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}