{"id":7343,"date":"2018-09-03T01:17:56","date_gmt":"2018-09-03T01:17:56","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=7343"},"modified":"2023-07-21T14:33:17","modified_gmt":"2023-07-21T19:33:17","slug":"sexto-informe-solo-al-final-intento-proteger-a-periodistas","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/sexto-informe-solo-al-final-intento-proteger-a-periodistas\/","title":{"rendered":"Sexto informe; s\u00f3lo al final, intent\u00f3 proteger a periodistas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En los primeros meses del a\u00f1o pasado se recrudeci\u00f3 m\u00e1s la violencia de todo tipo contra periodistas<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"> Encontrar\u00e1n bien poco en los 33 p\u00e1rrafos que dedica al tema de protecci\u00f3n y s\u00f3lo tres medidas que debieron iniciarse seis a\u00f1os antes.<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/semmexico.com\/gallery-post.php?id=5736#\">Rogelio Hern\u00e1ndez<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. Cd. de M\u00e9xico. 3 de septiembre de 2018.- Colegas ah\u00f3rrense el esfuerzo de hurgar&nbsp;en&nbsp;el sexto informe de Enrique Pe\u00f1a Nieto lo relacionado con los agravios a periodistas.&nbsp;Encontrar\u00e1n bien poco en los 33 p\u00e1rrafos que dedica al tema de protecci\u00f3n y s\u00f3lo tres medidas que debieron iniciarse seis a\u00f1os antes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si recordaremos este sexenio por los 143&nbsp;asesinatos,&nbsp;21desaparecidos, 3 agresiones diarias y una impunidad del 93 por ciento de nuestros casos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el resumen ejecutivo algunos de ustedes sonreir\u00e1n con iron\u00eda porque en los 8 p\u00e1rrafos que Enrique Pe\u00f1a Nieto dedica al tema, en la primera parte de las 357 palabras enunci\u00f3 los principios de gobierno que debi\u00f3 cumplir y no lo hizo, probablemente porque nunca entendi\u00f3 los significados:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLos cr\u00edmenes cometidos contra defensores de Derechos Humanos y periodistas agravian y lastiman no solamente a las v\u00edctimas y sus familiares, sino a la sociedad entera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs obligaci\u00f3n del Estado mexicano, en su conjunto, otorgar garant\u00edas a activistas de Derechos Humanos y profesionales de la comunicaci\u00f3n para el adecuado desempe\u00f1o de sus labores, especialmente ante la grave amenaza que hoy representa la delincuencia organizada.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta 2017 estimul\u00f3 al mecanismo y a la fiscal\u00eda<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las 860 palabras que abarc\u00f3 este tema en&nbsp;este&nbsp;informe todas fueron para asegurar que se fortaleci\u00f3&nbsp;el Mecanismo de Protecci\u00f3n para Personas Defensoras de Derechos Humanos y Periodistas&nbsp;y las acciones que en 2018 ha realizado la Fiscal\u00eda Especial para Delitos contra la Libertad de Expresi\u00f3n (Feadle) de la PGR.&nbsp;Y lo que describe es lo que muchos esper\u00e1bamos que hiciera desde diciembre de 2012.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Informa:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDe diciembre de 2012 a junio de 2018, un total de 948 personas han estado bajo la protecci\u00f3n de este Mecanismo; de ellas, 519 son defensoras de derechos humanos y 429 periodistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y sin referir que los primeros meses del a\u00f1o pasado se recrudeci\u00f3 m\u00e1s la violencia de todo tipo contra periodistas en ejercicio reconoce expl\u00edcitamente que hasta entonces decidi\u00f3 medidas especiales:&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn mayo de 2017, ante el aumento en la incidencia de este tipo de delitos, se anunciaron medidas adicionales&nbsp;para fortalecer la estructura y el presupuesto asignado a este Mecanismo; establecer un Esquema Nacional de Coordinaci\u00f3n con las Entidades Federativas y un Protocolo de Operaci\u00f3n, y consolidar la Fiscal\u00eda Especial para la Atenci\u00f3n de Delitos Cometidos Contra la Libertad de Expresi\u00f3n.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eso y nada&nbsp;es casi lo mismo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si se asign\u00f3 un presupuesto adicional al mecanismo y a la&nbsp;Feadle, pero tan poco que ya en 30 d\u00edas m\u00e1ximos ya no podr\u00e1n continuar con las medidas de protecci\u00f3n ni atender nuevos casos, seg\u00fan la denuncia que hizo el 30 de agosto el titular de la Comisi\u00f3n Nacional de los Derechos Humanos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso del impulso que si se dio desde junio de 2017 con los gobiernos de los estados desde el mecanismo de la&nbsp;Segob, mejoraron el&nbsp;Protocolo de Coordinaci\u00f3n entre el Mecanismo Federal y las Unidades Estatales de Protecci\u00f3n&nbsp;que ya hab\u00eda, pero pocas entidades participaron en el redise\u00f1o; no se colectiviz\u00f3 el&nbsp;monitoreo de agresiones y elaboraci\u00f3n de mapas de riesgo&nbsp;que acordaron y menos en&nbsp;el Protocolo Homologado de investigaci\u00f3n de&nbsp;delitos, que como se reconoce en el informe&nbsp;apenas&nbsp;\u201cse encuentra en etapa de validaci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O sea&nbsp;reci\u00e9n&nbsp;se inici\u00f3 la coordinaci\u00f3n con los estados, con un protocolo de acci\u00f3n com\u00fan, en un solo monitoreo y otro protocolo de investigaci\u00f3n pero, ya se les acab\u00f3 el tiempo y ya llegaron otros gobernadores.&nbsp;Y dentro del mecanismo hicieron algunos cursos para el personal que no ha renunciado y siguieron haciendo evaluaciones de riesgos\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La impunidad sigue aqu\u00ed<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este \u00faltimo y principal impulso de las dos entidades la&nbsp;Feadle&nbsp;le inform\u00f3 que en 2018, a pesar de tener m\u00e1s recursos y agentes tanto de investigaci\u00f3n como de ministerio p\u00fablico fueron pocos sus avances.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el tema de&nbsp;Procuraci\u00f3n de justicia en delitos cometidos en contra de periodistas.&nbsp;(12 p\u00e1rrafos con 2 mil 269 caracteres) se&nbsp;destaca:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u2026del sistema tradicional&nbsp;(de justicia), se consignaron 19 indagatorias, ejercit\u00e1ndose acci\u00f3n penal contra 25 personas (seis mujeres y 19 hombres) como probables responsables: nueve por abuso de autoridad, cuatro por amenazas, tres por da\u00f1o en propiedad ajena, y tres por robo\u2026 \u201cBajo el SJPA se iniciaron 56 carpetas de investigaci\u00f3n y se recibieron 17 por incompetencia interna y se determinaron 66 carpetas de investigaci\u00f3n\u2026&nbsp;Se ejerci\u00f3 la facultad de atracci\u00f3n en cinco investigaciones\u2026&nbsp;&#8211;&nbsp;Se cuenta con 19 personas vinculadas a proceso y seis personas con \u00f3rdenes de aprehensi\u00f3n\u2026.&nbsp;En coordinaci\u00f3n con las fiscal\u00edas y\/o procuradur\u00edas estatales, se obtuvieron 23 \u00f3rdenes de aprehensi\u00f3n en ocho investigaciones por el delito de homicidio\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eso es todo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si al menos esto que orden\u00f3 el Ejecutivo Federal en su \u00faltimo a\u00f1o hubiera ocurrido desde el principio de su administraci\u00f3n el mensaje a los agresores (funcionarios del Estado y de la delincuencia organizada) les habr\u00eda inhibido y tambi\u00e9n se hubiera creado la percepci\u00f3n social de que se debe respetar el ejercicio del periodismo porque es parte vital de las relaciones pol\u00edticas&nbsp;y creaci\u00f3n de consensos sociales. Pero no hubo quien tuviera la sensibilidad suficiente. Tambi\u00e9n por esto perdieron sus espacios de mando p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfYa qu\u00e9 se puede esperar en los 3 meses que restan a esta administraci\u00f3n federal? Solo hay algo seguro: se intensificar\u00e1n las agresiones y los asesinatos a periodistas por los vac\u00edos de autoridad que se ahondaron desde el 2 de julio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Colegas, cuid\u00e9monos entre nosotros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En los primeros meses del a\u00f1o pasado se recrudeci\u00f3 m\u00e1s la violencia de todo tipo contra periodistas Encontrar\u00e1n bien poco en los 33 p\u00e1rrafos que dedica al tema de protecci\u00f3n y s\u00f3lo tres medidas que debieron iniciarse seis a\u00f1os antes. Rogelio Hern\u00e1ndez SemM\u00e9xico. Cd. de M\u00e9xico. 3 de septiembre de 2018.- Colegas ah\u00f3rrense el esfuerzo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7234,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[689,85],"tags":[],"class_list":["post-7343","post","type-post","status-publish","format-standard","has-post-thumbnail","category-689","category-rogelio-hernandez-lopez"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/7343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=7343"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/7343\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/7234"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=7343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=7343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=7343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}