{"id":72724,"date":"2023-10-17T13:20:26","date_gmt":"2023-10-17T19:20:26","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=72724"},"modified":"2023-10-17T13:20:29","modified_gmt":"2023-10-17T19:20:29","slug":"los-estamos-observando-retan-a-los-partidos-politicos-y-a-las-autoridades-electorales-a-cumplir-con-la-paridad","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/los-estamos-observando-retan-a-los-partidos-politicos-y-a-las-autoridades-electorales-a-cumplir-con-la-paridad\/","title":{"rendered":"Los estamos observando retan a los partidos pol\u00edticos y a las autoridades electorales a cumplir con la paridad"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong>En un llamado por la Democracia Paritarios Libre de Violencia, mujeres de todo el pa\u00eds amenaza con ir a tribunales si no cumplen<\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>En el INE avala criterios para las gubernaturas y el gobierno de la Ciudad de M\u00e9xico, que deber\u00e1 acordar el Consejo General: 5 y 4<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sara Lovera<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 17 de octubre, 2023.- Mujeres de todo el pa\u00eds, hicieron un en\u00e9rgico llamado &nbsp;a las autoridades electorales, les advierten &nbsp;que los est\u00e1n observando y los retaron &nbsp;a defender, asegurar y consolidar la democracia paritaria como medida sustantiva &nbsp;para eliminar la discriminaci\u00f3n ancestral de que las mujeres han sido objeto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Denominado <em>Por una Democracia Paritaria Libre de Violencia<\/em>, se firma en todo M\u00e9xico, por &nbsp;mujeres en defensa de sus derechos y arremete que \u201cse oiga fuerte y claro\u201d&nbsp; tampoco permitir\u00e1n que &nbsp;ning\u00fan agresor por violencia pol\u00edtica pueda ser considerado para un cargo de elecci\u00f3n o puesto p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La airada demanda de feministas y luchadoras pol\u00edticas &nbsp;sucede en el momento en que en&nbsp; comisiones unidas el Instituto Nacional Electoral acord\u00f3 el criterio &nbsp;&nbsp;para que los partidos pol\u00edticos postulen al menos a 5 mujeres en las 9 entidades de cambio de gobierno en 2024, criterio fundado &nbsp;estrictamente a la Constituci\u00f3n. El acuerdo de las comisiones, sin embargo, &nbsp;no podr\u00e1 ser definitivo hasta que lo vote el Consejo General, donde se advierten diferencias y omisiones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las argumentaciones de los criterios que tambi\u00e9n se sujeta a la competitividad, han sido defendidos, principalmente por las mujeres consejeras, y coincide con el llamamiento feminista: porque&nbsp; la paridad no es el techo, es el punto de partida. Y es &nbsp;urgente&nbsp; que se postulen, al menos cinco mujeres en la renovaci\u00f3n de los puestos ejecutivos, pero tambi\u00e9n en todos los dem\u00e1s&nbsp; -m\u00e1s de 20 mil- porque \u201c que la raz\u00f3n est\u00e1 de nuestro lado\u201d, afirman las feministas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante la posibilidad de que el acuerdo se derrote, apareci\u00f3 esta madrugada el llamamiento, donde las mujeres recordaron a &nbsp;los partidos pol\u00edticos, al Instituto Nacional Electoral, INE, y al Tribunal Electoral del Poder Judicial de la Federaci\u00f3n, TEPJF, a los organismos electorales locales, que la democracia paritaria est\u00e1 establecida en la Constituci\u00f3n, que claramente se\u00f1ala que el 50 por ciento de todos los cargos electorales&nbsp; sean ocupados por mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n advierten que no hay que &nbsp;confundir las acciones afirmativas &nbsp;para otros grupos, con la paridad y afirman \u201cno aceptamos &nbsp;que las acciones afirmativas para grupos discriminados se consideren para el cumplimiento de la paridad\u201d,&nbsp; aludiendo a otros&nbsp; criterios del INE, que ponen en peligro la paridad entre hombres y mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras el debate est\u00e1 abierto, debido a la oposici\u00f3n a los criterios del INE desde los partidos pol\u00edticos nacionales, argumentando que ese instituto se mete con la vida interna de los partidos, las feministas se ponen al frente, y como si los miraran a los ojos dicen: \u201cla historia nos observa, y frente a la renovaci\u00f3n de m\u00e1s de veinte mil cargos electorales, les recordamos que la paridad no es una opci\u00f3n, es un principio y un derecho para las mujeres, por lo que debe asegurarse la igualdad de condiciones en la contienda y la igualdad de resultados en la integraci\u00f3n de los congresos, ayuntamientos y gubernaturas en disputa\u201d.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>En el INE la decisi\u00f3n<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Las Comisiones Unidas de Prerrogativas y Partidos Pol\u00edticos y de Igualdad de G\u00e9nero y No Discriminaci\u00f3n del Instituto Nacional Electoral (INE) anoche &nbsp;aprobaron emitir los criterios para garantizar la paridad de g\u00e9nero en la postulaci\u00f3n el Proceso Electoral Local 2023-2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este acuerdo deber\u00e1 ser aprobado por el Consejo General, establece que a fin de dar cumplimiento a lo ordenado por la Sala Superior del Tribunal Electoral del Poder Judicial de la Federaci\u00f3n, los partidos pol\u00edticos nacionales informar\u00e1n al INE los criterios para garantizar la paridad sustantiva en candidaturas a gubernaturas, un d\u00eda antes del inicio de las precampa\u00f1as respectivas, as\u00ed como la forma en que aplicar\u00e1n la competitividad en la postulaci\u00f3n de mujeres a las candidaturas a gubernaturas, conforme a los criterios m\u00ednimos precisados en sus documentos b\u00e1sicos y de acuerdo con el mandato para que los particos cumplan con la Constituci\u00f3n. Los partidos cambiaron sus estatutos. Est\u00e1n obligados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de varios d\u00edas de discusi\u00f3n, incluso p\u00fablica, los partidos alegan que el INE se excede, -igual hicieron en 2021- y &nbsp;anoche&nbsp;&nbsp; al reanudarse la sesi\u00f3n de las &nbsp;Comisiones Unidas, se aprob\u00f3 la propuesta que entre hoy y ma\u00f1ana tendr\u00e1 una conclusi\u00f3n. Est\u00e1 en peligro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Las mujeres votan<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">De ah\u00ed que el llamado de las mujeres, de muchas agrupaciones feministas del pa\u00eds, y &nbsp;desde todas las entidades federativas, es c\u00f3mo &nbsp;alzan su &nbsp;voz, unidas en este &nbsp;emplazamiento &nbsp;urgente y les &nbsp;recuerdan que lo establecido en la constituci\u00f3n \u201cnos pertenece, no como un favor o concesi\u00f3n, sino como un derecho irrenunciable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les dicen, por si no se acuerdan&nbsp; de que los&nbsp;&nbsp; partidos pol\u00edticos, son &nbsp;entidades de inter\u00e9s p\u00fablico, financiadas por el pueblo ; &nbsp;que tienen una responsabilidad jur\u00eddica y \u00e9tica ineludible, por lo que &nbsp;no solo deben garantizar la paridad en todos los cargos electorales, sino tambi\u00e9n prevenir y proteger a las mujeres de cualquier forma de violencia pol\u00edtica.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2023\/10\/Imagen2-9.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"409\" height=\"349\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2023\/10\/Imagen2-9.jpg\" alt=\"\" class=\"wp-image-72725\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Y agregan<strong><em>: &nbsp;que&nbsp; se oiga fuerte y claro<\/em><\/strong> ning\u00fan agresor por violencia pol\u00edtica puede ser considerado para un cargo de elecci\u00f3n ya sea por sentencia administrativa o penal tal y como lo establece la legislaci\u00f3n vigente que ha sido contenida en mucho gracias al impulso y acompa\u00f1amiento permanente del movimiento feminista y amplio de mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Argumentan que para 2023-2024, la clase pol\u00edtica debe saber que la Ley 3 de 3 contra la violencia ha contado con la &nbsp;determinaci\u00f3n de todas, que aspiran a &nbsp;ver postulaciones respetables y dignas y advierten que \u201c no aceptaremos por ning\u00fan motivo candidatos con antecedentes de agresiones sexuales, deudas alimenticias o cualquier forma de violencia contra las mujeres, hacerlo significar\u00eda \u201c una afrenta a nuestra democracia y a nuestra integridad\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El llamado que se difunde este 17 de octubre, cuando se cumplen 70 a\u00f1os desde que las mexicanas accedieron al voto femenino, se\u00f1ala que \u201cla historia nos observa, y frente a la renovaci\u00f3n de m\u00e1s de veinte mil cargos electorales, les recordamos que la paridad no es una opci\u00f3n, es un principio y un derecho para las mujeres, por lo que debe asegurarse la igualdad de condiciones en la contienda y la igualdad de resultados en la integraci\u00f3n de los congresos, ayuntamientos y gubernaturas en disputa\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las mujeres feministas, una vez m\u00e1s les dicen a los partidos pol\u00edticos y a las autoridades electorales que no aceptan &nbsp;que las acciones afirmativas para grupos discriminados se consideren para el cumplimiento de la paridad\u201d,&nbsp; aludiendo a los criterios del INE.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explican que la paridad no es el techo, es el punto de partida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puntualizan &nbsp;la urgente necesidad de que se postulen, al menos cinco mujeres para las nueve elecciones en 9 entidades que habr\u00e1n de renovarse en las pr\u00f3ximas elecciones. Y se\u00f1alan que la raz\u00f3n est\u00e1 del lado de las mexicanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afirman que imprescindible que los partidos pol\u00edticos reconozcan el valor, la capacidad y la tenacidad de las mujeres respetando los criterios de compatibilidad y poblacional, haciendo que la representaci\u00f3n y participaci\u00f3n pol\u00edtica de las mujeres sea sustantiva.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>EL INE<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El INE por su parte, reitera que los procesos de selecci\u00f3n de candidaturas deber\u00e1n establecer reglas claras que exijan la publicidad oportuna de todos los actos que integren las etapas del proceso y su debida notificaci\u00f3n a quienes aspiran a obtener una candidatura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explica que como acci\u00f3n afirmativa y derivado de que persiste una subrepresentaci\u00f3n de mujeres en la titularidad de los Poderes Ejecutivos Locales y tomando en consideraci\u00f3n el contexto hist\u00f3rico de las entidades con proceso electoral local, donde apenas han sido electas tres mujeres en toda la historia, los partidos pol\u00edticos nacionales deber\u00e1n postular al menos cinco mujeres en las entidades donde se elegir\u00e1 la gubernatura -Chiapas, Guanajuato, Jalisco, Morelos, Puebla, Tabasco, Veracruz y Yucat\u00e1n-, as\u00ed como la Jefatura de Gobierno de la Ciudad de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los criterios del INE &nbsp;tambi\u00e9n establecen que la solicitud de registro de candidaturas a gubernaturas la deber\u00e1n presentar los partidos pol\u00edticos o coaliciones ante los Organismos P\u00fablicos Locales y ser\u00e1 remitida a la Direcci\u00f3n Ejecutiva de Prerrogativas y Partidos Pol\u00edticos del Instituto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se mandata a los partidos pol\u00edticos locales para que respeten el principio de alternancia de g\u00e9nero que hubieran postulado en la \u00faltima elecci\u00f3n en cada gubernatura y Jefatura de Gobierno de la Ciudad de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Previo a la emisi\u00f3n de las convocatorias para los procesos internos de selecci\u00f3n de candidaturas a gubernaturas, los partidos pol\u00edticos nacionales deber\u00e1n definir, en el contexto de los procesos electorales locales a llevarse a cabo, en qu\u00e9 entidades habr\u00e1n de postular candidaturas de mujeres y hombres -garantizando que ninguno de los g\u00e9neros sea postulado exclusivamente en entidades de baja competitividad- y determinando cu\u00e1les y cu\u00e1ntas convocatorias ser\u00e1n exclusivamente para mujeres, as\u00ed como los criterios de competitividad con los que garantizar\u00e1n la paridad sustantiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La sesi\u00f3n de anoche estuvo presidida por la Consejera Rita Bell L\u00f3pez y en la que estuvieron las Consejeras Dania Ravel, Norma De la Cruz, Claudia Zavala y Carla Humphrey, con los Consejeros Uuc-kib Espadas, Arturo Castillo y Jorge Monta\u00f1o, donde se\u00f1alaron que, en la mesa de trabajo, realizada en d\u00edas previos, escucharon propuestas, inquietudes y objeciones de representantes de partidos pol\u00edticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las principales, se refieren a que el INE no tiene facultad para emitir estos criterios, que los partidos pol\u00edticos quieren cumplir con la paridad y que se debe de tomar en cuenta que tres estados: Yucat\u00e1n, Jalisco y Puebla, ya han legislado en materia de paridad en gubernaturas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En respuesta, se mantuvo la propuesta del \u00e1rea t\u00e9cnica, con argumentos jur\u00eddicos hechos por las Consejeras y Consejeros que reforzaron la fundamentaci\u00f3n y la motivaci\u00f3n. Tanto en la mesa de trabajo como en la sesi\u00f3n virtual participaron la Consejera Presidenta del INE, Guadalupe Taddei y el Consejero Jaime Rivera.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Las Mujeres dicen; es ley, no se hagan<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El llamado feminista, &nbsp;que a estas horas circula en todo M\u00e9xico, recuerda que la legislaci\u00f3n electoral establece responsabilidades a las instituciones como el INE y el TEPJF, a fin de supervisar y garantizar el cumplimiento de la paridad y la no violencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y advierte a las y los consejeros que las miradas de todas las mujeres est\u00e1n y estar\u00e1n puestas en las instituciones y organizaciones que intervienen en las elecciones, y \u201cno vamos a ser aplaudidoras ni testigas silenciosas frente a quienes&nbsp; no protejan o violen nuestros derechos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstaremos vigilantes y en caso de ser necesario llevaremos a cabo las acciones legales para la defensa de estos\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La 3 de 3<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La ley recientemente aprobada y publicada en apego a Derecho, Ley #3de3VsViolencia, es ahora un mandato constitucional impulsado por diversas colectivas y legisladoras de todos los partidos pol\u00edticos, que debe ser aplicada con eficacia, ya que busca garantizar que quienes aspiren a una candidatura o un cargo p\u00fablico respondan a un comportamiento \u00e9tico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo podemos esperar menos de nuestros futuros gobernantes y representantes. Esta lucha no es solo por nosotras. Es por la legitimidad y salud de nuestra democracia. Es por un M\u00e9xico m\u00e1s justo, equitativo y libre de violencia\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este llamado es &nbsp;en\u00e9rgico: es hora de que la paridad y la ausencia de violencia sean una realidad palpable en nuestra democracia. Las mujeres mexicanas, unidas y decididas, no daremos un paso atr\u00e1s, queremos un M\u00e9xico que refleje verdaderamente la igualdad, la justicia y el respeto para todas y todos en 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todas votamos, Todas contamos, Todas al Poder.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un llamado por la Democracia Paritarios Libre de Violencia, mujeres de todo el pa\u00eds amenaza con ir a tribunales si no cumplen<\/p>\n","protected":false},"author":3,"featured_media":72726,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[141],"tags":[],"class_list":["post-72724","post","type-post","status-publish","format-standard","has-post-thumbnail","category-elecciones-2020-2021"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/72724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=72724"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/72724\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/72726"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=72724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=72724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=72724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}