{"id":72599,"date":"2023-10-14T16:29:03","date_gmt":"2023-10-14T22:29:03","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=72599"},"modified":"2023-10-14T16:29:05","modified_gmt":"2023-10-14T22:29:05","slug":"desaparecidas-invisibles-hasta-la-muerte-tlachinollan-centro-de-derechos-humanos-de-la-montana","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/desaparecidas-invisibles-hasta-la-muerte-tlachinollan-centro-de-derechos-humanos-de-la-montana\/","title":{"rendered":"Desaparecidas invisibles hasta la muerte: Tlachinollan, Centro de Derechos Humanos de la Monta\u00f1a\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/ceprovysa.com\/?p=66391\"><\/a>Redacci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/Ceprovysa, Tlapa, Guerrero, a 14 de octubre, \u00a02023.- Ninguna autoridad se interesa en registrar a las ni\u00f1as y ni\u00f1os ind\u00edgenas que nacen en las comunidades m\u00e1s rec\u00f3nditas de la Monta\u00f1a. Las madres monoling\u00fces padecen los estragos de la discriminaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2023\/10\/desaparecidas-02.jpg\"><img decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2023\/10\/desaparecidas-02-1024x768.jpg\" alt=\"\" class=\"wp-image-72600\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ellas no existen en las estad\u00edsticas oficiales. No cuentan con su acta de nacimiento para hacer alg\u00fan tr\u00e1mite. No son beneficiarias de nada, ni el derecho a tener un nombre y un lugar digno para vivir. Sobre la tierra realizan todas sus actividades. No cuenta con alguna moneda para comprar lo m\u00ednimo: ropa, jab\u00f3n, y hasta minas porque tampoco tienen derecho a la tierra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Son las pol\u00edticas del coloniaje la que engendra el vasallaje en las familias m\u00e1s pobres e indefensas. No solo padecen esta pol\u00edtica de exclusi\u00f3n y descarte social, tambi\u00e9n padecen la violencia y el exterminio. Son tratadas como objetos, como seres manipulables, ingenuas, pasivas y sumisas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los gobernantes han mantenido este r\u00e9gimen de esclavitud, con estamentos sociales indignos, porque confina a la gente ind\u00edgena a su propia desgracia de sobrevivir en el fango del olvido. La violencia secular se ha incrustado en las mujeres que son invisibles hasta la muerte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la impunidad los justicieros del sistema penal condenan a las mujeres a padecer la violencia de los hombres. Las obligan a soportar todos sus instintos y acciones salvajes. Morir en sus chozas de cart\u00f3n es su destino funesto. Los casos de feminicidios y desapariciones de ni\u00f1as y mujeres ind\u00edgenas se han incrementado sin que las autoridades de los 3 niveles de gobierno se comprometan a parar de tajo este flagelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las estad\u00edsticas de las personas desaparecidas en la Monta\u00f1a son espantosas. Como Centro de Derechos Humanos de la Monta\u00f1a Tlachinollan acompa\u00f1amos a 49 personas desaparecidas, 13 son mujeres ind\u00edgenas, y de estas 7 son ni\u00f1as, de los municipios de Tlapa, Zapotitl\u00e1n Tablas, Cochoapa el Grande, Atlamajalcingo del Monte, Tlacoapa, Alpoyeca, Iliatenco, Copanatoyac, Alcozauca, as\u00ed como Chilpancingo y Aguascalientes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2023\/10\/desaparecidas-03.jpg\"><img decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2023\/10\/desaparecidas-03-1024x768.jpg\" alt=\"\" class=\"wp-image-72601\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En un conteo que realizamos de las denuncias en redes sociales y de familias coincidentemente se registraron 45 personas desaparecidas, de estas 16 son mujeres y ni\u00f1as, de los municipios de Zapotitl\u00e1n Tablas, 28; Acatepec, 6; Cochoapa el Grande, 6; Olinal\u00e1, 2; Metlat\u00f3noc, Huamuxtitl\u00e1n y Tlalixtaquilla fueron uno respectivamente. Las cifras de las personas desaparecidas son m\u00e1s elevadas, sin embargo, no denuncian porque temen por sus vidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, los feminicidios siguen al alza en esta regi\u00f3n golpeada por la violencia machista. Desde el 2016 a la fecha Tlachinollan acompa\u00f1a a 27 v\u00edctimas de feminicidios de mujeres ind\u00edgenas de los municipios de Acatepec, Tlapa, Malinaltepec, Alpoyeca, Tlacoapa, Copanatoyac, Cochoapa el Grande, Zapotitl\u00e1n Tablas y Acapulco. Hay 9 \u00f3rdenes de aprehensi\u00f3n contra los feminicidas, sin embargo, las autoridades judiciales no las han ejecutado. En la comunidad de Copanatoyac hay 6 feminicidios, tres cuentan con orden de aprehensi\u00f3n y tres est\u00e1n en la etapa de investigaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay varios factores que influyen para las desapariciones de personas. En el caso de las ni\u00f1as que han desaparecido en la escuela se presenta porque desde las redes sociales los delincuentes hacen sus fechor\u00edas. El tr\u00e1fico de ni\u00f1as y mujeres es constante. La Fiscal\u00eda no investiga los perfiles de Facebook para hacer se\u00f1alamientos y castigar a los responsables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La desaparici\u00f3n de ni\u00f1as y adolescentes de los municipios de Cochoapa el Grande y Metlat\u00f3noc se dan para evitar los matrimonios forzados. Tambi\u00e9n huyen por la violencia machista en sus hogares en sus comunidades. La vulnerabilidad es mayor. En Tlapa hay personas que contratan a los grupos de la delincuencia organizada para asesinar y desaparecer a las personas, por ejemplo, en el caso de Atlamajac desaparecieron a la abuela, a la hija y a la nieta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los temas de feminicidios, se trata de mujeres muy vulnerables porque sus agresores conocen toda la situaci\u00f3n que viven dentro de un hogar. Se suma porque algunas est\u00e1n solas, separadas, divorciadas y viven lugares muy apartados. Las v\u00edctimas no se pueden defender, ni pedir auxilio. La violencia machista y patriarcal se extiende en todos los \u00e1mbitos de la vida. Los hombres que asesinan a sus esposas solamente quieren mostrar su autoridad y su salvajismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la regi\u00f3n de la Monta\u00f1a es una realidad que duele y sangra por la herida que ha causado la violencia. Las familias lloran en silencio, buscan a sus seres queridos en c\u00edrculos vac\u00edos. Las autoridades no hacen las investigaciones, sus falencias determinan la repetici\u00f3n de la falta de verdad y de justicia. Las desapariciones como los feminicidios siguen rompiendo los tejidos comunitarios, destruyendo vidas y dejando a las familias con el dolor y la angustia. Las personas desaparecidas son invisibles hasta la muerte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ninguna autoridad se interesa en registrar a las ni\u00f1as y ni\u00f1os ind\u00edgenas que nacen en las comunidades m\u00e1s rec\u00f3nditas de la Monta\u00f1a. Las madres monoling\u00fces padecen los estragos de la discriminaci\u00f3n.<\/p>\n","protected":false},"author":3,"featured_media":72602,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[63],"tags":[],"class_list":["post-72599","post","type-post","status-publish","format-standard","has-post-thumbnail","category-reportajes"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/72599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=72599"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/72599\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/72602"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=72599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=72599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=72599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}