{"id":71511,"date":"2023-09-22T12:09:29","date_gmt":"2023-09-22T18:09:29","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=71511"},"modified":"2023-09-22T12:14:31","modified_gmt":"2023-09-22T18:14:31","slug":"feminismo-bastardo-de-maria-galindo-entre-las-nuevas-adquisiciones-de-la-biblioteca-rosario-castellanos","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/feminismo-bastardo-de-maria-galindo-entre-las-nuevas-adquisiciones-de-la-biblioteca-rosario-castellanos\/","title":{"rendered":"Feminismo Bastardo de Mar\u00eda Galindo entre las nuevas adquisiciones de la Biblioteca Rosario Castellanos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u2022 Materia memorable recuerda la vida y obra de la periodista y escritora Elena Poniatowska<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Redacci\u00f3n<br>SemM\u00e9xico, Ciudad de M\u00e9xico, 22 de septiembre, 2023.- La Biblioteca Rosario Castellanos del Centro de Investigaciones y Estudios de G\u00e9nero (CIEG) de la UNAM presenta Materia Memorable. Bolet\u00edn de nuevas adquisiciones y servicios bibliotecarios, un producto bimestral que recupera las novedades editoriales, as\u00ed como recomendaciones bibliogr\u00e1ficas para explorar los estudios de g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>En su \u00faltima entrega dedican la secci\u00f3n Personaje del mes a la periodista, escritora y activista Elena Poniatowska. Tambi\u00e9n presentan El evento del mes, que en esta ocasi\u00f3n es la inauguraci\u00f3n de la Biblioteca \u201cRosario Castellanos\u201d en su nueva sede ubicada en el Antiguo Edificio de Posgrados, primer piso, Ala Sur, Ciudad Universitaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>Elena Poniatowska, \u201cLa princesa roja\u201d<\/strong><br>Periodista, novelista, ensayista, narradora, activista y m\u00e1s. H\u00e9l\u00e8ne Elizabeth Louise Amelie Paula Dolores Poniatowska Amor, mejor conocida como Elena Poniatowska naci\u00f3 en Francia en 1932. Integrante de una familia noble polaca y sobrina de la poeta Pita Amor. Elena lleg\u00f3 a M\u00e9xico a los diez a\u00f1os de edad, durante la Segunda Guerra Mundial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Su carrera period\u00edstica comenz\u00f3 en 1953 en el peri\u00f3dico Exc\u00e9lsior donde, con entrevistas y cr\u00f3nicas, consigui\u00f3 retratar la realidad del pa\u00eds. En 1955 public\u00f3 su primera novela: Lilus Kikus. Su carrera literaria ha sido extensa, ha abordado diversos g\u00e9neros, desde ensayos hasta cuentos infantiles y teatro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Su largo historial como periodista, escritora y profesora le ha permitido recibir numerosos honores y premios, por ejemplo: Premio Xavier Villaurrutia (1971) \u2014que rechaz\u00f3 con una carta al presidente Echeverr\u00eda d\u00f3nde escrib\u00eda \u201c\u00bfQui\u00e9n va a premiar a los muertos?\u201d\u2014, Premio Mazatl\u00e1n (1969 y 1992), Premio Alfaguara (2001), Premio Nacional de Ling\u00fc\u00edstica y Literatura (2002), Premio Internacional R\u00f3mulo Gallegos (2007), Premio Biblioteca Breve (2011), Premio Cervantes (2013), Medalla Gabriela Mistral, Medalla Bellas Artes, La Orden Nacional de la Legi\u00f3n de Honor del Gobierno de Francia y Doctora Honoris Causa por universidades de todo el mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Obras como: Las soldaderas (1999), Jard\u00edn de Francia (2008), Tin\u00edsima (1992) y Obras Reunidas (2005) est\u00e1n disponibles para consulta en la Biblioteca Rosario Castellanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>Biblioteca Rosario Castellanos: m\u00e1s espacio, m\u00e1s libros<\/strong><br>Tras su mudanza a las nuevas instalaciones, la Biblioteca Rosario Castellanos ahora cuenta con m\u00e1s espacio y contin\u00faa expandi\u00e9ndose para seguir siendo una de las bibliotecas m\u00e1s ricas en publicaciones especializadas en estudios de g\u00e9nero y feminismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Entre los \u00faltimos t\u00edtulos de libros adquiridos este bimestre se encuentra: Feminismo Bastardo, El fin de la novela de amor, Por qu\u00e9 volv\u00edas cada verano, Marica y sus amigas entre revoluciones, The New Gender Paradox: Fragmentation and Persistence of the Binary; Becoming a Visible Man; entre otros en diversos idiomas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>En la secci\u00f3n de revistas se encuentra Cihuat, un impreso que retoma la segunda ola del feminismo mexicano de finales de la d\u00e9cada de los setenta. Esta revista es pionera de las publicaciones feministas, junto con La Revuelta (septiembre, 1976) y fem (diciembre, 1976); se public\u00f3 por primera vez en mayo de 1977.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>La creaci\u00f3n de esta publicaci\u00f3n corri\u00f3 a cargo de la Coalici\u00f3n de Mujeres Feministas, surgida por iniciativa de la doctora Mireya Toto Guti\u00e9rrez, quien pertenec\u00eda al Movimiento Feminista Mexicano. Algunos ejemplares pueden ser consultados en los Archivos Hist\u00f3ricos del Feminicidio del CIEG.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>En Base de Datos, Materia Memorable destaca a SERIUNAM, un cat\u00e1logo colectivo con informaci\u00f3n de t\u00edtulos y fasc\u00edculos de revistas impresas y electr\u00f3nicas disponibles en el Sistema Bibliotecario y de Informaci\u00f3n de la UNAM.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>En el bloque para la difusi\u00f3n de las publicaciones del CIEG se encuentran Hortensia Moreno Esparza: escribir en feminismo, un libro homenaje a la obra y aportaciones de Hortensia Moreno, directora de la revista Debate Feminista. Tambi\u00e9n se menciona Masculinidades dobles: hombres, normatividades e identidades religiosas de g\u00e9nero, un texto de Al\u00ed Siles donde se exploran las nuevas masculinidades desde el contexto sociocultural de la Ciudad de M\u00e9xico a principios del siglo XXI.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><br>Alter\/textus. Psicolog\u00eda de la salud en la promoci\u00f3n de la salud sexual<\/strong><br>En la secci\u00f3n Alter\/textus, Materia memorable comparte ensayos interesantes, creativos e imaginativos sobre temas de inter\u00e9s. En esta ocasi\u00f3n presenta Psicolog\u00eda de la salud, perspectiva de g\u00e9nero e interseccionalidad en la promoci\u00f3n de la salud sexual escrito por Ricardo S\u00e1nchez Medina como ensayo final del XIX Diplomado Relaciones de G\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>En \u00e9l, Ricardo S\u00e1nchez hace un an\u00e1lisis nacional sobre los prejuicios que existen para que una persona con VIH tenga acceso a una salud sexual respetuosa. Para ello hace un abordaje en tres partes: 1) la psicolog\u00eda de la salud, 2) la importancia de considerar la perspectiva de g\u00e9nero y 3) la interseccionalidad en la evaluaci\u00f3n e intervenci\u00f3n psicol\u00f3gica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Este y otros n\u00fameros de Materia Memorable pueden consultarse en cieg.unam.mx<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\u00a1Conoce la nueva sede!<br>La Biblioteca Rosario Castellanos est\u00e1 ubicada en el Antiguo Edificio de Posgrados, Ala Sur, Ciudad Universitaria. Su cat\u00e1logo est\u00e1 disponible en cieg.bibliotecas.unam.mx<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Materia memorable recuerda la vida y obra de la periodista y escritora Elena Poniatowska<\/p>\n","protected":false},"author":3,"featured_media":71512,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[45,46],"tags":[],"class_list":["post-71511","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura","category-cultura-cultura"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/71511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=71511"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/71511\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/71512"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=71511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=71511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=71511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}