{"id":71286,"date":"2023-09-14T11:25:53","date_gmt":"2023-09-14T17:25:53","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=71286"},"modified":"2023-09-14T11:28:34","modified_gmt":"2023-09-14T17:28:34","slug":"tras-la-puerta-del-poder-esta-ya-es-una-eleccion-de-estado-xochitl-galvez-ruiz","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/tras-la-puerta-del-poder-esta-ya-es-una-eleccion-de-estado-xochitl-galvez-ruiz\/","title":{"rendered":"Tras la puerta del poder| \u201cEsta ya es una elecci\u00f3n de Estado\u201d: X\u00f3chitl G\u00e1lvez Ru\u00edz\u00a0\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&nbsp;Roberto Vizca\u00edno<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 14 de septiembre, 2023.- Para la candidata presidencial de la oposici\u00f3n, la senadora\u00a0X\u00f3chitl G\u00e1lvez\u00a0Ru\u00edz el acoso que ejerce el presidente\u00a0Andr\u00e9s Manuel L\u00f3pez Obrador\u00a0y su entorno partidario en su contra ya contiene todos los elementos de una elecci\u00f3n presidencial de Estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy como&nbsp;Daniel Ortega,&nbsp;Hugo Ch\u00e1vez&nbsp;o&nbsp;Nicol\u00e1s Maduro&nbsp;lo han hecho y hacen con sus adversarios, a ella&nbsp;AMLO&nbsp;y Morena pretenden demoler su casa ubicada en una colonia clase media, no residencial o fif\u00ed, por supuestamente no contar con uso de suelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y al amenazarla con la demolici\u00f3n, en un desplegado p\u00fablico, dieron a conocer todos los datos de su vivienda exponi\u00e9ndola as\u00ed a ella y a su familia a los radicales del lopezobradorismo y la 4T por lo cual responsabiliza al Presidente&nbsp;L\u00f3pez Obrador&nbsp;de lo que le pase a ella o a sus hijos y marido, o dem\u00e1s familiares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00c9l es el director de esta orquestaci\u00f3n\u201d, denuncia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy todo eso, afirma, es ya \u201cuna elecci\u00f3n de Estado.&nbsp;El fondo de todo esto es, dice, \u201cque estamos subiendo en las encuestas y eso los tiene muertos del miedo\u2026 no encuentran c\u00f3mo bajarme de la candidatura, est\u00e1n muertos del miedo, apanicados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYa me mandaron a todos sus voceros, a los gobernadores, al de Oaxaca, al de Sonora y pues me van a echar mont\u00f3n. Eso solo demuestra que la orquesta de la 4T es dirigida desde Palacio Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHoy (ayer) el presidente me vuelve a mencionar en la ma\u00f1anera, ya sabe que tiene una restricci\u00f3n y es \u00e9l quien est\u00e1 operando esta orquesta, es real.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLo que est\u00e1 en juego es el poder&nbsp;y el presidente se va a querer imponer a como d\u00e9 lugar\u2026 no importa si es a las malas, en forma inconstitucional, con violencia\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMiren, es claro: las dictaduras empiezan por quitarle su hogar a los opositores. Si no preg\u00fantenle a&nbsp;Daniel Ortega&nbsp;que hace unos d\u00edas le quit\u00f3 a la escritora&nbsp;Gioconda Belli&nbsp;su casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYo estoy segura de que si tiran mi casa millones de mexicanos me van a abrir la suya. Pero mi casa est\u00e1 dentro de la ley. Todo certificado por 2 notarios \u2026 se construye en tiempos de&nbsp;V\u00edctor Hugo Romo&nbsp;como delegado de la Miguel Hidalgo y yo compr\u00e9 en preventa, no soy la constructora.&nbsp; Todo est\u00e1 documentado en el Registro P\u00fablico de la Propiedad\u2026 y s\u00ed, la ley s\u00ed es la ley para m\u00ed\u2026 y los reto a que la demuelan\u201d, subraya.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su casa, insiste a lo largo de la entrevista realizada en el Senado y explica: \u201ces legal, la compr\u00e9 a un precio legal y con un cr\u00e9dito bancario\u2026 no es como la casa Gris de Houston\u2026\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que tienen, insiste, \u201ces miedo y me est\u00e1n inventando delitos que no comet\u00ed. Aqu\u00ed no hay conflicto de inter\u00e9s, el uso de suelo es legal. Romo (quien la sucedi\u00f3 en la delegaci\u00f3n Miguel Hidalgo, de Morena, es uno de quienes la han acusado sin fundamento, alega), ped\u00eda moches para entregar esas terminaciones de obra\u201d. Y da datos de muchas obras y sus direcciones para que se compruebe lo que afirma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero los periodistas insisten: \u00bfsu empresa familiar recibi\u00f3 alg\u00fan tipo de contrato por parte de la constructora que realiz\u00f3 la casa en la que usted vive hoy?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00a1No!\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\u00bfVa a responder jur\u00eddicamente?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00a1No!\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y agrega<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u2026 no tengo nada ilegal en mi vida, yo soy una mujer honesta, trabajadora y valiente, y la verdad es que este gobierno me tiene miedo, me quiere intimidar\u2026 parece incre\u00edble que se apaniquen tanto con las encuestas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00bfPor qu\u00e9 no hablamos de la responsabilidad de&nbsp;Claudia Sheinbaum&nbsp;en el Colegio R\u00e9bsamen?, ah\u00ed s\u00ed su ineptitud mat\u00f3 a 26 personas porque el Programa de Protecci\u00f3n Civil depende de la delegaci\u00f3n, y en dos a\u00f1os como delegada no clausur\u00f3 ese colegio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00bfPor qu\u00e9 no hablamos del Metro?, donde se murieron 26 personas por ineptos, porque no le dieron mantenimiento. \u00a1Ah!, ah\u00ed s\u00ed el gobierno no ve, \u00bfverdad?, y se est\u00e1 fijando en una casa de clase media que tengo con qu\u00e9 comprar y acreditar c\u00f3mo la compr\u00e9\u2026 \u00a1les voy a ganar!\u201d, concluye.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>V\u00cdA PARA NOMBRAMIENTOS EN SENADO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El morenista chiapaneco Eduardo Ram\u00edrez, presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica, se\u00f1al\u00f3 que existe ya una ruta legislativa para avanzar en los temas m\u00e1s urgentes, entre ellos unos 100 nombramientos que el Senado de la Rep\u00fablica tiene pendientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a todos los coordinadores parlamentarios, dijo, en las dos sesiones que se realizan semanalmente en el Senado, se abordar\u00e1n asuntos espec\u00edficos por separado: la aprobaci\u00f3n de dict\u00e1menes y la exposici\u00f3n de iniciativas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los dict\u00e1menes que se tramitar\u00e1n los martes, no habr\u00e1 posicionamientos pues ya contar\u00edan con acuerdos un\u00e1nimes a fin de tener un rendimiento legislativo adecuado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La exposici\u00f3n de iniciativas y pendientes se har\u00e1n los mi\u00e9rcoles para sacar adelante los 100 nombramientos que el Senado de la Rep\u00fablica tiene pendientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adelant\u00f3 que el pr\u00f3ximo martes, 19 de septiembre, se comenzar\u00e1 con el nombramiento relativo al Consejo de la Judicatura Federal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De los otros pendientes en el Instituto Nacional de Transparencia, Acceso a la Informaci\u00f3n y Protecci\u00f3n de Datos Personales, el presidente de la Jucopo refiri\u00f3 que las bancadas del Senado contin\u00faan con los di\u00e1logos para llegar a un acuerdo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8230;<a href=\"mailto:rvizcainoa@gmail.com\" target=\"_blank\" rel=\"noreferrer noopener\">rvizcainoa@gmail.com<\/a>&nbsp;\/ Twitter: @_Vizcaino \/ Facebook \/&nbsp;<a href=\"https:\/\/www.facebook.com\/rvizcainoa\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.facebook.com\/rvizcainoa<\/a>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para la candidata presidencial de la oposici\u00f3n, la senadora\u00a0X\u00f3chitl G\u00e1lvez\u00a0Ru\u00edz el acoso que ejerce el presidente\u00a0Andr\u00e9 Manuel L\u00f3pez Obrador\u00a0y su entorno partidario en su contra ya contiene todos los elementos de una elecci\u00f3n presidencial de Estado.<\/p>\n","protected":false},"author":3,"featured_media":39589,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[35,623,622],"tags":[],"class_list":["post-71286","post","type-post","status-publish","format-standard","has-post-thumbnail","category-opinion","category-roberto-vizcaino","category-tras-la-puerta-del-poder"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/71286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=71286"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/71286\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/39589"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=71286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=71286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=71286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}