{"id":71273,"date":"2023-09-13T16:40:05","date_gmt":"2023-09-13T22:40:05","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=71273"},"modified":"2023-09-13T16:40:06","modified_gmt":"2023-09-13T22:40:06","slug":"el-presupuesto-2024-recorta-recursos-para-la-igualdad-los-derechos-humanos-la-violencia-y-la-tortura-feminicida","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/el-presupuesto-2024-recorta-recursos-para-la-igualdad-los-derechos-humanos-la-violencia-y-la-tortura-feminicida\/","title":{"rendered":"El presupuesto 2024 recorta recursos para la igualdad, los derechos humanos, la violencia y la tortura feminicida"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>El paquete econ\u00f3mico desconsidera la Salud Sexual y Reproductiva y la comisi\u00f3n de b\u00fasqueda<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Propone FUNDAR que las y los diputados reorienten la propuesta presidencial que desv\u00eda de la igualdad el 89 por ciento del presupuesto<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Sara Lovera<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 13 de septiembre, 2023.- El presupuesto 2024 carece nuevamente de perspectiva de g\u00e9nero, reduce todos los programas previstos en el Anexo 13 y descobija los programas de prevenci\u00f3n y atenci\u00f3n a la violencia, salud sexual y reproductiva y derechos humanos, es inaudito el recorte del 19 por ciento al presupuesto para atender la tortura, como puede ser el feminicidio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo m\u00e1s grave es que durante 5 a\u00f1os la asignaci\u00f3n presupuestaria para las dependencias encargadas de operar la pol\u00edtica de igualdad de g\u00e9nero y combate a la violencia contra las mujeres sigue sin ser progresiva, concluye la primera exploraci\u00f3n de la iniciativa presidencial de Fundar, Centro de An\u00e1lisis e Investigaci\u00f3n A.C<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Explica en un texto p\u00fablico y difundido hoy que es necesario incrementar el presupuesto para la igualdad de g\u00e9nero y la no violencia. Sostiene que la tendencia de a\u00f1os recientes, el PPEF 2024 propone recortes presupuestarios a programas importantes etiquetados en el Anexo 13, creado para fomentar la igualdad entre hombres y mujeres hace 13 a\u00f1os. A decir de TodasMX constantemente vaciado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ejemplo, se\u00f1ala FUNDAR, hay disminuci\u00f3n presupuestaria al Programa de Apoyo para el Bienestar de las Ni\u00f1as y Ni\u00f1os hijos de madres trabajadoras (-0.3%), y para el Programa de Apoyo a las Instancias de Mujeres en las Entidades Federativas (PAIMEF), el \u00fanico en prevenci\u00f3n de la violencia y para el Programa de Apoyo a Refugios Especializados se mantendr\u00e1n estancados respecto a 2023 (+0.02% en ambos casos).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agrega que la asignaci\u00f3n presupuestaria para las dependencias encargadas de operar la pol\u00edtica de igualdad de g\u00e9nero y combate a la violencia contra las mujeres sigue sin ser progresiva; salvo la Comisi\u00f3n Nacional para Prevenir y Erradicar la Violencia contra las Mujeres (CONAVIM), todas ellas contar\u00e1n en 2024 con menos recursos de los asignados en 2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Critica que la ausencia de una metodolog\u00eda robusta, clara y transparente que contin\u00faa siendo un gran pendiente para la integraci\u00f3n del Anexo 13, creado hace tres lustros y, siempre, tortuosamente negociado con la Secretar\u00eda de Hacienda por diputadas y grupos feministas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Denuncia FUNDAR que en 2024 sigue sin incorporarse una perspectiva de g\u00e9nero y feminista en el presupuesto, ya que 89 por ciento de \u00e9ste se dirigir\u00e1 a los programas insignia del presidente Andr\u00e9s Manuel L\u00f3pez Obrador, o sea programas sociales prioritarios que no inciden directamente en la reducci\u00f3n de brechas de desigualdad ni en la incidencia de la violencia contra las mujeres.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><br>Salud materna, sexual y reproductiva sin mirar<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><br>FUNDAR sostiene la necesidad de incrementar el presupuesto para Salud Materna, Sexual y Reproductiva (SMSyR). Puesto que la asignaci\u00f3n de 2,758.42 millones de pesos para el Programa de SMSyR y si es 17.5 por ciento mayor que el aprobado para 2023, a\u00fan es insuficiente para compensar los recortes que el programa ha tenido desde 2019 (a\u00f1o en que tuvo la mayor asignaci\u00f3n de recursos, de 3,224.43 millones de pesos).<br>Este programa es fundamental para reducir las brechas de desigualdad de g\u00e9nero, ya que est\u00e1 dirigido a garantizar la salud sexual y reproductiva de al menos 34 millones de mujeres que no cuentan con empleo formal y est\u00e1n en una mayor situaci\u00f3n de vulnerabilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Los recortes que ha tenido desde 2019 impactan directamente los servicios de salud que las mujeres reciben (personal, medicamentos, infraestructura, equipo, etc.).<br>De aprobarse este presupuesto, la entidad rectora de la pol\u00edtica de salud sexual y reproductiva, el Centro Nacional de Equidad de G\u00e9nero y Salud Reproductiva de la Secretar\u00eda de Salud (CNEGySR), tendr\u00eda menos recursos para operar. Por ello, en el marco de la negociaci\u00f3n presupuestaria 2024, el poder legislativo debe aumentar por lo menos 466 millones de pesos a este programa, para que se le asigne un monto m\u00ednimo de 3,224.43 millones de pesos, cifra que ha no logrado tener desde 2019.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><br>Los olvidados: Derechos Humanos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Puntualiza que no se financia progresivamente la atenci\u00f3n a v\u00edctimas y las violaciones graves de derechos humanos. El Paquete Econ\u00f3mico 2024 contempla un presupuesto pr\u00e1cticamente id\u00e9ntico al del PEF 2023 para la b\u00fasqueda de personas desaparecidas (0.02 por ciento m\u00e1s para la Comisi\u00f3n Nacional de B\u00fasqueda (CNB), con un presupuesto de 1,149 millones de pesos y 1.6 por ciento m\u00e1s para la Fiscal\u00eda Especializada en Investigaci\u00f3n de Delitos de la Desaparici\u00f3n Forzada, con un presupuesto de 23,500 millones de pesos); mientras que, en materia de tortura presenta un descenso del 19 por ciento respecto de los recursos que tuvo la Fiscal\u00eda Especial en Investigaci\u00f3n del Delito de Tortura en 2023, con un total de 24,900 millones de pesos para 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Contrario a estas tendencias de incrementos inerciales en materia de desaparici\u00f3n y de descenso en materia de tortura, la incidencia de estos delitos y de violaciones graves a los derechos humanos ha ido al alza, por lo tanto, los recursos destinados para su atenci\u00f3n deber\u00edan incrementar de manera progresiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Por su parte, la Comisi\u00f3n Ejecutiva de Atenci\u00f3n a V\u00edctimas (CEAV) tendr\u00eda un presupuesto de 1,113 millones de pesos, un aumento del 0.5% respecto de 2023. Sin embargo, este aumento se ve reflejado principalmente en materia de servicios personales, mientras que el presupuesto para medidas de ayuda, asistencia y reparaci\u00f3n para las v\u00edctimas de delitos y violaciones graves de derechos humanos, equivalente a 633 millones de pesos, se mantiene en los mismos niveles que en 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Esta cifra dista a\u00fan del m\u00ednimo presupuestario de 908 millones de pesos (0.014% del gasto programable) que exist\u00eda como piso m\u00ednimo en la Ley General de V\u00edctimas, para una instituci\u00f3n que tiene un rezago de alrededor del 26% en la atenci\u00f3n de solicitudes para el Registro Nacional de V\u00edctimas al cierre del segundo trimestre de 2023.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Salud en el piso<br><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para el 2024 la funci\u00f3n Salud representar\u00eda el 2.8% del PIB y 10.6 por ciento del Gasto Neto Total, ubic\u00e1ndose como la cuarta funci\u00f3n con mayor presupuesto en el PPEF 2024. A pesar de esto, el gasto en salud contin\u00faa muy por debajo del 6 por ciento del PIB recomendado internacionalmente. Esta tarea resulta urgente considerando que la poblaci\u00f3n con carencia por acceso a la salud increment\u00f3 de 16.2 por ciento a 39.1 por ciento entre 2018 y 2022.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La Cultura \u00bfpara qu\u00e9?<br><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Preocupa a FUNDAR, la falta de financiamiento a la cultura. Dice que el derecho a la Cultura se menosprecia. El proyecto de presupuesto para 2024 prev\u00e9 un monto de recursos para la Secretar\u00eda de Cultura por 16 mil 754 millones de pesos, un aumento real del 0.39%. Sin embargo, el presupuesto es insuficiente para garantizar el derecho a la cultura para todas las personas, sobre todo para quienes menos tienen. Sobresale el incremento del 61.20% propuesto al Instituto Nacional de Antropolog\u00eda e Historia (INAH) y del 846.89% al programa Provisiones para la adquisici\u00f3n de terrenos de Zonas Arqueol\u00f3gicas, recursos que ser\u00e1n ejecutados para regularizar los terrenos alrededor del Tren Maya.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>As\u00ed fue<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><br>El pasado 8 de septiembre, la Secretar\u00eda de Hacienda y Cr\u00e9dito P\u00fablico (SCHP) entreg\u00f3 al Congreso de la Uni\u00f3n el Paquete Econ\u00f3mico para el ejercicio fiscal 2024, una serie de documentos que revelan cu\u00e1les son los planes del Gobierno Federal para recaudar y gastar nuestros recursos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>En 2024, se propone un gasto hist\u00f3rico de m\u00e1s de 9 billones de pesos, y gran parte de estos recursos se destinar\u00e1n hacia los programas y proyectos prioritarios de esta administraci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Desde Fundar se pone \u00e9nfasis en algunos puntos, que deben ser atendidos por el Congreso de la Uni\u00f3n durante la fase de negociaci\u00f3n presupuestaria, para as\u00ed convertir al presupuesto federal en una herramienta para reducir las extremas desigualdades y avanzar en la realizaci\u00f3n de los derechos humanos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Crisis Clim\u00e1tica no\u00a1 primero lo f\u00f3sil<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n puntualiza la necesidad de incrementar el presupuesto para enfrentar la crisis clim\u00e1tica. Se\u00f1ala que la Secretar\u00eda de Medio Ambiente y Recursos Naturales (SEMARNAT) tendr\u00e1 un recorte del 7.1%, lo cual mantiene la tendencia regresiva de recortes al sector ambiental durante esta administraci\u00f3n, que trae consecuencias graves para la garant\u00eda del derecho a un medio ambiente sano de toda la poblaci\u00f3n. En ello sufren principalmente las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presupuesto proyectado para la SEMARNAT, equivalente a 70,245 millones de es apenas al 15 por ciento de los recursos propuestos para PEMEX -empresa que a pesar de la inyecci\u00f3n in\u00e9dita de recursos que ha recibido por parte del Gobierno Federal, no ha logrado revertir la ca\u00edda sostenida de las reservas y de la producci\u00f3n petrolera. Aun as\u00ed, se contin\u00faa con la firme apuesta de afianzar un modelo f\u00f3sil que agrava la crisis clim\u00e1tica y ambiental.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Propone que, de igual forma, resulta primordial modificar el dise\u00f1o del Anexo Transversal para la Adaptaci\u00f3n y Mitigaci\u00f3n del Cambio Clim\u00e1tico, pues en este instrumento contin\u00faan etiquet\u00e1ndose recursos que no se relacionan con el combate a la crisis clim\u00e1tica, como el Tren Maya y el Transporte de Gas Natural.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La organizaci\u00f3n llama como cada a\u00f1o, al Congreso de la Uni\u00f3n a debatir profundamente las razones por las que nuestro pa\u00eds contin\u00faa recaudando pocos impuestos por parte de las personas y corporaciones con mayores recursos, y a incrementar los recursos disponibles para la garant\u00eda de los derechos humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n hacemos un llamado al poder Legislativo para que la discusi\u00f3n ponga al centro las voces de quienes han vivido los impactos, as\u00ed como de la academia y sociedad civil que damos seguimiento al presupuesto, y que demuestre con ello la voluntad para reducir las desigualdades en nuestro pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El paquete econ\u00f3mico desconsidera la Salud Sexual y Reproductiva y la comisi\u00f3n de b\u00fasqueda<\/p>\n","protected":false},"author":3,"featured_media":71274,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[702],"tags":[],"class_list":["post-71273","post","type-post","status-publish","format-standard","has-post-thumbnail","category-economia"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/71273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=71273"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/71273\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/71274"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=71273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=71273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=71273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}