{"id":7115,"date":"2019-02-25T22:42:25","date_gmt":"2019-02-25T22:42:25","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=7115"},"modified":"2023-07-21T14:47:06","modified_gmt":"2023-07-21T19:47:06","slug":"tengo-pasion-y-compromiso-dice-nueva-presidenta-del-organo-rector-de-la-politica-de-genero","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/tengo-pasion-y-compromiso-dice-nueva-presidenta-del-organo-rector-de-la-politica-de-genero\/","title":{"rendered":"Tengo pasi\u00f3n y compromiso, dice nueva Presidenta del \u00f3rgano rector de la pol\u00edtica de g\u00e9nero."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.semmexico.com\/gallery-post.php?id=7346#\">Elda Montiel<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 25 febrero 2019.- Una nueva etapa en la estrategia de funcionamiento del Instituto Nacional de las Mujeres (INMUJERES), para lo cual se est\u00e1 preparando un paquete integral legislativo, desde el reglamento, y que abarque todas las legislaciones, ya que actualmente carece de dientes para poder avanzar en la igualdad sustantiva entre hombres y mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed lo anunci\u00f3 hoy la secretaria de Gobernaci\u00f3n, Olga S\u00e1nchez Cordero, al dar posesi\u00f3n a Nadine Gasman, como presidenta del INMUJERES.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPuede haber problemas, errores o temporales confusiones, pero que nadie tenga duda que, en la Cuarta Transformaci\u00f3n, las mujeres tenemos un espacio propio, que haremos valer para beneficio de todas las mexicanas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asegur\u00f3 que el Presidente Andr\u00e9s Manuel L\u00f3pez Obrador reconoce la importancia del INMUJERES en promover la perspectiva de g\u00e9nero en la implementaci\u00f3n de las pol\u00edticas p\u00fablicas e impulsar acciones para alcanzar la igualdad de oportunidades entre mujeres y hombres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por esa raz\u00f3n, anunci\u00f3 que en los pr\u00f3ximos d\u00edas presentar\u00e1 una terna para que el presidente elija a la titular de la Comisi\u00f3n Nacional para Prevenir y Erradicar la Violencia contra las Mujeres (CONAVIM).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Transformaciones profundas y factibles<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, la nueva presidenta del INMUJERES, Nadine Gasman, dio a conocer que tiene propuestas de transformaci\u00f3n, profundas y factibles, para incidir en el Plan Nacional de Desarrollo, para crear las condiciones de una efectiva transversalizaci\u00f3n de la perspectiva de g\u00e9nero para que el instituto juegue el papel conductual que le corresponde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTengo la pasi\u00f3n y el compromiso\u201d, dijo tras se\u00f1alar que esta es una oportunidad que no se puede desperdiciar, por lo que est\u00e1 comprometida para aportar sus conocimientos, trabajando, para lograrlo, con todas y todos, en igualdad con los otros \u00f3rganos del estado, las organizaciones feministas y el movimiento amplio de mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con un presupuesto de 800 millones de pesos, anunci\u00f3, entre los objetivos, garantizar el ejercicio de los derechos sexuales y reproductivos, promover la educaci\u00f3n sexual, el acceso a los servicios adecuados para todas las mujeres, revisando la Estrategia Nacional para Prevenir el Embarazo Adolescente e Infantil, que incluya la democratizaci\u00f3n del acceso a los servicios de salud sexual y reproductiva, incluyendo los de aborto legal y trabajando con un abordaje intercultural.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Miseria y precariedad<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La doctora con experiencia internacional en ONU Mujeres, es maestra en Salud P\u00fablica, reconoci\u00f3 que tenemos leyes normativas al m\u00e1s alto nivel, seg\u00fan los est\u00e1ndares internacionales de derechos humanos, pero las mujeres mexicanas siguen despertando en la miseria y la precariedad, la discriminaci\u00f3n y la pobreza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a OXFAM, nuestro pa\u00eds est\u00e1 dentro del 25 por ciento de los pa\u00edses con mayores niveles de desigualdad en el mundo con un modelo econ\u00f3mico que beneficia solo a las \u00e9lites y donde de cada tres pesos ganados para los hogares mexicanos, dos son percibidos por los hombres, donde una gran parte del trabajo de las mujeres es invisible y no remunerado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfatiz\u00f3 que hoy \u201cel gobierno mexicano pone en marcha una propuesta integral y de cambio profundo para hacer avanzar a quienes han vivido en el rezago hist\u00f3rico casi en el olvido\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>No creo en las imposiciones<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e9dica por vocaci\u00f3n de servicio, dijo que se form\u00f3 en un modelo de liderazgo inclusivo, dialogante y de consensos. \u201cNo creo en las imposiciones y en ese sentido quiero darles tranquilidad a todas las personas que trabajan en el INMUJERES\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El prop\u00f3sito es posicionar al INMUJERES en su papel de actor pol\u00edtico influyente como rector de la pol\u00edtica nacional de igualdad entre mujeres y hombres utilizando todos los instrumentos para promover y fomentar las condiciones que posibiliten la no discriminaci\u00f3n y la igualdad sustantiva, el fin de todas las formas de violencia contra ni\u00f1as y mujeres, dando impulso pol\u00edtico, asesor\u00eda t\u00e9cnica y coordinaci\u00f3n a todos los niveles de gobierno y fomentando la participaci\u00f3n de la sociedad civil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nadie Gasman se\u00f1al\u00f3 la necesidad de una pol\u00edtica nacional de cuidados que desarrolle un sistema, que articule los recursos que ya existen y que ponga en funcionamiento los tres actores fundamentales: los hogares, el Estado y el sector privado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se dijo una convencida de atender todos los tipos de violencia contra las mujeres, incluyendo el feminicidio, desde un amplio espectro de mirada de la paz y seguridad que permitir\u00e1 revisar, coordinar y poner en el centro del Sistema de Prevenci\u00f3n, Atenci\u00f3n y Sanci\u00f3n y Eliminaci\u00f3n de la violencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agradeci\u00f3 a todas las mujeres que le permitieron llegar al Instituto como las organizaciones feministas, las legisladoras, en particular la diputada Wendy Brice\u00f1o y a la senadora Mal\u00fa M\u00edcher, presentes en la conferencia, y a la Secretar\u00eda de Gobernaci\u00f3n, as\u00ed como al Presidente de la Rep\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gasman reconoci\u00f3 a Marcela Eternod Arambur\u00fa, quien estuvo a cargo del INMUJERES durante los \u00faltimos meses. Posteriormente, se reuni\u00f3 con las y los trabajadores del instituto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>No fueron invitadas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, en su muro de Facebook, la consejera consultiva de INMUJERES, Maricarmen Rioseco Gallegos, de Baja California, se\u00f1al\u00f3 que las consejeras no fueron invitadas a la toma de protesta de la nueva titular del INMUJERES, Nadine Gasman.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bajo el t\u00edtulo. (\u00a1) Mal inicio!, se\u00f1al\u00f3:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstoy segura que nos van a contestar desde el instituto que no hay obligatoriedad para invitarnos, pero por cordialidad y respeto a nuestra comprometida labor en el proceso, las funcionarias del INMUJERES no debieron excluir a la representaci\u00f3n ciudadana que ostentamos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cExplico: Por informaci\u00f3n casual nos enteramos que hoy lunes 25 a las 10:30 am la Secretaria de Gobernaci\u00f3n estar\u00e1 en INMUJERES para dar posesi\u00f3n a la nueva titular, Nadine Gasman. Y los \u00d3rganos Auxiliares, Consejo Social y Consejo Consultivo de la instituci\u00f3n, fuimos excluidos. No se nos avis\u00f3, ni se nos invit\u00f3, mucho menos convoc\u00f3 a las oficinas en San Jer\u00f3nimo L\u00eddice para esta acci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSin embargo no debe sorprendernos esta discriminaci\u00f3n por parte de la Secretaria Ejecutiva del Instituto, ya que durante todo el proceso para realizar una elecci\u00f3n transparente para Presidenta del INMUJERES, recibimos amenazas y obst\u00e1culos, e intentos de descalificaci\u00f3n al proceso a trav\u00e9s de una denuncia que \u00e9sta funcionaria present\u00f3 contra los Consejos ante la Funci\u00f3n P\u00fablica. Lo que es incongruente si se revisa el prop\u00f3sito de esa denuncia\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/em\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elda Montiel SemM\u00e9xico, Cd. de M\u00e9xico, 25 febrero 2019.- Una nueva etapa en la estrategia de funcionamiento del Instituto Nacional de las Mujeres (INMUJERES), para lo cual se est\u00e1 preparando un paquete integral legislativo, desde el reglamento, y que abarque todas las legislaciones, ya que actualmente carece de dientes para poder avanzar en la igualdad [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7119,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[690,51],"tags":[],"class_list":["post-7115","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-ejecutivo"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/7115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=7115"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/7115\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/7119"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=7115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=7115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=7115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}