{"id":7034,"date":"2018-08-30T21:19:15","date_gmt":"2018-08-30T21:19:15","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=7034"},"modified":"2023-07-21T14:33:18","modified_gmt":"2023-07-21T19:33:18","slug":"entresemana-32","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/entresemana-32\/","title":{"rendered":"Entresemana"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00bfPe\u00f1a Nieto suplente del ni\u00f1o Verde?<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"> \u2022 La alianza del PVEM m\u00e1s que con el PRI, est\u00e1 firme y comprometida con EPN<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/semmexico.com\/gallery-post.php?id=5702#\">Mois\u00e9s S\u00e1nchez<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, 30 agosto 2018.- \u00bfUna curul para Enrique Pe\u00f1a Nieto, cuando concluya su gesti\u00f3n el pr\u00f3ximo 1 de diciembre? Cualquiera imaginar\u00eda elemental que el primer priista del pa\u00eds fuera a la C\u00e1mara de Diputados a sumarse a la lucha de los legisladores del PRI en defensa de sus reformas, como lo ha adelantado en el Senado el yucateco Jorge Carlos Ram\u00edrez Mar\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero no. No ser\u00e1 Enrique Pe\u00f1a Nieto quien asuma una curul en la naciente LXIV Legislatura federal ni mucho menos en la menguada fracci\u00f3n del tricolor en el Palacio Legislativo de San L\u00e1zaro. Hay un personaje pr\u00f3ximo, dir\u00eda que muy pr\u00f3ximo, a mandatario quien ocupar\u00e1 una curul en relevo del ex ni\u00f1o verde Jorge Emilio Gonz\u00e1lez Mart\u00ednez, dirigente real del Partido Verde Ecologista de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y es que, mire usted, la alianza del PVEM m\u00e1s que con el PRI, est\u00e1 firme y comprometida con el a\u00fan primer priista del pa\u00eds y jefe del tricolor, Enrique Pe\u00f1a Nieto, quien seguramente cuenta los d\u00edas y las horas para entregar la banda tricolor y, por supuesto, la cauda de pendientes que hay en su administraci\u00f3n a su relevo, el due\u00f1o de Morena y presidente electo, Andr\u00e9s Manuel L\u00f3pez Obrador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este tenor, \u00bfusted le crey\u00f3 al diputado Arturo Escobar y Vega que el Partido Verde rompi\u00f3 con el PRI? Yo tampoco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Menos, elemental, es cre\u00edble que el verde haya roto con el presidente Enrique Pe\u00f1a Nieto. En todo caso se trat\u00f3 de una especie de deslinde para que los verdes puedan, como dijo Escobar y Vega, hacer alianzas legislativas y, por qu\u00e9 no, electorales hasta con el diablo, o Morena.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pol\u00edtica es as\u00ed. No hay rubor cuando se rompen alianzas, pactos de sangre y hermandades pol\u00edticas, si de obtener el poder se trata. Por eso, nadie crey\u00f3 la versi\u00f3n de Escobar y Vega, e incluso hubo quienes matizaron con el dicho de que s\u00f3lo se trataba de la alianza legislativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incluso, ayer, el ni\u00f1o verde dijo, en entrevista en la C\u00e1mara de Diputados, que su partido est\u00e1 dispuesto a hacer alianza y acuerdos con todos los partidos porque, adujo algo que nadie le cree, que \u201cel Partido Verde es un partido independiente fundado hace m\u00e1s de 20 a\u00f1os, participamos en una coalici\u00f3n de gobierno para colaborar y ayudar a los buenos resultados del gobierno de Enrique Pe\u00f1a Nieto y el primero de diciembre acaba el gobierno de Enrique Pe\u00f1a Nieto y el Partido Verde volver\u00e1 a lo de antes que es un partido de oposici\u00f3n independiente\u201d. \u00bfSer\u00e1?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que no se trata de una ruptura, \u201csimplemente es otra etapa de la vida pol\u00edtica de cada partido y hay que entenderlo as\u00ed\u201d, refiri\u00f3 y acot\u00f3 el ment\u00eds respecto de la versi\u00f3n del divorcio con el PRI:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAcaba el gobierno de nuestro amigo Enrique Pe\u00f1a el 30 de noviembre y el Partido Verde regresa a ser un partido independiente que ya no tiene la necesidad de apoyar el proyecto del PRI, porque ya se acab\u00f3 el gobierno\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;\u00bfSin la tutela del PRI, el Verde Ecologista no se sentir\u00e1 solito o perdido?\u2014se le pregunt\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;Nunca hubo tutela del PRI. Hubo una coalici\u00f3n de gobierno, cada partido es independiente y el Partido Verde est\u00e1 muy contento de los a\u00f1os que acompa\u00f1amos al gobierno de Pe\u00f1a, pero tambi\u00e9n estamos muy contentos de estos a\u00f1os que vamos a ser, que vamos a vivir otra realidad\u2014respondi\u00f3 Jorge Emilio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y s\u00ed, en efecto, el verde vivir\u00e1 otra realidad, aunque a su amigo Enrique Pe\u00f1a Nieto no lo puede negar, como tampoco le puede negar un espacio en la C\u00e1mara de Diputados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El compromiso es de tanta importancia que el propio Jorge Emilio se ofreci\u00f3 en sacrificio, \u00a1vaya sacrificio!, para cobrar como diputado federal hasta el mes de abril del a\u00f1o pr\u00f3ximo, cuando solicitar\u00e1 licencia al cargo para dar&nbsp; paso a un colaborador cercan\u00edsimo a Enrique Pe\u00f1a Nieto, tanto que implicar\u00eda como cederle la curul al, para entonces, ex Presidente de la Rep\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y por qu\u00e9 calificar esa cesi\u00f3n como un acto de sacrificio. Porque a Jorge Emilio le gusta el poder y, sin duda, seguir\u00e1 disfrut\u00e1ndolo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El caso es que, en mayo de 2019, ante la Comisi\u00f3n Permanente del Congreso de la Uni\u00f3n, rendir\u00e1 protesta como uno de los 16 integrantes de la bancada del PVEM en la C\u00e1mara de Diputados, Jorge Corona M\u00e9ndez, secretario particular auxiliar del presidente Pe\u00f1a Nieto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Corona M\u00e9ndez, no es precisamente secretario auxiliar, no. Es quiz\u00e1 el hombre de m\u00e1s confianza de Enrique Pe\u00f1a Nieto, con quien ha trabajado desde que \u00e9ste era gobernador del Estado de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bueno, y usted se preguntar\u00e1 por qu\u00e9 esperar hasta mayo para asumir el relevo de Jorge Emilio, si su encomienda concluye el \u00faltimo d\u00eda de noviembre entrante. Seguramente porque don Jorge Corona M\u00e9ndez est\u00e1 obligado a tomarse unas vacaciones, despu\u00e9s de 12 a\u00f1os de desgastante y delicada tarea de acompa\u00f1ar a Enrique Pe\u00f1a Nieto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El secretario auxiliar Corona M\u00e9ndez tiene m\u00e1s cercan\u00eda que la que en tu momento se presume tuvo Aurelio Nu\u00f1o. Y, bueno, de Eduardo S\u00e1nchez Hern\u00e1ndez, ni qu\u00e9 decir porque la proximidad con el presidente fue tir\u00e1ndole de gris a gris Oxford. \u00bfUna curul para Pe\u00f1a Nieto?, bueno, s\u00ed, pero ser\u00e1 para su, sin duda, amigo. Conste.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:sanchezlimon@gmail.com\">sanchezlimon@gmail.com<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.entresemana.mx\/\">www.entresemana.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">@msanchezlimon<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfPe\u00f1a Nieto suplente del ni\u00f1o Verde? \u2022 La alianza del PVEM m\u00e1s que con el PRI, est\u00e1 firme y comprometida con EPN Mois\u00e9s S\u00e1nchez SemM\u00e9xico, 30 agosto 2018.- \u00bfUna curul para Enrique Pe\u00f1a Nieto, cuando concluya su gesti\u00f3n el pr\u00f3ximo 1 de diciembre? Cualquiera imaginar\u00eda elemental que el primer priista del pa\u00eds fuera a la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6811,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[689,83],"tags":[],"class_list":["post-7034","post","type-post","status-publish","format-standard","has-post-thumbnail","category-689","category-moises-sanchez-limon"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/7034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=7034"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/7034\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/6811"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=7034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=7034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=7034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}