{"id":69245,"date":"2023-07-22T16:53:01","date_gmt":"2023-07-22T21:53:01","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=69245"},"modified":"2023-07-22T16:57:53","modified_gmt":"2023-07-22T21:57:53","slug":"hallazgos-una-nina-como-tu","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/hallazgos-una-nina-como-tu\/","title":{"rendered":"Hallazgos| Una ni\u00f1a como t\u00fa"},"content":{"rendered":"<p>Roc\u00edo Fiallega<\/p>\n<p>&nbsp;<\/p>\n<p>SemM\u00e9xico, Ciudad de M\u00e9xico, 22 de julio, 2023.- Francisca era una ni\u00f1a como t\u00fa, le gustaba mucho el lugar donde viv\u00eda, en Villa Ocampo, Durango, donde la tierra era roja y el viento era un sabio que lleva y trae historias, su casa estaba cerca del hermoso R\u00edo Florido. Naci\u00f3 en 1900, muchos a\u00f1os despu\u00e9s cambi\u00f3 su nombre por Nellie Campobello.<\/p>\n<p>Su abuelo Mateo le contaba historias de apaches y de luchas por la tierra, ella escuchaba con sus ojos siempre abiertos, brillantes y alegres.<\/p>\n<p>Con su mam\u00e1 Rafaela y sus hermanitos se fue a vivir a Parral, en Chihuahua, que era una noble tierra. Poco tiempo despu\u00e9s estall\u00f3 la Revoluci\u00f3n Mexicana de 1910.<\/p>\n<p>No ten\u00edan muchas cosas, solo a su mam\u00e1 que les cantaba y les cos\u00eda ropita, eran tiempos dif\u00edciles. La ni\u00f1a Francisca con su vestido y sus botitas nunca se imagin\u00f3 que lograr\u00eda ser la \u00fanica mujer que escribir\u00eda sobre la Revoluci\u00f3n Mexicana siendo testigo de ella, ni que ser\u00eda una gran maestra de danza, as\u00ed como core\u00f3grafa (porque su hermanita Soledad, que luego se cambi\u00f3 el nombre por Gloria fue la bailarina), ni que ser\u00eda directora de la Escuela Nacional de Danza o que crear\u00eda el \u201cBallet de la Ciudad de M\u00e9xico\u201d, ni que se olvidar\u00edan de ella cuando fuera mayor.<\/p>\n<p>Despu\u00e9s de estar en Parral, cuando Francisca era adulta se mud\u00f3 a la Ciudad de M\u00e9xico con sus hermanos y su mam\u00e1 para quedarse mucho tiempo. Entonces, se cambia su nombre de Francisca Moya Luna a Nellie Campobello.<\/p>\n<p>&nbsp;<\/p>\n<p>La Escritura<\/p>\n<p>Le gustaba escribir desde chiquita. Ya en la ciudad de M\u00e9xico conoci\u00f3 al Dr. Atl, quien decidi\u00f3 publicarle sus poemas con el t\u00edtulo Francisca \u00a1Yo! \u2013si te fijas a\u00fan no se hab\u00eda cambiado el nombre-. Tambi\u00e9n sigui\u00f3 escribiendo poes\u00eda a lo largo de los a\u00f1os y public\u00f3 en Mis Libros una parte de esos primeros poemas y los nuevos con el t\u00edtulo \u201cAbra en la roca\u201d; despu\u00e9s escribi\u00f3 Tres poemas.<\/p>\n<p>Nellie tra\u00eda en los ojos im\u00e1genes de la Revoluci\u00f3n, algunas alegres, pero casi todas tristes o crueles, por ejemplo, al pie de su ventana en la calle Segunda del Rayo un d\u00eda estaba el cad\u00e1ver de un hombre; tambi\u00e9n en su coraz\u00f3n estaban las historias que le contaba su madre sobre los revolucionarios.<\/p>\n<p>Casi todos conocemos historias o sabemos lo que ha ocurrido en la Revoluci\u00f3n Mexicana, pero ella no ley\u00f3 esos libros, todo lo vivi\u00f3. Entonces, decidi\u00f3 contar la historia de la revoluci\u00f3n no s\u00f3lo hablando de las batallas, los caudillos o los generales, sino desde los revolucionarios que conoci\u00f3, en el libro Cartucho. Relato de la lucha en el Norte de M\u00e9xico, recre\u00f3 esos personajes con cari\u00f1o, con ternura. A Nellie tambi\u00e9n le interesaba que no se olvidara a uno de los m\u00e1s aguerridos l\u00edderes de la revoluci\u00f3n, por eso escribi\u00f3 Apuntes sobre la vida militar de Francisco Villa.<\/p>\n<p>La mam\u00e1 de Nellie era una mujer esbelta y de cabellos negros, con ojos que eran en la ma\u00f1ana amarillos y verdes, indecisos a las tres de la tarde, despu\u00e9s se volv\u00edan de oro, con unas cejas que se mov\u00edan cuando levantaba la voz para cantar; muri\u00f3 en 1922, eso le caus\u00f3 mucho dolor a Nellie, quien la extra\u00f1\u00f3 hasta la muerte, as\u00ed es que escribi\u00f3 el libro Las manos de mam\u00e1 para contar que con esas manos formaba tortillas h\u00famedas de l\u00e1grimas porque ten\u00eda que alimentar bocas hambrientas, sin razonamientos, sin coraz\u00f3n. Rafaela era una mujer a la que la vida le dio el dolor de nosotros quit\u00e1ndole todo, pero extend\u00eda sus sue\u00f1os como una ni\u00f1a que tiende sus mu\u00f1ecas para empezar a moverlas.<\/p>\n<p>&nbsp;<\/p>\n<p>La Danza<\/p>\n<p>En la Ciudad de M\u00e9xico, Nellie y Gloria fueron a ver a Ana Pavlova y entonces naci\u00f3 la pasi\u00f3n por la danza; al principio Nellie acompa\u00f1aba a su hermana a sus clases, luego decidi\u00f3 estudiar. Estuvo en el Ballet Carroll e interpret\u00f3 papeles chiquitos.<\/p>\n<p>Juntas estuvieron en las Misiones culturales en las que participaban muchos artistas, y viajaban mucho para llevar sus danzas mexicanas a muchos lugares de la Rep\u00fablica. Hay una foto muy bonita en la que Nellie y Gloria bailan el jarabe tapat\u00edo y como no hab\u00eda muchachos, pues Nellie sale de hombre y Gloria de mujer.<\/p>\n<p>Luego Nellie realiz\u00f3 la coreograf\u00eda del Ballet 30-30 que se trataba sobre el levantamiento armado de 1910 y se escenificaba en un estadio o un lugar muy grande porque participaban como 400 personas.<\/p>\n<p>Tiempo despu\u00e9s, Nellie dio clases y fue directora de la Escuela Nacional de Danza desde 1937 hasta su desaparici\u00f3n en 1985. Fue pionera de la danza en nuestro pa\u00eds ya que busc\u00f3 que se tuvieran espacios dignos y que todos pudieran practicar este arte.<\/p>\n<p>Nellie quer\u00eda que sus alumnos de danza conocieran los movimientos de las danzas ind\u00edgenas, no s\u00f3lo como pasos a seguir en una coreograf\u00eda sino que fueran fieles a la parte \u00edntima, entra\u00f1able, que es donde lo esencial del ritmo tiene su verdadero origen, por eso con su hermanita Gloria (Soledad) y su hermano Mauro dise\u00f1aron un libro \u00fanico: Ritmos ind\u00edgenas de M\u00e9xico, es muy diferente a todos los dem\u00e1s porque viene la explicaci\u00f3n de algunas danzas ind\u00edgenas, as\u00ed como los dibujos que ense\u00f1an cada paso.<\/p>\n<p>Fund\u00f3 el Ballet de la Ciudad de M\u00e9xico, el primero que hubo en el pa\u00eds, con su hermana Gloria, Mart\u00edn Luis Guzm\u00e1n y Jos\u00e9 Clemente Orozco, solamente hizo tres Temporadas (en 1943, en 1945 y en 1947). Para este Ballet hizo las coreograf\u00edas: Fuensanta, Obertura Republicana, Ixtepec, Vespertina, Presencia y Feria (basada en bailes folkl\u00f3ricos mexicanos).<\/p>\n<p>&nbsp;<\/p>\n<p>La soledad<\/p>\n<p>Nellie fue una mujer del norte, poderosa en su voz y su talante, siendo adulta le gustaban los abrigos de piel, vestir bien y hablar de la Revoluci\u00f3n Mexicana; se alimentaba de miel, d\u00e1tiles, nueces, germen de trigo, tortillas de harina y caf\u00e9&#8230; de la carne seca, el chile con queso, sopaip\u00edas, mochomos y chacales.<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>.<\/p>\n<p>Siempre tuvo la necesidad de hacer justicia mediante su escritura (para que no se olvidaran de los revolucionarios verdaderos), decir la verdad, esforzarse hasta lograr sus objetivos (tener una danza mexicana a la altura de las mejores del mundo), quiz\u00e1 por eso no tuvo tiempo para casarse.<\/p>\n<p>Pero con el tiempo se fue quedando sola, primero se muri\u00f3 su hermanita Gloria en 1968 y luego su mejor amigo, Mart\u00edn Luis Guzm\u00e1n en 1976; aunque siempre estaba ocupada en la Escuela Nacional de Danza, cada vez sal\u00eda menos, as\u00ed es que una alumna suya y su marido se acercaron a ella porque no ten\u00edan d\u00f3nde vivir, despu\u00e9s de eso se fueron adue\u00f1ando de la vida de Nellie, no la dejaban salir.<\/p>\n<p>Muchas personas se preocuparon por eso y entonces ella sali\u00f3 a la calle en 1985 con esas dos personas, pero luego desapareci\u00f3; ellos siempre dec\u00edan que ella estaba de viaje, pero nadie la ve\u00eda.<\/p>\n<p>Artistas y escritores pidieron durante varios a\u00f1os que las autoridades la buscaran, pero hasta 1998 la Comisi\u00f3n de Derechos Humanos del Distrito Federal encontr\u00f3 una tumba con las siglas NCM-FML (Nellie Campobello Morton-Francisca Moya Luna).<\/p>\n<p>Nellie hab\u00eda muerto el 9 de julio de 1996. Aunque llegaron tarde los reconocimientos, la memoria nos trae a esa mujer que siempre quiso ser como una mariposa, que ped\u00eda manos rojas para derribar cerros, que amaba su tierra y que fue una ni\u00f1a como cada una de nosotras.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Las sopaip\u00edas se comen en la temporada navide\u00f1a, son una especie de bu\u00f1uelos, galletas de harina un tanto gruesas que se fr\u00eden y son cubiertas por az\u00facar y canela; los mochomos es carne molida seca que tiene la apariencia de hormigas \u2013a las que se les dice mochomos- y los chacales es un guiso que se come por lo general en Semana Santa, consiste en una sopa que se hace con ma\u00edz quebrado (duro), queso, jitomate y especias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roc\u00edo Fiallega &nbsp; SemM\u00e9xico, Ciudad de M\u00e9xico, 22 de julio, 2023.- Francisca era una ni\u00f1a como t\u00fa, le gustaba mucho el lugar donde viv\u00eda, en Villa Ocampo, Durango, donde la tierra era roja y el viento era un sabio que lleva y trae historias, su casa estaba cerca del hermoso R\u00edo Florido. Naci\u00f3 en 1900, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":39324,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[620,35,621],"tags":[],"class_list":["post-69245","post","type-post","status-publish","format-standard","has-post-thumbnail","category-hallazgos","category-opinion","category-rocio-fiallega"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/69245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=69245"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/69245\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/39324"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=69245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=69245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=69245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}