{"id":6883,"date":"2019-01-10T17:19:54","date_gmt":"2019-01-10T17:19:54","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=6883"},"modified":"2023-07-21T14:43:23","modified_gmt":"2023-07-21T19:43:23","slug":"entresemana-13","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/entresemana-13\/","title":{"rendered":"Entresemana"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u2022 \u201cAs\u00ed lo recibimos\u201d<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"> Esta p\u00e9sima estrategia del combate al huachicol<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/semmexico.com\/gallery-post.php?id=6792#\">Mois\u00e9s S\u00e1nchez<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, 10 enero 2019.- Abierta parcialmente al p\u00fablico, m\u00e1s que al que Andr\u00e9s Manuel L\u00f3pez Obrador ha llamado pueblo sabio \u2013el que vot\u00f3 por \u00e9l, por supuesto&#8211; la residencia presidencial de Los Pinos, registra un constante flujo de visitantes que intercambian comentarios, ya de sorpresa que de ofendida condici\u00f3n personal por observar y enterarse del que algunos consideran lujo excesivo, con el que viv\u00edan los presidentes en turno en las casas construidas a modo en ese espacio del rumbo del bosque de Chapultepec, en la que fue Hacienda de La Hormiga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y mire usted que en cada uno de los letreros que aluden lo mismo a la rec\u00e1mara presidencial, en la Casa Miguel Alem\u00e1n que en la oficina que, con absoluta certidumbre refiere el anuncio orientador, el entonces presidente L\u00e1zaro C\u00e1rdenas del R\u00edo pens\u00f3 y redact\u00f3 las l\u00edneas del decreto de la expropiaci\u00f3n petrolera y la entrega de millones de tierras a los sintierra, se lee: \u201cAs\u00ed lo recibimos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En efecto, as\u00ed recibieron los administradores de este espacio residencial que se denomina Los Pinos, por cierto, custodiado por elementos de la Polic\u00eda Militar y j\u00f3venes civiles que orientan y ordenan a los visitantes por d\u00f3nde caminar y no entrometerse en espacios que en realidad nada tienen de especial ni secreto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, en el alto mando del primer c\u00edrculo de Andr\u00e9s Manuel L\u00f3pez Obrador, ungido Presidente de la Rep\u00fablica hace 41 d\u00edas, no pueden presumir en este momento que \u201cas\u00ed recibieron al pa\u00eds\u201d, porque en ese breve tiempo con una tendencia que ven\u00eda desde los d\u00edas m\u00e1s crudos de la campa\u00f1a electoral, al pa\u00eds le han variado ofensivamente la pretendida esencia del cambio aterciopelado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ed, el 1 de diciembre de 2018 no hubo gritos ni sombrerazos, ausentes los grupos de anarquistas que seis a\u00f1os atr\u00e1s provocaron al Ej\u00e9rcito y a la Polic\u00eda Federal, en una bravuconada al entrante presidente Enrique Pe\u00f1a Nieto, en el Palacio Legislativo de San L\u00e1zaro corri\u00f3 la ceremonia de la unci\u00f3n de L\u00f3pez Obrador en un ambiente de sobrado aburrimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la residencia oficial de Los Pinos los vestidores de las rec\u00e1maras presidenciales lucen brillantes, sin brizna de polvo; la ampl\u00edsima cocina sin enseres, por supuesto, m\u00e1s parece un limp\u00edsimo quir\u00f3fano, en tanto las salas de juntas de gabinete o las de espera y el llamado b\u00fanker de paredes recubiertas de aislante de ruido y hasta la sala de cine con c\u00f3modos sillones de espacio VIP.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed la recibieron los nuevos due\u00f1os del poder en M\u00e9xico: limpia y dispuesta a ser auscultada por visitantes nacionales y turistas extranjeros. Analizada por estos simpatizantes de L\u00f3pez Obrador que acusaron la ausencia de libros sin conocer c\u00f3mo estaban los estantes de las bibliotecas de las casas de este espacio enorme, o que acusaron robo de obras de arte en una prisa por llevar a picota a los anteriores inquilinos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, al pa\u00eds que recibieron el 1 de diciembre lo han comenzado a desmantelar en su estructura institucional merced al voluntarismo de un hombre que se ha gastado la vida en busca de llegar al m\u00e1ximo cargo de elecci\u00f3n popular en M\u00e9xico y, cuando lo logr\u00f3, no sabe c\u00f3mo se gobierna, carece del tama\u00f1o de un estadista y se entretiene con dichos muy suyos como si el pa\u00eds se gobernara por mis cojones, que es finalmente una de las traducciones del me canso ganso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ed, la residencia presidencial de Los Pinos tiene sus asegunes, como en su momento lo acot\u00f3 cada inquilino con su familia, con sus voluntades como la de construir una residencia de pedigr\u00ed, la que pidi\u00f3 Miguel Alem\u00e1n Vald\u00e9s porque la anterior, la L\u00e1zaro C\u00e1rdenas era muy peque\u00f1a para recibir a visitantes distinguidos, o la caba\u00f1ita acogedora, seg\u00fan confes\u00f3 Marta Sahag\u00fan Jim\u00e9nez en su momento al espacio donde dorm\u00eda su entonces jefe y luego marido Vicente Fox Quesada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante, han sido medidos y espec\u00edficos los voluntarismos para decorar o hacer cambios en esa residencia que el hoy presidente Andr\u00e9s Manuel L\u00f3pez Obrador desde\u00f1\u00f3 para vivir porque ofend\u00eda a sus convicciones de austeridad juarista, aunque Benito Ju\u00e1rez nunca vivi\u00f3 en la median\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed la recibieron, pero al pa\u00eds que recibieron con sus bemoles de violencia, inseguridad, corrupci\u00f3n y diversidad cuando tambi\u00e9n enorme pobreza, no le han hecho m\u00e1s que sumirlo en la zozobra, en el enfrentamiento de buenos y malos, de llenarlo de expectativas que tienden m\u00e1s a la oscuridad aderezada con la galopante impunidad que L\u00f3pez Obrador maquilla con la gracejada, la frase del chistorete, la burla y la difamaci\u00f3n, la descalificaci\u00f3n y el insulto hacia los periodistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De esa decisi\u00f3n de echar al bote de la basura la avanzada obra del Nuevo Aeropuerto Internacional de M\u00e9xico, que a los mexicanos costar\u00e1 pagar hasta el a\u00f1o 2040, cuando Andr\u00e9s Manuel dijo implicar\u00eda un ahorro de cien millones de pesos, se suma esta p\u00e9sima estrategia del combate al huachicol que tiene tantas aristas como sospechas derivadas del dizque accidente a\u00e9reo en el que perdieron la vida la gobernadora de Puebla, Martha \u00c9rika Alonso Hidalgo y su esposo Rafael Moreno Valle Rosas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al pa\u00eds no lo recibieron as\u00ed hace 41 d\u00edas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Del insulto y la sospecha de componendas al perd\u00f3n ofensivo que tiene tufo a impunidad como se respira en ese apoyo del dirigente del sindicato petrolero, Carlos Romero Deschamps, el mismo que fue cuestionado y del que se tiene un n\u00famero no cuantificado de demandas, incluidas las del orden penal, pero que el coordinador de los diputados federales de Morena, Mario Delgado, ha ponderado, se desprende todo lo que usted quiera pensar respecto de acuerdos bajo cuerda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ed, como est\u00e1 hoy recibieron a la residencia presidencial de Los Pinos, por aquello de que falte o sobre algo. Pero al pa\u00eds que hoy vivimos no lo recibieron as\u00ed, en la ruta de una severa crisis. \u00bfY el crimen organizado y los huachicoleros y los funcionarios enriquecidos con ese saqueo a Pemex, incluido el dirigente sindical pr\u00e1cticamente exonerado? Bien, gracias. Insisto, Presidente, \u00bfpor qu\u00e9 le tiembla la mano? M\u00e9xico no se merece ser gobernado con chistoretes y voluntarismos. Digo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:sanchezlimon@gmail.com\">sanchezlimon@gmail.com<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.entresemana.mx\/\">www.entresemana.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">@msanchezlimon<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 \u201cAs\u00ed lo recibimos\u201d Esta p\u00e9sima estrategia del combate al huachicol Mois\u00e9s S\u00e1nchez SemM\u00e9xico, 10 enero 2019.- Abierta parcialmente al p\u00fablico, m\u00e1s que al que Andr\u00e9s Manuel L\u00f3pez Obrador ha llamado pueblo sabio \u2013el que vot\u00f3 por \u00e9l, por supuesto&#8211; la residencia presidencial de Los Pinos, registra un constante flujo de visitantes que intercambian comentarios, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6811,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,83],"tags":[],"class_list":["post-6883","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-moises-sanchez-limon"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/6883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=6883"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/6883\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/6811"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=6883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=6883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=6883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}