{"id":68776,"date":"2023-07-12T14:14:49","date_gmt":"2023-07-12T19:14:49","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=68776"},"modified":"2023-07-12T14:14:50","modified_gmt":"2023-07-12T19:14:50","slug":"reconocimiento-raquel-berman-a-la-resiliencia-femenina-contra-la-adversidad-en-camara-de-diputados","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/reconocimiento-raquel-berman-a-la-resiliencia-femenina-contra-la-adversidad-en-camara-de-diputados\/","title":{"rendered":"Reconocimiento \u201cRaquel Berman a la Resiliencia Femenina contra la Adversidad\u201d en C\u00e1mara de Diputados"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong>La justicia para las mujeres debe ser un asunto de Estado: Raquel Berman<\/strong><\/li>\n\n\n\n<li><strong>Muchas mujeres todav\u00eda est\u00e1n sujetas al entramado patriarcal en M\u00e9xico<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Micaela M\u00e1rquez<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 12 de julio 2023.- El premio \u201cRaquel Berman a la Resiliencia Femenina frente a la Adversidad\u201d visualiza la violencia estructural contra la mujer en la sociedad, se destac\u00f3 en la s\u00e9ptima entrega que se realiz\u00f3 en la C\u00e1mara de Diputados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A las galardonadas se premia por su capacidad de transformaci\u00f3n interna, recuperarse del trauma y participar activamente en la sociedad a favor de otras mujeres, como se dijo en la entrega del premio, que fue organizada por la Comisi\u00f3n de Igualdad de G\u00e9nero, la Secretar\u00eda General y la Unidad para la Igualdad de G\u00e9nero de la C\u00e1mara de Diputados, con la colaboraci\u00f3n de la Fundaci\u00f3n Raquel Berman.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fueron reconocidas Nallely Guarneros, Norma Andrade y Natalia Lococo, con el primero, segundo y tercer lugar, respectivamente, por desaparici\u00f3n y feminicidio de un\/a familiar y violencia domestica. Tambi\u00e9n se reconoci\u00f3 en premio especial a las j\u00f3venes Brenda Joselyn Leonel, Rub\u00ed Coello y por violencia pol\u00edtica a Consuelo Valle, una de las v\u00edctimas de la Guerra Sucia entre 1950 y 190.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presidenta de la Comisi\u00f3n de Igualdad de G\u00e9nero, diputada morenista Julieta Kristal Vences Valencia, destac\u00f3 que se quiere reconocer a las mujeres que han transformado el dolor y sufrimiento, pero sobre todo a quienes rompieron el silencio. &nbsp;Consider\u00f3 que se requiere de trabajo y determinaci\u00f3n para ser agentes de cambio, y crear mejores condiciones para mujeres, ni\u00f1as y adolescentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Raquel Berman presente en la premiaci\u00f3n y luego de haber creado esta distinci\u00f3n desde hace siete a\u00f1os, narr\u00f3 que se ha se recibieron &nbsp;&nbsp;m\u00e1s de dos mil 500 relatos y solamente la tercera parte mostraron signos de resiliencia que se tradujeron en alg\u00fan grado de transformaci\u00f3n personal y en conductas en beneficio de otras mujeres. Este porcentaje, agreg\u00f3, \u201cnos ha producido j\u00fabilo, admiraci\u00f3n y esperanza de que las cosas est\u00e1n cambiando para las mujeres en este pa\u00eds\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3 la importancia de leer y estudiar el resto de los relatos, a fin de conocer los motivos por los que la mayor\u00eda de las mujeres siguen a expensas del machismo. \u201cNo debemos condenar a las mujeres a\u00fan encadenadas al patriarcado, no debemos culparlas, sino entenderlas como v\u00edctimas de un sistema familiar y social que las volvi\u00f3 impotentes\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La psicoanalista Raquel Berman indic\u00f3 que en esta traves\u00eda y promoci\u00f3n de siete a\u00f1os qued\u00f3 claro que la justicia legal para las mujeres debe ser un problema de Estado, y dijo que por los relatos se sabe que con frecuencia se trata de incesto infantil, violencia sexual a ni\u00f1as y adolescentes en la familia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bertha Elnora Jim\u00e9nez, directora de la Asociaci\u00f3n Mexicana para la Pr\u00e1ctica, Investigaci\u00f3n y Ense\u00f1anza del Psicoan\u00e1lisis (AMPIEP), refiri\u00f3 que el reconocimiento de la mujer resiliente visualiza un problema de violencia estructural contra las mujeres en la sociedad. Premiarlas por su capacidad de transformaci\u00f3n interna y recuperarse del trauma, as\u00ed como participar activamente en la sociedad en favor de otras mujeres, &nbsp;se vuelve fundamental.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De las galardonadas destac\u00f3 el reconocimiento especial quien enfrent\u00f3 violencia pol\u00edtica durante la Guerra Sucia entre 1950 y 1990, Consuelo Valle, quien dijo es un reconocimiento\u201d a las mujeres de mi generaci\u00f3n que dieron su vida, sus hijos y su estabilidad emotiva por un pa\u00eds libre de violencia\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed como premio juvenil a Rub\u00ed Coello quien pidi\u00f3 que haya traductores ind\u00edgenas en la impartici\u00f3n de justicia y fiscal\u00edas especializadas para la violencia que sufren las mujeres ind\u00edgenas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nelly Guarneros se convirti\u00f3 en buscadora de justicia y verdad cuando desapareci\u00f3 su esposo el 16 de julio de 2019. Norma Andrade sigue en busca de justicia por el feminicidio de su hija en Ciudad Ju\u00e1rez, y Natalia Lococo quien sufri\u00f3 todo tipo de agresiones por su pareja y al denunciar fue violentada institucionalmente. Ella tiene una d\u00e9cada defendiendo derechos humanos desde su asociaci\u00f3n \u201cAyuda Humanitaria\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ganadora del premio juvenil, Brenda Joselyn Leonel, dijo estar honrada de ser galardonada, pero \u201cme siento indignada por las impunidades, aunque tambi\u00e9n muy inspirada por mujeres valientes, fuertes, poderosas e imparables\u201d.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La secretaria general de la C\u00e1mara de Diputados, Graciela B\u00e1ez Ric\u00e1rdez, felicit\u00f3 a las ganadoras y extern\u00f3 su reconocimiento a Raquel Berman y a la diputada Julieta Vences, por hacer posible la promoci\u00f3n y entrega de este reconocimiento y expres\u00f3 su deseo de que cada a\u00f1o se realice esta premiaci\u00f3n.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La justicia para las mujeres debe ser un asunto de Estado: Raquel Berman<\/p>\n","protected":false},"author":3,"featured_media":68777,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[50],"tags":[],"class_list":["post-68776","post","type-post","status-publish","format-standard","has-post-thumbnail","category-congreso"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/68776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=68776"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/68776\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/68777"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=68776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=68776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=68776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}