{"id":68753,"date":"2023-07-12T08:20:30","date_gmt":"2023-07-12T13:20:30","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=68753"},"modified":"2023-07-12T08:20:31","modified_gmt":"2023-07-12T13:20:31","slug":"mirada-violeta-instituto-nacional-de-transparencia-acceso-a-la-informacion-y-proteccion-de-datos-personales-inai","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/mirada-violeta-instituto-nacional-de-transparencia-acceso-a-la-informacion-y-proteccion-de-datos-personales-inai\/","title":{"rendered":"Mirada Violeta| Instituto Nacional de Transparencia, Acceso a la Informaci\u00f3n y Protecci\u00f3n de Datos Personales (INAI)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Guadalupe Ramos Ponce<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Guadalajara, Jalisco, 12 de julio, 2023.- En pr\u00f3ximos d\u00edas, en el pleno de la Suprema Corte de Justicia de la Naci\u00f3n (SCJN), se discutir\u00e1 sobre la omisi\u00f3n del Senado de la Rep\u00fablica de designar a tres integrantes del pleno del Instituto Nacional de Transparencia, Acceso a la Informaci\u00f3n y Protecci\u00f3n de Datos Personales (INAI). Diversas organizaciones y personas, dieron a conocer un posicionamiento p\u00fablico, en el que hacen un llamado contundente a las y los ministros de la SCJN a votar a favor del derecho humano a saber.&nbsp;Manifiestan tambi\u00e9n su inconformidad con el proyecto de sentencia de la ministra ponente Loretta Ortiz, ya que seg\u00fan se\u00f1alan, representa un retroceso democr\u00e1tico y vulnera los derechos de acceso a la informaci\u00f3n y protecci\u00f3n de datos personales.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo al pronunciamiento, el Senado de la Rep\u00fablica ha sido omiso en su obligaci\u00f3n constitucional de designar a las tres personas comisionadas faltantes para integrar el Pleno del INAI, dos de ellas desde hace 466 d\u00edas y 101 d\u00edas para la tercera vacante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las faltas del Senado y de la Comisi\u00f3n Permanente se suman al desacato de varias resoluciones judiciales que les han ordenado cumplir con esta responsabilidad, para que el \u00f3rgano garante aut\u00f3nomo del acceso a la informaci\u00f3n ejerza a cabalidad sus funciones y proteja el derecho a saber de la sociedad mexicana.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De ser aprobado el proyecto de sentencia de la ministra Loretta Ortiz, el INAI podr\u00eda quedar imposibilitado para llevar a cabo de manera plena sus facultades y competencias, entre las que se encuentran: expedir y vigilar el cumplimiento de legislaciones sobre transparencia, derecho a la informaci\u00f3n y datos personales; resolver los recursos de revisi\u00f3n que las personas presenten ante negativas de informaci\u00f3n; interponer acciones en contra de leyes que vulneren los derechos de acceso a la informaci\u00f3n y protecci\u00f3n de datos personales, todo lo cual puede acarrear afectaciones serias a los derechos humanos de la ciudadan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El contexto es grave, pues se registran m\u00faltiples estrategias de opacidad que limitan conocer el funcionamiento cotidiano del gobierno. El debilitamiento deliberado de un instituto central para eliminar la cultura del secreto del quehacer gubernamental tiene repercusiones directas en la vida de las personas. Cada minuto se toman decisiones que limitan el bienestar del pueblo, como negar y ocultar informaci\u00f3n que nos permitir\u00eda saber c\u00f3mo se ejercen los recursos p\u00fablicos que todas y todos pagamos o decisiones que nos afectan como sociedad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada d\u00eda que se sigue limitando el funcionamiento de un instituto que vigila la rendici\u00f3n de cuentas en temas de informaci\u00f3n se atenta con los logros de m\u00e1s de 20 a\u00f1os a favor de la transparencia que permite un mejor gobierno. A la fecha, el INAI ha informado de 6,764 recursos de revisi\u00f3n que no ha podido resolver por la falta de qu\u00f3rum legal, son 6,764 personas a las que se les est\u00e1 vulnerando su derecho y tambi\u00e9n es un agravio a la sociedad en su conjunto.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a las intervenciones del INAI hemos podido conocer m\u00e1s sobre violaciones graves a derechos humanos y casos de corrupci\u00f3n que las entidades de gobierno han querido ocultar. Por ejemplo, qu\u00e9 pas\u00f3 realmente en el caso de Tlatlaya y qu\u00e9 actores p\u00fablicos intervinieron; por qu\u00e9 no se han sancionado a las personas vinculadas con el esc\u00e1ndalo de corrupci\u00f3n de la Estafa Maestra y qu\u00e9 no est\u00e1 haciendo el gobierno para evitar la repetici\u00f3n de estos casos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El INAI es una pieza clave para conocer decisiones p\u00fablicas que son parte de nuestra vida cotidiana, como por qu\u00e9 las instituciones de salud no entregan historiales cl\u00ednicos o en qu\u00e9 condiciones se encuentran las compras de medicamentos que requerimos, por qu\u00e9 hay personas que no han recibido sus pensiones y dem\u00e1s informaci\u00f3n p\u00fablica que no ha sido resuelta en estos 101 d\u00edas porque el INAI no ha podido intervenir debido a que no tiene qu\u00f3rum legal.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin duda, se hace necesario hoy m\u00e1s que nunca, garantizar la protecci\u00f3n de los derechos de acceso a la informaci\u00f3n y protecci\u00f3n de datos personales a partir de una valoraci\u00f3n desde el marco de los derechos humanos y los est\u00e1ndares m\u00e1s altos de protecci\u00f3n.&nbsp;Como se hace necesario tambi\u00e9n, fortalecer el Instituto Nacional de Transparencia, Acceso a la Informaci\u00f3n y Protecci\u00f3n de Datos Personales (INAI) y se garantice el nombramiento de las personas comisionadas faltantes para integrar el Pleno del INAI.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En pr\u00f3ximos d\u00edas, en el pleno de la Suprema Corte de Justicia de la Naci\u00f3n (SCJN), se discutir\u00e1 sobre la omisi\u00f3n del Senado de la Rep\u00fablica de designar a tres integrantes del pleno del Instituto Nacional de Transparencia, Acceso a la Informaci\u00f3n y Protecci\u00f3n de Datos Personales (INAI). <\/p>\n","protected":false},"author":3,"featured_media":8967,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[91,35],"tags":[],"class_list":["post-68753","post","type-post","status-publish","format-standard","has-post-thumbnail","category-lupita-ramos-ponce","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/68753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=68753"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/68753\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/8967"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=68753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=68753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=68753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}