{"id":6836,"date":"2019-02-19T16:41:13","date_gmt":"2019-02-19T16:41:13","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=6836"},"modified":"2023-07-21T14:47:08","modified_gmt":"2023-07-21T19:47:08","slug":"la-nueva-mafia-del-poder","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/la-nueva-mafia-del-poder\/","title":{"rendered":"La nueva mafia del poder"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Andr\u00e9s Manuel no es un presidente que respete al estado laico que es el mexicano.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"> \u00bfGuardia Nacional? La que quiera y como quiera se\u00f1orpresidenteustedordena.<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/semmexico.com\/gallery-post.php?id=7273#\">Mois\u00e9s S\u00e1nchez<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. Cd. de M\u00e9xico. 19 de febrero de 2019.- Te quito para ponerme, es la m\u00e1xima de quien se hace del poder por el poder mismo y en el trayecto ajusta cuentas y proyecta ambiciones, persigue pillos y apenas encarcela a carteristas de poca monta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfGuardia Nacional? La que quiera y como quiera se\u00f1orpresidenteustedordena. Y las indicaciones son \u00f3rdenes a cumplirse al pie de la letra aun cuando se arriesga el honor propio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfReforma al art\u00edculo 19 constitucional para aplicar la prisi\u00f3n preventiva oficiosa a todo lo que parezca un delito, aunque se violen los derechos elementales? Como ustedordenese\u00f1orpresidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQuitarle a Pemex todo elemento de empresa productiva del Estado para darle m\u00e1ximo poder al director general que de petroqu\u00edmica y elementos de hidrocarburos sabe lo que usted y yo de f\u00edsica nuclear? Adelante, adelante, se trata de un amigazo del se\u00f1orpresidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfContrarreforma educativa? D\u00e9mosles gusto a estos profesores de la oposici\u00f3n, estos mariscales de la Coordinadora Nacional de Trabajadores de la Educaci\u00f3n que, por as\u00ed convenir a sus intereses, pasaron por encima incluso de su amigo benefactor Andr\u00e9s Manuel L\u00f3pez Obrador y desmadraron al sistema econ\u00f3mico que usa a los ferrocarriles de los puertos de L\u00e1zaro C\u00e1rdenas, Michoac\u00e1n, y Manzanillo, Colima. \u00a1Faltaba m\u00e1s, faltaba menos!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y, vaya, \u00bfqu\u00e9 no fue bandera del licenciado L\u00f3pez Obrador en campa\u00f1a echar abajo a la que calific\u00f3 \u201cmal llamada Reforma Educativa\u201d? Al jefe de jefes lo que diga, porque para eso es Presidente de la Rep\u00fablica y me canso ganso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Ah!, pero se\u00f1oras y se\u00f1ores, todo este proceso legislativo se hace mediante el llamado Parlamento abierto en el que s\u00f3lo llegan a desahogar propuestas invitados de todos lados, lo mismo acad\u00e9micos que expertos en la materia, docentes universitarios, investigadores, luchadores sociales, legisladores de la oposici\u00f3n y etc\u00e9tera porque al final nadie los tomar\u00e1 en cuenta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed, con ese desprecio por el que piensa diferente, pero sabe mucho de la materia en comento, del fondo de una reforma constitucional, fueron tomadas las participaciones de los expertos en las consultas p\u00fablicas dizque para enriquecer las minutas de la Guardia Nacional y la de la prisi\u00f3n preventiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Porque, finalmente se cumpli\u00f3 la previsi\u00f3n de Juan Carlos Romero Hicks, el coordinador de los diputados federales del PAN, cuando advirti\u00f3 el riesgo de que ese Parlamento abierto, la consulta p\u00fablica fuese s\u00f3lo una mascarada, el mecanismo para lavar la cara a la diputaci\u00f3n federal de Morena que, con todo y su mayor\u00eda de 258 legisladores, har\u00eda lo que le viniera en gana con tal de cumplir las indicaciones presidenciales y sacar adelante la reforma constitucional en materia de prisi\u00f3n preventiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Misma ruta seguida en el Senado de la Rep\u00fablica, donde a la bancada de Morena le import\u00f3 un pito que las bancadas del PAN y del PRI condicionaran votar la minuta de la Guardia Nacional, con cambios elementales que no tiendan a dejar en manos de la Sedena y del fuero militar un cuerpo que debe ser dirigido por un civil, porque debe atenderse a pie juntillas, sin chistar y con dedo alzado, la l\u00ednea tirada desde Palacio Nacional para que la Guardia Nacional viera la luz, as\u00ed fuera por ces\u00e1rea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfY la mafia del poder? Paulatinamente Andr\u00e9s Manuel L\u00f3pez Obrador ha relegado esa frase de su cotidiana homil\u00eda de prensa en Palacio Nacional. Porque, le dec\u00eda, ahora \u00e9l encabeza a la neo mafia del poder en los mejores t\u00e9rminos \u00e9ticos, honestos y sin cargo de conciencia, como ha presumido reiteradamente. \u00bfAlguien lo duda?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ser\u00e1 que tambi\u00e9n hace b\u00e1sica la m\u00e1xima de que si el Presidente se equivoca y se vuelve a equivocar porque para eso es el Presidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y nadie le reprocha, nadie le contradice, aunque Clara Torres le renunci\u00f3 al encargo del sistema de estancias infantiles de la llamada Secretar\u00eda de Bienestar, y eso no le gust\u00f3 nada. Tanto que ya dio la orden, acatada en todos sus t\u00e9rminos de que ni un centavo para organizaciones civiles que manejaban las estancias, no importa que le quite el negocio a sus cuates del PT, al que llam\u00f3 \u201corganizaci\u00f3n que nos ha acompa\u00f1ado\u201d para no darle un rasp\u00f3n a Beto Anaya y su se\u00f1ora esposa que fue acusada en 2017 de lavar cien millones de pesos destinados a los Centros de Desarrollo Infantil, que no son otros que estancias infantiles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfPor qu\u00e9? Porque ese grupo que lleg\u00f3 al poder con el respaldo de los 30 millones de votos que se depositaron en las urnas a favor de Andr\u00e9s Manuel L\u00f3pez Obrador act\u00faa como una mafia, en el desplante y despliegue de quien ha tomado el control de la plaza, una vez que ech\u00f3 a aquellos que reiteradamente acusan de ladrones, corruptos y todo tipo de etc\u00e9teras mas no se atreven a meter a prisi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese tenor dejan abierta la sospecha de la negociaci\u00f3n con quienes se fueron, el equipo de las grandes ligas de Enrique Pe\u00f1a Nieto y los herederos de las administraciones neoliberales \u2013las mismas que el Presidente acusa causantes de divorcios&#8211;, y dejan correr la especie y s\u00f3lo esa masa fan\u00e1tica en las redes sociales descalifica, injuria y estigmatiza en nombre del reverendo L\u00f3pez Obrador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y es que, usted tiene la \u00faltima palabra, Andr\u00e9s Manuel no es un presidente que respete al estado laico que es el mexicano. No, no. Enhiesta la Biblia advierte de los pecados en que incurren los mentirosos, aunque \u00e9l est\u00e1 en ese pecado como lo demostr\u00f3 el investigador del CIDE Alejandro Madrazo Lajous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En fin, se votar\u00e1n reformas, se pasar\u00e1 por encima de acuerdos legislativos. Morena y sus pr\u00f3ceres convertidos en heraldos de las buenas nuevas, de lo que imaginan apisonar el basamento de la 4T, ir\u00e1n en pos del Vellocino de Oro, sin percatarse o no querer percatarse de que entre esos 30 millones de ciudadanos que votaron por \u201cJuntos haremos historia\u201d, pueden dar un giro fundamental en el reacomodo de las fuerzas pol\u00edticas en la elecci\u00f3n intermedia de 2021, y la reelecci\u00f3n no ser\u00e1 generalizada en la C\u00e1mara de Diputados e incluso el se\u00f1orpresidente estar\u00e1 en el riesgo de ser relevado del mando, de ce\u00f1irse absolutamente al mandato constitucional. Aqu\u00ed la neo mafia del poder. Conste.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">sanchezlimon@gmail.com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.entresemana.mx\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.entresemana.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">@msanchezlimon<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Andr\u00e9s Manuel no es un presidente que respete al estado laico que es el mexicano. \u00bfGuardia Nacional? La que quiera y como quiera se\u00f1orpresidenteustedordena. Mois\u00e9s S\u00e1nchez SemM\u00e9xico. Cd. de M\u00e9xico. 19 de febrero de 2019.- Te quito para ponerme, es la m\u00e1xima de quien se hace del poder por el poder mismo y en el [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6811,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[690,83],"tags":[],"class_list":["post-6836","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-moises-sanchez-limon"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/6836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=6836"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/6836\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/6811"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=6836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=6836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=6836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}