{"id":6704,"date":"2018-12-06T04:19:00","date_gmt":"2018-12-06T04:19:00","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=6704"},"modified":"2023-07-21T14:34:43","modified_gmt":"2023-07-21T19:34:43","slug":"rafaga-5","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/rafaga-5\/","title":{"rendered":"R\u00e1faga"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Vapuleado el atlacomulquense y golpeados los dos panistas.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"> El inicio de una nueva forma de gobierno<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/semmexico.com\/gallery-post.php?id=6577#\">LA OPINI\u00d3N<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jorge Herrera Valenzuela<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, 6 diciembre 2018.- El escenario no pod\u00eda ser mejor. El momento preciso e irrepetible. Plet\u00f3rico en las partes bajas como en las altas. Cientos de mexicanos y decenas de invitados procedentes de pa\u00edses latinoamericanos, europeos, asi\u00e1ticos y de Medio Oriente. Por primera vez en nuestra Historia Patria, no era tan solo un cambio de Presidente de la Rep\u00fablica y s\u00ed el inicio de una nueva forma de gobierno, un estilo innovador que rompi\u00f3 las tradiciones y protocolos acostumbrados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ed, esa fue mi apreciaci\u00f3n del suceso que enmarc\u00f3 la solemne sesi\u00f3n del Congreso de la Uni\u00f3n, cuyo \u00fanico prop\u00f3sito fue el de que Andr\u00e9s Manuel L\u00f3pez Obrador recibiera la banda presidencial, despu\u00e9s ir al micr\u00f3fono y sumamente emocionado rindiera protesta de respetar y hacer respetar la Constituci\u00f3n Pol\u00edtica de los Estados Unidos Mexicanos. Enseguida un discurso, interrumpido varias ocasiones por el aplauso de la concurrencia, donde fue directo en cada punto que tocaba. Hizo un juicio objetivo de los gobiernos del pasado y reiter\u00f3 su batalla contra la corrupci\u00f3n y la impunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin hacer menci\u00f3n de Carlos Salinas de Gortari, impulsor de la pol\u00edtica neoliberal, el presidente L\u00f3pez Obrador sentenci\u00f3, con voz fuerte y mirando hacia el lunetario: \u201cEn el per\u00edodo neoliberal la corrupci\u00f3n se convirti\u00f3 en la principal funci\u00f3n del poder pol\u00edtico\u201d. Asegur\u00f3 el primer tabasque\u00f1o que es Presidente de M\u00e9xico: \u201cen las \u00faltimas tres d\u00e9cadas las m\u00e1ximas autoridades se han dedicado, como en el porfiriato, a concesionar el territorio y a transferir empresas y bienes p\u00fablicos e incluso funciones en el Estado a particulares nacionales y extranjeros\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00f3pez Obrador fue contundente al decir: \u201cMi postura, la defin\u00ed, con toda claridad, desde la campa\u00f1a. Dije que no es mi fuerte la venganza y que si bien no olvido, si soy partidario del perd\u00f3n y la indulgencia\u201d. Eso para despu\u00e9s insistir en que la nueva etapa se inicia sin perseguir a nadie, \u201cporque no apostamos al circo y a la simulaci\u00f3n\u201d. Precis\u00f3 que no buscar\u00e1 \u201cchivos expiatorios\u201d y que no habr\u00eda juzgados ni c\u00e1rceles suficientes para meter en prisi\u00f3n empezando \u201cpor los de mero arriba, tanto del sector p\u00fablico como del sector privado\u201d. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Duras cr\u00edticas a expresidentes<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00f3pez Obrador no dej\u00f3 t\u00edtere con cabeza. Fue directo contra el neoliberalismo que comenz\u00f3 a la mitad del sexenio del colimense Miguel de la Madrid, quien, influenciado por su secretario de Programaci\u00f3n y Presupuesto junto con el extranjero Jos\u00e9 Mar\u00eda C\u00f3rdoba Montoya, hizo que M\u00e9xico entrara en crisis, esto debido al \u201cfracaso del modelo econ\u00f3mico neoliberal\u201d y al predominio \u201cde la m\u00e1s inmunda corrupci\u00f3n p\u00fablica y privada\u201d.&nbsp; A\u00f1adi\u00f3 que \u201cnada ha da\u00f1ado m\u00e1s a M\u00e9xico que la deshonestidad de los gobernantes y de la peque\u00f1a minor\u00eda que ha lucrado con el influyentismo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Presidente n\u00famero 65 de nuestra Rep\u00fablica federal, popular y representativa, abri\u00f3 un par\u00e9ntesis de su severa cr\u00edtica a los gobiernos del pasado, cuando expres\u00f3 que \u201cen dos sexenios consecutivos, de 1958 a 1970, cuando fue Ministro de Hacienda Antonio Ortiz Mena, la econom\u00eda del pa\u00eds no solo creci\u00f3 al 6 por ciento anual, sino que este avance se obtuvo sin inflaci\u00f3n y sin incremento de la deuda p\u00fablica. Por cierto, Ortiz Mena no era economista, sino abogado\u201d. Cierto en su apreciaci\u00f3n fue con los presidentes Adolfo L\u00f3pez Mateos y Gustavo D\u00edaz cuando M\u00e9xico fue autosuficiente alimentariamente, se produjo la zafra m\u00e1s alta, a nivel mundial, y export\u00e1bamos ma\u00edz, arroz, trigo, az\u00facar, frutas y legumbres. Hoy, somos importadores de casi todo eso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Prosigui\u00f3 el tabasque\u00f1o en su cr\u00edtica anal\u00edtica contra el neoliberalismo que propici\u00f3 la inflaci\u00f3n y el endeudamiento mayor, as\u00ed como que los mexicanos emigraran masivamente del territorio nacional, buscaran la vida en el trabajo informal o tomando el camino de conductas antisociales. Han sido 36 a\u00f1os de ese sufrimiento del pueblo mexicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Vicente Fox y a Felipe Calder\u00f3n, mencionados por sus apellidos paternos, los calific\u00f3 como derrochadores del cuantioso ingreso que se tuvo por la venta de petr\u00f3leo al extranjero. \u201cTodo se derroch\u00f3 o se fue por el ca\u00f1o de la corrupci\u00f3n\u201d. Obvio, los dos expresidentes PANistas no recibieron invitaci\u00f3n para asistir a la transici\u00f3n presidencial. Con Fox la deuda p\u00fablica era de 1.7 billones y Calder\u00f3n la dej\u00f3 en 5.2 billones y el saldo al t\u00e9rmino del sexenio de Pe\u00f1a Nieto, es de \u00a1Diez Billones!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pe\u00f1a Nieto solamente frunci\u00f3 el ce\u00f1o, pero m\u00e1s fuerte recibi\u00f3 el golpe, seco dir\u00edan los jugadores de ruleta, cuando escuch\u00f3 una frase de siete palabras, dichas por su sucesor: \u201cSe cancelar\u00e1 la mal llamada Reforma Educativa\u201d. Minutos antes L\u00f3pez Obrador manifest\u00f3 que cuando se habl\u00f3 de la Reforma Energ\u00e9tica \u201cnos dijeron que vendr\u00eda a salvarnos (y eso) solo ha significado la ca\u00edda de la producci\u00f3n de petr\u00f3leo y el aumento desmedido en los precios de las gasolinas, el di\u00e9sel, el gas y la electricidad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSomos la Naci\u00f3n que m\u00e1s importa ma\u00edz en el mundo. Antes del neoliberalismo, produc\u00edamos y \u00e9ramos autosuficientes en gasolinas, di\u00e9sel, gas, energ\u00eda el\u00e9ctrica, ahora compramos m\u00e1s de la mitad de lo que consumimos, de estos insumos\u201d, dijo en otra parte de su discurso de toma de posesi\u00f3n, este s\u00e1bado 1 de diciembre de 2018. Seguramente Pe\u00f1a Nieto, para esos momentos, ya no agradecer\u00eda las palabras que el tabasque\u00f1o le dedic\u00f3 al inicio del discurso: \u201cLicenciado Enrique Pe\u00f1a Nieto, le agradezco sus atenciones, pero sobre todo le reconozco el hecho de no haber intervenido, como lo hicieron otros presidentes, en las pasadas elecciones presidenciales\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pregunta para meditar:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfLos cuatro expresidentes referidos en el texto del discurso, seguramente prefieren mantenerse en absoluto silencio, o har\u00e1n alguna declaraci\u00f3n personal o indirectamente?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">jherrerav@live.com.mx<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vapuleado el atlacomulquense y golpeados los dos panistas. El inicio de una nueva forma de gobierno LA OPINI\u00d3N Jorge Herrera Valenzuela SemM\u00e9xico, 6 diciembre 2018.- El escenario no pod\u00eda ser mejor. El momento preciso e irrepetible. Plet\u00f3rico en las partes bajas como en las altas. Cientos de mexicanos y decenas de invitados procedentes de pa\u00edses [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6705,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[689,82],"tags":[],"class_list":["post-6704","post","type-post","status-publish","format-standard","has-post-thumbnail","category-689","category-la-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/6704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=6704"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/6704\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/6705"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=6704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=6704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=6704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}