{"id":64613,"date":"2023-03-20T10:51:46","date_gmt":"2023-03-20T16:51:46","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=64613"},"modified":"2023-03-20T10:51:53","modified_gmt":"2023-03-20T16:51:53","slug":"miradas-de-reportero-nueve-universidades-proponen-tres-cajas-de-herramientas-para-profesionalizar-periodistas","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/miradas-de-reportero-nueve-universidades-proponen-tres-cajas-de-herramientas-para-profesionalizar-periodistas\/","title":{"rendered":"Miradas de Reportero| Nueve universidades proponen tres cajas de herramientas para profesionalizar periodistas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Rogelio Hern\u00e1ndez L\u00f3pez<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 20 de marzo del 2023.- S\u00ed, es noticia muy buena para periodistas esenciales que quieren mejorar su quehacer cotidiano; lo es tambi\u00e9n para demostrar que desde la academia se pueden hacer aportes concretos para profesionalizar la practica period\u00edstica y, sobre todo, es un hecho confirmatorio de que el periodismo es una profesi\u00f3n que requiere utilizar metodolog\u00edas cient\u00edficas y diluir la percepci\u00f3n muy extendida de que es un mero oficio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El martes 21 de febrero, durante la Sexta Semana de Periodismo en Hidalgo se difundi\u00f3 una nota breve en Facebook que dec\u00eda: <em>\u201c\u00a1Atenci\u00f3n colegas! Se present\u00f3 un libro, como una caja de herramientas (metodolog\u00edas y t\u00e9cnicas) para hacer periodismo\u201d.<\/em> De inmediato comenzaron a acumularse 52 reacciones de periodistas de varias entidades del pa\u00eds, 21 de \u00e9stas ped\u00edan datos de d\u00f3nde conseguir el libro. S\u00ed era noticia de inter\u00e9s para colegas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La noticia mejor\u00f3. Se pidieron m\u00e1s datos de esa <em>Caja de Herramientas<\/em> a Elvira Hern\u00e1ndez Carballido (una de las coordinadoras) y ella informa que no es un solo libro, que ser\u00e1n tres y que dos de ellos ya se pueden conseguir impresos o en formato digital.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La academia s\u00ed puede ayudar<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los tres tomos incluyen ensayos de mujeres y hombres que hicieron reporterismo y que hoy imparten clases y realizan investigaciones acad\u00e9micas en nueve universidades p\u00fablicas: la Universidad Nacional Aut\u00f3noma de M\u00e9xico y las de Aguascalientes, Chiapas, Colima, del Estado de M\u00e9xico, Guadalajara, Hidalgo, la Metropolitana y la de Nuevo Le\u00f3n. Eso es la mejor parte de la noticia buena.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Informan que lograron reunirse y analizar que desde los estudios (acad\u00e9micos) de periodismo se debe hacer un compromiso con su profesionalizaci\u00f3n;&nbsp; que en consecuencia acordaron \u201ccompartir t\u00e9cnicas, m\u00e9todos y estrategias que reafirmen la importancia de informar a la sociedad de este siglo XXI\u201d. Resolvieron llamar al conjunto de textos <em>Caja de Herramientas<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer tomo tiene como subtitulo<em>: \u201cReflexiones metodol\u00f3gicas desde las ciencias sociales\u201d<\/em>. \u00c9ste lo presentaron en Hidalgo, durante la Semana de Periodismo, Elvira Hern\u00e1ndez Carballido, Alma Elena Guti\u00e9rrez y Arnoldo Delgadillo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El segundo tomo, ya tambi\u00e9n en circulaci\u00f3n, tiene como eje: <em>metodolog\u00edas para hacer periodismo<\/em> y el tercero ya est\u00e1 en preparaci\u00f3n y lo coordina Elvira Hern\u00e1ndez desde la Universidad Aut\u00f3noma del Estado de Hidalgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elvira comenta que todos representan \u201cun esfuerzo por hacer un puente entre la academia y el ejercicio period\u00edstico, en bien de nuestros estudiantes y los planes de estudio de las universidades. Queremos un mejor periodismo en M\u00e9xico. Este a\u00f1o planeamos el tercer tomo y me toca coordinarlo a m\u00ed\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Es profesi\u00f3n, no oficio<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El primer tomo alberga 7 ensayos. En el inicial, el doctor Vicente Castellanos Cerda, de la Universidad Aut\u00f3noma Metropolitana Unidad Cuajimalpa, lo titul\u00f3: <em>El valor de la teor\u00eda y la metodolog\u00eda en el periodismo de investigaci\u00f3n<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Castellanos explica ampliamente las dos \u00e1reas del periodismo, la del &nbsp;oficio \u201cdonde el periodista se hace en el d\u00eda a d\u00eda, y el de la formaci\u00f3n, donde el periodista adquiere en la universidad aprendizajes de campo, as\u00ed como aspectos contextuales, conceptuales y filos\u00f3ficos.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los otros ensayos de ese primer tomo son:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>El periodismo como m\u00e9todo de interpretaci\u00f3n de la realidad social <\/em>elaborado por Arnoldo Delgadillo Grajeda y Aide\u00e9 Arellano Ceballos de la Universidad de Colima;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>El m\u00e9todo del periodismo feminista. Una reconstrucci\u00f3n hist\u00f3rica que traza el ejercicio period\u00edstico de las mujeres mexicanas en la prensa<\/em> de Elvira Hern\u00e1ndez y Alejandra Araiza de la Universidad de Hidalgo;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2023\/03\/Imagen1-10.jpg\"><img decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2023\/03\/Imagen1-10-1016x1024.jpg\" alt=\"\" class=\"wp-image-64614\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El tercer ensayo de Salvador de Le\u00f3n V\u00e1zquez de la Aut\u00f3noma de Aguascalientes es novedoso en su propuesta de consejos pr\u00e1cticos para <em>Aprovechar la etnograf\u00eda para hacer periodismo de investigaci\u00f3n<\/em>:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De Le\u00f3n refiere que un buen etn\u00f3grafo debe ir a los sitios, volver con informaci\u00f3n sobre la gente que vive all\u00ed, y poner dicha informaci\u00f3n a disposici\u00f3n de la comunidad profesional de un modo pr\u00e1ctico; si en esa cita sustituy\u00e9ramos las palabras \u201cetn\u00f3grafo\u201d por \u201cperiodista\u201d y \u201ccomunidad profesional\u201d por \u201cciudadan\u00eda\u201d, la sentencia tendr\u00eda completo sentido para vincular m\u00e9todos y t\u00e9cnicas para informar, valora el acad\u00e9mico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agrega: \u201cMuchos periodistas de nuestro pa\u00eds son etn\u00f3grafos pr\u00e1cticos, aunque no lo sepan. Hay periodistas que atraviesan el pa\u00eds acompa\u00f1ando a los migrantes centroamericanos\u2026 Tambi\u00e9n hay los que acuden a las comunidades que viven problemas graves como el despojo por parte de las empresas transnacionales\u2026 entre otras cosas. Y se dan a la tarea de convivir con ellos y ellas, sufrir con ellos\/as.\u201d<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ejemplos de profesionalidad<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El resto de los ensayos contienen varios ejemplos de trabajos de periodistas profesionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre <em>La autoetnograf\u00eda en el ejercicio period\u00edstico<\/em> de Alma Elena Guti\u00e9rrez Leyt\u00f3n de la Universidad Aut\u00f3noma de Nuevo Le\u00f3n; <em>Pautas para escribir relatos period\u00edsticos<\/em> de Francisca Robles de Universidad Nacional Aut\u00f3noma de M\u00e9xico; y <em>Periodismo colaborativo, recuperaci\u00f3n de una apuesta metodol\u00f3gica en investigaci\u00f3n <\/em>de Sarelly Mart\u00ednez Mendoza y Diego Noel Ramos Rojas de las universidades p\u00fablicas de Chiapas y de Guadalajara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El segundo tomo tiene, como ejes, ejemplos de la pr\u00e1ctica profesional y de las metodolog\u00edas \u00fatiles para el periodismo. Incluye los temas:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Adaptaci\u00f3n de las t\u00e9cnicas de investigaci\u00f3n de la metodolog\u00eda de las Ciencias Sociales a la metodolog\u00eda del periodismo de investigaci\u00f3n; Definiciones del fotoperiodismo de nota roja; Las mujeres presentes al escribir historia del periodismo; La voz femenina en el periodismo deportivo en el Valle de Toluca. Pasi\u00f3n y deporte bajo la lupa de las mujeres<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y como peque\u00f1os manuales, propone las gu\u00edas metodol\u00f3gicas: <em>La entrevista como g\u00e9nero period\u00edstico y t\u00e9cnica de investigaci\u00f3n cualitativa; Aportes para el periodismo de investigaci\u00f3n; Los ojos profundos del periodismo ambiental; Fuentes de informaci\u00f3n y perfil del periodista<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En conversaci\u00f3n con la doctora Elvira Hern\u00e1ndez Carballido se le pidi\u00f3 el sitio web o plataforma digital a la que deban dirigirse los interesados para comprar los dos primeros libros en formato digital o impresos, que no los regalen. Corramos la noticia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tomo uno se puede comprar en la editorial: <a href=\"mailto:direcciongelementum@gmail.com\">direcciongelementum@gmail.com<\/a>; y el n\u00famero dos se adquiere en Amazon <a href=\"https:\/\/www.amazon.com.mx\/Caja-herramientas-Reflexiones-metodolog%C3%ADas-periodismo-ebook\/dp\/B0BTB4QS98\/ref=sr_1_2?__mk_es_MX=%C3%85M%C3%85%C5%BD%C3%95%C3%91&amp;crid=1AFT9WIYWR450&amp;keywords=arnoldo+delgadillo&amp;qid=1675099360&amp;sprefix=arnoldo+delgadi%2Caps%2C350&amp;sr=8-2\">https:\/\/www.amazon.com.mx\/Caja-herramientas-Reflexiones-metodolog%C3%ADas-periodismo-ebook\/dp\/B0BTB4QS98\/ref=sr_1_2?__mk_es_MX=%C3%85M%C3%85%C5%BD%C3%95%C3%91&amp;crid=1AFT9WIYWR450&amp;keywords=arnoldo+delgadillo&amp;qid=1675099360&amp;sprefix=arnoldo+delgadi%2Caps%2C350&amp;sr=8-2<\/a>&gt;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Los aportes<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El aporte mayor de los ensayos en los tres libros no es solo para periodistas: demasiados pol\u00edticos\/as y funcionarios\/as todav\u00eda dicen que el periodismo es un oficio y se niegan a reconocer que es una profesi\u00f3n del mayor inter\u00e9s p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Son muchas personas que trabajan en el medio o estudian periodismo que solo conocen los anacr\u00f3nicos manuales de periodismo del siglo pasado, que insisten en que este es un oficio y que la academia solo ense\u00f1a teor\u00edas y no prepara para la pr\u00e1ctica. Y hay muchas otras personas que se dicen periodistas porque plagian informaci\u00f3n y la deforman al convertirla en comentarios sensacionalistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Peor a\u00fan, es posible probar que son demasiados los y las colegas que se subestiman por la creencia de que practican un oficio y por eso aceptan los maltratos laborales, profesionales y hasta personales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por todo, insisto en que la aparici\u00f3n del primer libro de la <em>Caja de Herramientas<\/em> s\u00ed es noticia muy buena para las y los periodistas esenciales (son quienes hacen reporterismo en la calle, en las fuentes y no solo plagian trabajo de otros para ganar vistas en sus redes sociales o hacer comentarios sin sustento).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esos tres libros muestran tambi\u00e9n lo que deber\u00eda ser una buena pr\u00e1ctica de las escuelas de comunicaci\u00f3n y periodismo: vincularse con el ejercicio cotidiano y ayudar a la capacitaci\u00f3n continua de las y los trabajadores del periodismo, coadyuvar a profesionalizar a tantos que se arriesgan con malas pr\u00e1cticas por impreparaci\u00f3n. Mirada de reportero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> S\u00ed, es noticia muy buena para periodistas esenciales que quieren mejorar su quehacer cotidiano; lo es tambi\u00e9n para demostrar que desde la academia se pueden hacer aportes concretos para profesionalizar la practica period\u00edstica <\/p>\n","protected":false},"author":3,"featured_media":38348,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[106,35,85],"tags":[],"class_list":["post-64613","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mirada-de-reportero","category-opinion","category-rogelio-hernandez-lopez"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/64613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=64613"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/64613\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/38348"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=64613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=64613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=64613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}