{"id":62362,"date":"2023-02-05T10:38:17","date_gmt":"2023-02-05T16:38:17","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=62362"},"modified":"2023-02-05T10:50:15","modified_gmt":"2023-02-05T16:50:15","slug":"pacifista-defensora-de-la-democracia-con-las-mujeres-contra-un-territorio-banado-en-sangre-rabia-e-impotencia","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/pacifista-defensora-de-la-democracia-con-las-mujeres-contra-un-territorio-banado-en-sangre-rabia-e-impotencia\/","title":{"rendered":"Pacifista, defensora de la democracia, con las mujeres contra un territorio, ba\u00f1ado en sangre, rabia e impotencia."},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2023\/02\/hermila-galindo-02.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"369\" height=\"566\" data-id=\"62366\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2023\/02\/hermila-galindo-02.jpg\" alt=\"\" class=\"wp-image-62366\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2023\/02\/hermila-galindo-03.png\"><img loading=\"lazy\" decoding=\"async\" width=\"156\" height=\"228\" data-id=\"62367\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2023\/02\/hermila-galindo-03.png\" alt=\"\" class=\"wp-image-62367\"\/><\/a><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En el 5 de febrero recordarla como constitucionalista y primera congresista en M\u00e9xico: Hermila Galindo Acota<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Del voto libre y la ley para las mujeres, reivindic\u00f3 la libertad del cuerpo y las decisiones aut\u00f3nomas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">He aqu\u00ed un recordatorio, de d\u00f3nde venimos y que nos toca<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong><em>La esfera de la mujer est\u00e1 en todas partes, porque la mujer representa m\u00e1s de la mitad del g\u00e9nero humano, y su vida est\u00e1 \u00edntimamente ligada a la de la otra mitad. Los intereses de las mujeres y de los hombres no pueden separarse. La esfera de la mujer est\u00e1, por lo tanto, dondequiera que est\u00e9 la del hombre; es decir, en el mundo entero.<\/em><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong><em>Las leyes que rigen y regulan los contratos de matrimonio, los derechos de los c\u00f3nyuges, la patria potestad, est\u00e1n hechas por hombres, y son evidentemente injustas. \u00bfPor qu\u00e9 la mujer no ha de intervenir en la elaboraci\u00f3n de las leyes que deciden la parte m\u00e1s importante de su vida? Hermila Galindo Acosta, 1917<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sara Lovera y Ana Ma. Portugal*<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 5 de febrero, 2023.- Hermila Galindo Acosta y una potente generaci\u00f3n de mujeres, protagonistas de la Revoluci\u00f3n Mexicana, so\u00f1aron en una rep\u00fablica justa y democr\u00e1tica. Hermila se defini\u00f3 constitucionalista desde 1916, fue&nbsp;&nbsp; pacifista y defensora de la democracia; puso en el centro a las mujeres que dejaron en los campos de batalla su sangre, su energ\u00eda, los cad\u00e1veres de sus hombres, de sus hijos e hijas, la mism\u00edsima situaci\u00f3n que estamos viviendo en esta ahora de nuestra naci\u00f3n, un territorio, ba\u00f1ado en sangre, rabia e impotencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A los 106 a\u00f1os de la Constituci\u00f3n Pol\u00edtica de los Estados Unidos Mexicanos. Ley Suprema del sistema jur\u00eddico mexicano, promulgada el 5 de febrero de 1917 por Venustiano Carranza en el Teatro de la Rep\u00fablica de la ciudad de Quer\u00e9taro, es necesario que hablar de Hermila Galindo Acosta, sin romanticismo y con valor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ella a sus 20 a\u00f1os, convencida, comprometida, feminista y constitucionalista fue capaz de decir a Venustiano Carranza, que la revoluci\u00f3n -1917-1921- que \u00e9sta ser\u00eda totalmente in\u00fatil si no ofrec\u00eda un lugar humano y pol\u00edtico a las mujeres; lo convenci\u00f3 sobre la necesidad de decretar el divorcio civil; logr\u00f3 orillar al jefe de la revoluci\u00f3n, para que fuera su c\u00f3mplice en la tarea de difundir el feminismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ella fue constructora, de lo que la historiadora Gabriela Cano, llama el feminismo constitucionalista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Viaj\u00f3 por todo el pa\u00eds hablando a las mujeres de su dignidad, de sus derechos, soliviant\u00e1ndolas a defender para ellas, como Olimpia de Gauges, las ventajas de participar y hacer pol\u00edtica, explic\u00e1ndoles todo acerca de la importancia de la naci\u00f3n renovada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sac\u00e1ndolas del ostracismo y la desesperanza que vivieron, despu\u00e9s de los duros episodios de la violencia armada, con todas las palabras que difund\u00eda su Revista La Mujer Moderna, una de car\u00e1cter pol\u00edtico\/feminista que edit\u00f3 mensualmente durante 3 a\u00f1os, (entre 1915 1918), con el deseo desbordante de que fueran capaces de defender a la Revoluci\u00f3n porque \u00e9sta promet\u00eda asegurarles todos sus derechos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su c\u00e9lebre discurso Mujeres del Porvenir, es un significativo antecedente para las mexicanas de la modernidad. Cuando lo escribi\u00f3 &nbsp;no sab\u00eda, que muy pronto, como lo cont\u00f3 Elena Garro en su espl\u00e9ndida novela Los Recuerdos del Porvenir, que la revoluci\u00f3n ser\u00eda traicionada y todas las fantas\u00edas de emancipaci\u00f3n femenina, tendr\u00edan que conseguirse en una inmensa zaga&nbsp; que nos ha significado ir arrancando lentamente, el derecho al voto, &nbsp;el derecho al aborto, el derecho al trabajo bien remunerado, el derecho a vivir sin miedo y el derecho a&nbsp; la libertad de elegir, el derecho a vivir una plena&nbsp; y placentera vida sexual, el derecho simplemente a&nbsp; estar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hermila fue una mujer moderna, que en su tiempo se nutr\u00eda del pensamiento de las l\u00edderes de Seneca Falls, de los empe\u00f1os Emma Goldman, y pas\u00f3 sus d\u00edas leyendo en la penumbra \u201cLa sujeci\u00f3n de la mujer\u201d del fil\u00f3sofo ingl\u00e9s John Stuart Mill (1869) y continu\u00f3 muchos a\u00f1os, hasta 1954, deshilvanando la doble moral sexual, la urgencia de tomar la voz, la necesidad de que todas las mujeres aprendieran de su dignidad y de sus derechos humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ella reivindica la persistencia, la necia terquedad de las feministas para que todas las mexicanas den la vuelta y miren nuestra maravillosa historia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ella, nosotras que batallamos por derribar un sistema, un gobierno, que alegremente ha condenado a miles de hombres y mujeres a tener hambre, a experimentar la persecuci\u00f3n y la tortura, a ponerse en riesgo todos los d\u00edas, como mis compa\u00f1eros compa\u00f1eras periodistas, a resistir la inaceptable violencia y encima a temer, porque en cada recodo del camino se puede hallar la muerte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y es que Hermila comprendi\u00f3 el sentido de la democracia, de la paz y de la vida equilibrada entre hombres y mujeres, como la \u00fanica salida que permitir\u00e1 a la humanidad continuar o exterminarse.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2023\/02\/hermila-galindo-04.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2023\/02\/hermila-galindo-04-693x1024.jpg\" alt=\"\" class=\"wp-image-62364\" width=\"449\" height=\"663\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">HERMILA GALINDO ACOSTA: CONSIDERADA LA PRIMERA CONGRESISTA DEL PA\u00cdS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maestra, revolucionaria y periodista. Naci\u00f3 en la ex hacienda de Avil\u00e9s de Villa Ju\u00e1rez, Lerdo, estado de Durango. En los registros parroquiales aparece inscrita como \u201chija natural\u201d y s\u00f3lo con el apellido materno. Su madre, Hermila Marcela Acosta muere a los tres d\u00edas de nacimiento de su hija. Su padre Rosario Galindo agricultor, estaba casado con Eulalia Vargas con quien no tuvo hijos, por esta raz\u00f3n y ante la orfandad de la reci\u00e9n nacida decide reconocer legalmente a Hermila como su hija, llev\u00e1ndola a vivir con \u00e9l. Como parece que su esposa no se mostr\u00f3 dispuesta a criar a Hermila como su hija, don Rosario encomend\u00f3 a su hermana \u00c1ngela, el cuidado de la ni\u00f1a solventando los gastos de su manutenci\u00f3n, y en 1891, le cede a su hermana, mediante escritura p\u00fablica, una casa de su propiedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;La t\u00eda \u00c1ngela ser\u00e1 considerada por Hermila como su segunda madre, por el cuidado y cari\u00f1o que siempre le brind\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando Hermila tuvo edad para estudiar, su padre la envi\u00f3 interna a una escuela primaria en Durango, y posteriormente a la Escuela Industrial para Se\u00f1oritas de Chihuahua. Esta Escuela, herencia del porfiriato, era uno de los pocos establecimientos modernos que a\u00fan quedaban. Las alumnas aprend\u00edan mecanograf\u00eda, taquigraf\u00eda, tenedur\u00eda de libros, ingl\u00e9s y gram\u00e1tica espa\u00f1ola.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hermila obtuvo el certificado de Telegraf\u00eda. Laura Orellana, destaca que el inter\u00e9s de don Rosario por la educaci\u00f3n de su hija no era frecuente en esa \u00e9poca, pues bastaba que las mujeres aprendieran a leer y escribir porque luego se casar\u00edan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero su padre ante la eventualidad de su fallecimiento, quiso asegurar el futuro de su hija mediante la educaci\u00f3n. Al quedar viudo don Rosario se produce un mayor acercamiento con Hermila, en ese per\u00edodo, \u00e9l constata que su hija tiene una inteligencia poco com\u00fan y que ama el estudio por lo que decide enviarla a Estados Unidos a estudiar qu\u00edmica, deseo que no pudo concretar al contraer nuevamente matrimonio, y fallecer al poco tiempo v\u00edctima de un accidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hermila vuelve a quedar hu\u00e9rfana. Tiene 16 a\u00f1os y a pesar de provenir de una familia que contaba con ciertos recursos econ\u00f3micos, sus parientes paternos no la tomaron en cuenta en la repartici\u00f3n de la herencia. Debe enfrentarse sola al mundo y sostener econ\u00f3micamente su hogar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La vida laboral de Hermila se inicia en 1908 dando clases particulares de mecanograf\u00eda y taquigraf\u00eda en Coahuila, luego, en Torre\u00f3n es profesora de varios colegios donde ofrece conferencias a sus alumnos fuera del horario de clases, sobre \u201cla necesidad de violentar la evoluci\u00f3n pol\u00edtica de la Rep\u00fablica\u201d (Orellana Trinidad, 2001).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s adelante, algunos de sus estudiantes, se incorporaron en el movimiento armado durante la Revoluci\u00f3n. Simult\u00e1neamente se emplea como mecan\u00f3grafa en bufetes de abogados, circunstancia que la acerca al mundo pol\u00edtico de ese momento. Dos a\u00f1os antes se hab\u00eda involucrado con un grupo de mujeres anti reeleccionistas integrantes del club \u201cLas admiradoras de Ju\u00e1rez\u201d que realizaba acciones contra el porfirismo. &nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 1909, en el Teatro Ricardo de la Vega de Torre\u00f3n se realiza un acto en conmemoraci\u00f3n de Benito Ju\u00e1rez. El orador principal, el abogado Francisco Mart\u00ednez, conocido por su antiporfirismo, se refiere en t\u00e9rminos duros al gobierno de D\u00edaz. En estas circunstancias, el alcalde proh\u00edbe la difusi\u00f3n del discurso del orador, pero Hermila ten\u00eda versi\u00f3n taquigr\u00e1fica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s tarde, un grupo de simpatizantes de la candidatura del gobernador de Nuevo Le\u00f3n, el general Bernardo Reyes (1840-1913) a las elecciones generales de 1910 por el Partido Democr\u00e1tico, organizan un mitin, de apoyo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enterados de los problemas que tuvo Francisco Mart\u00ednez y conocer que Hermila ten\u00eda la versi\u00f3n del discurso mencionado, la llaman para ped\u00edrselo, de esta forma el texto circul\u00f3 en Durango y Coahuila.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ese mismo a\u00f1o, Galindo regresa a Durango, su lugar natal. Llevaba cartas de recomendaci\u00f3n de los reeleccionistas de Torre\u00f3n. El abogado Carlos Patoni colaborador del secretario de Gobernaci\u00f3n, la emplea en su bufete donde destaca por la excelencia de su trabajo, de manera cuando dos a\u00f1os despu\u00e9s decide ir a la ciudad de M\u00e9xico, Patoni, da fe de la eficiencia de su trabajo, y del \u201centusiasmo por nuestra causa libertaria, discreci\u00f3n, habilidad y empe\u00f1o en su trabajo\u201d (Orellana Trinidad, 2001).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con este aval consigue un empleo como secretar\u00eda del general maderista Eduardo T. Hay (1877-1941) con quien trabaja hasta la ca\u00edda de Madero. En ese tiempo se relaciona con las mujeres maderistas del Club Feminista \u201cAntonia Nava\u201d. La cercan\u00eda a Eduardo Hay, connotado dirigente que fue Jefe del Estado Mayor de Madero en su primera campa\u00f1a y m\u00e1s tarde, en 1912, diputado federal, la sit\u00faa en un lugar de privilegio para conocer cercanamente los mecanismos del poder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 1914, el general Victoriano Huerta M\u00e1rquez (1850-1916) lidera un golpe de estado contra el gobierno de Francisco Madero quien poco despu\u00e9s es asesinado a igual que su vicepresidente Jos\u00e9 Mar\u00eda Pino Su\u00e1rez. Este hecho sume al pa\u00eds en una atm\u00f3sfera de confusi\u00f3n y violencia. Hermila pierde su trabajo y s\u00f3lo cuenta con los cursos de taquigraf\u00eda que ofrece en la Escuela Comercial Miguel Lerdo de Tejada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pa\u00eds nuevamente se prepara para nuevos enfrentamientos armados con un solo prop\u00f3sito, derrocar a Huerta. Se inicia la segunda etapa de la Revoluci\u00f3n Mexicana liderada por el general Venustiano Carranza (1859-1920) como Primer Jefe del Ej\u00e9rcito Constitucionalista, cargo legalmente suscrito en el Plan de Guadalupe que \u00e9ste lanz\u00f3 en 1913 con la convocatoria a luchar para derrocar al gobierno de facto.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2023\/02\/hermila-galindo-05.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"510\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2023\/02\/hermila-galindo-05.jpg\" alt=\"\" class=\"wp-image-62365\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Mujeres apoyan la Revoluci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las mujeres que apoyaron a Madero y\/o que est\u00e1n adheridas a las facciones de Francisco Villa (1876-1923) y Emiliano Zapata (1879-1919), nuevamente se movilizan, reorganizando los clubes femeniles para las tareas de espionaje, producci\u00f3n y difusi\u00f3n de panfletos, concentraci\u00f3n de informaci\u00f3n sobre las acciones armadas de los enemigos, intercambio de correspondencia y transporte de armas y municiones. Muchas fueron objeto de represalias, persecuci\u00f3n y c\u00e1rcel. En julio de 1914, Victoriano Huerta derrotado presenta su dimisi\u00f3n, huyendo a Estados Unidos. Hermila Galindo a igual que muchas otras activistas se siente convocada por el programa de Carranza contenido en el Plan de Guadalupe, que posteriormente es radicalizado con medidas sociales como la Ley de Relaciones Familiares, Ley de Divorcio en 1914 y la promulgaci\u00f3n de una nueva Constituci\u00f3n (1917).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 20 de agosto de 1914, Carranza y su ej\u00e9rcito victorioso ingresan en la ciudad de M\u00e9xico. El discurso de bienvenida es pronunciado por una joven de 18 a\u00f1os llamada Hermila Galindo Acosta comisionada, en tanto integrante, por el Club liberal \u201cAbraham Gonz\u00e1les\u201d, para esta misi\u00f3n. En ese momento, Hermila era conocida en los c\u00edrculos pol\u00edticos por gran habilidad oratoria y un amplio conocimiento sobre cultura general, por este motivo el Club la design\u00f3 para esta tarea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Carranza muy impresionado \u201cpor su ret\u00f3rica y entusiasmo revolucionario le propuso formar parte de su grupo de colaboradores\u201d (Jaime Espinosa). En octubre de ese a\u00f1o, Carranza convoca en Aguascalientes la llamada Gran Convenci\u00f3n de Jefes Militares con mando de fuerzas y a los gobernadores de los estados, para discutir su programa revolucionario y asuntos de gobierno. En su transcurso se producen desacuerdos entre zapatistas, villistas y carrancistas que llevan a la destituci\u00f3n de Carranza y el nombramiento el 6 de noviembre de 1914, del general Eulalio Guti\u00e9rrez Ortiz (1881-1939) gobernador y comandante militar del estado de San Luis Potos\u00ed, como Presidente interino y a Francisco Villa como Jefe del Ej\u00e9rcito convencionista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un mes despu\u00e9s, el 6 de diciembre de 1914, Villa y Zapata toman la ciudad de M\u00e9xico con un ej\u00e9rcito de 60 mil hombres. Eulalio Guti\u00e9rrez al sentirse manipulado por Villa, seg\u00fan afirman algunos historiadores, traslada su gobierno a San Luis Potos\u00ed, y el 2 de junio de 1915 renuncia formalmente al cargo, por su parte, Carranza se declar\u00f3 en rebeld\u00eda, partiendo a Veracruz con un grupo de colaboradores de su administraci\u00f3n. Acompa\u00f1ando al l\u00edder, se embarc\u00f3 en el tren, un n\u00famero importante de profesoras decididas a desempe\u00f1ar diversas tareas. Por ejemplo, Adela Elodia Arce, se encarg\u00f3 de la correspondencia en ingl\u00e9s, Guadalupe Aguilar y Mora, del archivo del peri\u00f3dico de <em>El Pueblo, <\/em>Esperanza Aguilar Mart\u00ednez se incorpora en la Direcci\u00f3n de Correos de la Revoluci\u00f3n como guarda valores, y en Veracruz, Concepci\u00f3n Aguilar de Silva, ofrece sus servicios para realizar propaganda constitucionalista entre la poblaci\u00f3n del estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hermila Galindo Acosta que hab\u00eda aceptado el ofrecimiento de Carranza para integrar su equipo de trabajo, tambi\u00e9n es parte de la comitiva en calidad de secretaria particular del Primer Jefe. La acompa\u00f1a su t\u00eda que siempre le demostr\u00f3 su apoyo y confianza. Instalado Carranza en Veracruz, destina una parte importante de los recursos de su administraci\u00f3n para financiar una campa\u00f1a de propaganda a favor de su causa, y para el reclutamiento de voluntarios. Con este prop\u00f3sito creo las Oficinas de Informaci\u00f3n y Propaganda Revolucionaria con filiales en los estados fieles a sus ideas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En virtud de su cargo, Hermila fue comisionada por Carranza para realizar una gira de de propaganda por varios estados. Entre los a\u00f1os 1915 y 1917, Galindo Acosta viaja por el estado de Yucat\u00e1n donde visit\u00f3 las ciudades de Motul, Espita, M\u00e9rida y Campeche, tambi\u00e9n Tabasco, Saltillo y Coahuila. El objetivo de esta gira fue convocar especialmente a las mujeres, en particular a las maestras, a apoyar los postulados del carrancismo mediante la formaci\u00f3n de asociaciones feministas con el objetivo de \u201cdespertar a la mujer para que sea un elemento \u00fatil a su Patria, a su pueblo y a ella misma\u2026\u201d (Orellana Trinidad, 2001).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Yucat\u00e1n traba amistad con gobernador el general Salvador Alvarado (1880-1924), militar revolucionario que emprendi\u00f3 un avanzado programa de reformas sociales y que convoc\u00f3 y apoy\u00f3 la realizaci\u00f3n de los dos primeros Congresos Feministas en 1916. Alvarado admiraba a Hermila, la reconoc\u00eda como correligionaria y manten\u00eda correspondencia con ella (Valles Ru\u00edz, 2011).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;El 21 de mayo de 1915, Hermila ante un p\u00fablico compuesto de militares y obreros, ofrece una conferencia en el Teatro Pe\u00f3n Contreras de M\u00e9rida sobre la revoluci\u00f3n constitucionalista y la personalidad de Carranza. En M\u00e9rida preside la fundaci\u00f3n de la sociedad feminista \u201cRita Cetina Guti\u00e9rrez\u201d. En la localidad de Motul dicta tres conferencias sobre \u201cla emancipaci\u00f3n de la mujer\u201d y asiste a la fundaci\u00f3n de la asociaci\u00f3n \u201cJosefa Ortiz de Dom\u00ednguez\u201d y en Espita es elegida por unanimidad presidenta honoraria de la organizaci\u00f3n \u201cLa mujer fuerte\u201d en referencia al t\u00edtulo de su conferencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Campeche y Tabasco sus conferencias fueron objeto de algunas cr\u00edticas, por su apasionada defensa al constitucionalismo. En Saltillo, Hermila ofreci\u00f3 la \u00faltima de sus conferencias sobre este tema. Un peri\u00f3dico rese\u00f1\u00f3 la actuaci\u00f3n de Hermila destacando su inteligencia y su oratoria, anotando la asistencia de todas las Escuelas Municipales, \u201cque gustan de escuchar la elocuente palabra de la propagandista del feminismo, que viene predicando la emancipaci\u00f3n de la mujer, en esta \u00e9poca en que la Revoluci\u00f3n reconstruye sobre las bases nuevas, el gran edificio social\u201d (Valles Ruiz, 2011). &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta etapa, las mujeres activistas aprovechan los espacios que se abren. Entre 1915 y 1919, dice Martha Eva Rocha, \u201cse empieza a delinear un proyecto feminista inserto en el constitucionalismo\u201d, cre\u00e1ndose clubes feministas en varios estados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Mujer Moderna &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En marzo de 1915, Hermila se declara feminista durante el Congreso Magisterial de Veracruz donde ofrece una conferencia titulada \u201cLa reivindicaci\u00f3n de la mujer mexicana\u201d. Galindo Acosta consideraba que las mujeres deb\u00edan participar tanto en asuntos pol\u00edticos relacionados con el pa\u00eds como en la defensa de sus derechos. Este ideario ser\u00e1 la pauta que marcar\u00e1 sus giras de propaganda y particularmente cuando se embarque ese a\u00f1o, en la empresa de crear el semanario <em>La mujer moderna,<\/em> considerada la primera revista que promovi\u00f3 abiertamente el feminismo en M\u00e9xico en las primeras d\u00e9cadas del siglo XX (Jaime Espinosa), y la \u201cprimera muestra de prensa pol\u00edtica feminista\u201d (Cano, 2007).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El domingo 16 de septiembre de 1915, conmemorando el aniversario de la independencia, en la ciudad de M\u00e9xico recuperada por Carranza luego de la derrota de Francisco Villa, aparece el primer n\u00famero de <em>La mujer moderna<\/em>, semanario ilustrado de 16 p\u00e1ginas que lleva en la portada la foto del presidente. El editorial, con el t\u00edtulo de \u201cLaboremos\u201d, se\u00f1ala la ruta que se ha trazado la revista: \u201celevar el esp\u00edritu femenino a la altura de su deber y su derecho, para que la mujer no permanezca por m\u00e1s tiempo impasible ante la soluci\u00f3n de los m\u00e1s trascendentes problemas sociales y pol\u00edticos que afectan tanto al hombre como a la mujer que es su compa\u00f1era y su igual\u201d (Cano, 1989).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como escribi\u00f3 Salom\u00e9 Carranza integrante del equipo de redactoras, las mujeres deben \u201ctomar parte activa en el movimiento pol\u00edtico\u201d. En este sentido, la revista llama a las mujeres integrantes de organizaciones feministas a defender al \u201creci\u00e9n constituido gobierno encabezado por Venustiano Carranza que ten\u00eda dificultades financieras\u201d, y pide a estas organizaciones \u201corganizar una colecta p\u00fablica voluntaria para contribuir a la solvencia de la revoluci\u00f3n\u2026\u201d (Cano, 1989). El cuerpo de colaboradoras de <em>La mujer moderna\u201d<\/em> estaba compuesto exclusivamente por mujeres. Para su sostenimiento, cont\u00f3 en buena medida, con dineros del gobierno y una privilegiada difusi\u00f3n, posibilitando que la revista tuviera una amplia circulaci\u00f3n a trav\u00e9s de los gobiernos estatales en manos del constitucionalismo que adquirieron ejemplares a pedido de Carranza para repartirlos entre el profesorado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En <em>La mujer moderna <\/em>sin bien no faltaron las t\u00edpicas secciones de una revista para mujeres como recetas de cocina, consejos de belleza y modas, el \u00e9nfasis se puso en los art\u00edculos de fondo con temas sobre el significado de la emancipaci\u00f3n de la mujer, el papel de la iglesia cat\u00f3lica en mantener a las mujeres bajo su tutela, y el derecho al sufragio. La revista se pronunci\u00f3 por la educaci\u00f3n laica y obligatoria rechazando el fanatismo religioso. Tambi\u00e9n se publicaron art\u00edculos y noticias relacionados con los avances y victorias del Ej\u00e9rcito Constitucionalista, y peque\u00f1as biograf\u00edas de los principales jefes militares, como Salvador Alvarado (Jaime Espinosa).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El \u00faltimo n\u00famero de <em>La mujer moderna <\/em>se public\u00f3 el 16 de septiembre de 1919. Bi\u00f3grafas de Galindo, atribuyen su t\u00e9rmino al desgaste del gobierno de Carranza que ya se empezaba a vislumbrar, y las dificultades econ\u00f3micas para el sostenimiento de la revista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 14 de septiembre de 1916, Venustiano Carranza convoca a un Congreso Constituyente para reformar la Constituci\u00f3n de 1857. Ese mismo a\u00f1o, se realiza en Yucat\u00e1n, el Primer Congreso Feminista convocado por el gobernador del estado, Salvador Alvarado en el teatro Pe\u00f3n Contreras, los d\u00edas 13 y 16 de enero, se reunieron alrededor de 700 mujeres, la mayor\u00eda maestras que discuten las formas de participaci\u00f3n de la mujer en el M\u00e9xico revolucionario y su contribuci\u00f3n a la construcci\u00f3n de una nueva sociedad. Temas como la educaci\u00f3n mixta y laica (\u201ceducaci\u00f3n racionalista\u201d) y el derecho a voto, acapararon las discusiones muchas veces acaloradas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Libertad de las mujeres y el voto<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero fue la ponencia de Hermila Galindo dedicada a Salvador Alvarado, la que suscit\u00f3 reacciones encontradas. Como Hermila no pudo asistir, pidi\u00f3 a su amigo C\u00e9sar Gonz\u00e1lez, comandante militar del Partido Constitucional en Espita, que leyera su ponencia titulada <em>La mujer en el porvenir<\/em>. En \u00e9l, Hermila afirma que el instinto sexual es parte del amor maternal que ning\u00fan artificio hip\u00f3crita es capaz de destruir, modificar o refrenar\u201d. A continuaci\u00f3n, pide que, en las escuelas secundarias, se impartan cursos de anatom\u00eda y fisiolog\u00eda\u2026\u201d Las mujeres\u201d, afirma \u201cdeb\u00edan ser educadas en el conocimiento de su cuerpo\u201d. En suma, demand\u00f3 \u201cuna sola moral para ambos sexos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas tesis de Hermila \u201cescandalizaron a la mayor\u00eda de maestras cat\u00f3licas, que se sintieron ofendidas en su pudor\u201d (Valles Ruiz, 2011). En cuanto el derecho a voto, s\u00f3lo una peque\u00f1a minor\u00eda lo reclam\u00f3 y 31 congresistas se pronunciaron por el voto municipal para las mujeres, pero&nbsp;&nbsp; el Congreso en su conjunto no aval\u00f3 esta petici\u00f3n. Hermila al calificarse como \u201cmujer de mi tiempo, e iconoclasta\u201d fue atacada por la prensa local que la calific\u00f3 de \u201cinmoral\u201d y de propagandista del \u201camor libre\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un Segundo Congreso Feminista fue convocado para el mes de noviembre de ese a\u00f1o (23 de noviembre y 3 de diciembre). Hermila sorprendida por las reacciones producidas que tuvo su ponencia, env\u00eda el Op\u00fasculo titulado <em>Estudio de la Srta. Hermila Galindo con motivo de los temas que han de absolverse en el segundo Congreso Feminista de Yucat\u00e1n. <\/em>Se trata de una defensa \u201cradical y enf\u00e1tica de su anterior trabajo\u201d (Orellana Trinidad, 2001).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le\u00edda por Rosa Torres feminista y revolucionaria, en esta ponencia su autora propone la igualdad de la ilustraci\u00f3n entre hombres y mujeres y los mismos derechos y obligaciones, y se ratifica en sus posiciones sobre la sexualidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En septiembre de 1916, el Presidente la env\u00edo a La Habana y Colombia con la misi\u00f3n de ofrecer conferencias donde sostuvo que era \u201cindispensable que se sepa en qu\u00e9 consiste la bondad del r\u00e9gimen pol\u00edtico implantado en la Rep\u00fablica Mexicana por el se\u00f1or Carranza\u201d (Orellana Trinidad, 2001). La eficiencia de su labor y compromiso con el constitucionalismo son refrendadas por Carranza en la \u201cMenci\u00f3n de Honor\u201d que reconoce sus \u201cpatri\u00f3ticos servicios prestados a la Causa del Pueblo, en los momentos dif\u00edciles de lucha contra la reacci\u00f3n y siguiendo al Gobierno cuando hubo de trasladarse de esta ciudad a Veracruz\u201d. 20 de mayo de 1916. (Valles Ruiz, 2011).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La primera congresista del pa\u00eds y la Constituci\u00f3n sin las mujeres &nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En febrero de 1917, es aprobada la nueva Constituci\u00f3n que introdujo reformas como la educaci\u00f3n laica, igualdad de salarios para mujeres y hombres, jornada laboral de 8 horas, protecci\u00f3n a la maternidad, prohibici\u00f3n de trabajos insalubres y peligrosos para mujeres y ni\u00f1os menores de 16 a\u00f1os. En el curso de las sesiones de la Asamblea Constituyente, Hermila present\u00f3 una iniciativa a favor del voto femenino. Una segunda iniciativa fue del general Silvestre Gonz\u00e1lez Torres. Ambas fueron rechazadas. En las actas del Congreso consta que los diputados se rieron del proyecto. Hermila creyente en el ideario constitucionalista, estaba segura que los constituyentes aprobar\u00edan el voto femenino. En una entrevista al peri\u00f3dico <em>La Opini\u00f3n<\/em>, durante su visita a Quer\u00e9taro para presentar su propuesta, dijo que su viaje ten\u00eda la finalidad de \u201csometer a consideraci\u00f3n de la Asamblea Constituyente la iniciativa del voto, cosa que juzgo dentro de los ideales revolucionarios y que exige la \u00e9poca por la que atravesamos\u201d (Valles Ruiz, 2011). Los constituyentes esgrimieron argumentos como que \u201cen las condiciones en que se encuentra la sociedad mexicana no se advierte la necesidad de conceder el voto a las mujeres\u201d, y que \u00e9stas \u201cno sienten pues la necesidad de participar en los asuntos p\u00fablicos, como lo demuestra la falta de todo movimiento colectivo en este sentido\u201d (Tu\u00f1\u00f3n Pablos, 1998).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 1\u00b0 de mayo de 1917, las elecciones generales dieron el triunfo a Venustiano Carranza. Elegido Presidente Constitucional de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al a\u00f1o siguiente se introduce una modificaci\u00f3n de la ley electoral donde se especifica que el derecho a voto es s\u00f3lo para los hombres. Sin perder su optimismo, y sabiendas que su candidatura no prosperar\u00eda, Galindo Acosta decide postularse como diputada al Quinto Distrito de la ciudad de M\u00e9xico. Una noticia aparecida en <em>El Universal <\/em>destac\u00f3 que el grupo \u201cJuventud Femenil Revolucionaria\u201d de Quer\u00e9taro, le hab\u00eda pedido que se presentara como candidata y que votar\u00eda por ella, por ser una digna representante de las ideas liberales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;En este tramo, Galindo Acosta inicia una serie de actividades de propaganda de su candidatura. Era la primera vez que una mujer participaba para un cargo de elecci\u00f3n electoral, y a pesar que fueron cientos de mujeres las que le dieron el voto su elecci\u00f3n fue invalidada por el Consejo Electoral como era de esperarse. Con su candidatura, Galindo quiso demostrar al gobierno que las mujeres quer\u00edan votar, y \u201cdejar sentado un precedente para las generaciones posteriores\u201d (Cano, 1991).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El siguiente paso de Galindo fue auto postularse al cargo de \u201cCensor Legislativo\u201d de las actividades del diputado Ernesto Aguirre Colorado que gan\u00f3 las elecciones en el Quinto Distrito Electoral, de esta forma Hermila encontr\u00f3 la forma de estar vigente en el espacio p\u00fablico. Rosa Mar\u00eda Valles Ru\u00edz dice que \u201cno se tiene registro en M\u00e9xico de una mujer de aquella \u00e9poca que haya desarrollado una acci\u00f3n de tal magnitud, lo m\u00e1s cercano en nuestros d\u00edas a la rendici\u00f3n de cuentas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego del t\u00e9rmino del semanario <em>La mujer moderna, <\/em>Hermila continua su trabajo como propagandista del constitucionalismo, publicando el libro <em>La doctrina Carranza y el acercamiento indolatino <\/em>que fue editado por el gobierno con una encuadernaci\u00f3n especial y enviado a los presidentes de Am\u00e9rica Latina.\u201cMientras lo escrib\u00eda, le enviabacap\u00edtulo por cap\u00edtulo al presidente, pidi\u00e9ndole su opini\u00f3n, adem\u00e1s de comentar la situaci\u00f3n pol\u00edtica que dominaba como pocas mujeres debieron haberlo hecho\u201d (Orellana Trinidad, 2001). Este libro fue dedicado a su t\u00eda \u00c1ngela Galindo, a quien agradece por su cari\u00f1o, ternura y los cuidados que recibi\u00f3 de ni\u00f1a. La llama \u201cMadre\u201d. Al mismo tiempo, Carranza resuelve enviarla de gira a Espa\u00f1a, Centroam\u00e9rica y Sudam\u00e9rica, viaje que se trunc\u00f3 luego del tr\u00e1gico suceso que fue su asesinato. &nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n en ese a\u00f1o, Hermila public\u00f3 <em>Un presidenciable. El general Don Pablo Gonz\u00e1lez. <\/em>Galindo consideraba que Gonz\u00e1les ten\u00eda suficientes credenciales revolucionarias para suceder a Carranza, pero \u00e9ste apost\u00f3 por su embajador en Washington, Ignacio Bonilla (1858-1942) porque quer\u00eda que fuera un civil el pr\u00f3ximo presidente. Pero el ambiente pol\u00edtico que se viv\u00eda en esos momentos le fue adverso al l\u00edder constitucionalista que estaba aislado en lo militar, pol\u00edtico y social. Esta situaci\u00f3n fue aprovechada por sus principales opositores, los generales \u00c1lvaro Obreg\u00f3n (1880-1928) Secretario de Guerra y Marina, y Plutarco El\u00edas Calles (1877-1945) quienes organizaron un complot contra el gobierno cuyo corolario fue el asesinato de Carranza el 20 de mayo de 1920 en Tlaxcantongo, por orden de Plutarco El\u00edas Calles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hermila condena duramente el asesinato y muestra su indignaci\u00f3n por el silencio de los pol\u00edticos, calificando a la pol\u00edtica mexicana de \u201ccenagosa y tortuosa\u201d. Para ella fue un golpe devastador. Seg\u00fan Ana Mac\u00edas, cuando asume la presidencia \u00c1lvaro Obreg\u00f3n el 1\u00b0 de diciembre de 1920, Galindo no se demora en descubrir que est\u00e1 \u201cquemada\u201d pol\u00edticamente y que ha perdido influencia. Esto signific\u00f3 el t\u00e9rmino de su vida p\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Existe poca informaci\u00f3n de este per\u00edodo de su vida, pero se sabe que en el primer aniversario de la muerte de Carranza, acudi\u00f3 al Pante\u00f3n Civil de Dolores acompa\u00f1ada de un grupo de amigas para depositar una corona de flores, pronunciando un discurso en memoria del presidente asesinado, y que tambi\u00e9n p\u00fablico art\u00edculos espor\u00e1dicamente en algunos peri\u00f3dicos, tambi\u00e9n intent\u00f3 publicar dos libros para dejar constancia de la labor del carrancismo, lamentablemente esos textos quedaron in\u00e9ditos por falta de recursos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 1923 contrae matrimonio a la edad de 37 a\u00f1os, con Miguel Enr\u00edquez Topete de 40 a\u00f1os, dedicado a las actividades comerciales, sin inter\u00e9s por las actividades pol\u00edticas. Por su notable timbre de voz fue apodado el \u201cCaruso de M\u00e9xico\u201d, y aunque en Guadalajara hab\u00eda tomado clases en el Conservatorio nunca se dedic\u00f3 profesionalmente al canto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hermila tuvo una hija, Hermila del Rosario, a la que se uni\u00f3 una hija del anterior compromiso de su esposo, Mar\u00eda Concepci\u00f3n que vivi\u00f3 un tiempo con ellos. En 1954, el periodista Daniel Mu\u00f1oz entrevist\u00f3 a Miguel Enr\u00edquez Topete quien le cont\u00f3 que despu\u00e9s del asesinato de Carranza, Hermila se dedic\u00f3 a la pintura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el sal\u00f3n de su casa, Mu\u00f1oz pudo un par de retratos de dos metros de altura cada uno, realizados por ella, de Venustiano Carranza y de su esposo. El 7 de febrero de 1940, la Secretar\u00eda de Defensa Nacional la reconoci\u00f3 como \u201cVeterana de la Revoluci\u00f3n\u201d otorg\u00e1ndole una pensi\u00f3n y la distinci\u00f3n \u201cAl M\u00e9rito Revolucionario, \u201cpor los servicios prestados al movimiento durante el primer y segundo per\u00edodos (19 de noviembre de 1910 al 15 de mayo de 1911 y del 20 de febrero de 1913 al 15 de agosto de 1914)\u201d. Aunque alejada de la actividad feminista, no por ello dej\u00f3 de seguir con atenci\u00f3n la aparici\u00f3n de organizaciones que dar\u00e1n inicio a campa\u00f1as para la obtenci\u00f3n del voto electoral, como el Frente \u00danico Pro- Derechos de las Mujeres. Una prueba de ello fue la carta que el 17 de octubre de 1953, un a\u00f1o antes de su fallecimiento, env\u00edo al Presidente Adolfo Ruiz Cortines, inst\u00e1ndole a modificar el art\u00edculo 34 constitucional para otorgar el voto a las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 19 de agosto de 1954, producto de un infarto, falleci\u00f3 en la ciudad de M\u00e9xico, Hermila Galindo. Cuando su hija Rosario fue a su recamara la encontr\u00f3 sin vida, a un costado de la cama estaba su m\u00e1quina de escribir Olivetti y en el rodillo quedaron unas p\u00e1ginas escritas sin concluir. (Valles Ruiz, 2011).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuentes:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Orellana Trinidad, Laura. 2001. <em>Hermila Galindo: una mujer moderna. <\/em>Instituto Nacional de Bellas Artes. Centro Nacional de Informaci\u00f3n y Promoci\u00f3n de la Literatura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jaime Espinosa, Mar\u00eda Elizabeth. S\/f. \u201cHermila Galindo Acosta y La Mujer Moderna (1915-1919)\u201d. <a href=\"http:\/\/www.historiadoresdelaprensa.com.mx\/\">www.historiadoresdelaprensa.com.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Valles Ruiz, Rosa Mar\u00eda. 2011. <em>Sol de la Libertad. Hermila Galindo: Feminista, Constitucionalista y Primera Censora Legislativa en M\u00e9xico.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.uach.edu.mex\/investigacion\/productos\/4961\">www.uach.edu.mex\/investigacion\/productos\/4961<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rocha Islas, Martha Eva. 2011. \u201cFeminismo y Revoluci\u00f3n\u201d, en Espinosa Dami\u00e1n, Gisela, Lau Jaiven, Ana. <em>Un fantasma recorre el siglo: luchas feministas en M\u00e9xico 1910-1920. <\/em>Universidad Aut\u00f3noma Metropolitana. Unidad Xochimilco. Editorial Itaca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tu\u00f1\u00f3n Pablos, Enriqueta. 1998. \u201cLos movimientos de las mujeres en pro del sufragio en M\u00e9xico, 1917-1953\u201d.&nbsp; <a href=\"http:\/\/www.cdigital.uv.mx\/\">www.cdigital.uv.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cano, Gabriela. 1991. \u201cLas feministas en campa\u00f1a: la primera mitad del siglo XX\u201d. <em>Debate Feminista. Vol.4.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cano, Gabriela. 2007. \u201cLas mujeres en el M\u00e9xico del siglo XX. Una cronolog\u00eda m\u00ednima\u201d, en Lamas, Martha. <em>Miradas feministas sobre las mexicanas del siglo XX.<\/em> Fondo de Cultura Econ\u00f3mica. Consejo Nacional para la Cultura y las Artes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cano, Gabriela. 1989. \u201cMemorias del Olvido. La Mujer Moderna, un Semanario Ilustrado\u201d. <em>Fem. <\/em>N\u00b0 5.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">*Texto construido de un discurso -premio Hermila Galindo a Sara Lovera \u2013 y elaborado cuidadosamente con Ana Ma. Portugal, para un libro que no vio la luz. &nbsp;<em>&nbsp;<\/em>&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermila Galindo Acosta y una potente generaci\u00f3n de mujeres, protagonistas de la Revoluci\u00f3n Mexicana, so\u00f1aron en una rep\u00fablica justa y democr\u00e1tica. Hermila se defini\u00f3 constitucionalista desde 1916, fue pacifista y defensora de la democracia<\/p>\n","protected":false},"author":3,"featured_media":62368,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[64],"tags":[],"class_list":["post-62362","post","type-post","status-publish","format-standard","has-post-thumbnail","category-para-saber"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/62362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=62362"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/62362\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/62368"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=62362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=62362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=62362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}