{"id":6179,"date":"2019-02-05T21:02:22","date_gmt":"2019-02-05T21:02:22","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=6179"},"modified":"2023-07-21T14:46:10","modified_gmt":"2023-07-21T19:46:10","slug":"los-de-arriba-y-los-de-abajo","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/los-de-arriba-y-los-de-abajo\/","title":{"rendered":"Los de arriba y los de abajo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Es tan grande la desigualdad que una moneda que dispensen hace la diferencia en la vida de las personas.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"> El resentimiento social es tanto que los que \u201clograron\u201d la victoria saborean a diario en decidir quien vive y quien muere.<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/semmexico.com\/gallery-post.php?id=7090#\">Billy Parker<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. Veracruz. 5 de febrero de 2019- El Presidente L\u00f3pez Obrador es recibido en sus giras por Veracruz, como en ninguna otra entidad federativa. Constancia de que el tercer estado con el padr\u00f3n m\u00e1s amplio de electores es basti\u00f3n morenista. En mucho, sin olvidarnos del agravio de los gobiernos del PRI y el PAN, gracias a la personal cercan\u00eda de Andr\u00e9s Manuel con la gente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el sur y centro de Veracruz la recepci\u00f3n fue como suele calificarlo la prensa, como \u201cfigura del Rock Star\u201d. Hubo quienes hasta pagaron por verlo, como los que erogaron mil pesos por estar presentes desde el balc\u00f3n de los Portales. En los actos masivos se ubic\u00f3 a muchos acarreados, pero llenos de la esperanza incubada en 18 a\u00f1os de campa\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seguidores apostados atr\u00e1s de las barreras met\u00e1licas, donde se observan, lo mismo a legisladores que empresarios, campesinos, j\u00f3venes o exfuncionarios duartistas (los m\u00e1s aferrados a captar la atenci\u00f3n de AMLO), junto a sus v\u00edctimas, ciudadana\/os de a pie. Mujeres y hombres, con la esperanza de ser tomados en cuenta, con el sobre, o la mano extendida. Un escenario distinto a los que vemos en los actos oficiales donde AMLO no est\u00e1, donde se identifica una nueva clase pol\u00edtica emergente, que no aplica la l\u00ednea de la 4T y recicla la atm\u00f3sfera clasista \u201cde los de arriba y los de abajo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mandatario mexicano atendi\u00f3 a la multitud hasta con selfies, besos y apapachos. Los otros, a diferencia de lo que practican cotidianamente, lo imitaron esos d\u00edas. Hubo quienes recibieron abrazo m\u00e1s efusivo de L\u00f3pez Obrador, otros albergaron un cuidado especial y su carpeta fue turnada inmediatamente. La campa\u00f1a sigue su marcha por tierra y afianz\u00e1ndose, con su muy peculiar condici\u00f3n asistencialista. Es tan grande la desigualdad que una moneda que dispensen hace la diferencia en la vida de las personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los que hoy se ubican en \u201clos de arriba\u201d, siguen inercialmente el camino de quienes cayeron el 1 de junio. Forrados de soberbia se les ve\u00eda venir. Desde antes de que tomaran posesi\u00f3n miraban para abajo, bloqueaban el paso con aires de divinidad a los que consideran fif\u00eds, el clasismo al rev\u00e9s. Es la hora de la venganza para ellos. Pero cuando est\u00e1n con el que manda se tornan, todas sonrisas fingidas, todas atenciones, pese a su divisi\u00f3n y los rega\u00f1os del jefe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Cu\u00eddate Andr\u00e9s Manuel! \u00a1Te amo! Gritaba la se\u00f1ora que luchaba, entre espaldas de hombres que ansiaban saludarlo. Ninguno delante de ella se atrevi\u00f3 a ceder un cent\u00edmetro de su lugar, siquiera para que lo viera. Es la ley patriarcal, la de la selva pues, donde mujeres, tercera edad, ni\u00f1os y ni\u00f1as, son los sometidas.&nbsp; Muchos discursos, pero en sus acciones son los m\u00e1s maltratados. Esto lo repiten en esa c\u00fapula.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el templete s\u00f3lo el gobernador Cuitl\u00e1huac Garc\u00eda y el super delegado, Manuel Huerta de la clase pol\u00edtica, y alg\u00fan invitado del gabinete presidencial. Nadie m\u00e1s,&nbsp;enviando la se\u00f1al, quiero creer, de que la divisi\u00f3n de \u201clos de arriba y los de bajo\u201d no tienen cabida. El resentimiento social es tanto que los que \u201clograron\u201d la victoria saborean a diario en decidir quien vive y quien muere en la reci\u00e9n llegada \u00e9lite al poder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes del espaldarazo de AMLO al gobernador de Veracruz, para acallar las voces que lo tiran de la silla, el presidente atiende a la gente en las vallas. Lo mismo a la octogenaria que lo envuelve con su collar de rosas, como a las Diputadas locales de Morena. Los y las legisladoras ya no gozan de privilegios, menos los funcionarios, o quienes pretenden la log\u00edstica de los que se fueron. Innovaci\u00f3n no sin abusos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo atestiguamos en Xalapa durante la visita de Alejandro Encinas. S\u00f3lo los m\u00e1s cercanos en su c\u00edrculo les fue permitido el acompa\u00f1amiento a despedir al subsecretario de Gobernaci\u00f3n, el pasado 25 de enero en la capital del estado de Veracruz. Las formas del \u201cnuevo\u201d estado mayor \u201cde facto\u201d, no respetan investiduras, o razonamientos. Para ellos solo valen sus \u201ccamaradas\u201d, como qued\u00f3 registrado, al impedirles el paso a legisladoras, precisamente el d\u00eda que lanzaban el programa Cero Tolerancia a la violencia contra las Mujeres y las Ni\u00f1as en Veracruz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLos de arriba y las de abajo\u201d rememora a Los Miserables de V\u00edctor Hugo&nbsp;que muestra la pobreza en el siglo XIX,&nbsp;durante el establecimiento de la Tercera Rep\u00fablica en las \u00faltimas d\u00e9cadas del siglo. El autor retrata muy bien la implosi\u00f3n de una sociedad conservadora, clasista y machista que colaps\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cEl humano sometido a la necesidad extrema es conducido hasta el l\u00edmite de sus recursos y al infortunio para todos los que transitan por este camino. Trabajo y salario, comida y cobijo, coraje y voluntad, para ellos todo est\u00e1 perdido. La luz del d\u00eda se funde con la sombra y la oscuridad entra en sus corazones; y en medio de esta oscuridad el hombre se aprovecha de la debilidad de las mujeres y los ni\u00f1os y los fuerza a la ignominia. Luego de esto cabe todo el horror. La desesperaci\u00f3n encerrada entre unas endebles paredes da cabida al vicio y al crimen&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Parecen totalmente depravados, corruptos, viles y odiosos; pero es muy raro que aquellos que hayan llegado tan bajo no hayan sido degradados en el proceso, adem\u00e1s, llega un punto en que los desafortunados y los infames son agrupados, fusionados en un \u00fanico mundo fat\u00eddico. Ellos son \u00abLos Miserables\u00bb, los parias, los desamparados\u201d, cita el escritor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Galeano lo actualiza de acuerdo al contexto hist\u00f3rico en su libro, \u201cLos Ni\u00f1os: Los de arriba, los de abajo y los del medio\u201d. El autor asevera que el mundo trata a los ni\u00f1os ricos y a los ni\u00f1os pobres de manera diferenciada. \u201cA los ricos los trata como si fueran dinero, para que se acostumbren a actuar como el dinero act\u00faa. El mundo trata a los ni\u00f1os pobres, como si fueran basura, para que se conviertan en basura y los del medio, que no son ricos o pobres, los tienen atados a la pata del televisor para que se vayan acostumbrando a una vida prisionera\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y lo reciclan algunos en la 4t.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dif\u00edcil de entender para quien est\u00e1 desubicado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">*Directora Gral BillieParkerNoticias.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es tan grande la desigualdad que una moneda que dispensen hace la diferencia en la vida de las personas. El resentimiento social es tanto que los que \u201clograron\u201d la victoria saborean a diario en decidir quien vive y quien muere. Billy Parker SemM\u00e9xico. Veracruz. 5 de febrero de 2019- El Presidente L\u00f3pez Obrador es recibido [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6161,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[690,81,1],"tags":[],"class_list":["post-6179","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-billy-parker","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/6179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=6179"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/6179\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/6161"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=6179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=6179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=6179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}