{"id":61405,"date":"2023-01-14T16:51:36","date_gmt":"2023-01-14T22:51:36","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=61405"},"modified":"2023-01-14T16:51:38","modified_gmt":"2023-01-14T22:51:38","slug":"vida-y-lectura-el-cisne-negro-de-cristina-rivera-garza","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/vida-y-lectura-el-cisne-negro-de-cristina-rivera-garza\/","title":{"rendered":"Vida y Lectura| EL CISNE NEGRO DE CRISTINA RIVERA GARZA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Marcela Eternod Ar\u00e1mburu<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Aguascalientes, 14 de enero, 2023.- Narra Nassim Nicholas Taleb, en su libro \u201cEl cisne negro. El impacto de lo altamente improbable\u201d que, las sociedades est\u00e1n expuestas a permanentes e imprevisibles cisnes negros. Cuenta que la historia de la humanidad se explica por enormes saltos imprevisibles y que los cisnes negros explican \u201ccasi todo lo concerniente a nuestro mundo, desde el \u00e9xito de las ideas y las religiones hasta la din\u00e1mica de los acontecimientos hist\u00f3ricos y los elementos de nuestra propia vida personal\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque Taleb se centra en el impacto imprevisible, impredecible y con frecuencia inesperado de muy diversos hechos, a los que conceptualiza como cisnes negros, aporta suficiente evidencia para afirmar que la causalidad est\u00e1 sobre valorada por nuestra estupidez e ignorancia, la cual abarca a las y los expertos, (economistas, historiadores, cient\u00edficos, pol\u00edticos, soci\u00f3logos y una larga lista de farsantes) que se esfuerzan en predecir lo impredecible: el futuro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este concepto del cisne negro es perfectamente aplicable a lo que viven las personas en su d\u00eda a d\u00eda; siempre expuestas a sucesos, generalmente externos, extremos, impensables, inimaginados y sorpresivos que, de pronto, trastocan todo el orden cotidiano de la vida, provocan sucesos incomprensibles y reacciones incluso m\u00e1s desconcertantes a\u00fan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando le\u00eda el libro de Cristina Rivera Garza, \u201cEl invencible verano de Liliana\u201d, no pod\u00eda dejar de pensar en ese momento cuando Cristina se enteran de la muerte de Liliana, su hermana. Una llamada que le informa de su muerte y su causa: asesinada. Estupor, p\u00e1nico, angustia ante lo inimaginable. Ella ya no est\u00e1, muri\u00f3 por la mano de un feminicida. Ese enorme cisne negro que impact\u00f3 y destruy\u00f3 los s\u00f3lidos cimientos de la hermandad y a toda la familia. Ese cisne negro que aparece y trastoca las vidas de manera imprevisible, brutal y despiadada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 16 de julio de 1990, Liliana Rivera Garza, \u00fanica hermana de Cristina \u2014la voz que narra esta historia con maestr\u00eda\u2014 muri\u00f3 presumiblemente en manos de su exnovio, \u00c1ngel Gonz\u00e1lez Ramos. Liliana conoci\u00f3 a \u00c1ngel en 1984 y mantuvo una relaci\u00f3n (con ese primer amor de preparatoria) por varios a\u00f1os caracterizada por el control, la dominaci\u00f3n, el acoso y la violencia por parte de \u00e9l. Relaci\u00f3n que termin\u00f3 en feminicidio cuando la jovencita Liliana (20 a\u00f1os) decidi\u00f3 que ya no, y trat\u00f3 de alejarse de la toxicidad de ese exnovio, con el que reincid\u00eda, bravuc\u00f3n, irracional y, finalmente, feminicida. Cristina Rivera aporta evidencias, extra\u00eddas de los propios textos de su hermana, de la decisi\u00f3n de terminar con su asesino y concluye que \u00c1ngel decidi\u00f3 que \u201cella no tendr\u00eda una vida sin \u00e9l\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El libro, escrito 30 a\u00f1os despu\u00e9s del feminicidio, fue el tiempo que le tom\u00f3 a Rivera Garza procesar a ese enorme cisne negro que la priv\u00f3 de una hermana y de la justicia que exig\u00eda su muerte. Fue el tiempo que necesito la escritora para abrir las cajas que guardaban los recuerdos de Liliana. Fue el tiempo que le tom\u00f3 a la sociedad mexicana entender que los feminicidios son una de las expresiones m\u00e1s brutales del patriarcado. Y fue, tambi\u00e9n, el tiempo que se necesit\u00f3 para construir un andamiaje conceptual y jur\u00eddico que permitiera identificar la violencia contra las mujeres en sus m\u00faltiples formas y construir la tipolog\u00eda penal del feminicidio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl invencible verano de Liliana\u201d es una odisea, la de Cristina, inmersa en complejidades que se diseccionan con bistur\u00ed y que sorprenden por su estulticia y crueldad. Todo el texto est\u00e1 marcado por la ausencia, no de Liliana que es obvio, sino por la ausencia de un compromiso del Estado mexicano para investigar el feminicidio, de mecanismos para entender qui\u00e9nes son realmente las v\u00edctimas, para saber interactuar con sus familiares. Falencias, mentiras, valemadrismos e inercias que a\u00fan hoy impiden identificar a esos miles de machitos depredadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La odisea de Rivera Garza implic\u00f3 investigar, revisar, documentar, entrevistar, reconstruir, imaginar y completar todo el suceso y su entorno, para enfrentar a su cisne negro y tratar de entender. La b\u00fasqueda del expediente de su hermana, desaparecido hasta hoy, es un ejemplo de esa larga, penosa e infructuosa tarea que le permiti\u00f3 entender, como historiadora que es, que hay fuentes que ya no existen, que hay evidencias que desaparecen y que solo la narrativa puede reconstruir. Y es ah\u00ed, en la manera en que narra y da voz a los otros (sus padres, las y los amigos, la voz de los recuerdos) para explicar lo que pas\u00f3, donde el libro adquiere su verdadera dimensi\u00f3n, su densidad ontol\u00f3gica y su conmovedora fuerza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No es una novela, no es una cr\u00f3nica, no es un ensayo. Es todo eso y m\u00e1s, entretejido con respeto, ponderaci\u00f3n, elegancia y sensibilidad. Es un complejo andamiaje de hechos, presentados desde el dolor de la ausencia, acicateados por un b\u00e1sico deseo de justicia, destacados con maestr\u00eda para prevenir y denunciar lo que ocurri\u00f3, con el prop\u00f3sito de que no se repita. Es una fuerte llamada de atenci\u00f3n sobre los cientos de casos de feminicidios que ocurren en M\u00e9xico y que no se investigan. Es un lamento profundo y leg\u00edtimo ante la impunidad, pero tambi\u00e9n un yo acuso directo a los responsables de garantizar la seguridad, a quienes tienen la obligaci\u00f3n de procurar e impartir justicia, y ante una sociedad adormecida que todav\u00eda se pregunta qu\u00e9 es el feminismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi sugerencia es que se lea con la misma generosidad fraterna con que fue escrito, aunque duela, conmueva y cause desasosiego. Es una posibilidad real de que aprendamos y que tanto sufrimiento devenga en una peque\u00f1a luz de esperanza y un amplio, rabioso y estridente reclamo ante la violencia contra las mujeres en todas sus formas: \u00a1YA NO M\u00c1S!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Narra Nassim Nicholas Taleb, en su libro \u201cEl cisne negro. El impacto de lo altamente improbable\u201d<br \/>\nCuenta que la historia de la humanidad se explica por enormes saltos imprevisibles<\/p>\n","protected":false},"author":3,"featured_media":38638,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[515,35,514],"tags":[],"class_list":["post-61405","post","type-post","status-publish","format-standard","has-post-thumbnail","category-marcela-eternod-aramburu","category-opinion","category-vida-y-lectura"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/61405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=61405"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/61405\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/38638"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=61405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=61405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=61405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}