{"id":61340,"date":"2023-01-12T17:33:12","date_gmt":"2023-01-12T23:33:12","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=61340"},"modified":"2023-01-12T17:33:55","modified_gmt":"2023-01-12T23:33:55","slug":"letra-clara-ni-muertas-las-mujeres-aparecen","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/letra-clara-ni-muertas-las-mujeres-aparecen\/","title":{"rendered":"<strong>Letra Clara| \u00a1Ni muertas, las mujeres aparecen!<\/strong>"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Teresa Vald\u00e9s Betancourt<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Colima, 12 de enero del 2023.- La rectificaci\u00f3n y reclasificaci\u00f3n todav\u00eda insuficiente, de la Fiscal\u00eda General del Estado de Colima, conmovi\u00f3 la opini\u00f3n p\u00fablica, al reconocer 16 casos de feminicidios en las&nbsp; investigaciones sobre las muertes violentas de mujeres que estaban clasificadas como v\u00edctimas de homicidio doloso, seg\u00fan se conoci\u00f3 a partir de la denuncia publicada por <em>Mexicanos Contra la Corrupci\u00f3n y la Impunidad<\/em>&nbsp; organizaci\u00f3n civil de CDMX, dedicada a realizar investigaciones period\u00edsticas, acad\u00e9micas, litigios estrat\u00e9gicos, an\u00e1lisis y comunicaci\u00f3n, fundada desde 2015.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La informaci\u00f3n inicial del per\u00edodo enero a julio de 2022, registraba en M\u00e9xico 530 feminicidios y Colima, estaba como \u00fanica entidad que aparec\u00eda con cero mes por mes, aunque estaban en carpetas de investigaci\u00f3n 79 mujeres asesinadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras que en CDMX y otros estados se integra como feminicidio, la muerte de mujeres en las carpetas de investigaci\u00f3n, hasta que se demuestre la contrario. No obstante, en Colima se siguen iniciando las investigaciones sobre muertes violentas de mujeres como <em>Homicidios dolosos,<\/em> aunque la palabra homicidios viene de <em>homo que significa hombre y no mujer<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como respuesta a la denuncia de la organizaci\u00f3n civil, la Fiscal\u00eda Especializada de Delitos de G\u00e9nero y Trata de Personas Estatal revis\u00f3 las carpetas de 2022 y acept\u00f3, 16 casos tipificados como feminicidios a pesar que faltaban las 63 mujeres muertas, que siguen registradas con la calificaci\u00f3n jur\u00eddica de <em>Homicidios dolosos.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es un tema esencialmente de apreciaci\u00f3n jur\u00eddica que lleva impl\u00edcita evidente manifestaci\u00f3n de las violencias contra las mujeres. No hay casualidad, es otra resistencia patriarcal que se manifiesta en el plano personal, en la familia, en la sociedad y hasta en las esferas profesionales. La violencia continua siempre presente, en qui\u00e9nes las realizan y en quienes la padecen, desde familia hasta la sociedad, en la pol\u00edtica y hasta en la jurisprudencia que viola los derechos m\u00e1s elementes de las mujeres donde se considera su propia supervivencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para identificar una vez m\u00e1s esas manifestaciones con los elementos conceptuales que identifican a las violencias,&nbsp; acudo a las palabras de Ana Gabriela Buquet Corleto, investigadora de la UNAM quien se\u00f1ala: \u201cLa discriminaci\u00f3n es resultado de la desigualdad impuesta desde el poder patriarcal. Nunca es natural, porque es consecuencia de una construcci\u00f3n cultural y no se fundamenta en las capacidades naturales diferenciadas entre los sexos.\u201d <a href=\"https:\/\/www.scielo.org.mx\/scielo\">https:\/\/www.scielo.org.mx\/scielo<\/a><em><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nadie duda que, las violencias contra las mujeres y las ni\u00f1as, sus tipos y modalidades&nbsp; son una violaci\u00f3n de Derechos Humanos, un problema de justicia social, pensamiento jur\u00eddico y de salud p\u00fablica que puede ser evitable. Conocidas son sus caracter\u00edsticas muy diversas, por eso, quiero explicarlas en plural. Se reconocen como el uso intencional de la fuerza f\u00edsica, amenazas, que tengan como consecuencia, traumatismo f\u00edsico, da\u00f1o psicol\u00f3gico, problemas de desarrollo y hasta la muerte.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La violencia feminicida resulta esa forma m\u00e1s extrema de las violencias contra las mujeres. Ellas mueren por el solo hecho de ser mujeres, y se fundamenta con la violaci\u00f3n de sus derechos humanos, en los espacios p\u00fablico y privado; la ley es expresa al considerarlas como conductas de odio o rechazo hacia las mujeres, que puede terminar en homicidio y otras formas de muerte violenta. \u00bfC\u00f3mo pueden las estad\u00edsticas judiciales omitirlas?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las violencias contra las mujeres y las ni\u00f1as resultan una violaci\u00f3n de nuestros Derechos Humanos y est\u00e1 extendida, afincada y tolerada por las manifestaciones de poder que se fundamentan con la cultura androc\u00e9ntrica tradicional y profundamente arraigada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hiere la inteligencia estas resistencias ideol\u00f3gicas y justificaciones insostenibles en profesionales de las esferas jur\u00eddicas policiales quienes por sus funciones, devienen como primeros receptores de las mujeres v\u00edctimas de las violencias. Y en casos extremos, tramitan sus cuerpos mutilados. Si en otros estados se cumplen estas normativas \u00bfQu\u00e9 fuerza pol\u00edtica se requiere para que en Colima, se abran las carpetas de investigaci\u00f3n como feminicidios ante &nbsp;cada cuerpo de mujer asesinada de manera violenta? La sociedad merece una respuesta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">@Letra Clara<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La informaci\u00f3n inicial del per\u00edodo enero a julio de 2022, registraba en M\u00e9xico 530 feminicidios y Colima, estaba como \u00fanica entidad que aparec\u00eda con cero mes por mes, aunque estaban en carpetas de investigaci\u00f3n 79 mujeres asesinadas.<\/p>\n","protected":false},"author":3,"featured_media":9180,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[101,35,79],"tags":[],"class_list":["post-61340","post","type-post","status-publish","format-standard","has-post-thumbnail","category-letra-clara","category-opinion","category-teresa-valdes-betancourt"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/61340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=61340"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/61340\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/9180"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=61340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=61340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=61340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}