{"id":61320,"date":"2023-01-12T11:00:51","date_gmt":"2023-01-12T17:00:51","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=61320"},"modified":"2023-01-12T11:00:53","modified_gmt":"2023-01-12T17:00:53","slug":"yasmin-esquivel-mossa-si-copio-parte-sustancial-del-contenido-de-su-tesis-analisis-unam","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/yasmin-esquivel-mossa-si-copio-parte-sustancial-del-contenido-de-su-tesis-analisis-unam\/","title":{"rendered":"<strong>Yasm\u00edn Esquivel Mossa, SI copi\u00f3 parte sustancial del contenido de su tesis, an\u00e1lisis UNAM<\/strong>"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong>El contenido de la resoluci\u00f3n del Comit\u00e9 de la FES Arag\u00f3n ser\u00e1 enviado a la Secretar\u00eda de Educaci\u00f3n P\u00fablica para los fines a que haya lugar.<\/strong><\/li>\n\n\n\n<li><strong>El plagio, es una pr\u00e1ctica inadmisible que continuaran combatiendo.<\/strong><strong><\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Redacci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 12 de enero del 2023.- La Universidad Aut\u00f3noma de M\u00e9xico (UNAM) informa a la comunidad universitaria y sociedad mexicana que del an\u00e1lisis comparado de contenidos, cronolog\u00eda y estilos de escritura, el Comit\u00e9 concluy\u00f3 que la entonces alumna de la FES Arag\u00f3n, Yasm\u00edn Esquivel Mossa, copi\u00f3 parte sustancial del contenido de la tesis presentada un a\u00f1o atr\u00e1s por el alumno de la Facultad de Derecho, \u00c9dgar Ulises B\u00e1ez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El director de la Facultad de Estudios Superiores (FES) Arag\u00f3n comunic\u00f3 a la Rector\u00eda el resultado del an\u00e1lisis realizado por el Comit\u00e9 de integridad acad\u00e9mica y cient\u00edfica de esa entidad, sobre la apropiaci\u00f3n indebida de los textos de las tesis de 1986 y 1987, del entonces estudiante Edgar Ulises B\u00e1ez y de Yasm\u00edn Esquivel Mossa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yasm\u00edn Esquivel Mossa finaliz\u00f3 sus estudios y present\u00f3 su examen profesional ante el jurado designado, recibiendo el voto aprobatorio de todos sus integrantes para obtener el t\u00edtulo que la acredita como Licenciada en Derecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De la interpretaci\u00f3n solicitada a la Oficina de la Abogac\u00eda General se desprende que la normatividad universitaria carece de los mecanismos para invalidar un t\u00edtulo expedido por la Universidad Nacional, a\u00fan y cuando el plagio de una tesis est\u00e9 documentado.&nbsp; <a href=\"http:\/\/www.abogadogeneral.unam.mx\">http:\/\/www.abogadogeneral.unam.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El contenido de la resoluci\u00f3n del Comit\u00e9 de la FES Arag\u00f3n ser\u00e1 enviado a la Secretar\u00eda de Educaci\u00f3n P\u00fablica para los fines a que haya lugar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se ha informado tambi\u00e9n que en la FES Arag\u00f3n est\u00e1 en curso el procedimiento de investigaci\u00f3n administrativa, como lo establecen la legislaci\u00f3n universitaria y los compromisos contractuales, a la profesora Martha Rodr\u00edguez Ortiz, quien fungi\u00f3 como directora de las tesis mencionadas, para que explique las razones de su actuar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La UNAM considera que siempre ser\u00e1 mejor prevenir casos tan lamentables y penosos como \u00e9stos, por lo que en acuerdo con el Colegio de Directores de Facultades y Escuelas, se han tomado ya las primeras medidas en ese sentido, as\u00ed como el estudio de las alternativas que permitan fortalecer nuestra normatividad para prevenir asuntos como el que nos ocupa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Universidad fomenta altos valores como la \u00e9tica y la integridad a quienes conforman la comunidad universitaria. El plagio, es una pr\u00e1ctica inadmisible que continuaran combatiendo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/MG<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La UNAM informa que del an\u00e1lisis comparado de contenidos, cronolog\u00eda y estilos de escritura, el Comit\u00e9 concluy\u00f3 que la entonces alumna de la FES Arag\u00f3n, Yasm\u00edn Esquivel Mossa, copi\u00f3 parte sustancial del contenido de la tesis presentada un a\u00f1o atr\u00e1s por el alumno de la Facultad de Derecho, \u00c9dgar Ulises B\u00e1ez.<\/p>\n","protected":false},"author":3,"featured_media":61321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[51],"tags":[],"class_list":["post-61320","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ejecutivo"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/61320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=61320"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/61320\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/61321"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=61320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=61320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=61320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}