{"id":60193,"date":"2022-12-04T12:22:48","date_gmt":"2022-12-04T18:22:48","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=60193"},"modified":"2023-07-21T19:24:35","modified_gmt":"2023-07-22T00:24:35","slug":"veracruz-con-mil-287-desapariciones-y-423-feminicidios-solo-7-por-ciento-de-casos-en-proceso","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/veracruz-con-mil-287-desapariciones-y-423-feminicidios-solo-7-por-ciento-de-casos-en-proceso\/","title":{"rendered":"Veracruz con mil 287 desapariciones y 423 feminicidios: s\u00f3lo 7 por ciento de casos en proceso"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ahora detienen a dos personas implicadas en la desaparici\u00f3n de Rosa Isela, cuya desaparici\u00f3n caus\u00f3 estupor e indignaci\u00f3n en la entidad&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La entidad es una de las ocho con mayor n\u00famero de desapariciones y asesinatos en el pa\u00eds<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Libertad L\u00f3pez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico*, Veracruz, Ver., 4 de diciembre, 2022.-La Fiscal\u00eda General del Estado, inform\u00f3 la detenci\u00f3n de Gonzalo \u201cN\u201d y Ver\u00f3nica \u201cN\u201d como presuntos responsables del delito de desaparici\u00f3n cometida por particulares en agravio de la v\u00edctima Rosa Isela, joven embarazada que desapareci\u00f3 el 30 de noviembre en el municipio de Veracruz. El estado de&nbsp;Veracruz es una de las&nbsp;ocho entidades donde se concentran m\u00e1s desapariciones de mujeres y ni\u00f1as.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con una investigaci\u00f3n conjunta del Instituto Mexicano de Derechos Humanos y Democracia, el Observatorio Ciudadano Nacional de Feminicidios y Justicia Pro Persona el Estado de M\u00e9xico, la Ciudad de M\u00e9xico, Nuevo Le\u00f3n, Guerrero, Colima, Jalisco, Puebla y Veracruz concentran el 53.13 por ciento de las desapariciones reportadas en todo el pa\u00eds, siendo los focos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los datos del Diagn\u00f3stico de Mujeres Desaparecidas elaborado y puesto a disposici\u00f3n por el organismo dan cuenta de que&nbsp;de&nbsp;2020 a la fecha se ten\u00edan reportadas mil 827 desapariciones de mujeres y ni\u00f1as que representa el 24.66 por ciento de las desapariciones registradas a nivel nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Veracruz, estas desapariciones se concentran en municipios como&nbsp;Xalapa con 102 casos; Veracruz puerto con 100 casos; Coatzacoalcos 44 casos; C\u00f3rdoba 42; Poza Rica con 29 y Orizaba con 24. Estos cinco municipios concentran un 59.46 por ciento de los casos de todo el estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veracruz tiene reportados 423 feminicidios hasta el mes de marzo del 2020 y de este total solo el 7 por ciento hubo una vinculaci\u00f3n a proceso, y se desconocen las carpetas de investigaci\u00f3n, los procesos presentan una cifra muy baja.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/12\/imp-ver-02.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"280\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/12\/imp-ver-02.jpg\" alt=\"\" class=\"wp-image-60195\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Las detenciones en este caso<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de un comunicado la Fiscal\u00eda indic\u00f3 que al momento de su detenci\u00f3n ten\u00edan consigo a una menor reci\u00e9n nacida, la cual fue rescatada sana y salva y ya recibe atenci\u00f3n de las autoridades correspondientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cRespetando sus derechos humanos y el debido proceso ser\u00e1n presentados en audiencia inicial ante el juez de proceso y procedimiento penal oral del distrito judicial de Veracruz, para que defina su situaci\u00f3n jur\u00eddica\u201d, manifest\u00f3 la fiscal\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, la FGE confirm\u00f3 que se localiz\u00f3 el cuerpo sin vida de Rosa Isela, este s\u00e1bado, en el rancho \u201cLos Arrieros\u201d de la localidad Rancho del Padre, del municipio de Medell\u00edn de Bravo, por su asesinato ya se inici\u00f3 una carpeta de investigaci\u00f3n por el delito de feminicidio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La joven de 20 a\u00f1os y con embarazo de 8 meses desapareci\u00f3 el 30 de noviembre en Las Bajadas, luego de que acudiera a una cita que hab\u00eda acordado por Facebook con una se\u00f1ora que le regalar\u00eda ropa para su bebe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su caso caus\u00f3 indignaci\u00f3n en la sociedad y por medio de redes sociales se le buscaba. Fue hasta cerca de las 11 de la ma\u00f1ana cuando la joven fue hallada asesinada en el municipio de Medell\u00edn de Bravo y por la tarde su familia la reconoci\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es de mencionar que la familia de Rosa Isela fue notificada por la ma\u00f1ana de este s\u00e1bado, previo al hallazgo de la joven asesinada, que la beb\u00e9 se encontraba ingresada en el Hospital Infantil de Veracruz, y se encuentran a la espera de que se confirme su identidad para solicitar que se las entreguen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Antecedentes<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con base al estudio referido el rango de edades donde se concentran los casos de ni\u00f1as y mujeres desaparecidas va de los 15 a 19 a\u00f1os con m\u00e1s de 222 casos reportados, seguido del rango de 20 a 24 con 145 casos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a los registros de casos reportados, estos han crecido pues tan solo del 2006 al 2016 se ten\u00edan contabilizados&nbsp;3 mil 600 desapariciones en todo el estado, pero a trav\u00e9s de colectivos, acompa\u00f1amiento de casos y la denuncia aument\u00f3 la cifra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El documento, elaborado con financiaci\u00f3n del Fondo Fiduciario de la ONU para Eliminar la Violencia contra la Mujer, detalla que los delitos de desaparici\u00f3n y de trata son frecuentemente asociados, sin embargo, no siempre existe un nexo formal entre ambos delitos. \u201cPor un lado, es cada vez m\u00e1s frecuente que se realicen denuncias por la desaparici\u00f3n de mujeres, adolescentes y ni\u00f1as, pero no as\u00ed por el delito de trata, ya que en ocasiones no se puede demostrar la ocurrencia del tipo penal de trata\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/twitter.com\/intent\/tweet?text=Rosa+Isela+fue+presuntamente+asesinada+por+quien+la+enganch%C3%B3+en+facebook+para+robarle+su+beb%C3%A9&amp;url=https%3A%2F%2Fbillieparkernoticias.com%2Frosa-isela-fue-presuntamente-asesinada-por-quien-la-engancho-en-facebook-para-robarle-su-bebe%2F&amp;via=Billie+Parker+Noticias\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/billieparkernoticias.com\/rosa-isela-fue-presuntamente-asesinada-por-quien-la-engancho-en-facebook-para-robarle-su-bebe\/&amp;media=https:\/\/billieparkernoticias.com\/wp-content\/uploads\/2022\/12\/Rosa-Icela-Castro-Va.jpg&amp;description=Rosa+Isela+fue+presuntamente+asesinada+por+quien+la+enganch%C3%B3+en+facebook+para+robarle+su+beb%C3%A9\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/api.whatsapp.com\/send?text=Rosa+Isela+fue+presuntamente+asesinada+por+quien+la+enganch%C3%B3+en+facebook+para+robarle+su+beb%C3%A9%20%0A%0A%20https:\/\/billieparkernoticias.com\/rosa-isela-fue-presuntamente-asesinada-por-quien-la-engancho-en-facebook-para-robarle-su-bebe\/\"><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/12\/imp-ver-03.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"539\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/12\/imp-ver-03.jpg\" alt=\"\" class=\"wp-image-60194\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/billieparkernoticias.com\/wp-content\/uploads\/2022\/12\/Rosa-Icela-Castro-Va.jpg\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rosa Isela \u201cN\u201d, ten\u00eda 20 a\u00f1os y estaba embarazada. Fue reportada como desaparecida hace 5 d\u00edas en el municipio de Veracruz. De acuerdo con la fiscal\u00eda, una beb\u00e9 fue rescatada con vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a la investigaci\u00f3n, la joven fue aparentemente fue enga\u00f1ada, en un mensaje por internet; le ofrecieron donar ropa para el beb\u00e9 que estaba nacer, seg\u00fan la indagaci\u00f3n, fue una mujer quien la enga\u00f1\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;La familia de Rosa Icela N, narr\u00f3 que el pasado 30 de noviembre Rosa Isela desaparece tras reunirse con una mujer a la que conoci\u00f3 en redes sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoridades tuvieron acceso a las c\u00e1maras de seguridad de la zona conurbada de Veracruz, y ah\u00ed observaron su encuentro con una mujer que la amenaz\u00f3 por la espalda y luego la oblig\u00f3 a subir a un auto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rosa Isela desapareci\u00f3 en la prolongaci\u00f3n de la calle Las Bajadas del municipio de Veracruz; su cuerpo, sin la beb\u00e9 apareci\u00f3 en el rancho \u201cLos Arrieros\u201d de la localidad Rancho del Padre del municipio de Medell\u00edn de Bravo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoridades dijeron que la detenci\u00f3n de dos personas, fue resultado de la investigaci\u00f3n, una entre el 7 por ciento apenas de todos los casos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">*Con informaci\u00f3n de Testigo P\u00farpura y El Diario de Xalapa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fiscal\u00eda General del Estado, inform\u00f3 la detenci\u00f3n de Gonzalo \u201cN\u201d y Ver\u00f3nica \u201cN\u201d como presuntos responsables del delito de desaparici\u00f3n cometida por particulares en agravio de la v\u00edctima Rosa Isela, joven embarazada que desapareci\u00f3 el 30 de noviembre en el municipio de Veracruz.<\/p>\n","protected":false},"author":3,"featured_media":60196,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[693,47],"tags":[],"class_list":["post-60193","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-no-mas-impunidad"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/60193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=60193"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/60193\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/60196"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=60193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=60193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=60193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}