{"id":6016,"date":"2018-11-05T18:43:13","date_gmt":"2018-11-05T18:43:13","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=6016"},"modified":"2023-07-21T14:34:16","modified_gmt":"2023-07-21T19:34:16","slug":"aniversario-luctuoso-de-olimpe-de-gouges","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/aniversario-luctuoso-de-olimpe-de-gouges\/","title":{"rendered":"Aniversario luctuoso de Olimpe de Gouges"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">3 de Noviembre<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"> Autora de La Declaraci\u00f3n de Derechos de la Mujer y de la Ciudadana<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/semmexico.com\/gallery-post.php?id=6296#\">Martha Barrag\u00e1n<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. 05 de Noviembre 2018.- 3 de noviembre, aniversario luctuoso de Olimpe de Gouges, autora de La Declaraci\u00f3n de Derechos de la Mujer y de la Ciudadana. (1748-1793)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Olimpia de Gouges contribuy\u00f3 a que otras mujeres gozaramos de los derechos que se nos negaban por el simple hecho de considerar que \u00e9ramos inferiores a los hombres y le cost\u00f3 la vida, fue condenada a morir por \u00abtraicionar a la revoluci\u00f3n\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>3 de Noviembre Autora de La Declaraci\u00f3n de Derechos de la Mujer y de la Ciudadana Martha Barrag\u00e1n SemM\u00e9xico. 05 de Noviembre 2018.- 3 de noviembre, aniversario luctuoso de Olimpe de Gouges, autora de La Declaraci\u00f3n de Derechos de la Mujer y de la Ciudadana. (1748-1793) Olimpia de Gouges contribuy\u00f3 a que otras mujeres gozaramos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6017,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[689,80,1],"tags":[],"class_list":["post-6016","post","type-post","status-publish","format-standard","has-post-thumbnail","category-689","category-martha-barragan","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/6016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=6016"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/6016\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/6017"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=6016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=6016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=6016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}