{"id":59945,"date":"2022-11-30T14:44:13","date_gmt":"2022-11-30T20:44:13","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=59945"},"modified":"2023-07-21T19:23:29","modified_gmt":"2023-07-22T00:23:29","slug":"la-convencion-belem-do-para-compromiso-de-los-paises-para-proteger-los-derechos-humanos-de-las-mujeres-rosa-maria-alvarez","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/la-convencion-belem-do-para-compromiso-de-los-paises-para-proteger-los-derechos-humanos-de-las-mujeres-rosa-maria-alvarez\/","title":{"rendered":"La Convenci\u00f3n Belem do Par\u00e1 compromiso de los pa\u00edses para proteger los derechos humanos de las mujeres: Rosa Mar\u00eda \u00c1lvarez"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>D\u00eda 5 de activismo.<\/strong><\/li><li><strong>Es muy importante llamar a cuentas al Estado Mexicano por las violaciones que se cometen contra las mujeres en un pa\u00eds como el nuestro, que lejos de haber disminuido la violencia contra las mujeres va en aumento.<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Elda Montiel<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 30 de noviembre del 2022.- En un pa\u00eds en que se ha vulnerado los derechos humanos de las mujeres como en M\u00e9xico, donde la violencia va en aumento, es importante llamar a cuentas al Estado Mexicano, lo que se establece en la Convenci\u00f3n para prevenir, sancionar y erradicar la violencia contra las mujeres, conocida como la Convenci\u00f3n Belem do Par\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La doctora Rosa Mar\u00eda \u00c1lvarez de la Federaci\u00f3n Mexicana de Universitarias (FEMU) en la capsula del D\u00eda 5 de la campa\u00f1a de \u201cLos 16&nbsp; d\u00edas de activismo contra la violencia de G\u00e9nero\u201d que se transmite todos los d\u00edas a partir del 25 de noviembre y hasta el 10 de diciembre en el portal del Museo de la Mujer abordo el tema \u201cLegislaci\u00f3n Regional\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3 la importancia de la Convenci\u00f3n Interamericana &nbsp;para prevenir, sancionar y erradicar la violencia contra las mujeres, mejor conocida como la C<em>onvenci\u00f3n<\/em>&nbsp;Bel\u00e9m <em>do Par\u00e1<\/em> llamada as\u00ed por haberse firmado en esa ciudad brasile\u00f1a en 1994.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mencion\u00f3 el a\u00f1o 1994 porque en los \u00e1mbitos internacionales y, particularmente en el Regional, dijo, \u201cnos percatamos de que existe un grave problema de violencia contra las mujeres mismo que hab\u00eda estado aceptado como algo culturalmente vigente en nuestras sociedades sobre todo la violencia familiar\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Precis\u00f3 que la Convenci\u00f3n de Belem Do Par\u00e1 fue planteada en el \u00e1mbito latinoamericano como un compromiso pol\u00edtico para luchar contra la violencia contra las mujeres<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es la primera vez que se considera que la violencia contra las mujeres es una violaci\u00f3n de sus derechos humanos, en este tratado se han dado la pauta para posteriormente en cada uno de los pa\u00edses, y particularmente en M\u00e9xico establecer todo el marco jur\u00eddico en contra de la violencia contra las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se consider\u00f3 entonces que hab\u00eda tres tipos de violencia; la f\u00edsica, la sexual y la psicol\u00f3gica, estas violencias se pod\u00edan dar en la vida privada, esto es importante porque la violaci\u00f3n de los derechos humanos contra las mujeres &nbsp;se consideraba solo cuando el Estado participaba en un acto en contra de un particular.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la mayor\u00eda de los casos es un particular el quien ejerce esa violencia contra las mujeres, un esposo, un padre un hermano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Convenci\u00f3n establece la violaci\u00f3n de los derechos de las mujeres tanto en la vida privada como en la vida p\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro tercer aspecto es la violencia perpetrada o tolerada por el Estado, porque muchas veces las autoridades no toman las decisiones conducentes, lo que da lugar a muchas resoluciones de la Corte Interamericana de los Derechos Humanos (CIDH) en el que se analizan las violaciones a los derechos de las mujeres por violencia, en las cuales se puede considerar que el Estado no ha cumplido con la obligaci\u00f3n de proteger a las mujeres adecuadamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es muy importante llamar a cuentas al Estado Mexicano por las violaciones que se cometen contra las mujeres en un pa\u00eds como el nuestro, que lejos de haber disminuido la violencia contra las mujeres va en aumento, expres\u00f3. &nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n llam\u00f3 la atenci\u00f3n que no se ha atendido el aspecto educativo, esta violencia se puede erradicar con un programa de educaci\u00f3n s\u00f3lida que muestre la resoluci\u00f3n de conflictos, entre las personas, sobre todo a las que forman el n\u00facleo familiar, de muchas formas diferentes a la violencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/MG<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es muy importante llamar a cuentas al Estado Mexicano por las violaciones que se cometen contra las mujeres en un pa\u00eds como el nuestro, que lejos de haber disminuido la violencia contra las mujeres va en aumento.<\/p>\n","protected":false},"author":3,"featured_media":59946,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[670,693],"tags":[],"class_list":["post-59945","post","type-post","status-publish","format-standard","has-post-thumbnail","category-25n-2022","category-693"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/59945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=59945"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/59945\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/59946"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=59945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=59945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=59945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}