{"id":59420,"date":"2022-11-24T14:16:07","date_gmt":"2022-11-24T20:16:07","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=59420"},"modified":"2023-07-21T19:22:49","modified_gmt":"2023-07-22T00:22:49","slug":"politiqueria-gana-en-escuela-de-parteras","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/politiqueria-gana-en-escuela-de-parteras\/","title":{"rendered":"<strong>Politiquer\u00eda gana en Escuela de Parteras<\/strong>"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Alumnas \u201cpermiten\u201d que siga la abogada como Directora.<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mart\u00edn Mart\u00ednez Olvera<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/Ceprovysa, Tlapa de Comonfort, Guerrero, 24 de noviembre del 2022.- El movimiento de dignificaci\u00f3n de la Escuela de Parteras del estado de Guerrero que iniciaron alumnas ind\u00edgenas provenientes de las etnias Nahua, Mixteca y Tlapaneca, fue \u201cganado\u201d por la directora Rubicelia Arreola Vargas, que continuar\u00e1 al frente de la instituci\u00f3n, y por el delegado de Gobierno del Estado en esta regi\u00f3n de la Monta\u00f1a, Jos\u00e9 Baz\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Silenciadas desde la ma\u00f1ana de este mi\u00e9rcoles, convocadas a una reuni\u00f3n a las 11, luego de que su condici\u00f3n de vulnerabilidad por ser mujeres que buscaran mover a la abogada que despacha como directora, fuera mal vista al no darles atenci\u00f3n, tras 18 d\u00edas de movilizaci\u00f3n luego de ser arrojadas a la calle al negarles dormitorio y posteriormente una constancia para que cobraran sus becas bienestar, las alumnas firmaron el documento que las hace aceptar los siguientes acuerdos:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Primero: Que en este momento las estudiantes entregaran al delegado de gobierno Jos\u00e9 Baz\u00e1n Gonz\u00e1lez el pliego petitorio que solicitan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo: La propuesta de las estudiantes, es que se quede la directora de la escuela de parteras, pero que revisen al personal que tenga contacto con las estudiantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tercero: La pr\u00f3xima reuni\u00f3n se llevar\u00e1 a cabo el d\u00eda viernes 25 de noviembre de 2022, a las 12:00 horas, en gobernaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El documento, donde la directora firma en masculino su t\u00edtulo \u201cLcdo\u201d, fue tambi\u00e9n firmado por el delegado regional de Gobernaci\u00f3n, Lcdo. Jorge Rodr\u00edguez Ponce, el delegado regional de Gobierno, Jos\u00e9 Baz\u00e1n Gonz\u00e1lez, y entre otros funcionarios como Leobigildo Arriaga Reyes, promotor de Derechos Ind\u00edgenas, as\u00ed como por algunas alumnas y madres de familia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las alumnas de la Escuela de Parteras fueron \u201cinvitadas\u201d a no hablar ante los medios, ni tener contacto con ning\u00fan grupo de apoyo. Todo indica que el posicionamiento de \u201csomos de diferentes comunidades lejanas ind\u00edgenas y no conocemos la ciudad\u201d las dej\u00f3 en estado de indefensi\u00f3n, la abogada que no tiene el perfil para dirigir la Escuela de Parteras, contin\u00faa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La experta abogada ha trabajo en la Ciudad de las Mujeres donde demand\u00f3 en el 2017, con un paro laboral, pago de salarios. (SURIANA RADIO 107.9 FM XHSCDG)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/MG<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/politiqueria-parteras-02.jpg\"><img decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/politiqueria-parteras-02-765x1024.jpg\" alt=\"\" class=\"wp-image-59422\"\/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El movimiento de dignificaci\u00f3n de la Escuela de Parteras del estado de Guerrero que iniciaron alumnas ind\u00edgenas provenientes de las etnias Nahua, Mixteca y Tlapaneca, fue \u201cganado\u201d por la directora Rubicelia Arreola Vargas<\/p>\n","protected":false},"author":3,"featured_media":59421,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[693,51],"tags":[],"class_list":["post-59420","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-ejecutivo"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/59420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=59420"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/59420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/59421"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=59420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=59420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=59420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}