{"id":58421,"date":"2022-11-07T16:14:51","date_gmt":"2022-11-07T22:14:51","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=58421"},"modified":"2023-07-21T19:20:13","modified_gmt":"2023-07-22T00:20:13","slug":"piden-intervencion-de-la-fgr-para-localizar-a-deudor-alimentario","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/piden-intervencion-de-la-fgr-para-localizar-a-deudor-alimentario\/","title":{"rendered":"Piden intervenci\u00f3n de la FGR para localizar a deudor alimentario"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Contaron con el apoyo de las mujeres de Amicas Curiae, una colectiva que da seguimiento a casos de violencia vicaria y de deudores alimentarios<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>Mercedes Mart\u00ednez<\/strong><br>SemM\u00e9xico, Ciudad de M\u00e9xico, 7 de noviembre del 2022.- Alrededor de cuarenta mujeres con vestidos blancos acudieron a las instalaciones de la Fiscal\u00eda General de la Rep\u00fablica (FGR) para solicitar su intervenci\u00f3n en la localizaci\u00f3n de Leonel \u201cN\u00bb, funcionario p\u00fablico se\u00f1alado por su expareja como deudor alimentario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Las mujeres forman parte de Amicas Curiae, una colectiva que da seguimiento a casos de violencia vicaria y de deudores alimentarios, es decir, de hombres -principalmente- o mujeres que se niegan a pagar la pensi\u00f3n alimenticia de sus hijas e hijos.<br>En esta ocasi\u00f3n, la organizaci\u00f3n acudi\u00f3 a la FGR para entregar un oficio dirigido a Mar\u00eda de la Luz Mijangos Borja, titular de la Fiscal\u00eda Especializada en Materia de Combate a la Corrupci\u00f3n. Esto, con el fin de solicitar su intervenci\u00f3n y ayudar a dar con el paradero del deudor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>De acuerdo a la abogada y parte acusadora, Ingrid Tapia Guti\u00e9rrez, Leonel \u201cN\u00bb dej\u00f3 de brindar manutenci\u00f3n a sus hijos desde el a\u00f1o 2006, y ejerci\u00f3 violencia vicaria y psicol\u00f3gica en su contra. \u201cA m\u00ed me parece una burla que un servidor p\u00fablico no sea localizado\u201d, expres\u00f3 ante medios de comunicaci\u00f3n a las afueras de la FGR.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Tapia Guti\u00e9rrez y el colectivo entregaron una denuncia de hechos contra Leonel \u201cN\u00bb, \u201cya que en casi veinte a\u00f1os no ha cubierto pensi\u00f3n y sigue procesalmente oculto, a pesar de su notoriedad p\u00fablica como funcionario de la Secretar\u00eda de Hacienda y Cr\u00e9dito P\u00fablico\u201d, inform\u00f3 la organizaci\u00f3n en un comunicado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Claudia S\u00e1nchez, abogada de la organizaci\u00f3n, a\u00f1adi\u00f3 que Leonel \u201cN\u00bb funge como coordinador de asesores del Secretario de Hacienda, sin embargo, piden que esta informaci\u00f3n sea confirmada por las autoridades correspondientes. \u201cEs lo que venimos a pedir, que nos digan exactamente el lugar donde trabaja, sabemos que trabaja en el gobierno federal. Necesitamos saber d\u00f3nde para poder notificarlo y que responda con sus obligaciones alimentarias\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/Screenshot_20221107-160907_Office.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"983\" height=\"229\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/Screenshot_20221107-160907_Office.jpg\" alt=\"\" class=\"wp-image-58422\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La organizaci\u00f3n identific\u00f3 al caso de Ingrid como Caso 922. Desde el a\u00f1o 2006 el se\u00f1alado incumpli\u00f3 sus obligaciones paternas de crianza y manutenci\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDurante m\u00e1s de diecis\u00e9is a\u00f1os el agresor, con auxilio de terceros y de autoridades, despleg\u00f3 conductas de ocultamiento procesal para evitar que se le exigiera el cumplimiento de sus obligaciones\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\u201cDespu\u00e9s de tres a\u00f1os de b\u00fasqueda en diversos domicilios falsos, el Juzgado 14 de lo Familiar de la Ciudad de M\u00e9xico logr\u00f3 su llamamiento por edictos; mientras que en los juicios promovidos por sus hijos, desde a\u00f1os atr\u00e1s, se sigue enfrentando el ocultamiento del demandado\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>En su p\u00e1gina web, el colectivo narra que \u201cen el a\u00f1o de 2006, Leonel \u201cN\u00bb agredi\u00f3 f\u00edsica y psicol\u00f3gicamente a sus tres hijos como mecanismo de lesi\u00f3n en contra de su c\u00f3nyuge\u201d. Ingrid sac\u00f3 del domicilio a sus hijos y tuvo que resguardarse en hoteles durante dos semanas. \u201cEl agresor les despoj\u00f3 de todos los bienes muebles e inmuebles acumulados durante casi quince a\u00f1os de esfuerzo\u201d. El se\u00f1alado \u201cjam\u00e1s volvi\u00f3 a entablar comunicaci\u00f3n con sus hijos\u201d y \u201cabandon\u00f3 la totalidad de sus deberes de crianza y manutenci\u00f3n\u201d.<br>Amicas Cuerie dio a conocer que Leonel fue inhabilitado por corrupci\u00f3n en 2006, y se reincorpor\u00f3 al servicio p\u00fablico en marzo del a\u00f1o 2015. Sin embargo, la demandante y sus hijos no han tenido acceso al pago de las manutenciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>En una consulta expr\u00e9s a la plataforma de N\u00f3mina Transparente de la Administraci\u00f3n P\u00fablica Federal se muestra un registro a nombre de Leonel \u201cN\u00bb quien ocupa un puesto actual como \u00abEventual Jefe de Unidad\u00bb en la Secretar\u00eda de Hacienda y Cr\u00e9dito P\u00fablico con un sueldo bruto mensual de 161 mil 439 pesos.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/IMG-20221107-WA0009.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" data-id=\"58427\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/IMG-20221107-WA0009.jpg\" alt=\"\" class=\"wp-image-58427\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/IMG-20221107-WA0005.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" data-id=\"58424\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/IMG-20221107-WA0005.jpg\" alt=\"\" class=\"wp-image-58424\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/IMG-20221107-WA0006.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" data-id=\"58423\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/IMG-20221107-WA0006.jpg\" alt=\"\" class=\"wp-image-58423\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/IMG-20221107-WA0008.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1600\" data-id=\"58428\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/IMG-20221107-WA0008.jpg\" alt=\"\" class=\"wp-image-58428\"\/><\/a><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Tras la entrega del oficio en la FGR, integrantes de Amicas Curie realizaron una marcha sobre Paseo de Reforma hasta la Glorieta del \u00c1ngel de la Independencia, en la Ciudad de M\u00e9xico, con la finalidad de visibilizar el caso y solicitar el apoyo de las autoridades correspondientes que permita dar con la ubicaci\u00f3n de la parte se\u00f1alada.<br>SEM\/MG<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contaron con el apoyo de las mujeres de Amicas Curiae, una colectiva que da seguimiento a casos de violencia vicaria y de deudores alimentarios<\/p>\n","protected":false},"author":3,"featured_media":58426,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[693,54],"tags":[149],"class_list":["post-58421","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-mujeres","tag-mujeres"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/58421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=58421"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/58421\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/58426"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=58421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=58421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=58421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}