{"id":58154,"date":"2022-11-02T14:48:16","date_gmt":"2022-11-02T20:48:16","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=58154"},"modified":"2023-07-21T19:20:22","modified_gmt":"2023-07-22T00:20:22","slug":"juego-de-palabras-el-servilismo-de-la-cndh","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/juego-de-palabras-el-servilismo-de-la-cndh\/","title":{"rendered":"Juego de Palabras| El servilismo de la CNDH."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Yaneth Tamayo \u00c1valos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Quer\u00e9taro, Qro., 2 de noviembre, 2022.- El proyecto denominado 4t de Andr\u00e9s Manuel L\u00f3pez Obrador, se ha caracterizado por un clientelismo pol\u00edtico que atenta contra la verdadera democracia y la representaci\u00f3n pol\u00edtica. *<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El uso discrecional de poder y el servilismo de instituciones y partidos pol\u00edticos ponen en riesgo la democracia, al dejar de lado la voluntad de la ciudadan\u00eda y ejercer a forma de dominaci\u00f3n pol\u00edtica la imposici\u00f3n reformas que solo benefician los intereses de un gobierno en turno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La insistencia de eliminar los contrapesos que evitan el abuso de poder y la intromisi\u00f3n en los procesos democr\u00e1ticos, vali\u00e9ndose del uso de instituciones para amedrentar a dirigentes de partidos y obtener el apoyo en las C\u00e1maras del Congreso, es el reflejo de un gobierno que camina hacia un r\u00e9gimen autoritario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, resulta reprobable que ahora se utilice a la Comisi\u00f3n Nacional de Derechos Humanos (CNDH), para pronunciarse sobre un tema en el cual no tiene competencia, resultando absurdo que el propio \u00f3rgano aut\u00f3nomo se preste a emitir una supuesta \u201crecomendaci\u00f3n\u201d que carece de relevancia. **<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien, la CNDH reconoce que en el pasado la falta de limitaci\u00f3n al poder de partidos pol\u00edticos y el manejo faccioso de instituciones en los procesos electorales trajo consigo la creciente deslegitimaci\u00f3n de las instituciones y de la pol\u00edtica en general.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A la titular, se le olvid\u00f3 que los \u00f3rganos constitucionales aut\u00f3nomos fueron creados para fungir como contrapesos ante la falta de esa limitaci\u00f3n. Y que estos \u00f3rganos t\u00e9cnicos de control, no se pueden guiar por intereses partidistas o coyunturales, pues su funcionamiento no solo debe ser independiente de los poderes tradicionales, sino de los partidos o de otros grupos o factores reales de poder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Funci\u00f3n que claramente no est\u00e1 llevando a cabo, ya que su posicionamiento como titular de la CNDH se ve inclinado al actual sistema pol\u00edtico obradorista, por lo que resulta incongruente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De ah\u00ed que, tales acciones pongan en evidencia la intolerancia y la desbordante convicci\u00f3n personal con la que dichos pol\u00edticos y funcionarios ejercen su labor legislativa e institucional, sometiendo a una constante tensi\u00f3n lo amparado por la constituci\u00f3n, al provocar una contradicci\u00f3n que afecta a los derechos fundamentales tutelados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien, el cambio en los modelos pol\u00edticos, econ\u00f3micos y democr\u00e1ticos en los gobiernos, atienden a una forma de legitimar su ideolog\u00eda pol\u00edtica y el poder, estos deben estar fijados por l\u00edmites para que sus fines u objetivos pol\u00edticos no trastoquen la democracia y soberan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las actuales reformas constitucionales y la err\u00e1tica ejecuci\u00f3n de pol\u00edticas p\u00fablicas solo deval\u00faan los derechos de las y los ciudadanos, someti\u00e9ndolos a las reglas de su mercado pol\u00edtico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ejercicio del poder pol\u00edtico otorgado a los representantes en la toma de decisiones no debe ser absoluto ni permanente, las democracias representativas precisamente se caracterizan por la divisi\u00f3n del poder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depositar un poder limitado en el gobernante y establecer vigilantes, ayudar\u00e1 a resolver el conflicto que existe entre la necesidad de dotar de poder a un individuo para la toma de decisiones y la posibilidad de que este sobreponga sus intereses a los de la mayor\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">* El t\u00e9rmino de clientelismo se refiere al reparto de favores, bienes materiales, utilizaci\u00f3n de recursos p\u00fablicos o dinero a cambio de votos o apoyo pol\u00edtico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">** Art\u00edculo 102 constitucional. Los organismos de protecci\u00f3n de los derechos humanos que ampara el orden jur\u00eddico mexicano, conocer\u00e1n de quejas en contra de actos u omisiones de naturaleza administrativa provenientes de cualquier autoridad o servidor p\u00fablico, que violen estos derechos. Estos organismos no ser\u00e1n competentes trat\u00e1ndose de asuntos electorales y jurisdiccionales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El proyecto denominado 4t de Andr\u00e9s Manuel L\u00f3pez Obrador, se ha caracterizado por un clientelismo pol\u00edtico que atenta contra la verdadera democracia y la representaci\u00f3n pol\u00edtica. <\/p>\n","protected":false},"author":3,"featured_media":38546,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[693,103,35,93],"tags":[],"class_list":["post-58154","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-juego-de-palabras","category-opinion","category-yaneth-tamayo-avalos"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/58154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=58154"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/58154\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/38546"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=58154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=58154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=58154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}