{"id":5813,"date":"2019-04-29T14:53:47","date_gmt":"2019-04-29T14:53:47","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=5813"},"modified":"2023-07-21T14:48:42","modified_gmt":"2023-07-21T19:48:42","slug":"solo-11-de-23-instancias-municipales-presentaron-su-informe-trimestral-de-acciones-a-favor-de-las-mujeres","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/solo-11-de-23-instancias-municipales-presentaron-su-informe-trimestral-de-acciones-a-favor-de-las-mujeres\/","title":{"rendered":"Solo 11 de 23, instancias municipales, presentaron su informe trimestral de acciones a favor de las mujeres."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.semmexico.com\/gallery-post.php?id=8012#\">Josefina Aguilar Pastor,<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Semm\u00e9xico. Chilpancingo, Guerrero. 29 de abril de 2019.- Persiste la resistencia de funcionarios y funcionarias a participar para superar la Alerta de Violencia de G\u00e9nero (AVG), solo once de 23, instancias&nbsp; municipales, que integran el Sistema Municipal para Prevenir, Atender, Sancionar y Erradicar la Violencia contra las Mujeres del ayuntamiento de Chilpancingo, presentaron su informe trimestral de acciones a favor de las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este lunes se llev\u00f3 a cabo la Primera Sesi\u00f3n Extraordinaria del Sistema Municipal para Prevenir, Atender, Sancionar y Erradicar la Violencia contra las Mujeres del municipio de Chilpancingo, la cual es presidida por el Secretario General, Antonio Orozco Guadarrama, a la que fueron convocadas y convocados, los y las titulares de las distintas \u00e1reas municipales que conforman este \u00f3rgano, y algunas estatales, entre ellas, el Tribunal Superior de Justicia (TSJ), la Fiscal\u00eda General del Estado (FGE), y la Comisi\u00f3n de Derechos Humanos del Estado de Guerrero&nbsp; (CDHEG).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marina Reyna Aguilar, presidenta de la Asociaci\u00f3n Guerrerense contra la Violencia hacia las Mujeres, hizo notar la ausencia de los titulares de las distintas dependencias municipales; situaci\u00f3n que refiri\u00f3, tambi\u00e9n se da en el Sistema Estatal, lo que provoc\u00f3 que la semana pasada, las representantes de las asociaciones civiles, decidieran retirarse de la sesi\u00f3n, por la falta de seriedad, inter\u00e9s y respeto a un problema tan fuerte en el Estado de Guerrero, y el municipio de Chilpancingo, como es la violencia hacia las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, pidi\u00f3 al presidente y secretaria ejecutiva, hacer llamados de atenci\u00f3n, incluso extra\u00f1amientos, a aquellos titulares de las instancias municipales que falten a las sesiones, tambi\u00e9n pidi\u00f3 que dichos funcionarios y funcionarias, designen a un solo suplente, para aquellas ocasiones que no puedan acudir, debido a que suelen enviar a una y otra persona, y no dan un seguimiento puntual ni de las acciones ni acuerdos establecidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vianey Castorena Tenorio,&nbsp; S\u00edndica Procuradora, reconoci\u00f3 que&nbsp; persiste una resistencia por parte del funcionariado, y junto con el Secretario General, Antonio Orozco Guadarrama, coincidieron en la necesidad de tomar medidas para que las y los titulares acudan a estas sesiones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De las dependencias que presentaron informe, fueron las direcciones de Atenci\u00f3n a la Mujer, de educaci\u00f3n, Cultura y Artes, y diversidad sexual; de las Secretar\u00edas de Seguridad P\u00fablica, turismo, Finanzas y Administraci\u00f3n, y de Servicios Municipales; las coordinaciones de Prevenci\u00f3n del Delito y del Programa especial de Centros de Integraci\u00f3n Familiar; del Instituto Municipal de la Juventud; de la Procuradur\u00eda de la Defensa del Menor y la Familia as\u00ed como de la regidur\u00eda de participaci\u00f3n de la mujer y Cultura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No presentaron informe, la Segunda sindicatura, la Secretar\u00eda y de Desarrollo Social \u2013 de la cual no acudi\u00f3 la titular ni envi\u00f3 representante-, lo mismo que la Subsecretar\u00eda; Secretar\u00eda de Salud P\u00fablica; la direcci\u00f3n de comunicaci\u00f3n social, y el DIF Municipal. La Primera Sindica Vianey Castorena, dijo que no presentaba un informe concret\u00f3, debido a que su \u00e1rea abarcaba todo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las y los representantes de cada una de las dependencias que acudieron, dieron a conocer las actividades que han realizado del mes de febrero, en que se reinstal\u00f3 a la fecha.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En \u00e9sta misma sesi\u00f3n, aprobaron por unanimidad, la integraci\u00f3n de dos nuevas organizaciones; \u201cKaniche Eslava\u201d, y la \u201cCoalici\u00f3n&nbsp; Nacional de Mujeres Rurales\u201d, representadas por Beatriz Eslava Borja y Erika Salinas Valadez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eslava Borja, tambi\u00e9n pidi\u00f3 respeto a la mesa de trabajo, por parte de los funcionarios y funcionarias, al se\u00f1alar que la violencia en el municipio de Chilpancingo va al alza, y la indiferencia por parte de los encargados de aplicar las pol\u00edticas p\u00fablicas, en nada abona para superar la Alerta de Violencia de G\u00e9nero.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Josefina Aguilar Pastor, Semm\u00e9xico. Chilpancingo, Guerrero. 29 de abril de 2019.- Persiste la resistencia de funcionarios y funcionarias a participar para superar la Alerta de Violencia de G\u00e9nero (AVG), solo once de 23, instancias&nbsp; municipales, que integran el Sistema Municipal para Prevenir, Atender, Sancionar y Erradicar la Violencia contra las Mujeres del ayuntamiento de Chilpancingo, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5814,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[690,51],"tags":[],"class_list":["post-5813","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-ejecutivo"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/5813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=5813"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/5813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/5814"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=5813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=5813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=5813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}