{"id":58126,"date":"2022-11-01T10:09:19","date_gmt":"2022-11-01T16:09:19","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=58126"},"modified":"2023-07-21T19:20:22","modified_gmt":"2023-07-22T00:20:22","slug":"la-alerta-de-violencia-de-genero-empieza-a-rendir-frutos","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/la-alerta-de-violencia-de-genero-empieza-a-rendir-frutos\/","title":{"rendered":"La alerta de violencia de g\u00e9nero empieza a rendir frutos"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>La Alerta de Violencia de G\u00e9nero contra las Mujeres por Violencia Feminicida para los municipios de Ju\u00e1rez, Chihuahua, Cuauht\u00e9moc, Hidalgo del Parral y Guadalupe y Calvo del estado de Chihuahua est\u00e1 empezando a rendir frutos.<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Dora Villalobos Mendoza<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Chihuahua, 1 de noviembre del 2022.- Flor Alejandra Corral Requejo, directora de Derechos Humanos e Igualdad de G\u00e9nero del Poder Judicial del Estado, enumera las acciones que ha realizado esta instituci\u00f3n para cumplir con la Alerta de Violencia de G\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSin duda alguna, un factor de relevancia ha sido la voluntad pol\u00edtica y el compromiso por parte de la magistrada Myriam Victoria Hern\u00e1ndez Acosta, presidenta del Tribunal Superior de Justicia y del Consejo de la Judicatura del Poder Judicial del Estado de Chihuahua, a quien agradezco infinitamente el hacer personal esta causa, as\u00ed como la lucha para la erradicaci\u00f3n de las violencias, a trav\u00e9s de la prevenci\u00f3n, atenci\u00f3n, investigaci\u00f3n, sanci\u00f3n y reparaci\u00f3n integral, mediante la procuraci\u00f3n y administraci\u00f3n de una justicia de car\u00e1cter restaurativa\u201d, resalta la funcionaria y detalla algunas de las acciones que ha instrumentado el Poder Judicial para cumplir con la Alerta de Violencia de G\u00e9nero:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Tribunal especializado en violencia de g\u00e9nero en contra de las mujeres y ni\u00f1as<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Una de las acciones m\u00e1s importantes ha sido el fortalecimiento del Tribunal Judicial Especializado en Atenci\u00f3n a la Violencia de G\u00e9nero que opera en Ciudad Ju\u00e1rez bajo un enfoque de g\u00e9nero e inclusi\u00f3n social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El prop\u00f3sito del Poder Judicial es ampliar esta figura en los diversos distritos judiciales, priorizando en un primer momento a los cinco municipios donde se emiti\u00f3 la Declaratoria de Alerta por Violencia de G\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Ciudad Ju\u00e1rez, el Tribunal Judicial Especializado opera con siete jueces y juezas, personal de apoyo, equipo de c\u00f3mputo y salas de audiencias necesarias para ejercer la sensible funci\u00f3n que realiza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al ser un Tribunal Especializado, conlleva que las juezas y jueces \u00fanicamente conozcan de asuntos o casos en esta materia, lo que ha permitido la profesionalizaci\u00f3n y especializaci\u00f3n con la finalidad de que su funci\u00f3n se concentre en este tema tan delicado e importante.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/marcha-contra-la-violencia.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"479\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/marcha-contra-la-violencia.jpg\" alt=\"\" class=\"wp-image-58132\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El Poder Judicial reconoce el impulso y apoyo que ha tenido por parte de la sociedad civil para la creaci\u00f3n de este \u00f3rgano de justicia, particularmente de la Red Mesa de Mujeres de Ciudad Ju\u00e1rez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En aras de mejorar y ampliar la operatividad de este Tribunal, el Poder Judicial contempla que en los a\u00f1os 2023 y 2024 cuente con un \u00f3rgano jurisdiccional en el Centro de Justicia de la Mujeres de Ciudad Ju\u00e1rez, a fin de evitar actos de revictimizaci\u00f3n y con ello las personas denunciantes no tengan un proceso complejo, transitando en diversas instancias para su atenci\u00f3n y soluci\u00f3n a los procedimientos que enfrentan, ya que es en dicho Centro en donde acuden en un primer momento a denunciar los actos de violencia de los que son v\u00edctimas.\u00a0\u00a0\u00a0El Tribunal Superior de Justicia del Estado, comprometido con la ciudadan\u00eda, implementa los mecanismos necesarios para administrar e impartir justicia dentro del marco legal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Tribunal especializado en medidas de protecci\u00f3n<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El fortalecimiento del Tribunal Especializado en Medidas de Protecci\u00f3n, ubicado en el Distrito Judicial Morelos, en el municipio de Chihuahua, es otra de las acciones que lleva a cabo el Poder Judicial para atender las recomendaciones de la Alerta de Violencia de G\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este Tribunal facilita la justicia para mujeres, adolescentes y ni\u00f1as, mismas que, ante una situaci\u00f3n de violencia, requieren de la protecci\u00f3n del Estado, por lo que, al acudir a dicho Tribunal, el cual opera los 365 d\u00edas del a\u00f1o, las 24 horas del d\u00eda, obtienen medidas de protecci\u00f3n a fin de salvaguardar su integridad f\u00edsica y emocional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las medidas y \u00f3rdenes de protecci\u00f3n o restricci\u00f3n se dictan atendiendo a los principios rectores de buena fe y lealtad procesal, ante la urgencia y necesidad de protecci\u00f3n y salvaguarda de su integridad, por lo que se otorgan estas medidas con una simple comparecencia y, de ser necesario, pueden llevarse a cabo de forma telem\u00e1tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En dichas diligencias se procura resolver la situaci\u00f3n jur\u00eddica de las hijas e hijos de la compareciente, proveyendo la guarda y custodia, as\u00ed como pensi\u00f3n alimenticia a favor de este grupo etario y, de ser necesario, a favor de la compareciente, ambas con car\u00e1cter provisional, a fin de resolver, a\u00fan y cuando sea provisional, de manera integral aspectos mediante la ponderaci\u00f3n de derechos, basados en el principio del inter\u00e9s superior de la infancia y adolescencia, as\u00ed como el derecho humano alimentario y a una vida libre de violencia.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/images-1.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/images-1.jpg\" alt=\"\" class=\"wp-image-58129\" width=\"358\" height=\"200\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">En febrero del 2021 el Poder Judicial firm\u00f3 una serie de compromisos interinstitucionales en materia de medidas de protecci\u00f3n a mujeres v\u00edctimas de violencia con el Instituto Chihuahuense de las Mujeres (ICHMUJERES), la Fiscal\u00eda Especializada en Atenci\u00f3n a Mujeres V\u00edctimas del Delito por Raz\u00f3n de G\u00e9nero (FEM) y el Centro de Justicia para las Mujeres (CEJUM), a fin de establecer mecanismos de articulaci\u00f3n para optimizar el tr\u00e1mite relativo a las solicitudes de medidas de protecci\u00f3n en el estado de Chihuahua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De igual forma, el Poder Judicial cuenta con la colaboraci\u00f3n del Registro Civil del Estado, instancia que en caso de ser necesario informa los datos necesarios relativos al acta de nacimiento o del estado civil de las personas, proporcionando, incluso a trav\u00e9s de un oficio, actas de nacimiento para cumplimentar el objetivo de dicho Tribunal, generando con ello relaciones interinstitucionales con la finalidad de colaborar de la mano para la eliminaci\u00f3n de violencias.&nbsp;&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Bases y lineamientos para investigar y sancionar la violencia laboral, el hostigamiento y el acoso sexual<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Otra acci\u00f3n que est\u00e1 realizando el Poder Judicial para cumplir con la Alerta de Violencia de G\u00e9nero es mejorar la aplicaci\u00f3n de las Bases y Lineamientos para Investigar y Sancionar la Violencia Laboral, el Hostigamiento y el Acoso Sexual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas Bases y Lineamientos fueron creadas para llevar a cabo procedimientos de responsabilidad administrativa de car\u00e1cter interno, en los que se investiga, sustancia y resuelve sobre las probables faltas o responsabilidades administrativas de servidores y servidoras p\u00fablicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El \u00f3rgano investigador denominado Unidad de Investigaci\u00f3n de Responsabilidades Administrativas se encarga de llevar a cabo actos para recabar datos de prueba de una presunta o probable responsabilidad en la materia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Direcci\u00f3n de Derechos Humanos e Igualdad de G\u00e9nero, en aquellos casos que tratan temas relativos a violencia laboral, acoso y hostigamiento sexual, coadyuva en las investigaciones, ofrece acompa\u00f1amiento jur\u00eddico y psicol\u00f3gico a las personas denunciantes y v\u00edctimas, as\u00ed como asesor\u00eda en el proceso, lleva a cabo periciales en psicolog\u00eda por parte de personas expertas en la materia para contar con elementos suficientes que permitan determinar seg\u00fan cada caso en particular el programa de atenci\u00f3n que debe brindar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas Bases y Lineamientos abonan a la erradicaci\u00f3n de las violencias en los centros de trabajo, avanzando con ello en el cumplimiento de la NOM 025 y NOM 035, as\u00ed como en las recomendaciones internacionales y nacionales realizadas al Estado mexicano.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Centro de personas traductoras e int\u00e9rpretes<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La creaci\u00f3n del Centro de Personas Traductoras e Int\u00e9rpretes es una acci\u00f3n m\u00e1s que lleva a cabo el Poder Judicial para atender la Alerta de Violencia de G\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chihuahua, al ser un estado fronterizo, cuenta con una diversidad cultural muy amplia, lo que ha permitido que su poblaci\u00f3n tenga diferentes or\u00edgenes. Por ello el Poder Judicial cre\u00f3 el Centro de Personas Traductoras e Int\u00e9rpretes como parte de la necesidad de juzgar con perspectiva intercultural, para contar con int\u00e9rpretes que no solo conozcan las variantes ling\u00fc\u00edsticas, sino tambi\u00e9n tengan conocimiento en los procesos jur\u00eddicos, as\u00ed como con personas traductoras en los diversos idiomas, para cualquier tipo de procedimientos jurisdiccional, incluso actos preparatorios a juicio. Con ello cumple con la transversalizaci\u00f3n de la perspectiva de g\u00e9nero y con la inclusi\u00f3n social.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Capacitaci\u00f3n<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para el Poder Judicial es fundamental la capacitaci\u00f3n, eje indispensable para cumplir con la Alerta de Violencia de G\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Instituto de Formaci\u00f3n y Actualizaci\u00f3n Judicial (INFORAJ) tiene a su cargo la capacitaci\u00f3n, formaci\u00f3n, actualizaci\u00f3n y profesionalizaci\u00f3n del funcionariado del Poder Judicial, incluyendo en ocasiones al personal de otros Poderes del Estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Direcci\u00f3n de Derechos Humanos e Igualdad de G\u00e9nero, de igual forma, lleva a cabo capacitaci\u00f3n interna y externa a los diversos Poderes del Estado en materia de derechos humanos, violencia laboral, acoso y hostigamiento sexual, as\u00ed como en aquellos temas en los que dada la naturaleza de dicha Direcci\u00f3n se pueda llevar a cabo la capacitaci\u00f3n constante, impulsado programas formativos y de profesionalizaci\u00f3n en materia de juzgar con perspectiva de g\u00e9nero e inclusi\u00f3n social, a trav\u00e9s de un enfoque interseccional y diferenciado.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Poder Judicial cuenta con diversas maestr\u00edas y un programa de doctorado que se imparten en el INFORAJ con el fin de mejorar y ampliar la profesionalizaci\u00f3n del funcionariado jurisdiccional. En dichos programas educativos se ha incorporado la perspectiva de g\u00e9nero y la inclusi\u00f3n social, ampliando con ello la visi\u00f3n derecho humanista de las y los servidores p\u00fablicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos programas de maestr\u00eda y doctorado han sido debidamente autorizados por la Secretar\u00eda de Educaci\u00f3n, cuya matr\u00edcula implica temas de protecci\u00f3n de derechos humanos y aplicaci\u00f3n de una amplia perspectiva de g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n, de manera constante, lleva a cabo capacitaci\u00f3n a trav\u00e9s de talleres, conferencias, cursos, diplomados, entre otros, a todo el funcionariado judicial.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/images-2.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/images-2.jpg\" alt=\"\" class=\"wp-image-58130\" width=\"374\" height=\"192\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Emplea como herramienta los diversos protocolos en materia de acceso a la justicia emitidos por la Suprema Corte de Justicia de la Naci\u00f3n, las convenciones y tratados internacionales en materia de derechos humanos, as\u00ed como toda aquella legislaci\u00f3n aplicable en la materia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cRecientemente se llev\u00f3 a cabo la primera sesi\u00f3n ordinaria del presente a\u00f1o en el Comit\u00e9 Acad\u00e9mico del Poder Judicial, del cual soy parte como titular de la Direcci\u00f3n de Derechos Humanos e Igualdad de G\u00e9nero, habiendo sugerido la implementaci\u00f3n de diversas materias que abonen no solo al cumplimiento de la Declaratoria de Alerta de G\u00e9nero, sino, sobre todas las cosas, a la erradicaci\u00f3n de violencias procurando un cambio cultural y estructural tanto del personal como de la instituci\u00f3n, as\u00ed como la amplitud en los conocimientos que nos ocupan\u201d, enfatiza Corral Requejo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anuncia que, en pr\u00f3ximos d\u00edas, en el marco del D\u00eda Internacional para Erradicar la Violencia en contra de las Mujeres, el 25 de noviembre, se llevar\u00e1n a cabo diversas acciones que abonar\u00e1n a dicho fin.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Mesas t\u00e9cnicas<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Flor Alejandra Corral Requejo reconoce que el Poder Judicial est\u00e1 cumpliendo con la Alerta de Violencia de G\u00e9nero gracias al acompa\u00f1amiento que recibe del Grupo Interinstitucional y Multidisciplinario (GIM) en la Mesa T\u00e9cnica que instalaron de manera conjunta, donde se re\u00fanen de manera peri\u00f3dica, por lo menos una vez al mes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cContar con el apoyo, acompa\u00f1amiento y conocimientos del GIM ha sido de gran val\u00eda, ya que es a trav\u00e9s de esta Mesa que se da el seguimiento a la implementaci\u00f3n de las acciones realizadas\u201d, indica la directora Derechos Humanos e Igualdad de G\u00e9nero del Poder Judicial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sus observaciones y recomendaciones, afirma la funcionaria, abonan para cumplimentar la Declaratoria y no solo eso, sino para ampliar la visi\u00f3n en la mejora de la funci\u00f3n jurisdiccional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Corral Requejo dice que los programas instaurados y otros que el Poder Judicial est\u00e1 proyectando a corto y mediano plazo, tienen la finalidad de avanzar en pol\u00edticas p\u00fablicas para garantizar una justicia con perspectiva de g\u00e9nero, aplicando los diversos ordenamientos internacionales, nacionales y locales, con base en los protocolos que ha emitido por la Suprema Corte de Justicia y mediante el an\u00e1lisis de derecho comparado, que sume a la actividad jurisdiccional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como ejemplo, menciona la creaci\u00f3n del Tribunal Especializado en Violencia de G\u00e9nero que surge como una alternativa para atender las obligaciones del Poder Judicial, misma que tiene como fin primordial que el sistema de justicia en materia penal y familiar aborde adecuada e integralmente las necesidades de las v\u00edctimas en los casos de violencia de g\u00e9nero en contra de mujeres y ni\u00f1as, procurando en todo momento la reparaci\u00f3n del da\u00f1o integral y la impartici\u00f3n de una justicia de car\u00e1cter restaurativa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La declaratoria<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Erika Mendoza Garc\u00eda, integrante del Grupo Interinstitucional y Multidisciplinario (GIM) de la Alerta de Violencia de G\u00e9nero contra las Mujeres por Violencia Feminicida para los municipios de Ju\u00e1rez, Chihuahua, Cuauht\u00e9moc, Hidalgo del Parral y Guadalupe y Calvo del estado de Chihuahua, recuerda que la AVGM es un mecanismo de protecci\u00f3n de los derechos humanos de las mujeres establecido en la Ley General de Acceso de las Mujeres a una Vida Libre de Violencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Gobierno Federal declar\u00f3 la Alerta de Violencia de G\u00e9nero para Chihuahua en agosto del 2021, despu\u00e9s de que el Grupo Interinstitucional y Multidisciplinario (GIM) realiz\u00f3 el Estudio y An\u00e1lisis de la Situaci\u00f3n de los Derechos Humanos de las Mujeres en Chihuahua en 59 sesiones de trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Declaratoria de Alerta de Violencia de G\u00e9nero es un conjunto de acciones de emergencia que deben cumplir los poderes Ejecutivo, Legislativo y Judicial de Chihuahua, as\u00ed como los cinco municipios mencionados, para erradicar la violencia feminicida y la existencia de un agravio comparado que impida el ejercicio pleno de los derechos humanos de las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El objetivo fundamental de la Alerta de Violencia de G\u00e9nero es garantizar la seguridad de las mujeres y el cese de la violencia en su contra, ocasionada por la violaci\u00f3n de sus derechos humanos, en los espacios p\u00fablico y privado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Declaratoria de la Alerta de Violencia de G\u00e9nero tiene como finalidad detener la violencia y erradicarla a trav\u00e9s de acciones gubernamentales de emergencia, conducidas por la Secretar\u00eda de Gobernaci\u00f3n a trav\u00e9s de la Comisi\u00f3n Nacional para Prevenir y Erradicar la Violencia contra las Mujeres (CONAVIM) en el \u00e1mbito federal y en coordinaci\u00f3n con las entidades federativas y los municipios, en este caso con los tres Poderes del Estado de Chihuahua y los municipios de Ju\u00e1rez, Chihuahua, Cuauht\u00e9moc, Hidalgo del Parral y Guadalupe y Calvo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/archivo-feminicidios-cuartoscuro.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"479\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/archivo-feminicidios-cuartoscuro.jpg\" alt=\"\" class=\"wp-image-58127\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Erika Mendoza aclara que la obligaci\u00f3n de garantizar a las mujeres una vida libre de violencia no nace \u00fanicamente de la solicitud de AVGM, sino de las responsabilidades constitucionales e internacionales en materia de derechos humanos a las que todas las autoridades, en sus distintos \u00e1mbitos de competencia, est\u00e1n sujetas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El informe del Grupo Interinstitucional y Multidisciplinario (GIM) identific\u00f3 las violaciones concretas a los derechos humanos de las mujeres que se presentan en los cinco municipios de Chihuahua y tales violaciones identificadas fueron la base para la consolidaci\u00f3n de sus conclusiones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El GIM analiz\u00f3 las causas y consecuencias de las violaciones a los derechos humanos que identific\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de la definici\u00f3n de tales causas y consecuencias estableci\u00f3 sus conclusiones sobre las acciones concretas que deben realizar los cinco municipios para cumplir con sus obligaciones y las reparaciones que deben recibir las v\u00edctimas de tales violaciones, de conformidad con la Ley General de V\u00edctimas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El GIM, a partir de las conclusiones que formul\u00f3 en su informe, establece las propuestas de acciones preventivas, de seguridad y justicia para enfrentar y abatir la violencia feminicida y, en su caso, el agravio comparado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Integraci\u00f3n del grupo de trabajo<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de las instituciones p\u00fablicas como la Comisi\u00f3n Nacional para Prevenir y Erradicar la Violencia contra las Mujeres (CONAVIM), Instituto Nacional para las Mujeres (INMUJERES), Comisi\u00f3n Nacional de Derechos Humanos (CNDH) y el Instituto Chihuahuense para las Mujeres (ICHMUJERES), tambi\u00e9n integran el Grupo Interinstitucional y Multidisciplinario (GIM) cuatro acad\u00e9micas, dos de Chihuahua y dos de \u00edndole nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A nivel nacional participan Gloria Ram\u00edrez Hern\u00e1ndez, representante de la C\u00e1tedra UNESCO de Derechos Humanos de la Universidad Nacional Aut\u00f3noma de M\u00e9xico y Andrea Medina Rosas, quien cuenta con el respaldo del Centro de Estudios e Investigaciones Interdisciplinarias en Ciencias y Humanidades de la Universidad Nacional Aut\u00f3noma de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De Chihuahua colabora Sandra Bustillos Dur\u00e1n, representante de la Universidad Aut\u00f3noma de Ciudad Ju\u00e1rez y la Rosa Ver\u00f3nica Terrazas Aragonez, representante del Instituto de Psicolog\u00eda Forense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Participan tambi\u00e9n representantes de la Oficina de la Alta Comisionada para los Derechos Humanos de Naciones Unidas y la Comisi\u00f3n Estatal de los Derechos Humanos (CEDH) de Chihuahua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como invitadas especiales participan dos integrantes del Movimiento Estatal de Mujeres de Chihuahua: Imelda Marrufo y Erika Mendoza Garc\u00eda.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La sociedad civil de Chihuahua<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien de manera formal la Declaratoria de la Alerta de Violencia de G\u00e9nero parte de las solicitudes que la Comisi\u00f3n Estatal de Derechos Humanos (CEDH) y la Comisi\u00f3n Nacional de Derechos Humanos (CNDH) presentaron ante el INMUJERES para que se investigaran los probables hechos que constituyan violencia feminicida en cinco municipios del estado de Chihuahua, para el Grupo Interinstitucional y Multidisciplinario (GIM) fue necesario reconocer la amplia, persistente y propositiva participaci\u00f3n social y ciudadana que ha tenido el estado de Chihuahua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el curso de las dos \u00faltimas d\u00e9cadas, diversos organismos internacionales de protecci\u00f3n y defensa de derechos de las mujeres han formulado 518 recomendaciones para atender y prevenir la violencia contra las mujeres en el estado de Chihuahua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dichas recomendaciones contemplan el abanico de violencia familiar, laboral, docente, comunitaria, institucional y feminicida. Estas recomendaciones est\u00e1n dirigidas hacia los poderes Ejecutivo, Legislativo y Judicial, as\u00ed como a los niveles municipal, federal y estatal.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/feminicidio_cdjuarez_cesarmartinezlopez_0.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/feminicidio_cdjuarez_cesarmartinezlopez_0.jpg\" alt=\"\" class=\"wp-image-58128\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Flor Alejandra Corral Requejo, directora de Derechos Humanos e Igualdad de G\u00e9nero, afirma que el Poder Judicial del Estado, ha mantenido las puertas abiertas a las organizaciones de la sociedad civil y de diversas colectivas feministas, as\u00ed como de personas de la comunidad LGBTQ+, en aras de trabajar en conjunto mediante la instalaci\u00f3n de mesas de trabajo, observatorios y capacitaciones en todos los temas relacionados a los derechos humanos y sobre todo en tema de acceso a la justicia con perspectiva de g\u00e9nero e inclusi\u00f3n social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Considera que este v\u00ednculo es prioritario, abona a la labor jurisdiccional, su operatividad, as\u00ed como al trabajo directo con aquellas personas que han sufrido alguna violencia o acompa\u00f1an durante los procesos correspondientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asegura que, mediante la cosmovisi\u00f3n de este sector, el an\u00e1lisis y comprensi\u00f3n es distinto, dado que tiene una radiograf\u00eda m\u00e1s amplia y completa del c\u00f3mo se viven las violencias, logrando una mayor sensibilizaci\u00f3n en las personas operadoras de justicia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Los pendientes del poder judicial<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La directora de Derechos Humanos e Igualdad de G\u00e9nero del Poder Judicial del Estado reconoce que una de las recomendaciones que queda por consolidar es la capacitaci\u00f3n en mecanismos de evaluaci\u00f3n en los t\u00e9rminos que establece el sistema de indicadores del Mecanismo de Seguimiento a la Convenci\u00f3n de Belem Do Par\u00e1 (MESECVI).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Poder Judicial est\u00e1 buscando la manera de gestionar una capacitaci\u00f3n por expertas en este tema, para ello el GIM se encuentra realizando un proyecto a fin de apoyar al respecto a este Tribunal, indica Flor Alejandra Corral Requejo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otra de las recomendaciones pendientes es la de armonizar la normatividad interna y la operaci\u00f3n de las obligaciones en materia de la producci\u00f3n de datos e informaci\u00f3n, la cual debe cumplir con perspectiva de g\u00e9nero, multiculturalidad e interseccionalidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ello se cre\u00f3 la Mesa de Trabajo Interdisciplinaria de Dise\u00f1o, Implementaci\u00f3n y Mejora de Bases de Datos, que permitir\u00e1 dar un debido cumplimiento respetando en todo momento lo relativo a la protecci\u00f3n de datos de car\u00e1cter confidencial de las personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta Mesa generar\u00e1 estad\u00edstica, debidamente desagregada, para provocar un impacto positivo en la creaci\u00f3n e implementaci\u00f3n de programas y pol\u00edticas p\u00fablicas, as\u00ed como en la norma jur\u00eddica, asegura la funcionaria.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Principales retos<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para Flor Alejandra Corral Requejo, el principal reto es la erradicaci\u00f3n de todo tipo de violencias, el cambio de paradigmas y la reeducaci\u00f3n cultural de las personas y de quienes integramos el Poder Judicial del Estado, labor de toda la ciudadan\u00eda y de los Poderes del Estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl trabajo en conjunto, sin duda, abonar\u00e1 para que pronto, la Declaratoria quede sin efecto porque estaremos en una situaci\u00f3n que implique que no resulte necesaria\u201d, se\u00f1ala la directora de Derechos Humanos e Igualdad de G\u00e9nero del Poder Judicial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conf\u00eda en que, con la voluntad pol\u00edtica de las personas actoras principales, con el perfil id\u00f3neo para la atenci\u00f3n de dicha Alerta de Violencia de G\u00e9nero y con el presupuesto indispensable, sin duda, se avanzar\u00e1 en la prevenci\u00f3n, atenci\u00f3n, investigaci\u00f3n, sanci\u00f3n y reparaci\u00f3n integral del da\u00f1o causado por cualquier tipo de violencia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La deuda hist\u00f3rica<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa deuda hist\u00f3rica sigue, no cabe duda de que hemos avanzado, se considera que s\u00ed, pero a\u00fan falta mucho por hacer\u201d, admite Corral Requejo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante, dice que, pese a su preocupaci\u00f3n y ocupaci\u00f3n por abonar para la erradicaci\u00f3n de las violencias y desigualdades por raz\u00f3n de g\u00e9nero en perjuicio de las mujeres y ni\u00f1as, se siente tranquila porque observa un Poder Judicial interesado y ocupado en saldar ese adeudo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTengo la firme convicci\u00f3n que con la voluntad pol\u00edtica que no solo he visto, sino tambi\u00e9n que he sentido por parte de la presidenta del Tribunal Superior de Justicia y del Consejo de la Judicatura del Poder Judicial, magistrada Myriam Victoria Hern\u00e1ndez Acosta, se ha dado un cambio con impacto positivo, por lo que considero que con el liderazgo de la presidenta continuaremos avanzando en la materia y en esta nuestra causa\u201d, enfatiza.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recuerda que la Suprema Corte de Justicia de la Naci\u00f3n public\u00f3 la nueva edici\u00f3n del Protocolo para Juzgar con Perspectiva de G\u00e9nero, documento elaborado en su primera edici\u00f3n para atender las medidas de reparaci\u00f3n ordenadas por la Corte Interamericana de Derechos Humanos (Corte IDH) en los casos Gonz\u00e1lez y otras (Campo Algodonero), Fern\u00e1ndez Ortega y otros, y Rosendo Cant\u00fa y otra, todos contra M\u00e9xico, ante la gravedad y la sistematicidad de la violencia contra las mujeres en el pa\u00eds.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/images.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/11\/images.jpg\" alt=\"\" class=\"wp-image-58131\" width=\"383\" height=\"214\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Este Protocolo constituy\u00f3 un primer ejercicio de reflexi\u00f3n sobre c\u00f3mo investigar y en su momento juzgar, aquellos casos en los que el g\u00e9nero y por raz\u00f3n de \u00e9ste, tiene un papel trascendente en la controversia para originar un impacto diferenciado en las personas que participan en ella, particularmente mujeres y ni\u00f1as.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El objetivo final de este instrumento es acelerar la modificaci\u00f3n y la eliminaci\u00f3n de pr\u00e1cticas culturales, actitudes y comportamientos individuales, sociales e institucionales que discriminan a las personas por su g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La funcionaria sostiene que el INFORAJ y la Direcci\u00f3n de Derechos Humanos e Igualdad de G\u00e9nero han difundido este Protocolo y han capacitado a quienes imparten justicia para el uso de todos los protocolos que emite la SCJN.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, han llevado a cabo talleres en materia de atenci\u00f3n a v\u00edctimas de violencia al personal de primer contacto y talleres para brindar primeros auxilios psicol\u00f3gicos, cursos y talleres en materia de violencia laboral, acoso y hostigamiento sexual, entre otros.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Importancia de la alerta<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La directora de Derechos Humanos e Igualdad de G\u00e9nero del Poder Judicial no duda en se\u00f1alar que la Alerta de Violencia de G\u00e9nero es un importante mecanismo para garantizar la seguridad e integridad de las mujeres y ni\u00f1as, el cese de la violencia en su contra, as\u00ed como para eliminar las desigualdades derivadas de los agravios comparados en materia de derechos humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPermite visibilizar la situaci\u00f3n real que enfrentamos las mujeres y ni\u00f1as en los \u00e1mbitos pol\u00edtico, social, econ\u00f3mico, cultural y geogr\u00e1fico, y en el caso particular, en lo que es y corresponde al acceso, procuraci\u00f3n e impartici\u00f3n de justicia\u201d, indica Flor Alejandra Corral Requejo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin duda, agrega, representa un \u00e1rea de oportunidad para que se realice una coordinaci\u00f3n con los tres Poderes y niveles de Gobierno, con el fin de que las acciones de emergencia y urgencia realmente logren un impacto positivo que lleve a la eliminaci\u00f3n de las violencias y mejora del sistema de justicia en el estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Considera que, como autoridad, la Alerta de Violencia de G\u00e9nero viene a activar y a profesionalizar al personal del Poder Judicial para mejorar los perfiles de personas operadoras de justicia y conocer las realidades, m\u00e1s all\u00e1 de un escritorio, que atraviesan las mujeres y ni\u00f1as, analizando el contexto que viven de manera integral, para llevar a cabo acciones que tengan un efecto positivo en aras de abonar a la igualdad sustantiva, en la identificaci\u00f3n de las relaciones de poder y asimetr\u00eda, en la aplicaci\u00f3n del trato diferenciado, en la interseccionalidad, en la diversidad cultural y sexual, en la erradicaci\u00f3n de las violencias, en la aplicaci\u00f3n de una amplia perspectiva de g\u00e9nero y derechos humanos, con un enfoque de inclusi\u00f3n social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/MG<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">*Titular de la Unidad de Igualdad de G\u00e9nero de la Comisi\u00f3n Estatal de los Derechos Humanos &#8211; CEDH Chihuahua<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Alerta de Violencia de G\u00e9nero contra las Mujeres por Violencia Feminicida para los municipios de Ju\u00e1rez, Chihuahua, Cuauht\u00e9moc, Hidalgo del Parral y Guadalupe y Calvo del estado de Chihuahua est\u00e1 empezando a rendir frutos.<\/p>\n","protected":false},"author":3,"featured_media":58133,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[693,51],"tags":[],"class_list":["post-58126","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-ejecutivo"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/58126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=58126"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/58126\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/58133"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=58126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=58126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=58126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}