{"id":56457,"date":"2022-09-26T06:19:51","date_gmt":"2022-09-26T12:19:51","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=56457"},"modified":"2023-07-21T19:16:20","modified_gmt":"2023-07-22T00:16:20","slug":"tras-la-puerta-del-poder-militares-en-calles-hasta-2028-por-acuerdo-plural-o-por-consulta-ciudadana","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/tras-la-puerta-del-poder-militares-en-calles-hasta-2028-por-acuerdo-plural-o-por-consulta-ciudadana\/","title":{"rendered":"Tras la Puerta del Poder| Militares en calles hasta 2028, \u00bfpor acuerdo plural o por consulta ciudadana?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Roberto Vizca\u00edno<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 26 de septiembre del 2022.- A partir de hoy se confrontan dos visiones y propuestas desde la 4T que buscar\u00e1n extender la presencia militar en calles hasta 2028: la de Andr\u00e9s Manuel L\u00f3pez Obrador y la de Ricardo Monreal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de que el mi\u00e9rcoles anterior en el Senado se regres\u00f3 a comisiones el dictamen aprobado por Diputados\/as, el Presidente de M\u00e9xico pint\u00f3 su raya y propuso que sean las y los ciudadanos quienes, en una consulta, como otras que ha impulsado antes, sean los que decidan si los militares deban quedarse hasta 2028 en el combate a la delincuencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Monreal por su parte anunci\u00f3 que esta semana convocar\u00e1 a todas las fuerzas pol\u00edticas a elaborar con participaci\u00f3n de organizaciones ciudadanas una nueva propuesta plural y democr\u00e1tica, para garantizar la constitucionalidad de esa propuesta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ex ministros\/as y especialistas en derecho constitucional advirtieron de inmediato que la propuesta del mandatario es absolutamente improcedente porque la Constitucional estipula que la seguridad p\u00fablica no puede ser sometida a consulta ciudadana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed es que las fuerzas armadas esperan la convocatoria de Monreal, para ir a un nuevo dictamen dise\u00f1ado y elaborado conjuntamente por todas y todos ellos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Presentando un libro en Xochimilco<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Sin apuros por este espinoso caso, el senador Ricardo Monreal se fue el s\u00e1bado a Xochimilco a presentar su libro \u201cOtro Campo es Posible\u201d, donde fue recibido por importantes contingentes al grito de:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Presidente! \u00a1Presidente! \u00a1Presidente!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Envuelto en ese ambiente, Monreal record\u00f3 su origen campesino y sus batallas pol\u00edticas anteriores en las que muchas y muchos simpatizantes suyos de Xochimilco lo acompa\u00f1aron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn 2017\u2026 cuando en la mayor\u00eda de las encuestas, en aquel momento, est\u00e1bamos arriba\u2026 no nos dejaron llegar, y (hoy) seguimos luchando\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u2026 yo estuve a punto de tomar una decisi\u00f3n para formar una alianza, convers\u00e9 con aquel l\u00edder que ahora recuerdo, era candidato y ahora presidente, el licenciado (Andr\u00e9s Manuel) L\u00f3pez Obrador, y me pidi\u00f3 que no me fuera, porque ten\u00edamos que cumplir un sue\u00f1o: el sue\u00f1o era ganar la presidencia de la Rep\u00fablica\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cY decid\u00ed quedarme\u2026&nbsp; por eso, yo los quiero exhortar, las quiero exhortar a que se mantengan con dignidad y con libertad en lo que queremos; \u00bfqu\u00e9 es lo que deseamos? Un campo justo. \u00bfQu\u00e9 m\u00e1s deseamos? Unidad. \u00bfQu\u00e9 queremos? Reconciliaci\u00f3n nacional. S\u00f3lo de esa manera podemos avanzar, podemos prosperar, podemos generar desarrollo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPor eso estamos aqu\u00ed, para organizarnos\u201d, subray\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como en otros foros y encuentros, advirti\u00f3 que le est\u00e1n haciendo el vac\u00edo y lo han alejado dentro de Morena y el Gobierno por \u201ctener mi criterio y defender mis ideas, en lo que creo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero les prometi\u00f3 que a pesar de esto y lo que venga, \u201cme voy a inscribir para suceder al presidente L\u00f3pez Obrador en la presidencia de la Rep\u00fablica\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su promesa provoca otros gritos: \u00a1Vamos a ganar!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Record\u00f3 que ha sido 3 veces diputado federal, 3 veces senador, gobernador de Zacatecas, delegado de la Cuauht\u00e9moc, \u201cy les puedo decir, con la frente en alto: en 42 a\u00f1os de servidor p\u00fablico, nunca he tenido una denuncia, nunca he tenido un se\u00f1alamiento, nunca he tenido nada de qu\u00e9 avergonzarme. Yo puedo caminar en cualquier parte del pa\u00eds con la frente en alto y por eso lucho y voy a seguir resistiendo, luchando por mi pa\u00eds, luchando por nuestra Patria\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s gritos: \u00a1No est\u00e1s solo! \u00a1No est\u00e1s solo! \u00a1No est\u00e1s solo!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pueblo, el pueblo es el \u00fanico que nos va a sacar adelante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y a la despedida: \u00a1Presidente! \u00a1Presidente! \u00a1Presidente!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pregunto yo: \u00bfser\u00e1 que ya est\u00e1 en campa\u00f1a?&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ram\u00edrez Mar\u00edn, con el mayor reconocimiento<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dif\u00edcilmente hay en esta legislatura otro senador que domine el reglamento interno y temas legislativos como el pri\u00edsta yucateco Jorge Carlos Ram\u00edrez Mar\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde esa perspectiva y con sentido de Estado e Historia Ram\u00edrez Mar\u00edn se declara antimilitarista y aboga por ir a la construcci\u00f3n de una alternativa distinta que la aprobada en diputados\/as para avalar la permanencia de las fuerzas armadas en las calles hasta el 2028.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aprobar el actual dictamen ser\u00eda, dijo, insistir en esta estrategia que no ha dado resultados y que ha hundido al pa\u00eds en una espiral de sangre y violencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEn el fondo lo que proponemos nosotros es que la Comisi\u00f3n Interamericana de Derechos Humanos pueda supervisar la actuaci\u00f3n de las fuerzas armadas en materia de seguridad, pero que esto no dependa de ellos ni del ejecutivo, que sea el Congreso el que llame a la CIDH a la que le podamos decir: \u00abnecesitamos que revises este caso\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aspirante con m\u00e9ritos amplios a la gubernatura desde hace ya al menos 2 sexenios, \u00fanico senador del PRI que gan\u00f3 por mayor\u00eda en su estado, Ram\u00edrez Mar\u00edn consider\u00f3 que en la oposici\u00f3n \u201chemos ca\u00eddo en el discurso del gobierno: en el est\u00e1s conmigo o est\u00e1s contra m\u00ed, un discurso no nos va a llevar a ninguna parte\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNos est\u00e1 haciendo renunciar a lo que tenemos que hacer: proponer, crear, dialogar, consensar, eso es lo que he hecho toda mi vida de parlamentario. No es con presiones como vamos a avanzar\u201d, concluy\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:...rvizcainoa@gmail.com\">&#8230;rvizcainoa@gmail.com<\/a> &nbsp;\/ Twitter: @_Vizcaino \/ Facebook \/ <a href=\"https:\/\/www.facebook.com\/rvizcainoa\">https:\/\/www.facebook.com\/rvizcainoa<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de hoy se confrontan dos visiones y propuestas desde la 4T que buscar\u00e1n extender la presencia militar en calles hasta 2028: la de Andr\u00e9s Manuel L\u00f3pez Obrador y la de Ricardo Monreal.<\/p>\n","protected":false},"author":3,"featured_media":39589,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[693,35,623,622],"tags":[459],"class_list":["post-56457","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-opinion","category-roberto-vizcaino","category-tras-la-puerta-del-poder","tag-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/56457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=56457"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/56457\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/39589"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=56457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=56457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=56457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}