{"id":56373,"date":"2022-09-23T11:47:41","date_gmt":"2022-09-23T17:47:41","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=56373"},"modified":"2023-07-21T19:16:22","modified_gmt":"2023-07-22T00:16:22","slug":"desde-la-mano-izquierda-siguen-pagando-las-mismas","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/desde-la-mano-izquierda-siguen-pagando-las-mismas\/","title":{"rendered":"Desde la mano izquierda| Siguen pagando las mismas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Claudia Espinosa Almaguer<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, San Luis Potos\u00ed, 23 de septiembre del 2022.- Hace un a\u00f1o se abordaron los pendientes de armonizaci\u00f3n que deb\u00edan producirse dentro de las leyes de las entidades federativas de M\u00e9xico creadas para garantizar el derecho de las mujeres a vivir una vida libre de violencia. Hoy volvemos a ello porque no se ha hecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Han transcurrido dieciocho meses, la reforma del 18 de marzo de 2021 a la Ley General de Acceso de las Mujeres a una Vida Libre de Violencia modific\u00f3 el cap\u00edtulo referente a las \u00f3rdenes de protecci\u00f3n, herramientas jur\u00eddicas para decretar en situaciones de riesgo con el fin de evitar la muerte de mujeres y ni\u00f1as a manos de sus agresores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed, ante el riesgo a la integridad, la libertad o la vida, estos actos de urgente aplicaci\u00f3n se otorgan por autoridades administrativas, el Ministerio P\u00fablico o los \u00f3rganos jurisdiccionales de acuerdo con determinados principios, bajo un an\u00e1lisis coherente del contexto de las v\u00edctimas y de las necesidades que se deriven de cada caso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre las de tipo administrativas y las de naturaleza jurisdiccional, las primeras abarcan aproximadamente veinte fracciones, destacan all\u00ed, el traslado de las v\u00edctimas a d\u00f3nde se requiera y cuantas veces sea necesario para garantizar su protecci\u00f3n, la custodia personal y domiciliaria, el alojamiento temporal en espacios seguros, la proveedur\u00eda de recursos econ\u00f3micos para transporte, alimentos, comunicaci\u00f3n, mudanza y tr\u00e1mites oficiales, la seguridad y el acondicionamiento de vivienda, el gasto dentro o fuera del pa\u00eds para la mujer y su familia, la reubicaci\u00f3n de su residencia, la protecci\u00f3n permanente por seguridad privada o policiaca, entre otras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De estos cambios es sumamente importante considerar un elemento de vigencia que trasciende la competencia territorial, es decir, todas las \u00f3rdenes de protecci\u00f3n conforme al Art\u00edculo 34 Bis, pueden solicitarse en cualquier Estado distinto a donde ocurrieron los hechos sin que ello sea excusa para no recibir la petici\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dado que eso a su vez implica estar en contacto directo con la mujer v\u00edctima cada 24 horas durante la primera semana hasta la elaboraci\u00f3n de un plan de seguridad, se determin\u00f3 que las autoridades administrativas, las fiscal\u00edas y poderes judiciales federales y locales elaborasen convenios de colaboraci\u00f3n para garantizar su aplicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed mismo todas las fiscal\u00edas y los poderes judiciales de M\u00e9xico ten\u00edan la obligaci\u00f3n junto con el Gobierno Federal de crear un plan de formaci\u00f3n especializada sobre el contenido de esta reforma y si bien es cierto no se provey\u00f3 de recursos para ello, tampoco se ha sabido de alguna acci\u00f3n m\u00ednima o inicial para cumplir con estas obligaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No es cosa menor, hasta julio de este a\u00f1o el Secretariado Ejecutivo Nacional de Seguridad P\u00fablica reporta en sus cifras sobre violencia contra las mujeres el inicio de 2,169 carpetas de investigaci\u00f3n por homicidio y feminicidio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sume que entidades como Ciudad de M\u00e9xico, Estado de M\u00e9xico, Guanajuato, Nuevo Le\u00f3n, Chihuahua, Michoac\u00e1n, Baja California, Oaxaca, Guerrero, San Luis Potos\u00ed, Veracruz, Jalisco, Hidalgo, Puebla y Zacatecas, son los de mayor incidencia en los delitos de violencia familiar (158,924), lesiones (39,268) y violaci\u00f3n (13,861), y que en estos mismos sitios hay Alertas de Violencia de G\u00e9nero vigentes desde 2015 de las cuales no se ha podido concretar su cierre. \u00bfConoce usted si all\u00ed d\u00f3nde vive estos cambios ya se hicieron? Apuesto a que no. A m\u00e1s ver.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace un a\u00f1o se abordaron los pendientes de armonizaci\u00f3n que deb\u00edan producirse dentro de las leyes de las entidades federativas de M\u00e9xico creadas para garantizar el derecho de las mujeres a vivir una vida libre de violencia.<\/p>\n","protected":false},"author":3,"featured_media":36870,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[693,131,35],"tags":[459],"class_list":["post-56373","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-claudia-almaguer","category-opinion","tag-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/56373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=56373"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/56373\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/36870"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=56373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=56373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=56373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}