{"id":5510,"date":"2017-09-18T01:21:16","date_gmt":"2017-09-18T01:21:16","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=5510"},"modified":"2023-07-21T14:25:14","modified_gmt":"2023-07-21T19:25:14","slug":"exige-al-gobierno-federal-frenar-la-ola-creciente-de-feminicidio-en-mexico","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/exige-al-gobierno-federal-frenar-la-ola-creciente-de-feminicidio-en-mexico\/","title":{"rendered":"Exige al gobierno federal frenar la ola creciente de feminicidio en M\u00e9xico"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.semmexico.com\/gallery-post.php?id=2985#\">Alicia Mendoza<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 18 septiembre 2017.- Claudia Castello Rebollar secretaria Nacional de Igualdad de G\u00e9neros del PRD, afirm\u00f3 que \u201cla epidemia en que se ha convertido la violencia de g\u00e9nero en M\u00e9xico, es resultante de que el Estado ha sido omiso en la aplicaci\u00f3n de las leyes en materia de prevenci\u00f3n, sanci\u00f3n y erradicaci\u00f3n de las de violencias contra las mujeres\u201d.<br><br>La l\u00edder perredista dio a conocer en un comunicado de prensa que \u201cel PRD se suma a la indignaci\u00f3n nacional por el feminicidio de Mara Fernanda Castilla Miranda\u201d, y demand\u00f3 al Estado mexicano \u201cque ning\u00fan feminicidio quede impune y que se declare ya la Alerta de Violencia de G\u00e9nero en Puebla\u201d.<br><br>Adem\u00e1s, agreg\u00f3 que el PRD exige al gobierno federal, a la Secretar\u00eda de Gobernaci\u00f3n y a los gobiernos de las entidades federativas, actuar frente a la violencia de g\u00e9nero y frenar la ola creciente de feminicidio en todo el pa\u00eds, \u201cya que de no hacerlo reproducen la violencia contra las mujeres por omisi\u00f3n, cometiendo con ello violencia institucional de g\u00e9nero\u201d.<br><br>Sostuvo que es grave que prevalezca en la sociedad \u201cconvicciones como la del rector de la Universidad Madero de Puebla, Job C\u00e9sar Romero, en el sentido de que las mujeres son culpables de ser v\u00edctimas de feminicidio\u201d.<br><br>Ante esas opiniones mis\u00f3ginas y machistas, dijo, deber\u00eda \u201cser destituido del cargo, ya que como representante de una instituci\u00f3n acad\u00e9mica debiera promover y participar en la prevenci\u00f3n de la violencia de g\u00e9nero, y no alentar la ignorancia y la misoginia frente al grave problema de feminicidio que tiene la entidad\u201d.<br><br>Aunque, puntualiz\u00f3 que \u201ca\u00fan es m\u00e1s grave es que las instituciones encargadas de garantizar la vida y la seguridad de las mujeres muestran su incapacidad para enfrentar la ola de feminicidios que azotan al pa\u00eds\u201d.<br><br>Se\u00f1al\u00f3 que la Comisi\u00f3n para Prevenir y Erradicar la Violencia contra las Mujeres (CONAVIM) se neg\u00f3 a promover la declaratoria de Alerta de Violencia de G\u00e9nero en Puebla, al considerar que \u201chab\u00eda acciones suficientes y voluntad del gobierno poblano para erradicar la violencia contra las mujeres\u201d.<br><br>A pesar del alto \u00edndice de asesinatos de mujeres por raz\u00f3n de g\u00e9nero en la entidad, y destac\u00f3 cifras de organizaciones civiles en 2016 quienes registraron un incremento del 143 por ciento de casos de feminicidio y con el asesinato de Mara, Puebla lleg\u00f3 al feminicidio 85 en lo que va de 2017.<br><br>As\u00ed, Castello Rebollar detall\u00f3 que con base en informes de la Fiscal\u00eda General del Estado, desde 2013 hasta septiembre de 2017, se cometieron casi 400 asesinatos de mujeres, aunque la mayor\u00eda de \u00e9stos no los tipific\u00f3 como feminicidios; y desde 2013 a la fecha, con el asesinato de Mara Fernanda Castilla Miranda, suman 9 los feminicidios de universitarias, 7 alumnas de la Benem\u00e9rita Universidad Aut\u00f3noma de Puebla.<br><br>Por lo que exigi\u00f3 \u201cno m\u00e1s omisi\u00f3n, corrupci\u00f3n e impunidad en la atenci\u00f3n, sanci\u00f3n, prevenci\u00f3n y erradicaci\u00f3n de la violencia de g\u00e9nero\u201d.<br><br>SEM\/am\/lr<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alicia Mendoza SemM\u00e9xico, Cd. de M\u00e9xico, 18 septiembre 2017.- Claudia Castello Rebollar secretaria Nacional de Igualdad de G\u00e9neros del PRD, afirm\u00f3 que \u201cla epidemia en que se ha convertido la violencia de g\u00e9nero en M\u00e9xico, es resultante de que el Estado ha sido omiso en la aplicaci\u00f3n de las leyes en materia de prevenci\u00f3n, sanci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5511,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[687,50],"tags":[],"class_list":["post-5510","post","type-post","status-publish","format-standard","has-post-thumbnail","category-687","category-congreso"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/5510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=5510"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/5510\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/5511"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=5510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=5510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=5510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}