{"id":54940,"date":"2022-08-22T09:45:21","date_gmt":"2022-08-22T15:45:21","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=54940"},"modified":"2023-07-21T19:12:00","modified_gmt":"2023-07-22T00:12:00","slug":"alfa-omega-con-incertidumbre-comienza-el-ciclo-escolar-una-titular-sin-experiencia-en-la-sep","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/alfa-omega-con-incertidumbre-comienza-el-ciclo-escolar-una-titular-sin-experiencia-en-la-sep\/","title":{"rendered":"Alfa Omega| Con incertidumbre comienza el ciclo escolar. Una Titular sin experiencia, en la SEP"},"content":{"rendered":"\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>A\u00fan existen ap\u00f3stoles de la educaci\u00f3n programas y planes que nadie conoce.<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Libre Rosario Robles y preso Jes\u00fas Murillo Karam, \u00bfcoincidencia?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jorge Herrera Valenzuela<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 22 de agosto del 2022.- El lunes 29 de agosto ser\u00e1 una fecha hist\u00f3rica y clave. Se inicia el Ciclo Escolar 2022-2023. Lo primero obedece a que por tercera ocasi\u00f3n una mujer estar\u00e1 al frente de la Secretar\u00eda de Educaci\u00f3n P\u00fablica. Lo segundo por el desconcierto, la desinformaci\u00f3n, la marginaci\u00f3n y falso inter\u00e9s gubernamental. Las profesoras y los profesores de Educaci\u00f3n Primaria junto con los Padres y Madres de Familia, est\u00e1n desconcertados, principalmente los de las escuelas oficiales, las de Gobierno, urbanas y rurales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Presidente de M\u00e9xico decidi\u00f3 que una de sus cercanas colaboradoras, <strong>Leticia Ram\u00edrez Amaya<\/strong>, dejara la Coordinaci\u00f3n Nacional de Atenci\u00f3n Ciudadana y sea desde el mi\u00e9rcoles 17 la titular de la Secretar\u00eda de Educaci\u00f3n P\u00fablica. Profesora Normalista y Antrop\u00f3loga. En 1984 dej\u00f3 de impartir clases en Educaci\u00f3n Primaria. Dedic\u00f3 su tiempo al sindicalismo tanto en el SNTE (Sindicato Nacional de Trabajadores de la Educaci\u00f3n) como en la CNTE (Coordinadora Nacional de Trabajadores de la Educaci\u00f3n). Desde hace 28 a\u00f1os es parte del equipo del tabasque\u00f1o y desde el inicio del Siglo XXI se retir\u00f3 del magisterio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En pocas palabras comento que la se\u00f1ora defe\u00f1a, de 55 a\u00f1os de edad, es una funcionaria \u201c<strong>orgullo del autoritarismo presidencial<\/strong>\u201d. Recuerden al presidente Jos\u00e9 L\u00f3pez Portillo y Pacheco nombr\u00f3 a su hijo <strong>Jos\u00e9 Ram\u00f3n<\/strong>, subsecretario en Programaci\u00f3n y Presupuesto y lo llam\u00f3 \u201corgullo de mi nepotismo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La se\u00f1ora Leticia no est\u00e1 actualizada con el tema de la <strong>Educaci\u00f3n P\u00fablica, <\/strong>tampoco lo estaba <strong>Delfina G\u00f3mez \u00c1lvarez<\/strong>, pues la ocupaci\u00f3n de ambas era en el medio pol\u00edtico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eso no importa ni es novedad, porque en 2006 el presidente Felipe Calder\u00f3n nombr\u00f3 a <strong>Josefina Eugenia V\u00e1zquez Mota<\/strong>, &nbsp;la primera mujer titular de la SEP, fundada en 1920. Economista, teziutleca, egresada de la Universidad Iberoamericana. Como las dos anteriores, ligada al ejercicio pol\u00edtico. Josefina sin experiencia magisterial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La morenista precandidata a gobernadora del Estado de M\u00e9xico (por segunda vez) y la senadora PANista en funciones, no dejaron huella en el despacho que ocuparon ilustres educadores como Jos\u00e9 Vasconcelos, Jaime Torres Bodet y Agust\u00edn Y\u00e1\u00f1ez Delgadillo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El banquillo de los ap\u00f3stoles<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hay muchas y largas historias de profesoras y profesores, a quienes com\u00fanmente llamamos maestras y maestros, que revelan la pasi\u00f3n, la vocaci\u00f3n y el deseo de estar frente al pizarr\u00f3n. Transmitir conocimientos para que la ni\u00f1a y el ni\u00f1o aprendan desde tomar el l\u00e1piz, abrir un cuaderno, quitarles la expresi\u00f3n de sorpresa, sonre\u00edrles para eliminar el miedo que reflejan los infantiles rostros y darles confianza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">He visto a maestras y a maestros, tardar horas preparando las clases. Anteriormente la Secretar\u00eda de Educaci\u00f3n P\u00fablica elaboraba los programas para la ense\u00f1anza, desde el primero hasta el sexto a\u00f1o. Conten\u00edan la tem\u00e1tica general, es decir lengua nacional o espa\u00f1ol, aritm\u00e9tica o matem\u00e1ticas, civismo, historia y geograf\u00eda. Se establec\u00edan horarios para deportes o educaci\u00f3n f\u00edsica e inclusive las aburridas clases de m\u00fasica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mentores o docentes, t\u00e9rminos que tambi\u00e9n se usan para identificar al educador y a la educadora, que laboran en las zonas rurales, fuera de las ciudades capitales, requieren de m\u00e1s poyos porque tienen que recorrer distancias, caminando, para llegar al sitio donde fue edificado el plantel. Existen poblados donde las carencias son de tal magnitud que representan diario sacrificio para profesorado y estudiantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Obvio, en las regiones urbanas los problemas abundan, pero son de otra naturaleza. Las soluciones las toman las y los profesores y los padres y madres de Familia, no la autoridad administrativa. Material para el aseo de los salones, papel para los sanitarios e inclusive dar mantenimiento a las instalaciones. Lo que proporciona la SEP no alcanza ni para medio a\u00f1o escolar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El profes@r, el <strong>Ap\u00f3st@l de Banquillo<\/strong>, es aquel que no pone l\u00edmite a sus esfuerzos, desarrolla toda su capacidad, act\u00faa con un especial humanismo. Enfoca la atenci\u00f3n hacia ni\u00f1as y ni\u00f1os, porque algunos de ellos sufren mal trato en su hogar o no cuentan con apoyo para hacer sus tareas. Papi y mami trabajan, no tienen tiempo para ayudar a los hijos, ni hijas. El profesorado no habr\u00e1 de mezclarse con esos problemas, pero s\u00ed apoyar al infante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la actualidad la situaci\u00f3n es cr\u00edtica, m\u00e1xime que la pandemia que padecemos desde hace tres a\u00f1os cort\u00f3 la asistencia a las escuelas. No hubo clases presenciales. Bien por disponer del uso de las clases v\u00eda zoom, pero el trabajo del profesorado no tiene la repercusi\u00f3n necesaria y el alumnado no pone la inmediata atenci\u00f3n. Hay orden oficial de que \u201c<strong>ning\u00fan alumno debe ser reprobado, aunque no sepa o no haya asistido a clases o no cumpla con su asistencia virtual<\/strong>\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El problema es complejo. Hay alumnos y alumnas que \u201cpasan el a\u00f1o\u201d sin saber leer ni escribir. Ya inscritos en el tercer a\u00f1o, por ejemplo, se dan caso de ese tipo. El trabajo del magisterio se triplica, pero poco se reconoce ese trabajo. Muchos Padres y Madres de Familia no cooperan con sus hijos, hijas y \u00e9stos no se dan cuenta del da\u00f1o que eso les causar\u00e1 m\u00e1s adelante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde aqu\u00ed hago un reconocimiento, con mucha satisfacci\u00f3n y orgullo, a nuestra querida hija, la profesora <strong>Claudia Leticia Herrera Navas<\/strong>, por cumplir con su vocaci\u00f3n que tuvo desde los 4 a\u00f1os de edad para ser profesora. \u201cJugaba a la escuelita\u201d, en el patio de la casa. Ten\u00eda su mesa (dizque escritorio), pizarr\u00f3n, gises, y \u201cdaba sus clases\u201d a sus mu\u00f1ecas y mu\u00f1ecos sentados en las sillitas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estudi\u00f3 en la Escuela Manuel M. Acosta. Titulada en 1985, sigue empe\u00f1ada en ense\u00f1ar a las y los peque\u00f1os a leer y a escribir, desde el primer a\u00f1o de Primaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Felicidades <strong>Maestra Lety<\/strong> por cumplir con tu apostolado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un saludo a la profesora <strong>Adriana Basulto Barocio<\/strong>, en su natal Guadalajara.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Empezaba bien y se descarril\u00f3<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En un recorrido reporteril, apoyado por colaboradores sin honorarios, las profesoras y los profesores entrevistados nos dijeron que la corta estancia de <strong>Esteban Moctezuma Barrag\u00e1n<\/strong> fue positiva y lamentaban que no continuara. Hab\u00eda una buena comunicaci\u00f3n con las y los maestros y los lineamientos eran de una persona enterada en asuntos pedag\u00f3gicos y se avizoraba un futuro de resultados favorables para la ni\u00f1ez. Los educadores y educadoras ten\u00edan mayor libertad para trabajar en los planes de ense\u00f1anza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La texcocana <strong>Delfina G\u00f3mez \u00c1lvarez <\/strong>dedic\u00f3 su tiempo a las tareas pol\u00edticas. Sab\u00eda que tendr\u00eda el apoyo del Presidente de M\u00e9xico para contender, en segunda oportunidad, por la gubernatura del Estado de M\u00e9xico. En la Secretar\u00eda de Educaci\u00f3n P\u00fablica tuvo mayor actividad un se\u00f1or de nombre Max Arriaga Navarro, encargado de hacer trizas los Libros de Texto Gratuitos \u00danico y cumplir \u00f3rdenes presidenciales de borrar \u201ca los conservadores que prohijaron el neoliberalismo\u201d. Dicha persona es doctor en filolog\u00eda y fue sinodal de la se\u00f1ora <strong>Beatriz Guti\u00e9rrez Miller<\/strong>, en la Universidad Aut\u00f3noma de M\u00e9xico, fundada por el tabasque\u00f1o y esposo de la \u201cno soy primera dama\u201d. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Delfina <\/strong>est\u00e1 calificada como \u201cla peor\u201d titular de la SEP. Nunca demostr\u00f3 tener capacidad magisterial, porque ella tiene la vocaci\u00f3n de ser pol\u00edtica y es lo que m\u00e1s aparece en su historial. Est\u00e1 acusada jur\u00eddicamente de haber descontado parte del salario a los trabajadores y trabajadoras del Ayuntamiento de Texcoco, cuando fue presidenta municipal, para dedicarlo a su campa\u00f1a. Ha sido diputada federal y senadora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El nombramiento de <strong>Leticia Ram\u00edrez Amaya, <\/strong>para encabezar la SEP, no tuvo un solo aplauso y s\u00ed mucho pesar, porque se trata de una profesora en retiro desde 1984 y activista de la fat\u00eddica CNTE, la Coordinadora Nacional de Trabajadores de la Educaci\u00f3n. A su favor el abrazo y beso que le dio el Presidente de M\u00e9xico, en Palacio Nacional, al presentarla en \u201cLa Ma\u00f1anera\u201d, diciendo: \u201ces de toda mi confianza, est\u00e1 preparada y la conozco desde hace 28 a\u00f1os\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le corresponde a la antrop\u00f3loga, tambi\u00e9n alejada de esa profesi\u00f3n, inaugurar el nuevo Ciclo Escolar, con un supuesto plan de ense\u00f1anza, en que \u201clos y las estudiantes deber\u00e1n de aprender en Civismo cu\u00e1les son las obras de infraestructura del Gobierno,&nbsp; qu\u00e9 partido (pol\u00edtico) las impulsa, si formaron parte de sus promesas de campa\u00f1a\u201d, seg\u00fan versi\u00f3n period\u00edstica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Coment\u00f3 que para elaborar el Plan de Ense\u00f1anza, el gobierno federal no convoc\u00f3 ni consult\u00f3 a los expertos en la materia y mucho menos llam\u00f3 a los dirigentes de las sociedades de Padres de Familia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quieren imponer una educaci\u00f3n partidista, sin recordar que en el primer gobierno sexenal, en 1934, el presidente L\u00e1zaro C\u00e1rdenas presionado por Vicente Lombardo Toledano, Francisco J. M\u00fagica y Narciso Bassols, pretendi\u00f3 implantar la educaci\u00f3n socialista. Ahora el tabasque\u00f1o, inquilino que no paga renta en Palacio Nacional, ordena cambios radicales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed pues, comienza un a\u00f1o escolar plagado de interrogantes, de una incertidumbre total y con una funcionaria que estaba dedicada a atender quejas y peticiones de la ciudadan\u00eda, telef\u00f3nicas, escritas y personales, muy ajeno al trabajo en un&nbsp; sal\u00f3n de Escuela Primaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P.D. <\/strong>La noche de este viernes 19 de agosto de 2022 dos noticias, con diferencia de horas. La Fiscal\u00eda General de la Rep\u00fablica aprehendi\u00f3 al licenciado <strong>JES\u00daS MURILLO KARAM <\/strong>por el Caso de los 43 Normalistas de Ayotzinapa y luego de 3 a\u00f1os y seis d\u00edas de estancia en el penal de Santa Martha Acatitla, sale la economista <strong>MAR\u00cdA DEL ROSARIO ROBLES BERLANGA<\/strong>, procesada por el asunto de la llamada \u201cEstafa Maestra\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ambas personas formaron parte del gabinete de <strong>Enrique Pe\u00f1a Nieto<\/strong>, quien disfruta feliz de la vida en Espa\u00f1a. Oficialmente el expresidente no est\u00e1 involucrado en ninguna averiguaci\u00f3n de la Fiscal\u00eda General de la Rep\u00fablica. <strong>La impunidad se impone <\/strong>a favor del mexiquense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:jherrerav@live.com.mx\"><strong>jherrerav@live.com.mx<\/strong><\/a><strong><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El lunes 29 de agosto ser\u00e1 una fecha hist\u00f3rica y clave. Se inicia el Ciclo Escolar 2022-2023. Lo primero obedece a que por tercera ocasi\u00f3n una mujer estar\u00e1 al frente de la Secretar\u00eda de Educaci\u00f3n P\u00fablica.<\/p>\n","protected":false},"author":3,"featured_media":7843,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[693,94,35],"tags":[459],"class_list":["post-54940","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-jorge-herrera-valenzuela","category-opinion","tag-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/54940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=54940"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/54940\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/7843"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=54940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=54940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=54940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}