{"id":54615,"date":"2022-08-13T11:56:48","date_gmt":"2022-08-13T17:56:48","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=54615"},"modified":"2023-07-21T19:11:20","modified_gmt":"2023-07-22T00:11:20","slug":"desde-la-mano-izquierda-aplicacion-de-la-ley-a-favor-de-las-mujeres-3","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/desde-la-mano-izquierda-aplicacion-de-la-ley-a-favor-de-las-mujeres-3\/","title":{"rendered":"Desde la mano izquierda| Aplicaci\u00f3n de la ley a favor de las mujeres"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Parte III. \u00bfC\u00f3mo debe utilizarse el Protocolo de Atenci\u00f3n para el MP en San Luis Potos\u00ed?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Claudia Espinosa Almaguer<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, San Luis Potos\u00ed, 13 de agosto, 2022.- En las dos anteriores entregas de esta columna se escribi\u00f3 acerca del <strong>Protocolo de Atenci\u00f3n a Mujeres, Ni\u00f1as, Ni\u00f1os y Adolescentes V\u00edctimas de Violencia<\/strong> de la Fiscal\u00eda General del Estado de San Luis Potos\u00ed que fue publicado en el Peri\u00f3dico Oficial del Estado en 2021. Nos preguntamos entonces si con las convenciones internacionales ratificadas por M\u00e9xico y la legislaci\u00f3n nacional era posible construir herramientas espec\u00edficas para, de acuerdo con las atribuciones de una autoridad, prevenir, atender y <strong>sancionar las agresiones contra las mujeres antes de que acaben en violencia feminicida.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El caso de la entidad, con un creciente n\u00famero de delitos contra mujeres y menores de edad principalmente en el contexto de v\u00ednculos familiares y de pareja, denota algo muy particular: <strong>el Protocolo es en s\u00ed mismo una garant\u00eda de no repetici\u00f3n textualmente se\u00f1alado en la Recomendaci\u00f3n 49\/2018 de la CNDH<\/strong>, es decir, exige del servicio p\u00fablico caracterizado aqu\u00ed por quienes representan el acceso a la justicia, la habilidad de aprender a largo plazo o al menos poder adecuarse a una forma regulada de actuaci\u00f3n para delitos de este tipo, de no ser as\u00ed <strong>\u00bfSe deber\u00eda trabajar en espacios dedicados a ello? porque la integridad de las v\u00edctimas no es un juego.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Imaginemos lo mejor, que somos una Ministerio P\u00fablico, una perito u orientadora de esa instituci\u00f3n que sabe que no sabe y quiere aprender, pero no tiene ninguna capacitaci\u00f3n adem\u00e1s de la licenciatura, o se encuentra en un lugar alejado y poco accesible en donde s\u00f3lo hay lo que durante a\u00f1os hubo en su momento en la antigua Subprocuradur\u00eda Especializada: gente sin un espacio digno, sin recursos materiales para atender a una poblaci\u00f3n de mujeres gravemente amenazada por la violencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es m\u00e1s, si usted es abogada o es v\u00edctima \u00bfDe qu\u00e9 le servir\u00eda saber que existe un Protocolo? El conocimiento es una fuerza \u00fatil para la exigibilidad de nuestros derechos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Empecemos diciendo que <strong>este instrumento es aplicable a todo el Estado de San Luis Potos\u00ed all\u00ed donde se encuentre un Ministerio P\u00fablico<\/strong> porque as\u00ed mismo es obligatorio desde su publicaci\u00f3n oficial para cualquier autoridad con ese cargo, a quien le corresponda iniciar una denuncia por los delitos de violencia familiar, los de car\u00e1cter sexual, lesiones, difusi\u00f3n il\u00edcita de im\u00e1genes, incumplimiento, sustracci\u00f3n, etc\u00e9tera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora bien, el <strong>Primer Cap\u00edtulo le responde al Ministerio P\u00fablico el por qu\u00e9 debe atender bajo determinados est\u00e1ndares<\/strong>, se compone de un marco conceptual que dota diversos criterios jur\u00eddicos vinculantes como la Convenci\u00f3n CEDAW, Belem do Par\u00e1 y sentencias como Gonz\u00e1lez y otras de la Corte Interamericana para el an\u00e1lisis con perspectiva de g\u00e9nero y de inter\u00e9s superior de la ni\u00f1ez. Aqu\u00ed tambi\u00e9n se dan ejemplos sobre los <strong>estereotipos y prejuicios vigentes en la procuraci\u00f3n de justicia acerca de las mujeres <\/strong>cuando son v\u00edctimas y que constituyen la materia principal de las quejas ante organismos de derechos humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego se hallar\u00e1 un <strong>Segundo Cap\u00edtulo<\/strong> denominado <strong>\u201cAtenci\u00f3n de Primera L\u00ednea Centrada en Mujeres, Ni\u00f1os, Ni\u00f1as y Adolescentes\u201d <\/strong>en donde se explica qu\u00e9 es la violencia, por qu\u00e9 es un problema en San Luis Potos\u00ed, cu\u00e1l suele ser su din\u00e1mica en la relaci\u00f3n de pareja y familiar, para qu\u00e9 sirve el <strong>Violent\u00f3metro<\/strong> elaborado por el Polit\u00e9cnico Nacional en 2011 y en d\u00f3nde se encuentran previstos los delitos en el Estado. Es posible identificar <strong>c\u00f3mo se debe presentar un Ministerio P\u00fablico con una v\u00edctima<\/strong>, qu\u00e9 debe preguntar al tiempo de entrevistarla, cu\u00e1l es la informaci\u00f3n m\u00ednima para investigar delitos como la violencia, de qu\u00e9 manera <strong>exactamente se debe canalizar con otras autoridades y con el \u00fanico refugio para v\u00edctimas <\/strong>de riesgo que existe en todo el territorio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si por ejemplo alg\u00fan funcionario no sabe c\u00f3mo tratar o entrevistar ni\u00f1os, ni\u00f1as y adolescentes v\u00edctimas, el Protocolo lo indica porque se sustenta en las <strong>Directrices sobre la Justicia en Asuntos Concernientes a los Ni\u00f1os V\u00edctimas y Testigos de Delitos de Naciones Unidas.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la \u00faltima secci\u00f3n de ese cap\u00edtulo se estructur\u00f3 un esquema detallado para la valoraci\u00f3n de riesgo y emisi\u00f3n de <strong>Medidas y \u00d3rdenes de Protecci\u00f3n<\/strong> que tiene la autoridad a su alcance. <strong>Esas directrices se comenzaron a usar desde 2019<\/strong> y se integraron en tres niveles que explican la vulnerabilidad de la v\u00edctima y la evoluci\u00f3n de la violencia, el riesgo alto de ataque f\u00edsico muy severo y el riesgo considerado de muerte que se basan en la campa\u00f1a <strong>\u201cDistancia Segura y sin Violencias\u201d<\/strong> del Observatorio Ciudadano Nacional del Feminicidio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Finalmente, en las p\u00e1ginas 15, 60, 69, 79 y 103<\/strong>, al final de cada secci\u00f3n del Protocolo se estableci\u00f3 la obligaci\u00f3n de capacitar, considerando que las mujeres, ni\u00f1as, ni\u00f1os y adolescentes de San Luis Potos\u00ed como poblaci\u00f3n destinataria de esta pol\u00edtica <strong>tienen el derecho a recibir la mejor atenci\u00f3n que pueda proveer el Estado<\/strong>, por eso encontrar\u00e1 el deber de formar en 27 temas diferentes para acreditar un grado de especializaci\u00f3n institucional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dejemos el \u00faltimo cap\u00edtulo, la atenci\u00f3n a la violencia sexual, materia esencial de la queja ante CNDH para la semana pr\u00f3xima. A m\u00e1s ver.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ac\u00e1 disponible otra versi\u00f3n:<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/08\/Protocolo.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de Incrustado de Protocolo..\"><\/object><a id=\"wp-block-file--media-ad88cb16-60b1-4952-be77-c7907e82349e\" href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/08\/Protocolo.pdf\">Protocolo<\/a><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/08\/Protocolo.pdf\" class=\"wp-block-file__button\" download aria-describedby=\"wp-block-file--media-ad88cb16-60b1-4952-be77-c7907e82349e\">Descarga<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Parte III. \u00bfC\u00f3mo debe utilizarse el Protocolo de Atenci\u00f3n para el MP en San Luis Potos\u00ed?<\/p>\n","protected":false},"author":3,"featured_media":36870,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[693,131,35],"tags":[],"class_list":["post-54615","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-claudia-almaguer","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/54615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=54615"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/54615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/36870"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=54615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=54615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=54615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}