{"id":54327,"date":"2022-08-08T07:07:15","date_gmt":"2022-08-08T13:07:15","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=54327"},"modified":"2023-07-21T19:10:39","modified_gmt":"2023-07-22T00:10:39","slug":"lucharemos-sin-miedo-para-lograr-un-mexico-prospero-y-justo-a-partir-de-2024-ricardo-monreal","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/lucharemos-sin-miedo-para-lograr-un-mexico-prospero-y-justo-a-partir-de-2024-ricardo-monreal\/","title":{"rendered":"Lucharemos sin miedo para lograr un M\u00e9xico pr\u00f3spero y justo a partir de 2024: Ricardo Monreal"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>La \u201cnomenclatura pol\u00edtica\u201d se opondr\u00e1 que sea candidato de Morena, pero se impondr\u00e1 la conciencia ciudadana, afirma el senador<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Redacci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 08 de agosto del 2022.- El senador Ricardo Monreal \u00c1vila afirm\u00f3 que la \u201cnomenclatura pol\u00edtica\u201d se opondr\u00e1 que sea candidato de Morena a la Presidencia de la Rep\u00fablica de 2024 e intentar\u00e1 erigir una facci\u00f3n en el poder, pero confi\u00f3 en que la conciencia ciudadana lograr\u00e1 profundizar la vida democr\u00e1tica de nuestro pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Monreal \u00c1vila public\u00f3 un mensaje en redes sociales, en el que destaca que tiene el entusiasmo, la capacidad, salud y autonom\u00eda \u201cpara lograr, juntos y juntas, un M\u00e9xico pr\u00f3spero y justo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Record\u00f3 que procede de una familia campesina pobre y que ahora forma parte de la clase media: \u201csoy acad\u00e9mico y servidor p\u00fablico, amante de mi pa\u00eds y una vez que llegue el tiempo legal luchar\u00e9 por suceder al presidente L\u00f3pez Obrador\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El coordinador parlamentario de Morena afirm\u00f3 que tiene claridad respecto a los grandes y enormes retos que enfrenta nuestro pa\u00eds en materia de seguridad, justicia, cambio clim\u00e1tico, campo, bienestar, ingresos, reservas actuariales, empleo y recuperaci\u00f3n econ\u00f3mica, entre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que no ser\u00e1 sencillo, pero para quienes provienen de abajo, el camino nunca ha sido f\u00e1cil y est\u00e1n acostumbrados a vencer adversidades y obst\u00e1culos. \u201cLa gente es la que decide y a ella me atengo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEntiendo mi realidad. La nomenclatura pol\u00edtica se opondr\u00e1 e intentar\u00e1 erigir una facci\u00f3n en el poder, pero conf\u00edo en que la conciencia ciudadana lograr\u00e1 profundizar la vida democr\u00e1tica de nuestro pa\u00eds\u201d, expres\u00f3 el senador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Monreal \u00c1vila subray\u00f3 que la libre voluntad se impondr\u00e1: \u201cconf\u00edo en ello y para ello lucharemos sin temor y sin miedo, con \u00e1nimo, rebeld\u00eda social y con causa\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/MG<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La \u201cnomenclatura pol\u00edtica\u201d se opondr\u00e1 que sea candidato de Morena, pero se impondr\u00e1 la conciencia ciudadana, afirma el senador<\/p>\n","protected":false},"author":3,"featured_media":27126,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[693,50],"tags":[],"class_list":["post-54327","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-congreso"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/54327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=54327"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/54327\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/27126"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=54327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=54327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=54327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}