{"id":53913,"date":"2022-07-31T02:44:00","date_gmt":"2022-07-31T08:44:00","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=53913"},"modified":"2023-07-21T19:10:50","modified_gmt":"2023-07-22T00:10:50","slug":"redim-delitos-contra-ninas-ninos-y-adolescentes-en-mexico-a-junio-de-2022","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/redim-delitos-contra-ninas-ninos-y-adolescentes-en-mexico-a-junio-de-2022\/","title":{"rendered":"REDIM: Delitos contra ni\u00f1as, ni\u00f1os y adolescentes en M\u00e9xico a junio de 2022"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Las ni\u00f1as viven corrupci\u00f3n de menores, feminicidio y trata<\/strong><\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>La incidencia delictiva advierte sobre sus responsabilidades al Estado Mexicano<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Redacci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 31 de julio, 2022.- En M\u00e9xico,\u00a0m\u00e1s delitos contra ni\u00f1os, ni\u00f1as y adolescentes \u00a0de 0 a 17 a\u00f1os se han reportado de enero a junio de 2022 que durante los mismos meses de 2021, de acuerdo a las\u00a0<a href=\"https:\/\/www.gob.mx\/sesnsp\/acciones-y-programas\/datos-abiertos-de-incidencia-delictiva?state=published\" target=\"_blank\" rel=\"noreferrer noopener\">cifras de incidencia delictiva del fuero com\u00fan<\/a>\u00a0del Secretariado Ejecutivo Nacional de Seguridad P\u00fablica SESNSP, que llegaron a 16 mil 395 para la infancia y 13 mil 515 en la adolescencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed resume la informaci\u00f3n la Red por los Derechos del Ni\u00f1o en M\u00e9xico REDIM, preocupada por todas las cifras al alza, y lo hace analizando las cifras oficiales, destaca adem\u00e1s que no cesan los feminicidios, y el incremento en lesiones es preocupante, porque tiene que ver con la violencia en casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destaca que, estos son los siete delitos contra ni\u00f1as, ni\u00f1os y adolescentes que han incrementado en el pa\u00eds entre 2021 y 2022 (cifras de enero a junio):<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Corrupci\u00f3n de menores (de 980 a 1,189: un incremento de 21.3%)<\/li><li>Extorsi\u00f3n (de 106 a 128, un incremento de 20.8%)<\/li><li>Feminicidio (de 52 a 59, un incremento de 13.5%)<\/li><li>Homicidio (de 1,214 a 1,272, un incremento de 4.8%)<\/li><li>Lesiones (de 6,765 a 8,781: un incremento de 29.8%)<\/li><li>Secuestro (de 27 a 30, un incremento de 11.1%)<\/li><li>Trata de personas (de 205 a 214, un incremento de 4.4%).<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">De estos delitos, el feminicidio, la trata de personas y la corrupci\u00f3n de menores afectan mayormente a las mujeres, mientras los homicidios, las lesiones y el secuestro se observan m\u00e1s en los hombres.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/07\/redim-02.png\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"431\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/07\/redim-02.png\" alt=\"\" class=\"wp-image-53914\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfCu\u00e1ntas ni\u00f1as, ni\u00f1os y adolescentes han sido v\u00edctimas de feminicidio y homicidio en M\u00e9xico?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Red Redim denunci\u00f3 alza de delitos en el primer semestre del 2022 contra menores de edad en M\u00e9xico, entre ellos el feminicidio infantil con un 13.5 por ciento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Red por los Derechos del Ni\u00f1o en M\u00e9xico Redim hizo un an\u00e1lisis de las cifras oficiales y las difundi\u00f3 este fin de semana en su portal oficial y que fueron recogidos por distintos portales digitales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De enero a junio de 2022 se han registrado 59 feminicidios de mujeres de entre 0 y 17 a\u00f1os en M\u00e9xico. De estos feminicidios, 11 fueron con arma de fuego y nueve con arma blanca. En el mismo periodo, 552 ni\u00f1as, ni\u00f1os y adolescentes han sido v\u00edctimas de homicidio doloso a nivel nacional (88 mujeres y 464 hombres). En total, 413 personas de entre 0 y 17 a\u00f1os han perdido la vida por homicidio con arma de fuego en M\u00e9xico de enero a junio de 2022 (68 mujeres y 345 hombres).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfEn qu\u00e9 entidades se han observado m\u00e1s delitos contra ni\u00f1as, ni\u00f1os y adolescentes?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Estado de M\u00e9xico, Nuevo Le\u00f3n y la Ciudad de M\u00e9xico han sido las entidades donde se han registrado m\u00e1s delitos contra personas de 0 a 17 a\u00f1os de enero a junio de 2022. En el mismo periodo, las entidades en las que se han registrado m\u00e1s feminicidios contra ni\u00f1as y adolescentes han sido Estado de M\u00e9xico, Nuevo Le\u00f3n y Veracruz, mientras que los homicidios dolosos de ni\u00f1as, ni\u00f1os y adolescentes han sido m\u00e1s observados en Guanajuato, Michoac\u00e1n y Zacatecas. M\u00e1s personas de entre 0 y 17 a\u00f1os han muerto por arma de fuego en 2021 en Guanajuato, Michoac\u00e1n (donde se registr\u00f3 un multihomicidio de seis adolescentes en el municipio de&nbsp;<a href=\"http:\/\/derechosinfancia.org.mx\/v1\/redim-exige-atencion-urgente-de-la-violencia-armada-contra-ninas-ninos-y-adolescentes-ante-la-masacre-de-seis-menores-de-edad-en-michoacan\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tangamandapio<\/a>) y Zacatecas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el art\u00edculo tercero de la&nbsp;<a href=\"https:\/\/www.un.org\/es\/events\/childrenday\/pdf\/derechos.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Convenci\u00f3n sobre los Derechos del Ni\u00f1o<\/a>, se establece que M\u00e9xico, como Estado parte, est\u00e1 comprometido \u201ca asegurar al ni\u00f1o la protecci\u00f3n y el cuidado que sean necesarios para su bienestar [\u2026]\u201d (CDN, Art. 3). M\u00e1s expresamente, en el art\u00edculo 19 del mismo instrumento se especifica que M\u00e9xico, como Estado parte, debe adoptar \u201ctodas las medidas legislativas, administrativas, sociales y educativas apropiadas para proteger al ni\u00f1o contra toda forma de perjuicio o abuso f\u00edsico o mental, descuido o trato negligente, malos tratos o explotaci\u00f3n, incluido el abuso sexual [\u2026]\u201d (CDN, Art. 19). Los art\u00edculos 32, 33, 34 y 35 incluyen contenidos m\u00e1s expl\u00edcitos sobre la protecci\u00f3n de la infancia y la adolescencia contra distintas formas de violencia, y en el art\u00edculo 36 se mandata que M\u00e9xico, como Estado parte, debe proteger a la ni\u00f1a o el ni\u00f1o \u201ccontra todas las dem\u00e1s formas de explotaci\u00f3n que sean perjudiciales para cualquier aspecto de su bienestar\u201d (CDN, Art. 36).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre 0 y 17 a\u00f1os han muerto por arma de fuego en 2021 en Guanajuato, Michoac\u00e1n (donde se registr\u00f3 un multihomicidio de seis adolescentes en el municipio de&nbsp;<a href=\"http:\/\/derechosinfancia.org.mx\/v1\/redim-exige-atencion-urgente-de-la-violencia-armada-contra-ninas-ninos-y-adolescentes-ante-la-masacre-de-seis-menores-de-edad-en-michoacan\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tangamandapio<\/a>) y Zacatecas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 podemos hacer para que se reduzcan los delitos de los que son v\u00edctimas las ni\u00f1as, ni\u00f1os y adolescentes?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muchas veces nos sentimos agobiados porque estas cifras parecen no reducirse mes a mes, pero lo cierto es que ninguno de estos eventos debe pasar y que hay maneras de prevenirlos, atenderlos y restituirlos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Al estado Mexicano corresponde la obligaci\u00f3n de garantizar los derechos de ni\u00f1as, ni\u00f1os y adolescentes para que sus vidas no est\u00e9n en riesgo y para que puedan desarrollarse enteramente. Por ello te compartimos algunas de las medidas que promovemos desde la Red por los Derechos de la Infancia en M\u00e9xico (REDIM) para que el estado Mexicano cumpla con su deber de defender, promover y garantizar los derechos de la infancia y la adolescencia:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Desarrollar una estrategia integral de seguridad y prevenci\u00f3n con enfoque de derechos, que garantice la protecci\u00f3n de ni\u00f1os, ni\u00f1as y adolescentes ante el incremento de la violencia armada en el pa\u00eds.<\/li><li>Es urgente, adem\u00e1s, que haya atenci\u00f3n y seguimiento particular a las acciones de prevenci\u00f3n de la violencia ya encausadas en la Comisi\u00f3n para poner fin a toda forma de Violencia hacia las Ni\u00f1as, Ni\u00f1os y Adolescentes (COMPREVNNA), estrategia articulada por el Sistema de Protecci\u00f3n Integral de los Derechos de las Ni\u00f1as, Ni\u00f1os y Adolescentes (SIPINNA).<\/li><li>Articular un proyecto prioritario para proteger el derecho a la vida y desarrollo de la infancia; el propuesto&nbsp;<a href=\"https:\/\/www.change.org\/p\/proyecto26-por-una-estrategia-nacional-frente-a-la-violencia-armada-contra-la-ni%C3%B1ez\" target=\"_blank\" rel=\"noreferrer noopener\">#Proyecto26<\/a>&nbsp;es una oportunidad para construir alternativas basadas en la comunidad, el fortalecimiento de las instituciones de infancia, la participaci\u00f3n de la ni\u00f1ez y juventud en la prevenci\u00f3n de la violencia, y especialmente importante avanzar en la construcci\u00f3n de paz en los territorios m\u00e1s conflictivos.<\/li><li>&nbsp;<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: SESNSP, Incidencia Delictiva del Fuero Com\u00fan (enero 2015 \u2013 junio 2022). Fuente de esta informaci\u00f3n&nbsp;<a href=\"https:\/\/blog.derechosinfancia.org.mx\/2022\/07\/20\/delitos-contra-ninas-ninos-y-adolescentes-en-mexico-a-junio-de-2022\/\">https:\/\/blog.derechosinfancia.org.mx\/2022\/07\/20\/delitos-contra-ninas-ninos-y-adolescentes-en-mexico-a-junio-de-2022\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/blog.derechosinfancia.org.mx\/2022\/07\/21\/homicidio-de-infancia-y-adolescencia-en-mexico-a-junio-de-2022\/\">Homicidio De Infancia Y Adolescencia En M\u00e9xico (a Junio De 2022) &#8211; Blog De Datos E Incidencia Pol\u00edtica De REDIM (derechosinfancia.org.mx)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las ni\u00f1as viven corrupci\u00f3n de menores, feminicidio y trata<\/p>\n","protected":false},"author":3,"featured_media":53915,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[693,47],"tags":[],"class_list":["post-53913","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-no-mas-impunidad"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/53913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=53913"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/53913\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/53915"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=53913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=53913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=53913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}