{"id":53814,"date":"2022-07-28T14:47:44","date_gmt":"2022-07-28T20:47:44","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=53814"},"modified":"2023-07-21T19:10:04","modified_gmt":"2023-07-22T00:10:04","slug":"rafaga-danzon-el-viento-y-una-broma-recordando-a-juarez","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/rafaga-danzon-el-viento-y-una-broma-recordando-a-juarez\/","title":{"rendered":"R\u00e1faga|\u00a0 Danz\u00f3n, El Viento y una Broma. Recordando a Ju\u00e1rez"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Jorge Herrera Valenzuela<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 28 de julio del 2022.- Estamos a 150 a\u00f1os del fallecimiento del Presidente de M\u00e9xico m\u00e1s querido, respetado, honrado y el primer ind\u00edgena que en el Siglo XIX despach\u00f3 en Palacio Nacional, donde vivi\u00f3 sus \u00faltimos d\u00edas en una habitaci\u00f3n del ala norte, hacia la calle de Moneda. Un mal card\u00edaco le cort\u00f3 la existencia a los 66 a\u00f1os de edad. Es el \u00fanico presidente itinerante que registra nuestra Historia Patria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este sesquicentenario de ese suceso, la Sociedad Mexicana de Geograf\u00eda y Estad\u00edstica, presidida por el soci\u00f3logo y acad\u00e9mico Hugo Castro Aranda, est\u00e1 celebrando Las Jornadas Juaristas, mediante un programa de conferencias los martes a las seis de la tarde en su local de Justo Sierra 19, en el Centro Hist\u00f3rico de la Ciudad de M\u00e9xico. Tambi\u00e9n interviene en la organizaci\u00f3n el historiador Oscar Gonz\u00e1lez Azuela, secretario general de la instituci\u00f3n fundada en 1833 por Valent\u00edn G\u00f3mez Far\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destacados intelectuales, juristas, historiadores y&nbsp; cronistas participar\u00e1n para hablar de los diversos aspectos de la presidencia a cargo del zapoteco que aprendi\u00f3 el espa\u00f1ol a los 12 a\u00f1os de edad, estudi\u00f3 Derecho, gobern\u00f3 su natal Oaxaca, presidi\u00f3 la Suprema Corte de Justicia y de 1858 a 1872 fue Presidente de la Rep\u00fablica. El martes 19 la doctora, historiadora, catedr\u00e1tica Patricia Galeana Herrera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta semana correspondi\u00f3 al historiador y escritor Ra\u00fal Gonz\u00e1lez Lezama comentar sobre \u201cBenito Ju\u00e1rez, El Estratega en Defensa de la Patria\u201d, ante la intervenci\u00f3n francesa y las decisiones radicales para liquidar al segundo imperio en M\u00e9xico, con el fusilamiento de Maximiliano en el Cerro de las Campanas, en Quer\u00e9taro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las Jornadas Juaristas, una retrospectiva en la voz de los historiadores del presente, terminar\u00e1 el martes 6 de septiembre y participar\u00e1n intelectuales como Jes\u00fas Gonz\u00e1lez Schmal. \u00c1ngeles Gonz\u00e1lez Gamio, Hugo Hiriart y Vicente Quirarte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cSi Ju\u00e1rez no hubiera muerto\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En todo el Pa\u00eds la m\u00fasica es algo imprescindible. No podemos vivir sin estar oyendo las composiciones musicales, instrumentales o cantadas. Hay para todos los gustos. En toda ciudad mexicana encontraremos un sal\u00f3n de baile, uno de los legendarios y famosos es el Sal\u00f3n Los \u00c1ngeles, al igual que El Breta\u00f1a y El Colonia y los desaparecidos Floresta, Riviera, El Pavill\u00f3n, La Playa, El Smyrna Dancing Club y El An\u00e1huac. Todos del antiguo Distrito Federal, la Capital Mexicana.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bueno, \u00bfqui\u00e9n no ha o\u00eddo, bailado y deleitado con el danz\u00f3n \u201cSi Ju\u00e1rez No Hubiera Muerto\u201d?&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pocos sabemos qui\u00e9n y por qu\u00e9 lo compuso. Cu\u00e1ndo y d\u00f3nde se origin\u00f3 este danz\u00f3n. Este comentarista se fue a los archivos y el olfato reporteril nos llev\u00f3 hasta Comit\u00e1n de Flores, hoy Comit\u00e1n de Dom\u00ednguez, Chiapas, donde en 1888 naci\u00f3 Esteban Alfonzo Garc\u00eda que tra\u00eda el esp\u00edritu y la mentalidad de ser m\u00fasico. Inicialmente estudi\u00f3 piano en su tierra y despu\u00e9s se inscribi\u00f3 en el Conservatorio de M\u00fasica de la Ciudad de M\u00e9xico. Imparti\u00f3 clases de m\u00fasica en escuelas oficiales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esteban estaba enamorado de una chica de Comit\u00e1n, que muri\u00f3 ahogada. En esos d\u00edas escuch\u00f3 un danz\u00f3n compuesto por el cubano Tereso Vald\u00e9s, quien vivi\u00f3 un romance similar y naci\u00f3 en \u00e9l la idea de recordar a la joven con \u201cClave a Caridad\u201d. El chiapaneco en 1916 escribi\u00f3 m\u00fasica y letra de su composici\u00f3n y tres a\u00f1os despu\u00e9s se produjo la primera grabaci\u00f3n con la interpretaci\u00f3n de la Orquesta Colombia. En muy corto tiempo se hizo popular en toda la tierra chiapaneca, transpuso l\u00edmites geogr\u00e1ficos y era el danz\u00f3n de moda como lo fue despu\u00e9s \u201cNereidas\u201d del mismo hijo de Comit\u00e1n de las Flores.&nbsp; Esteban fue distinguido con \u201cLa Batuta de Plata\u201d y fue su principal interprete el muy aplaudido Acerina y su Danzonera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Familia de Esteban, por deseo de \u00e9l, se traslad\u00f3 a radicar en Torre\u00f3n, Coahuila. Ah\u00ed falleci\u00f3 el 29 de septiembre de 1950. Es uno de los grandes m\u00fasicos, olvidado por su gremio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cA m\u00ed, el viento me hace\u2026\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde siempre he o\u00eddo en mi ochentera vida dos frases, muy populares a nivel nacional. Es tan repetida que hasta el actual Presidente de M\u00e9xico la pronuncia en su programa televisivo \u201cLa Ma\u00f1anera\u201d. Estas son: \u201cA m\u00ed, me hace lo que el viento a Ju\u00e1rez\u201d o \u201cLo que le hizo el viento a Ju\u00e1rez\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqu\u00ed se presenta la pregunta obligada, \u00bfqu\u00e9 le hizo el viento a Ju\u00e1rez?\u201d. Estamos acostumbrados a repetir lo que se hace popular, sin saber m\u00e1s all\u00e1 de la misma expresi\u00f3n. Al interrogar a unas personas sobre este tema, una dama sonriente me dijo: \u201cpues, \u00bfQu\u00e9 no sabe?, le tumb\u00f3 el sombrero\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay tres versiones. La primera es la m\u00e1s cre\u00edble, sin que este comentarista pueda afirmarlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La primera forma parte del libro \u201cUn indio zapoteco llamado Benito Ju\u00e1rez\u201d, cuyo autor fue el maestro Fernando Ben\u00edtez. En las p\u00e1ginas leemos que Benito Pablo Ju\u00e1rez Garc\u00eda se junt\u00f3 con varios amigos de su edad y se embarcaron en una canoa, sopl\u00f3 fuerte viento y los muchachitos se lanzaron, al agua, para salir nadando mientras Benito permaneci\u00f3 en la lancha y pasado el ventarr\u00f3n se orill\u00f3 y salt\u00f3 hacia tierra firme. Y el hecho se convirti\u00f3 en frase del pueblo: El viento no le atemoriz\u00f3 al que ser\u00eda Presidente de M\u00e9xico. No le pas\u00f3 nada.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pintor Antonio Gonz\u00e1lez Orozco en un mural que hizo en el Castillo de Chapultepec, pint\u00f3 a Benito Ju\u00e1rez sujetando el l\u00e1baro patrio mientras un fuerte viento ondeaba la bandera nacional y\u201d el personaje ni se inmuta, ni se despeina\u201d. Esta versi\u00f3n nadie la confirma y el muralista muri\u00f3 en junio de 2020, a los 82 a\u00f1os. Fue disc\u00edpulo de Diego Rivera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo hay quienes dicen que la frase est\u00e1 relacionada con una estatua ubicada en el Cerro de las Campanas, sitio en que fusilaron a Maximiliano, Miram\u00f3n y Mej\u00eda. Hay fuertes corrientes de aire y el monumento no ha sufrido ning\u00fan da\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El irrespetuoso \u201cloco\u201d Vald\u00e9s<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Precisamente en el A\u00f1o de Ju\u00e1rez, 1972, decretado por el presidente Luis Echeverr\u00eda \u00c1lvarez, durante el desarrollo de \u201cEl Show del \u201cLoco\u201d Vald\u00e9s\u201d, \u00e9ste artista tuvo \u201cla ocurrencia\u201d de hacer una broma, con juego de palabras, en las que involucr\u00f3 al oaxaque\u00f1o y a su esposa.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Manuel Vald\u00e9s sali\u00f3 de la pantalla del entonces Canal 2, hoy Canal de Las Estrellas. No lo vetaron, no lo multaron y en Gobernaci\u00f3n el titular, Mario Moya Palencia, lo rega\u00f1\u00f3 por irrespetuoso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 sucedi\u00f3? \u00bfQu\u00e9 dijo el pap\u00e1 de Christian Castro?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl Loco\u201d lleg\u00f3 al estudio vestido de bombero. Obvio hablar\u00eda de la labor de los tragahumo, como les llamamos a los heroicos&nbsp; bomberos. En el curso de sus di\u00e1logos improvisados, se le antoj\u00f3 preguntarse asimismo, \u00bfqui\u00e9n es el presidente bomberito? Se respondi\u00f3, entre carcajadas y sus ademanes acostumbrados, \u201cPues, Bomberito Ju\u00e1rez\u201d y no par\u00f3 ah\u00ed, volvi\u00f3 a autointerrogarse, \u00bfy qui\u00e9n le ayuda? Otra carcajada estruendosa, sus brincos y movimientos de manos, al decir, Do\u00f1a Manguerita Maza de Ju\u00e1rez\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La reacci\u00f3n presidencial fue natural, es decir no se coart\u00f3 la libertad de expresi\u00f3n pero si se censur\u00f3 la irreverencia hacia el matrimonio Benito Ju\u00e1rez y Margarita Maza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:jherrerav@live.com.mx\">jherrerav@live.com.mx<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estamos a 150 a\u00f1os del fallecimiento del Presidente de M\u00e9xico m\u00e1s querido, respetado, honrado y el primer ind\u00edgena que en el Siglo XIX despach\u00f3 en Palacio Nacional, donde vivi\u00f3 sus \u00faltimos d\u00edas en una habitaci\u00f3n del ala norte, hacia la calle de Moneda<\/p>\n","protected":false},"author":3,"featured_media":38023,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[693,94,35,107],"tags":[],"class_list":["post-53814","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-jorge-herrera-valenzuela","category-opinion","category-rafaga"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/53814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=53814"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/53814\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/38023"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=53814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=53814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=53814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}