{"id":53501,"date":"2022-07-22T11:41:58","date_gmt":"2022-07-22T17:41:58","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=53501"},"modified":"2023-07-21T19:09:21","modified_gmt":"2023-07-22T00:09:21","slug":"periodistas-alertan-sobre-corrupcion-y-opacidad-en-gobiernos-llaman-a-defender-a-instituciones-garantes-de-la-transparencia","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/periodistas-alertan-sobre-corrupcion-y-opacidad-en-gobiernos-llaman-a-defender-a-instituciones-garantes-de-la-transparencia\/","title":{"rendered":"Periodistas alertan sobre corrupci\u00f3n y opacidad en gobiernos, \u00a0llaman a defender a instituciones garantes de la transparencia"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Presentan en Chiapas el libro Periodismo de Investigaci\u00f3n en el \u00e1mbito local, editado por el INAI<\/strong><\/li><li><strong>Esta obra nos relata periodistas descubren, a trav\u00e9s del derecho de acceso a la informaci\u00f3n, presuntos actos de corrupci\u00f3n de autoridades en los estados: Norma Julieta del R\u00edo Venegas<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Redacci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. Tuxtla Guti\u00e9rrez, Chiapas. 22 de julio del 2022.-Mujeres periodistas alertan sobre tentaciones de opacidad en los gobiernos y llaman a defender a las instituciones encargadas de garantizar la transparencia y el acceso a la informaci\u00f3n en el pa\u00eds, durante la presentaci\u00f3n del libro Periodismo de Investigaci\u00f3n en el \u00e1mbito local, editado por el Instituto Nacional de Transparencia, Acceso a la Informaci\u00f3n y Protecci\u00f3n de Datos Personales (INAI), en el estado de Chiapas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el evento, la Comisionada Norma Julieta del R\u00edo Venegas, Presidenta del Comit\u00e9 Editorial del INAI, destac\u00f3 que el libro contiene seis historias de periodistas, quienes, a trav\u00e9s del ejercicio del derecho de acceso a la informaci\u00f3n lograron descubrir casos emblem\u00e1ticos de corrupci\u00f3n en las entidades federativas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cEsta obra, que fue coordinada por la reconocida periodista Sandra Romand\u00eda Vega, nos relata c\u00f3mo ella y sus compa\u00f1eros periodistas descubren, a trav\u00e9s del derecho de acceso a la informaci\u00f3n, presuntos actos de corrupci\u00f3n de autoridades en los estados (\u2026) El prop\u00f3sito del Comit\u00e9 Editorial es precisamente este: apoyar obras, investigaciones, reportajes, ensayos o cuadernillos que hablen de los dos derechos que tutela el INAI\u201d, expuso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y se\u00f1al\u00f3, que la Plataforma Nacional de Transparencia (PNT) ha contribuido de manera significativa al periodismo de investigaci\u00f3n y puntualiz\u00f3 que \u201ces un bien p\u00fablico, de todas y todos los mexicanos, que fue desarrollada en el a\u00f1o 2016 y, como todo desarrollo tecnol\u00f3gico, ha tenido sus altas y bajas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aclar\u00f3 que, si bien ha tenido intermitencias en su operaci\u00f3n a consecuencia de millones de ciberataques registrados desde 11 de julio, \u201cla plataforma est\u00e1 estable, nunca dej\u00f3 de estar en el aire, siempre estuvo trabajando\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su intervenci\u00f3n, la periodista y coordinadora del libro, Sandra Romand\u00eda Vega, al hablar de su reportaje \u201cEstado de M\u00e9xico: la f\u00e1brica de falsos culpables\u201d dijo que, gracias a la informaci\u00f3n obtenida v\u00eda transparencia, se pudo constatar c\u00f3mo operaba en la entidad este sistema de detenci\u00f3n de personas inocentes a las que les fabricaban delitos, con el fin de bajar los \u00edndices de impunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cRevelar esa realidad, desenmascarar a quienes nos gobiernan y cometen estos actos de corrupci\u00f3n, abuso de poder, conflicto de inter\u00e9s, tr\u00e1fico de influencias es y ser\u00e1 relevante siempre, y por eso es sumamente importante que el marco legislativo que hoy tenemos para garantizar el acceso a la informaci\u00f3n lo defendamos desde la trinchera del ciudadano, pero tambi\u00e9n del periodista\u201d, exhort\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su vez, la periodista Susana Guadalupe Sol\u00eds Esquinca, se\u00f1al\u00f3 que el sistema de transparencia en el pa\u00eds marca un antes y un despu\u00e9s en el periodismo de investigaci\u00f3n, pues ahora es m\u00e1s f\u00e1cil obtener evidencias documentales con el apoyo de los institutos locales y el nacional, para contrastar los datos y los dichos de las autoridades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cCuidado porque la tentaci\u00f3n de la opacidad sigue vigente. No solo desde el periodismo hay que defender a estas instituciones, sino tambi\u00e9n desde la ciudadan\u00eda; quiz\u00e1 lo que haya que hacer en estos momentos es socializar la forma en c\u00f3mo el ciudadano com\u00fan puede acceder a estos datos (\u2026) pero cuidado con estas tentaciones, el dinosaurio no se ha ido, sigue vivo, colea y se quiere poner ropajes transparentes: no hay que creerle\u201d, advirti\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su mensaje, el Comisionado Presidente del Instituto de Transparencia, Acceso a la Informaci\u00f3n y Protecci\u00f3n de Datos Personales del Estado de Chiapas (Itaipch), Hugo Villar Pinto, sostuvo que la obra demuestra la utilidad de la transparencia en el periodismo de investigaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cEs un trabajo que est\u00e1 diciendo que la transparencia es un asunto que sirve y mucho, porque puede instrumentar una serie de procesos sociales y que puede encaminar a una sociedad hacia mejores estadios\u201d, subray\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, la Coordinadora de los Organismos Garantes de las Entidades Federativas del Sistema Nacional de Transparencia y Comisionada Presidenta del IDAIP, Luz Mar\u00eda Mariscal C\u00e1rdenas, dijo que el libro permitir\u00e1 a la ciudadan\u00eda saber c\u00f3mo puede obtener informaci\u00f3n de utilidad para participar en la toma de decisiones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cCreo que, para combatir la opacidad, en la que por muchos a\u00f1os los gobiernos han permanecido, la Plataforma Nacional de Transparencia y el acceso a la informaci\u00f3n son una herramienta fundamental, al igual que para combatir la corrupci\u00f3n\u201d, recalc\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su turno, la Coordinadora de la Regi\u00f3n Sureste del SNT y Comisionada Presidenta del \u00f3rgano garante de Veracruz, Naldy Patricia Lagunes Rodr\u00edguez, indic\u00f3 que la obra demuestra lo pr\u00e1ctico y eficiente que puede llegar a ser el ejercicio del derecho de acceso a la informaci\u00f3n para conocer c\u00f3mo se entretejen algunos casos de corrupci\u00f3n en los estados, \u201cque impiden el crecimiento y el desarrollo de nuestros territorios, as\u00ed como condiciones reales de mejora para la poblaci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La obra fue comentada tambi\u00e9n por el Comisionado del Itaipch, Jes\u00fas David Pineda Carpio, y el Director de Promoci\u00f3n del INAI, Sergio Octavio. Particip\u00f3, en calidad de moderadora, la Comisionada del \u00f3rgano garante de Chiapas, Marlene Marisol Gordillo Figueroa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/MG<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presentan en Chiapas el libro Periodismo de Investigaci\u00f3n en el \u00e1mbito local, editado por el INAI<\/p>\n","protected":false},"author":3,"featured_media":53502,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[693,51],"tags":[],"class_list":["post-53501","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-ejecutivo"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/53501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=53501"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/53501\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/53502"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=53501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=53501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=53501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}