{"id":52341,"date":"2022-06-28T09:04:17","date_gmt":"2022-06-28T15:04:17","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=52341"},"modified":"2023-07-21T19:07:25","modified_gmt":"2023-07-22T00:07:25","slug":"mayo-el-mes-mas-violento-del-2022-27-mil-casos-de-violencia-familiar","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/mayo-el-mes-mas-violento-del-2022-27-mil-casos-de-violencia-familiar\/","title":{"rendered":"Mayo, el mes m\u00e1s violento del 2022: 27 mil casos de violencia familiar"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Violencia contra la mujer, tendencia con m\u00e1s de mil llamadas diarias al 911<\/strong><\/li><li><strong>La violencia en contra de las mujeres ha alcanzado niveles sin precedentes en M\u00e9xico<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Redacci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 28 de junio del 2022.- La actualizaci\u00f3n de la informaci\u00f3n sobre violencia contra las mujeres, la incidencia delictiva y llamadas de emergencia al 911 dado a conocer el s\u00e1bado por el Secretariado Ejecutivo del Sistema Nacional de Seguridad P\u00fablica, han&nbsp; dado cuenta del mayor pico en la incidencia de delitos de violencia familiar que super\u00f3 los 27 mil casos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esa informaci\u00f3n se\u00f1ala que, &nbsp;la incidencia de los delitos de violencia de g\u00e9nero en todas sus modalidades distinta a la violencia familiar, cuya tendencia despunt\u00f3 a partir de enero en los 300 casos, pero s\u00f3lo en mayo lleg\u00f3 a los 545 delitos, que signific\u00f3 un alza del 23 por ciento &nbsp;respecto a la ocurrencia de enero a mayo del 2021; mientras que en el n\u00famero de violaciones hubo un aumento de m\u00e1s de 13 por ciento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las llamadas de emergencia por incidentes de acoso u hostigamiento sexual, tambi\u00e9n reflejaron la mayor alza desde enero del 2016, con un total de mil 347 llamadas, lo cual tambi\u00e9n se replic\u00f3 con la mayor cantidad al 911 por abuso sexual y violencia contra la mujer, con una tendencia de m\u00e1s de mil llamadas diarias en mayo, al cerrar con 34 mil 719 reportes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La violencia en contra de las mujeres ha alcanzado niveles sin precedentes en M\u00e9xico. Durante mayo, el mes m\u00e1s violento del a\u00f1o, se registraron in\u00e9ditos incrementos en diversos delitos que evidenciaron el mayor aumento de mujeres asesinadas, as\u00ed como la mayor cantidad de mujeres extorsionadas de los \u00faltimos ocho a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque en mayo hubo una baja marginal del 4 por ciento &nbsp;en el delito de feminicidio, la cantidad de mujeres asesinadas estuvo lejos de disminuir, pues en el caso de los homicidios dolosos se alcanz\u00f3 un total de 272 v\u00edctimas, mientras que en el caso de las v\u00edctimas de homicidio culposo se lleg\u00f3 a las 349 mujeres. Es decir, 621 en 30 d\u00edas, m\u00e1s de 20 diarias. En ambos casos, los mayores registros desde 2015.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La hist\u00f3rica alza tambi\u00e9n alcanz\u00f3 otras incidencias, como fue el caso de la cantidad de mujeres extorsionadas, que in\u00e9ditamente en mayo, registr\u00f3 un total de 400 v\u00edctimas, con lo cual ya suman m\u00e1s de mil 600 mujeres v\u00edctimas de ese delito en los primeros cinco meses del a\u00f1o, que no hab\u00eda superado las 330 v\u00edctimas hasta este 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/MG<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Violencia contra la mujer, tendencia con m\u00e1s de mil llamadas diarias al 911<\/p>\n","protected":false},"author":3,"featured_media":52342,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[693,47,48],"tags":[],"class_list":["post-52341","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-no-mas-impunidad","category-no-mas-impunidad-no-mas-impunidad"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/52341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=52341"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/52341\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/52342"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=52341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=52341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=52341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}