{"id":51630,"date":"2022-06-12T10:38:03","date_gmt":"2022-06-12T16:38:03","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=51630"},"modified":"2023-07-21T19:06:19","modified_gmt":"2023-07-22T00:06:19","slug":"ganando-espacios-casualidades-del-5-de-junio","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/ganando-espacios-casualidades-del-5-de-junio\/","title":{"rendered":"Ganando Espacios| Casualidades del 5 de junio"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&nbsp;Noem\u00ed Mu\u00f1oz Cant\u00fa<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Toluca, Estado de M\u00e9xico, 12 de junio, 2022.- Las elecciones del pasado 5 de junio nos dejaron boquiabiertos. Todos cre\u00edmos que la alianza Va por M\u00e9xico ten\u00eda muchas posibilidades. Imagin\u00e1bamos que la derrota no ser\u00eda tan aparatosa, pero lo fue.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque Alito Moreno ha declarado que \u201chay tiro\u201d porque ahora es cuando se demostrar\u00e1 que la coalici\u00f3n es m\u00e1s fuerte que el partido del poder. Sin embargo, la p\u00e9rdida de cuatro estados de seis que se peleaban hizo pensar que era momento de recular y salir por la puerta de atr\u00e1s, pero Morena asegur\u00f3 que gan\u00f3 las elecciones a la dirigencia por cuatro a\u00f1os y en ese tiempo estar\u00e1 por encima del PRI.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con estos resultados, Morena se queda con 19 estados del pa\u00eds y la Ciudad del M\u00e9xico, es decir un 60 por ciento del territorio nacional, por lo cual m\u00e1s que un \u201ctiro\u201d debe ser una lucha a muerte por el 40 por ciento de lo que queda. En esa gresca, la joya de la corona, el estandarte priista, el tesoro ser\u00e1 sin duda el Estado de M\u00e9xico, el que todos los partidos querr\u00e1n obtener.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Morena en este momento est\u00e1 m\u00e1s all\u00e1 de las nubes, tan es as\u00ed que su dirigente nacional, Mario Delgado, ya llam\u00f3 a sus militantes a formar comit\u00e9s para prepararse para las elecciones del 2023 y del 2024, porque han reafirmado que tienen la supremac\u00eda en los electores. Lo que pas\u00f3 en Hidalgo confirma el temor de los que van en Alianza, ya que despu\u00e9s de 93 a\u00f1os de priismo, ha ganado Morena. As\u00ed que los resultados p\u00edrricos para el mont\u00f3n de partidos que han hecho equipo reafirma que no es tan importante ir todos juntos como una sola fuerza, que considero, nadie cree.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es urgente que reflexionen por qu\u00e9 la gente se est\u00e1 quedando con Morena. \u00bfSer\u00e1 como dice la candidata de Hidalgo, que es por los programas sociales que promete?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Considero que lo que hace Delgado deber\u00eda llevar a la reflexi\u00f3n a los otros.&nbsp; Seg\u00fan Leo Zuckerman en su columna del Universal, Morena es m\u00e1s fuerte porque sus opositores no est\u00e1n bien unidos, es decir, est\u00e1n juntos, pero no revueltos. Cada quien va por sus intereses y se nota.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a Leo, esta divisi\u00f3n le cae de perlas a Morena, porque la gente no ve un candidato claro. As\u00ed que asegura que, si Morena consigue que se separen las alianzas y Movimiento Ciudadano vaya solo, ya gan\u00f3 las elecciones. \u00bfY adivinen qu\u00e9? Dante Delgado, l\u00edder de dicho partido, ya dijo que va sin alianza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo rescatable de esta contienda es ver a las mujeres en las boletas electorales. Para llegar a este punto tuvieron que pasar siglos y saber que cualquiera de nosotras puede luchar en igualdad con los hombres, eso ya es hist\u00f3rico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las elecciones del pasado 5 de junio nos dejaron boquiabiertos. Todos cre\u00edmos que la alianza Va por M\u00e9xico ten\u00eda muchas posibilidades. Imagin\u00e1bamos que la derrota no ser\u00eda tan aparatosa, pero lo fue.<\/p>\n","protected":false},"author":3,"featured_media":45255,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[693,639,640,35],"tags":[],"class_list":["post-51630","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-ganando-espacios","category-noemi-munoz-cantu","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/51630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=51630"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/51630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/45255"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=51630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=51630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=51630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}