{"id":50536,"date":"2022-05-21T14:57:24","date_gmt":"2022-05-21T20:57:24","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=50536"},"modified":"2023-07-21T19:05:22","modified_gmt":"2023-07-22T00:05:22","slug":"hallazgos-vacio","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/hallazgos-vacio\/","title":{"rendered":"Hallazgos| Vac\u00edo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&nbsp;Roc\u00edo Fiallega<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 21 de mayo, 2022.- Mis pezones se asoman por la barandilla mientras me recargo en ella para mirar hacia la calle donde est\u00e1 mi vecina observando cu\u00e1ntas personas entran a mi casa. Hace unas semanas mi pecho estaba reservado a la intimidad de mi piel y ahora parece como si quisiera gritarle al mundo algo, creciendo; mientras que mi cintura se ha transformado de un caudaloso r\u00edo a un riachuelo que va dirigi\u00e9ndose hacia alg\u00fan manantial, ese lugar que sangra con la luna desde hace dos a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dejo de pensar en mi cuerpo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi padre ha muerto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No es cierto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9l nunca me dejar\u00eda sola.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi padre no ha muerto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La sala de mi casa se sigue poblando de gente. Mi madre y mis hermanos tratan de mover el cuerpo de mi padre, \u00bfpor qu\u00e9 no lo dejan descansar?, que no ven que se le meti\u00f3 ese aire cuando fue al ba\u00f1o y de repente al sentarse en la silla del comedor solamente empez\u00f3 a decir que no pod\u00eda respirar; entonces Elisa y Enrique lo abanicaron y mi madre, oyendo los gritos desde la sastrer\u00eda, acudi\u00f3 corriendo, mientras Herme y yo nos escondimos detr\u00e1s de las sillas, s\u00f3lo para ver si todo acababa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dicen que mi padre dej\u00f3 de respirar, pero tambi\u00e9n dicen que fue un paro cardiaco de esos fulminantes, pero nada es cierto, c\u00f3mo puede dejar de mirarme ese hombre de sonrisa eterna, con sus dos cicatrices en los p\u00f3mulos, como las marcas de los pachucos que se pelean en las calles; c\u00f3mo va a dejar mis manos huecas de amor ese pap\u00e1 que me llev\u00f3 de la mano al k\u00ednder de las madres de la Academia Moderna; c\u00f3mo ser\u00eda posible que aquel ni\u00f1o que apaleara a su madrastra y huyera con sus hermanos en la madrugada, dejara de contarme historias de revolucionarios y de c\u00f3mo se ganaba la vida en la frontera, y de c\u00f3mo en Lecumberri conoci\u00f3 a tanto truhan siendo Jefe de sastres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi padre ha muerto, eso dicen para hacerme sufrir. Mis hermanos no me quieren porque \u00e9l me quiere nada m\u00e1s a m\u00ed y a ellos les pega; tambi\u00e9n mi madre est\u00e1 celosa de que yo sea la mujer que \u00e9l m\u00e1s ama y amar\u00e1 en el mundo (\u00e9l me lo dijo, bueno, en realidad, con ese calorcito de su aliento me sopl\u00f3 en el o\u00eddo que yo era la ni\u00f1a m\u00e1s bonita y que nunca amar\u00eda a otra como a m\u00ed), aunque mi mam\u00e1 tenga ojos verdes, \u00e9l me ama a m\u00ed y ning\u00fan hombre podr\u00e1 hacerlo como \u00e9l.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi padre no ha muerto. Esa es la verdad, porque si fuera lo contrario entonces yo me morir\u00eda de pena y no tendr\u00edamos nada de comer, como cuando \u00e9l se fue una semana porque mi mam\u00e1 le dijo cosas feas, ah\u00ed ten\u00edamos hambre y no hab\u00eda nada, s\u00f3lo ve\u00edamos correr las ratas de un lado para otro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi padre ha muerto. Mi madre ha elegido la peor ropa para pon\u00e9rsela a \u00e9l. Todos los vecinos est\u00e1n en la sala, pero nadie ayuda, todos observan, se va quedando vac\u00edo el espacio entre mi coraz\u00f3n y mi sexo. Entran y salen de la cocina, ya alguien trajo dos guisados, ya mis hermanos comen unos tacos y yo con este espacio ciego adentro de m\u00ed, como si se me fuera a salir el alma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi padre no ha muerto. \u00c9l me llevar\u00e1 del brazo hacia el altar para entregarme al mejor hombre que pueda yo encontrarme. Debe estar en mi boda, aunque no vaya ninguno de mis hermanos, mejor que se mueran ellos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lleg\u00f3 mi T\u00edo To\u00f1o, el que es padre en la iglesia de Coyoac\u00e1n, con cuatro palabras de su boca sal\u00ed corriendo \u201cTu pap\u00e1 se muri\u00f3\u201d, encarrerada hacia la escalera escuch\u00e9 a lo lejos: \u201cYa le di los Santos \u00f3leos\u201d; por eso estoy aqu\u00ed recargada en la barandilla, para que Dios venga en una nube y me diga la verdad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis pezones se asoman por la barandilla mientras me recargo en ella para mirar hacia la calle donde est\u00e1 mi vecina observando cu\u00e1ntas personas entran a mi casa.<\/p>\n","protected":false},"author":3,"featured_media":39324,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[693,620,35,621],"tags":[],"class_list":["post-50536","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-hallazgos","category-opinion","category-rocio-fiallega"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/50536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=50536"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/50536\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/39324"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=50536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=50536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=50536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}