{"id":50095,"date":"2022-05-14T11:34:22","date_gmt":"2022-05-14T17:34:22","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=50095"},"modified":"2023-07-21T19:04:44","modified_gmt":"2023-07-22T00:04:44","slug":"hallazgos-entre-amoras","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/hallazgos-entre-amoras\/","title":{"rendered":"Hallazgos| Entre amoras"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Roc\u00edo Fiallega<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, CD. de M\u00e9xico, 14 de mayo, 2022.-Entre amoras. Lesbianismo en la narrativa mexicana, escrito por Maria Elena Olivera C\u00f3rdova, editado por la UNAM \u2013a trav\u00e9s del CEIICyH-, con pr\u00f3logo de Francesca Gargallo (qepd) es un delicioso libro para acercarnos a la literatura l\u00e9sbica y comprender la disidencia sexogen\u00e9rica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de ser un texto nacido en la academia, bien puede cumplir su funci\u00f3n de divulgaci\u00f3n del conocimiento por su lenguaje claro y por la explicaci\u00f3n de las categor\u00edas de an\u00e1lisis empleadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nunca nos hubi\u00e9ramos imaginado que la primera lesbiana de nuestra literatura apareci\u00f3 en Santa (de Federico Gamboa), ni que Rosa Mar\u00eda Roffiel es la causante de iniciar una nueva lectura de esta orientaci\u00f3n sexual elegida con su libro Amora, para que las lectoras actuales nos regocijemos con novelas, cuentos y poes\u00eda l\u00e9sbicas con otra perspectiva, m\u00e1s abierta y libertaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda Elena Olivera sabe su trabajo de narradora, nos conduce por el entramado te\u00f3rico literario (modelo adaptado, que retoma la autora a falta de uno que d\u00e9 las herramientas necesarias para entender la narrativa literaria pol\u00edtica), a al tiempo que nos relata el arduo camino de las lesbianas y las feministas.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para Olivera, la transici\u00f3n de las lesbianas como personajes estereotipados a la \u201cvisibilizaci\u00f3n positiva de la experiencia l\u00e9sbica y la franca resistencia al orden heteropatriarcal\u201d en la literatura fue producto \u2013como mencionamos ya- de Amora, as\u00ed como de la segunda ola feminista.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Amora se hace expl\u00edcita la disidencia sexogen\u00e9rica que no solamente tiene que ver con la visibilizaci\u00f3n de las mujeres con una orientaci\u00f3n sexual diferente a la establecida, sino como un entramado ideol\u00f3gico-pol\u00edtico en el ser y actuar en el mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre Amoras&#8230; aporta tambi\u00e9n estudios de la narrativa l\u00e9sbica en las novelas Dos mujeres de Sara Levi, R\u00e9quiem por una mu\u00f1eca rota de Eve Gil, Sandra. Secreto amor de Reyna Barrera y No hay princesa sin drag\u00f3n de Ana Klein; as\u00ed como en los cuentos \u201cCon fugitivo paso\u201d de Victoria Enr\u00edquez y \u201cLa primera revelaci\u00f3n\u201d de Rosa Mar\u00eda Roffiel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, las estudiosas y las lectoras ahora tenemos a la mano una basta bibliograf\u00eda sobre el tema.&nbsp;&nbsp; As\u00ed es que \u00a1A leer!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre amoras. Lesbianismo en la narrativa mexicana, escrito por Maria Elena Olivera C\u00f3rdova, editado por la UNAM \u2013a trav\u00e9s del CEIICyH-, con pr\u00f3logo de Francesca Gargallo (qepd) es un delicioso libro para acercarnos a la literatura l\u00e9sbica y comprender la disidencia sexogen\u00e9rica.<\/p>\n","protected":false},"author":3,"featured_media":39324,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[693,620,35,621],"tags":[],"class_list":["post-50095","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-hallazgos","category-opinion","category-rocio-fiallega"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/50095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=50095"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/50095\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/39324"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=50095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=50095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=50095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}