{"id":50083,"date":"2022-05-14T10:17:50","date_gmt":"2022-05-14T16:17:50","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=50083"},"modified":"2023-07-21T19:04:44","modified_gmt":"2023-07-22T00:04:44","slug":"participa-tepjf-inmujres-consejeros-consejeras-y-opl-en-la-vigesima-sesion-ordinaria-del-observatorio-de-participacion-politica-de-las-mujeres-en-mexico","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/participa-tepjf-inmujres-consejeros-consejeras-y-opl-en-la-vigesima-sesion-ordinaria-del-observatorio-de-participacion-politica-de-las-mujeres-en-mexico\/","title":{"rendered":"Participa TEPJF, INMUJRES, consejeros, consejeras y OPL en la Vig\u00e9sima Sesi\u00f3n Ordinaria del Observatorio de Participaci\u00f3n Pol\u00edtica de las Mujeres en M\u00e9xico"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Falta mucho camino por recorrer para consolidar la democracia sustantiva que todas y todos queremos: Lorenzo C\u00f3rdova<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Redacci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 14 de mayo, 2022.- Autoridades electorales, organizaciones de la sociedad civil e instituciones del Estado mexicano integrantes del Observatorio de Participaci\u00f3n Pol\u00edtica de las Mujeres en M\u00e9xico, externaron su compromiso de seguir trabajando hasta consolidar una democracia paritaria y, de cara a las elecciones del pr\u00f3ximo 5 de junio en seis entidades, las mujeres puedan ejercer no s\u00f3lo su derecho a la participaci\u00f3n pol\u00edtica, sino a ejercer los cargos en condiciones de igualdad y libre de violencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la&nbsp;Vig\u00e9sima Sesi\u00f3n Ordinaria&nbsp;del Observatorio, el Consejero Presidente del Instituto Nacional Electoral (INE), Lorenzo C\u00f3rdova Vianello, se\u00f1al\u00f3 que \u201cM\u00e9xico es, con cualquier indicador que se le mida, mucho m\u00e1s incluyente y paritario que el que ten\u00edamos en 2014, pero nos falta mucho camino por recorrer para consolidar la democracia sustantiva que queremos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como presidente del Observatorio y al inaugurar la sesi\u00f3n, dijo que la aspiraci\u00f3n que nutre a este organismo es que la paridad se convierta en una l\u00f3gica permanente de funcionamiento del sistema electoral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reconoci\u00f3 que, en ocho a\u00f1os de trabajo, M\u00e9xico ha cambiado y ha avanzado hacia la igualdad pol\u00edtica y hac\u00eda la inclusi\u00f3n, aunque lament\u00f3 que&nbsp;la violencia pol\u00edtica por razones de g\u00e9nero se increment\u00f3 a la par de la participaci\u00f3n pol\u00edtica de las mujeres cuando acceden a cargos p\u00fablicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa paridad en los municipios sigue siendo una asignatura pendiente, hoy en los municipios solamente el 27 por ciento son encabezados por mujeres y la violencia cobarde e inaceptable hacia las mujeres que se replica en las redes sociales son s\u00f3lo algunos pendientes sobre los que tenemos que reflexionar en este Observatorio y proponer decisiones para su erradicaci\u00f3n\u201d, plante\u00f3 C\u00f3rdova Vianello.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los logros, C\u00f3rdova Vianello enumer\u00f3 que en la C\u00e1mara de Diputados la paridad pas\u00f3 de 37 por ciento en 2012, a 46.6&nbsp; por&nbsp; ciento&nbsp; en 2015, a 48.2 por ciento&nbsp; en 2018 y a la paridad perfecta en 2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el Senado, se pas\u00f3 de 32.8 por ciento&nbsp; de senadoras en el 2012, a 49.2 por ciento en 2018, mientras que desde 2015, la paridad legislativa se ha impuesto en la totalidad de los congresos locales, e incluso en algunas entidades las mujeres legisladoras superan el n\u00famero de los legisladores varones y siete mujeres encabezan los ejecutivos locales, es decir, \u201ctenemos el mayor n\u00famero de mujeres gobernadoras de nuestra historia, y ese n\u00famero con las elecciones de este pr\u00f3ximo 5 de junio tender\u00e1 a crecer\u201d, augur\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Presidente del INE conf\u00edo en que el compromiso con la causa de la igualdad y la inclusi\u00f3n seguir\u00e1n siendo un motor para que las sesiones de este Observatorio sigan apuntalando la conformaci\u00f3n de la democracia sustantiva.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Necesario normalizar la participaci\u00f3n pol\u00edtica de la mujer<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En&nbsp; la sede del INE, el Magistrado Presidente del Tribunal Electoral del Poder Judicial de la Federaci\u00f3n (TEPJF), Reyes Rodr\u00edguez Mondrag\u00f3n subray\u00f3 el compromiso de diversas instituciones de construir \u201cun Estado paritario\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La paridad de g\u00e9nero, sostuvo el Magistrado, es indispensable para darle legitimidad a la democracia, pero \u00e9sta no se reduce a las elecciones, \u201ces indispensable normalizar la participaci\u00f3n paritaria en la vida p\u00fablica y para ello es necesario contar con reglas claras que proporcionen certeza a actores pol\u00edticos con acciones efectivas en contra de los obst\u00e1culos que impiden la participaci\u00f3n en condiciones de libertad e igualdad de las mujeres, y se requiere de la voluntad pol\u00edtica de los partidos ya que con sus definiciones pueden limitar o impulsar la participaci\u00f3n de las mujeres en la vida pol\u00edtica\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reyes Mondrag\u00f3n plante\u00f3 como reto que los congresos locales introduzcan en su legislaci\u00f3n las garant\u00edas que conllevan a la postulaci\u00f3n paritaria y efectiva y que los partidos pol\u00edticos reglamenten en su r\u00e9gimen interno las garant\u00edas de paridad en la postulaci\u00f3n de cargos.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Compromiso con erradicar la desigualdad y la violencia pol\u00edtica<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una intervenci\u00f3n virtual, la Presidenta del Instituto Nacional de las Mujeres (INMUJRES), Nadine Gasman Zylbermann,&nbsp;se dirigi\u00f3 a las mujeres que est\u00e1n contendiendo por uno de los 436 cargos de elecci\u00f3n popular en los comicios de Aguascalientes, Durango, Hidalgo, Oaxaca, Quintana Roo y Tamaulipas que se llevar\u00e1n a cabo el pr\u00f3ximo 5 de junio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCon su participaci\u00f3n la democracia se fortalece, transform\u00e1ndonos en una sociedad incluyente y pluralista. No est\u00e1n solas y como instituciones que integramos el Observatorio Nacional, queremos refrendar nuestro compromiso de seguir trabajando para dar cumplimiento de los derechos de participaci\u00f3n de las mujeres, especialmente resarcir la desigualdad en el acceso a las presidencias municipales y tambi\u00e9n erradicar la violencia contra las mujeres en el \u00e1mbito pol\u00edtico\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nadine Gasman advirti\u00f3 sobre la posibilidad de retrocesos por lo que para evitar que las candidatas de \u00e9sta y de las pr\u00f3ximas contiendas abandonen sus carreras pol\u00edticas, consider\u00f3 necesario un cambio cultural, pero en tanto, llam\u00f3 a los partidos pol\u00edticos a garantizar la participaci\u00f3n pol\u00edtica de las mujeres durante y despu\u00e9s del proceso electoral; a los observadores locales a brindar espacios de movilizaci\u00f3n pol\u00edtica; a la ciudadan\u00eda de las entidades con elecci\u00f3n, a que se pronuncien a favor de la igualdad sustantiva y refrend\u00f3 el compromiso del Observatorio de trabajar de manera coordinada para impulsar, promover, fortalecer y garantizar el pleno ejercicio de los derechos pol\u00edticos de las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre los trabajos de esta sesi\u00f3n del Observatorio, la Presidenta de la Comisi\u00f3n de Igualdad de G\u00e9nero y No Discriminaci\u00f3n del INE, Norma De la Cruz Maga\u00f1a, adelant\u00f3 los documentos analizados durante la misma que muestran aciertos en la instrumentaci\u00f3n de la paridad, pero tambi\u00e9n interrogantes y pendientes sobre el camino para seguir construyendo y que las mujeres accedan y ejerzan sus derechos pol\u00edticos electorales sin ser discriminadas y violentadas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3 que las recientes reformas, tanto en materia de paridad como en la atenci\u00f3n de la violencia pol\u00edtica en raz\u00f3n de g\u00e9nero, \u201cnos exige no abstraernos de la realidad nacional, y de manera decidida y comprometida nos implica llevar a cabo el cumplimiento de nuestras atribuciones y responsabilidades institucionales, a fin de mejorar y consolidar la calidad de la democracia\u201d.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Ante la ausencia de legislaci\u00f3n, aprobar Lineamientos en materia de paridad<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Posteriormente y al presentar \u201cLa paridad en las gubernaturas. Aspectos que debe monitorear la autoridad electoral\u201d, el Consejero Mart\u00edn Faz Mora record\u00f3 que gracias a unos Lineamientos aprobados por el INE se logr\u00f3 que las elecciones del pasado en donde estuvieron en disputa 15 gubernaturas, salieron electas seis gobernadoras&nbsp;en los estados de Baja California, Campeche, Colima, Chihuahua, Guerrero y Tlaxcala.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque lo ideal ser\u00eda que esta normatividad \u201cquedara reflejada en las legislaturas, tanto a nivel federal, como local\u201d, no ha sucedido por lo que el 29 de marzo del presente a\u00f1o, el Consejo General del INE, aprob\u00f3 el acuerdo relativo al cumplimiento al principio de paridad de g\u00e9nero en las postulaciones de candidaturas a gubernaturas en los procesos electorales 2021 y 2022, en los estados de Aguascalientes, Durango, Hidalgo, Oaxaca, Quintana Roo y Tamaulipas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias a ello, en Aguascalientes todos los partidos pol\u00edticos postularos a mujeres como candidatas a la gubernatura, aunque en contraparte en Tamaulipas todos los partidos postularon varones, por lo que el Consejero Faz sugiri\u00f3 que ante la ausencia de legislaciones, se apruebe y d\u00e9 seguimiento a estos Lineamientos para la conformaci\u00f3n de los cabildos en t\u00e9rminos generales, pero no para las candidaturas que encabezan los ayuntamientos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Posteriormente, la Consejera Claudia Zavala P\u00e9rez&nbsp;present\u00f3&nbsp;el Sistema de Candidatas y Candidatos, Con\u00f3celes, para los Procesos Electorales Locales 2021-2022, que \u201ctiene el objetivo de facilitar a la ciudadan\u00eda el acceso a la informaci\u00f3n de las personas candidatas que participar\u00e1n en los comicios locales\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Refiri\u00f3 que el sistema genera dos bases de datos importantes: el cuestionario de identidad, y el cuestionario curricular, por lo que se podr\u00e1 consultar la fotograf\u00eda reciente del aspirante, medios de contacto p\u00fablicos, su historia personal y laboral.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Atenci\u00f3n integral a casos de violencia pol\u00edtica en el INE<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para presentar&nbsp;el Protocolo del INE para la atenci\u00f3n a v\u00edctimas y la elaboraci\u00f3n del an\u00e1lisis de riesgo en los casos de violencia pol\u00edtica contra las mujeres en raz\u00f3n de g\u00e9nero, la Consejera Norma De la Cruz&nbsp;subray\u00f3 que tiene como eje rector la atenci\u00f3n de primer contacto a las personas que hacen denuncias o presentan quejas en la materiacon absoluta confidencialidad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstamos buscando que en este protocolo tengamos una metodolog\u00eda muy clara para que todas las personas que se acerquen a hacer una denuncia reciban una atenci\u00f3n de calidad, con mucho respeto, porque aqu\u00ed lo que estamos poniendo al centro es a la persona\u201d, detall\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En suma, agreg\u00f3 De la Cruz el protocolo \u201cnos ayuda a dar una buena atenci\u00f3n a las personas v\u00edctimas que se acercan al Instituto; dos, nos permite hacer una mejor documentaci\u00f3n y fundamento de la queja, y tercero, compartimos este protocolo con todas las instituciones con las que nos estamos coordinando para que estemos en sincron\u00eda, hablemos el mismo idioma y podamos dar una atenci\u00f3n integral a las personas que se nos acercan y presentan denuncias\u201d, abund\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que no haya elecciones sin la competencia de mujeres<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al comentar las presentaciones, la Consejera Carla Humphrey Jordan ponder\u00f3 que una vez que se logr\u00f3 la reforma, es necesario que autoridades e instituciones se coordinen adecuadamente para dar protecci\u00f3n y seguridad a las mujeres v\u00edctimas de violencia pol\u00edtica que tengan el valor de iniciar una denuncia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1al\u00f3 los claroscuros que se han encontrado en la paridad, como el hecho de que en el proceso electoral local actual en Aguascalientes hay puras mujeres candidatas; mientras que, en Tamaulipas no hay una sola mujer compitiendo por la gubernatura, esto debe llamarnos la atenci\u00f3n para que \u201cno vuelva a haber ninguna elecci\u00f3n en la que mujeres no est\u00e9n compitiendo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, consider\u00f3 importante seguir avanzando, pese a que el mes pasado, la Sala Superior determin\u00f3 como obligaci\u00f3n de los partidos pol\u00edticos establecer reglas de paridad sustantiva y competitividad, adem\u00e1s de que mandat\u00f3 al INE a verificar que las fuerzas pol\u00edticas definan estos criterios y por supuesto, que cumplan con ellos en la postulaci\u00f3n de candidaturas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Presencia de mujeres legisladoras no es incidencia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toc\u00f3 a la Consejera Adriana Favela Herrera comentar los resultados de la Investigaci\u00f3n:&nbsp;Fuerza pol\u00edtica de las legisladoras en los congresos locales de M\u00e9xico, presentado por Adriana B\u00e1ez Carlos, Directora del \u00c1rea de la Consultor\u00eda de Bur\u00f3 Parlamentario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El estudio, explic\u00f3 Favela, muestra que se ha logrado un avance muy importante, en la participaci\u00f3n cuantitativa de las mujeres en nuestro pa\u00eds, sobre todo en las legislaturas integradas por lo menos en un 40% por mujeres y forman parte de las comisiones legislativas tanto a nivel federal como local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, lament\u00f3, \u201cpresencia no es incidencia\u201d ya que las mujeres no est\u00e1n formando parte, en su mayor\u00eda de las Juntas de Coordinaci\u00f3n pol\u00edtica donde se toman realmente las decisiones m\u00e1s importantes del \u00f3rgano colegiado, ni tampoco integran o presiden las comisiones m\u00e1s importantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00bfPor qu\u00e9 si cada vez tenemos m\u00e1s mujeres en estos \u00f3rganos legislativos, por qu\u00e9 no se les permite o ellas no exigen acceder a las Juntas de Coordinaci\u00f3n Pol\u00edtica? Y cuando acceden representan a los grupos pol\u00edticos minoritarios y no a los m\u00e1s importantes\u201d, cuestion\u00f3 y sugiri\u00f3 sumar fuerzas entre mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Homologar criterios para sancionar la violencia pol\u00edtica<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Posteriormente, la Consejera Dania Ravel Cuevas coment\u00f3 la presentaci\u00f3n de los proyectos \u201cDel dicho al hecho\u201d. Observaci\u00f3n electoral jurisdicci\u00f3n en materia de violencia pol\u00edtica contra las mujeres en raz\u00f3n de g\u00e9nero en el Proceso Electoral Federal 2020-2021, y el de la Sistematizaci\u00f3n del Observatorio de Participaci\u00f3n Pol\u00edtica de las Mujeres. PNUD-ONU Mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Consejera Ravel coincidi\u00f3 que en materia de sanciones, la Ley General de Instituciones y Procedimientos Electorales establece amonestaciones gen\u00e9ricas pero no hay un cat\u00e1logo de sanciones espec\u00edficas para el procedimiento especial sancionador en materia de violencia pol\u00edtica por raz\u00f3n de g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTenemos que ir homologando criterios para sancionar este tipo de casos\u201d, propuso y coincidi\u00f3 con el que las autoridades que resuelven casos de violencia pol\u00edtica contra las mujeres por raz\u00f3n de g\u00e9nero, \u201ctengan capacitaci\u00f3n en materia de perspectiva de g\u00e9nero e interseccional para que las sanciones sean efectivamente proporcionales con las conductas que se cometen y as\u00ed puedan tener un efecto inhibitorio real\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es decir, las autoridades encargadas de instruir los casos deben elaborar normatividad que les permite atender de manera expedita y efectiva los procedimientos en la materia de violencia pol\u00edtica contra las mujeres por raz\u00f3n de g\u00e9nero, como lo hizo el INE en un reglamento espec\u00edfico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el segundo caso, la Consejera Ravel coincidi\u00f3 en formar un frente com\u00fan, pues constituye una gu\u00eda clara para los trabajos a realizar desde el Observatorio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-o0o-<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Categor\u00edas<a href=\"https:\/\/centralelectoral.ine.mx\/category\/al-dia\/\">Al d\u00eda<\/a>,&nbsp;<a href=\"https:\/\/centralelectoral.ine.mx\/category\/destacada\/\">Destacada INE<\/a>,&nbsp;<a href=\"https:\/\/centralelectoral.ine.mx\/category\/noticias\/\">Noticias<\/a>Etiquetas<a href=\"https:\/\/centralelectoral.ine.mx\/tag\/comunicados\/\">Comunicados<\/a>,&nbsp;<a href=\"https:\/\/centralelectoral.ine.mx\/tag\/comunicados-prensa\/\">Comunicados de Prensa<\/a>,&nbsp;<a href=\"https:\/\/centralelectoral.ine.mx\/tag\/democracia\/\">Democracia<\/a>,&nbsp;<a href=\"https:\/\/centralelectoral.ine.mx\/tag\/participacion-politica-de-la-mujer\/\">Participaci\u00f3n Pol\u00edtica de la Mujer<\/a>Navegaci\u00f3n de entradas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/centralelectoral.ine.mx\/2022\/05\/12\/el-ine-el-tepjf-y-el-inmujeres-continuan-acciones-para-promover-la-participacion-de-las-mujeres-en-espacios-de-toma-de-decision\/\">El INE, el TEPJF y el INMUJERES contin\u00faan acciones para promover la participaci\u00f3n de las mujeres en espacios de toma de decisi\u00f3n<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/centralelectoral.ine.mx\/2022\/05\/12\/vigesima-sesion-ordinaria-del-observatorio-de-participacion-politica-de-las-mujeres-en-mexico\/\">Vig\u00e9sima sesi\u00f3n Ordinaria del Observatorio de Participaci\u00f3n Pol\u00edtica de las Mujeres en M\u00e9xico<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autoridades electorales, organizaciones de la sociedad civil e instituciones del Estado mexicano integrantes del Observatorio de Participaci\u00f3n Pol\u00edtica de las Mujeres en M\u00e9xico<\/p>\n","protected":false},"author":3,"featured_media":50084,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[693,51],"tags":[],"class_list":["post-50083","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-ejecutivo"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/50083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=50083"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/50083\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/50084"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=50083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=50083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=50083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}