{"id":49351,"date":"2022-05-01T14:10:20","date_gmt":"2022-05-01T20:10:20","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=49351"},"modified":"2023-07-21T19:03:50","modified_gmt":"2023-07-22T00:03:50","slug":"respeto-total-al-trabajo-sexual-en-el-marco-del-dia-internacional-del-trabajo","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/respeto-total-al-trabajo-sexual-en-el-marco-del-dia-internacional-del-trabajo\/","title":{"rendered":"Respeto total al trabajo sexual en el marco del D\u00eda Internacional del Trabajo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Lizbeth \u00c1lvarez Mart\u00ednez.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 1\u00ba. de Mayo, 2022 .-Trabajadoras sexuales que laboran en las distintas calles de la Ciudad de M\u00e9xico se congregaron entre las calles de corregidora y soledad, alcald\u00eda Cuauht\u00e9moc, para salir juntas durante la marcha por el D\u00eda Internacional del Trabajo y exigir sus derechos laborales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de iniciar la manifestaci\u00f3n, les fueron repartidos condones para que los llevar\u00e1n durante la caminata a manera de protesta y exigir que el derecho a la salud debe ser para todas y todos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLos condones son fundamentales para nosotras en nuestra labor diaria en el ejercicio del trabajo sexual\u201d, extern\u00f3 una de las manifestantes del contingente.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-01-at-2.58.26-PM-2.jpeg\"><img decoding=\"async\" data-id=\"49354\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-01-at-2.58.26-PM-2-1024x768.jpeg\" alt=\"\" class=\"wp-image-49354\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-01-at-2.58.26-PM-1.jpeg\"><img decoding=\"async\" data-id=\"49353\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-01-at-2.58.26-PM-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-49353\"\/><\/a><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La marcha se llev\u00f3 a cabo para demandar el reconocimiento pleno del que los derechos sexuales, reproductivos, humanos, laborales y pol\u00edticos de las trabajadoras sexuales. De igual forma, exigieron el cese del hostigamiento por parte de las autoridades y grupos de la delincuencia organizada, pero tambi\u00e9n, pidieron que se respetaran los puntos de la ciudad donde laboran.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los puestos ambulantes fueron caminando las trabajadoras sexuales y gritando la consigna \u201cRespeto total al trabajo sexual\u201d. Entre las pancartas que tra\u00edan se le\u00eda \u201cNo a la violencia\u201d, \u201cNuestros clientes no son delincuentes\u201d, \u201cLa calle es de quien la trabaja\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe decir que, con la llegada de la pandemia del Covid-19, cientos de mujeres trabajadoras sexuales tuvieron que padecer econ\u00f3micamente los estragos del cierre de hoteles y moteles de la Ciudad de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En entrevista para Semmexico, Elvira Madrid Romero, presidente de la Brigada Callejera, mencion\u00f3 que se ha precarizado la situaci\u00f3n de las trabajadoras sexuales independientes, \u201csus ingresos han disminuido hasta en un 70%. Adem\u00e1s, se duplic\u00f3 el n\u00famero de trabajadoras sexuales en las calles de la Ciudad. Antes del Covid-19 se contabilizaban cerca de 7 mil 700 trabajadoras, la cifra m\u00e1s reciente suma 15 mil200\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asegur\u00f3 que el conteo es parte de un diagn\u00f3stico que implement\u00f3 la Brigada Callejera y, de la cifra total, la organizaci\u00f3n estima que el 40% son mujeres que hab\u00edan dejado el trabajo sexual, pero han tenido que regresar a las calles; otro 40% son mujeres que iniciaron a ra\u00edz de la crisis; y el 20% restante representa a las que no est\u00e1n en un punto espec\u00edfico, es decir, caminan en v\u00eda p\u00fablica buscando clientes.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-01-at-2.58.27-PM-1.jpeg\"><img decoding=\"async\" data-id=\"49355\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-01-at-2.58.27-PM-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-49355\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-01-at-2.58.27-PM.jpeg\"><img decoding=\"async\" data-id=\"49356\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-01-at-2.58.27-PM-1024x768.jpeg\" alt=\"\" class=\"wp-image-49356\"\/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Trabajadoras sexuales que laboran en las distintas calles de la Ciudad de M\u00e9xico se congregaron entre las calles de corregidora y soledad, alcald\u00eda Cuauht\u00e9moc, para salir juntas durante la marcha por el D\u00eda Internacional del Trabajo y exigir sus derechos laborales.<\/p>\n","protected":false},"author":3,"featured_media":49352,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[693,54],"tags":[],"class_list":["post-49351","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-mujeres"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/49351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=49351"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/49351\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/49352"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=49351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=49351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=49351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}