{"id":4897,"date":"2018-12-05T17:49:35","date_gmt":"2018-12-05T17:49:35","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=4897"},"modified":"2023-07-21T14:34:43","modified_gmt":"2023-07-21T19:34:43","slug":"23-mil-mujeres-en-las-fuerzas-armadas","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/23-mil-mujeres-en-las-fuerzas-armadas\/","title":{"rendered":"23 mil mujeres en las Fuerzas Armadas."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.semmexico.com\/gallery-post.php?id=6564#\">Redacci\u00f3n<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. Cd. de M\u00e9xico. 5 diciembre 2018.- Para que el personal militar femenino pueda modificar su licencia de maternidad, el pleno cameral aprob\u00f3 por unanimidad de 435 votos, el dictamen a la minuta que adiciona dos p\u00e1rrafos al art\u00edculo 152 de la Ley del Instituto de Seguridad Social para las Fuerzas Armadas Mexicanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El documento, devuelto con cambios al Senado de la Rep\u00fablica para sus efectos constitucionales, establece que \u201ca solicitud expresa del personal militar femenino, previa autorizaci\u00f3n escrita del m\u00e9dico tratante, y tomando en cuenta la naturaleza del trabajo que desempe\u00f1e, se podr\u00e1 transferir hasta medio mes de licencia anterior a la fecha probable del parto para despu\u00e9s del mismo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cLa licencia posterior al parto aumentar\u00e1 dos meses adicionales, en caso de que los hijos hayan nacido con cualquier tipo de discapacidad o requieran atenci\u00f3n m\u00e9dica hospitalaria, previa presentaci\u00f3n del certificado o dictamen correspondiente expedido por m\u00e9dicos militares o navales especialistas en servicio activo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los cambios que hizo la C\u00e1mara de Diputados a la minuta consisten en sustituir los t\u00e9rminos \u201cdescanso\u201d por \u201clicencia\u201d y el de \u201cm\u00e9dico del instituto\u201d por \u201cm\u00e9dico responsable de la paciente\u201d. Adem\u00e1s, contempla incluir tanto la expresi\u00f3n \u201ccertificado o dictamen\u201d, y acord\u00f3 aumentar de medio mes a dos meses la licencia posterior al parto, en caso de que los hijos hayan nacido con cualquier tipo de discapacidad o requieran atenci\u00f3n m\u00e9dica hospitalaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de la Comisi\u00f3n de Defensa Nacional, diputado Benito Medina Herrera (PRI), expres\u00f3 que estas reformas benefician a las militares. Su importante derecho de la licencia de maternidad plasmado en la Constituci\u00f3n Pol\u00edtica representa la obligaci\u00f3n del Estado mexicano de garantizarlo para madres trabajadoras del pa\u00eds.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los posicionamientos, la diputada Erika Mariana Rosas Uribe (Morena) expres\u00f3 que el dictamen facilita la legislaci\u00f3n, la protecci\u00f3n social de las Fuerzas Armadas, en particular, el acceso de las mujeres a su derecho a la maternidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su compa\u00f1ero de bancada, diputado Armando Javier Zertuche Zuani, resalt\u00f3 que estas reformas representan un acto elemental de justicia para el personal femenino de las Fuerzas Armadas, y constituye un ajuste legal a disposiciones del derecho internacional que el Estado mexicano ha suscrito y que son de cumplimiento obligatorio en todo el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n de Morena, la diputada Mar\u00eda Guillermina Alvarado Moreno, resalt\u00f3 que \u201cla incapacidad por maternidad tiene el objetivo fundamental de proteger la salud de las mujeres y sus hijos durante el periodo perinatal, dadas las necesidades fisiol\u00f3gicas asociadas al embarazo y parto\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Del PAN, la diputada Madeleine Bonnafoux Alcaraz resalt\u00f3 que estas mismas reformas ya se dieron desde el 30 de noviembre de 2012 para mujeres trabajadoras regidas por la Ley Federal del Trabajo, y hoy \u201cseis a\u00f1os despu\u00e9s, se propone que las valientes mujeres de las Fuerzas Armadas vean materializado este derecho respecto a la flexibilidad del periodo previo y posterior al parto\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La diputada Mariana Rodr\u00edguez Mier y Ter\u00e1n (PRI) expuso que, con la aprobaci\u00f3n de esta propuesta, se armoniza la legislaci\u00f3n en materia de seguridad social de las Fuerzas Armadas, con las prestaciones que hoy se contemplan en la Ley Federal del Trabajo, y cumplir con todos los tratados internacionales de los que M\u00e9xico es parte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>23 mil mujeres en el Ej\u00e9rcito<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por el PES, el diputado Manuel de Jes\u00fas Baldenebro Arredondo, precis\u00f3 que la participaci\u00f3n de las mujeres en las Fuerzas Armadas ha aumentado en los \u00faltimos a\u00f1os de manera considerable. Actualmente hay en sus filas m\u00e1s de 23 mil \u201ctalentosas y respetables mujeres\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con la Organizaci\u00f3n Internacional del Trabajo, la licencia de maternidad es un mecanismo de gran relevancia para salvaguardar la salud y seguridad econ\u00f3mica de las mujeres y de sus hijos. \u201cEstamos a favor de modificar las semanas en las que se garantiza al personal femenino militar esta licencia, previa autorizaci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Carmen Julia Prudencio Gonz\u00e1lez, diputada de MC, resalt\u00f3 que estas adiciones implican cambios positivos, inmediatos y palpables para beneficiar al personal militar femenino y a sus hijos. En esta Legislatura, \u201cla maternidad y lo que conlleva es un asunto prioritario\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La diputada Claudia Reyes Montiel (PRD) manifest\u00f3 que finalidad es cumplir con la obligaci\u00f3n de garantizar los derechos humanos de las mujeres trabajadoras, tal como se ha establecido en la Carta Magna, as\u00ed como en los tratados internacionales que el pa\u00eds ha signado, como la Convenci\u00f3n sobre la Eliminaci\u00f3n de Todas las Formas de Discriminaci\u00f3n contra la Mujer. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la discusi\u00f3n en lo general, la diputada Dionicia V\u00e1zquez Garc\u00eda (PT) se refiri\u00f3 al incremento considerable de mujeres dentro del Ej\u00e9rcito y Fuerza A\u00e9rea, y el descanso posparto es m\u00e1s importante que el de preparto, \u201cen virtud de que la gran mayor\u00eda de las embarazadas no requieren, salvo casos especiales, de un descanso prolongado previo al parto\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Del PRD, la diputada M\u00f3nica Bautista Rodr\u00edguez precis\u00f3 que el personal militar femenino, debe gozar de tiempos claros para el goce de su maternidad. \u201cLas mujeres de las Fuerzas Armadas, como cualquier mujer, tienen el derecho de disfrutar del ejercicio de su maternidad\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/sj<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Redacci\u00f3n SemM\u00e9xico. Cd. de M\u00e9xico. 5 diciembre 2018.- Para que el personal militar femenino pueda modificar su licencia de maternidad, el pleno cameral aprob\u00f3 por unanimidad de 435 votos, el dictamen a la minuta que adiciona dos p\u00e1rrafos al art\u00edculo 152 de la Ley del Instituto de Seguridad Social para las Fuerzas Armadas Mexicanas. El [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4898,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[689,50],"tags":[],"class_list":["post-4897","post","type-post","status-publish","format-standard","has-post-thumbnail","category-689","category-congreso"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/4897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=4897"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/4897\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/4898"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=4897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=4897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=4897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}